{"id":1436465,"date":"2023-01-11T15:01:47","date_gmt":"2023-01-11T23:01:47","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1436465"},"modified":"2023-01-11T15:01:47","modified_gmt":"2023-01-11T23:01:47","slug":"estos-fueron-todos-los-ganadores-de-los-golden-globes-2023","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/","title":{"rendered":"Estos fueron todos los ganadores de los Golden Globes 2023"},"content":{"rendered":"<p>Este martes se llev\u00f3 a cabo la 80\u00b0 Entrega de los Golden Globes, la cual premia a lo mejor del cine y la televisi\u00f3n en Estados Unidos, y que en el 2023 regres\u00f3 a la televisi\u00f3n abierta luego de la pol\u00e9mica en la que se vio envuelta hace un par de a\u00f1os.<\/p>\n<p>La noche desfil\u00f3 el talento de artistas de talla global, quienes han revolucionado la industria del entretenimiento y que compet\u00edan por una estatuilla.<\/p>\n<p>Adem\u00e1s de nominados, la ceremonia cont\u00f3 con invitados de lujo entre los que destacaron Tom Holland, Eddie Murphy, Jennifer Coolidge, Evan Peters, Julia Garner, Brad Pitt, Rihanna y Margot Robbie, por mencionar algunos.<\/p>\n<p>The Fabelmans se coron\u00f3 como la Mejor Pel\u00edcula en la categor\u00eda de Drama y la sorpresa de la noche, fue para la actriz Quinta Brunson que se llev\u00f3 a casa el premio a Mejor Actuaci\u00f3n de una Actriz en una Serie de Televisi\u00f3n, desplazando a Selena Gomez y Jenna Ortega, quienes figuraban como favoritas.<\/p>\n<p>El productor Ryan Murphy fue homenajeado por su exitosa carrera con m\u00e1s de 20 a\u00f1os y decenas de series exitosas, House Of The Dragon gan\u00f3 el premio a Mejor Serie de Televisi\u00f3n Dram\u00e1tica y para M\u00e9xico, Guillermo del Toro se coron\u00f3 con el premio a Mejor Pel\u00edcula Animada por su \u00faltimo largometraje, Pinocchio.<\/p>\n<p>Sin m\u00e1s, te dejamos con la lista de ganadores de la noche esperando que se haya cumplido tu quiniela.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Rihanna y A$AP Rocky rockeando en los <a href=\"https:\/\/twitter.com\/hashtag\/GoldenGlobes2023?src=hash&amp;ref_src=twsrc%5Etfw\">#GoldenGlobes2023<\/a> <a href=\"https:\/\/t.co\/GAzfCfDv86\">pic.twitter.com\/GAzfCfDv86<\/a><\/p>\n<p>&mdash; El Bot\u00f3n (@ElBotonRadio) <a href=\"https:\/\/twitter.com\/ElBotonRadio\/status\/1613010358431617026?ref_src=twsrc%5Etfw\">January 11, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p data-score=\"19\"><b>Mejor Actuaci\u00f3n de un Actor en una Serie de Televisi\u00f3n &#8212; Musical o Comedia<\/b><\/p>\n<ul data-score=\"83\">\n<li>Donald Glover, \u201cAtlanta\u201d<\/li>\n<li>Bill Hader, \u201cBarry\u201d<\/li>\n<li>Steve Martin, \u201cOnly Murders in the Building\u201d<\/li>\n<li>Martin Short, \u201cOnly Murders in the Building\u201d<\/li>\n<li><b>Jeremy Allen White, \u201cThe Bear\u201d GANADOR<\/b><\/li>\n<\/ul>\n<p data-score=\"19\"><b>Mejor Actuaci\u00f3n de una Actriz en una Serie de Televisi\u00f3n &#8212; Musical o Comedia<\/b><\/p>\n<ul data-score=\"82\">\n<li><b>Quinta Brunson, \u201cAbbott Elementary\u201d GANADOR<\/b><\/li>\n<li>Kaley Cuoco, \u201cThe Flight Attendant\u201d<\/li>\n<li>Selena Gomez, \u201cOnly Murders in the Building\u201d<\/li>\n<li>Jenna Ortega, \u201cWednesday\u201d<\/li>\n<li>Jean Smart, \u201cHacks\u201d<\/li>\n<\/ul>\n<p data-score=\"15\"><b>Mejor Actuaci\u00f3n de un Actor en una Serie de Televisi\u00f3n<\/b><\/p>\n<ul data-score=\"72\">\n<li>Jeff Bridges, \u201cThe Old Man\u201d<\/li>\n<li><b>Kevin Costner, \u201cYellowstone\u201d GANADOR<\/b><\/li>\n<li>Diego Luna, \u201cAndor\u201d<\/li>\n<li>Bob Odenkirk, \u201cBetter Call Saul\u201d<\/li>\n<li>Adam Scott, \u201cSeverance\u201d<\/li>\n<\/ul>\n<p data-score=\"15\"><b>Mejor Actuaci\u00f3n de una Actriz en una Serie de Televisi\u00f3n<\/b><\/p>\n<ul data-score=\"73\">\n<li>Emma D\u2019Arcy, \u201cHouse of the Dragon\u201d<\/li>\n<li>Laura Linney, \u201cOzark\u201d<\/li>\n<li>Imelda Staunton, \u201cThe Crown\u201d<\/li>\n<li>Hilary Swank, \u201cAlaska Daily\u201d<\/li>\n<li><b>Zendaya, \u201cEuphoria\u201d GANADOR<\/b><\/li>\n<\/ul>\n<p data-score=\"19\"><b>Mejor actuaci\u00f3n de un actor en una serie limitada o pel\u00edcula para televisi\u00f3n<\/b><\/p>\n<ul data-score=\"89\">\n<li>Taron Egerton, \u201cBlack Bird\u201d<\/li>\n<li>Colin Firth, \u201cThe Staircase\u201d<\/li>\n<li>Andrew Garfield, \u201cUnder the Banner of Heaven\u201d<\/li>\n<li><b>Evan Peters, \u201cMonster: The Jeffrey Dahmer Story\u201d GANADOR<\/b><\/li>\n<li>Sebastian Stan, \u201cPam and Tommy\u201d<\/li>\n<\/ul>\n<p data-score=\"20\"><b>Mejor actuaci\u00f3n de una actriz en una serie limitada o pel\u00edcula para televisi\u00f3n<\/b><\/p>\n<ul data-score=\"78\">\n<li>Jessica Chastain, \u201cGeorge and Tammy\u201d<\/li>\n<li>Julia Garner, \u201cInventing Anna\u201d<\/li>\n<li>Lily James, \u201cPam and Tommy\u201d<\/li>\n<li>Julia Roberts, \u201cGaslit\u201d<\/li>\n<li><b>Amanda Seyfried, \u201cThe Dropout\u201d GANADOR<\/b><\/li>\n<\/ul>\n<p data-score=\"11\"><b>Mejor serie de televisi\u00f3n dram\u00e1tica<\/b><\/p>\n<ul data-score=\"52\">\n<li>\u201cBetter Call Saul\u201d<\/li>\n<li>\u201cThe Crown\u201d<\/li>\n<li><b>\u201cHouse of the Dragon\u201d GANADOR<\/b><\/li>\n<li>\u201cOzark\u201d<\/li>\n<li>\u201cSeverance\u201d<\/li>\n<\/ul>\n<p data-score=\"16\"><b>Mejor serie limitada de televisi\u00f3n o pel\u00edcula para televisi\u00f3n<\/b><\/p>\n<ul data-score=\"62\">\n<li>\u201cBlack Bird\u201d<\/li>\n<li>\u201cMonster: The Jeffrey Dahmer Story\u201d<\/li>\n<li>\u201cPam and Tommy\u201d<\/li>\n<li>\u201cThe Dropout\u201d<\/li>\n<li><b>\u201cThe White Lotus: Sicily\u201d GANADOR<\/b><\/li>\n<\/ul>\n<p data-score=\"25\"><b>Mejor actuaci\u00f3n de una actriz en un papel secundario en una serie de televisi\u00f3n de comedia musical o drama<\/b><\/p>\n<ul data-score=\"78\">\n<li>Elizabeth Debicki, \u201cThe Crown\u201d<\/li>\n<li>Hannah Einbinder, \u201cHacks\u201d<\/li>\n<li><b>Julia Garner, \u201cOzark\u201d GANADOR<\/b><\/li>\n<li>Janelle James, \u201cAbbott Elementary\u201d<\/li>\n<li>Sheryl Lee Ralph, \u201cAbbott Elementary\u201d<\/li>\n<\/ul>\n<p data-score=\"25\"><b>Mejor actuaci\u00f3n de una actriz en un papel secundario en una serie, miniserie o pel\u00edcula para televisi\u00f3n<\/b><\/p>\n<ul data-score=\"98\">\n<li><b>Jennifer Coolidge, \u201cThe White Lotus\u201d GANADOR<\/b><\/li>\n<li>Claire Danes, \u201cFleishman Is in Trouble\u201d<\/li>\n<li>Daisy Edgar-Jones, \u201cUnder the Banner of Heaven\u201d<\/li>\n<li>Niecy Nash-Betts, \u201cMonster: The Jeffrey Dahmer Story\u201d<\/li>\n<li>Aubrey Plaza, \u201cThe White Lotus\u201d<\/li>\n<\/ul>\n<p data-score=\"24\"><b>Mejor actuaci\u00f3n de un actor en un papel secundario en una serie, miniserie o pel\u00edcula para televisi\u00f3n<\/b><\/p>\n<ul data-score=\"88\">\n<li>F. Murray Abraham, \u201cThe White Lotus\u201d<\/li>\n<li>Domhnall Gleeson, \u201cThe Patient\u201d<\/li>\n<li><b>Paul Walter Hauser, \u201cBlack Bird\u201d GANADOR<\/b><\/li>\n<li>Richard Jenkins, \u201cMonster: The Jeffrey Dahmer Story\u201d<\/li>\n<li>Seth Rogen, \u201cPam and Tommy\u201d<\/li>\n<\/ul>\n<p data-score=\"13\"><b>Mejor Serie de Televisi\u00f3n &#8212; Musical o Comedia<\/b><\/p>\n<ul data-score=\"55\">\n<li><b>\u201cAbbott Elementary\u201d GANADOR<\/b><\/li>\n<li>\u201cThe Bear\u201d<\/li>\n<li>\u201cHacks\u201d<\/li>\n<li>\u201cOnly Murders in the Building\u201d<\/li>\n<li>\u201cWednesday\u201d<\/li>\n<\/ul>\n<h3 data-score=\"0\">Pel\u00edculas<\/h3>\n<p data-score=\"11\"><b>Mejor Pel\u00edcula &#8212; musical o comedia<\/b><\/p>\n<ul data-score=\"71\">\n<li>\u201cBabylon\u201d<\/li>\n<li><b>\u201cThe Banshees of Inisherin\u201d GANADOR<\/b><\/li>\n<li>\u201cEverything Everywhere All at Once\u201d<\/li>\n<li>\u201cGlass Onion: A Knives Out Mystery\u201d<\/li>\n<li>\u201cTriangle of Sadness\u201d<\/li>\n<\/ul>\n<p data-score=\"8\"><b>Mejor Pel\u00edcula &#8212; Drama<\/b><\/p>\n<ul data-score=\"53\">\n<li>\u201cAvatar: The Way of Water\u201d<\/li>\n<li>\u201cElvis\u201d<\/li>\n<li><b>\u201cThe Fabelmans\u201d GANADOR<\/b><\/li>\n<li>\u201cTAR\u201d<\/li>\n<li>\u201cTop Gun: Maverick\u201d<\/li>\n<\/ul>\n<p data-score=\"11\"><b>Mejor Pel\u00edcula en lengua extranjera<\/b><\/p>\n<ul data-score=\"74\">\n<li>\u201cRRR\u201d (India)<\/li>\n<li>\u201cAll Quiet on the Western Front\u201d (Germany)<\/li>\n<li><b>\u201cArgentina, 1985\u201d (Argentina) GANADOR<\/b><\/li>\n<li>\u201cClose\u201d (Belgium)<\/li>\n<li>\u201cDecision to Leave\u201d (South Korea)<\/li>\n<\/ul>\n<p data-score=\"6\"><b>Mejor Gui\u00f3n<\/b><\/p>\n<ul data-score=\"97\">\n<li>Todd Field, \u201cT\u00e1r\u201d<\/li>\n<li>Tony Kushner &amp; Steven Spielberg, \u201cThe Fabelmans\u201d<\/li>\n<li>Daniel Kwan, Daniel Scheinert, \u201cEverything Everywhere All at Once\u201d<\/li>\n<li><b>The Banshees of Inisherin, \u201cMartin McDonagh\u201d GANADOR<\/b><\/li>\n<li>Sarah Polley, \u201cWomen Talking\u201d<\/li>\n<\/ul>\n<p data-score=\"8\"><b>Mejor Canci\u00f3n original<\/b><\/p>\n<ul data-score=\"156\">\n<li>\u201cCarolina,\u201d Taylor Swift (\u201cWhere the Crawdads Sing\u201d)<\/li>\n<li>\u201cCiao Papa,\u201d Guillermo del Toro &amp; Roeban Katz (\u201cGuillermo del Toro\u2019s Pinocchio\u201d)<\/li>\n<li>\u201cHold My Hand,\u201d Lady Gaga and Bloodpop (\u201cTop Gun: Maverick\u201d)<\/li>\n<li>\u201cLift Me Up,\u201d Tems, Ludwig G\u00f6ransson, Rihanna and Ryan Coogler (\u201cBlack Panther: Wakanda Forever\u201d)<\/li>\n<li><b>\u201cNaatu Naatu,\u201d Kala Bhairava, M. M. Keeravani, Rahul Sipligunj (\u201cRRR\u201d) GANADOR<\/b><\/li>\n<\/ul>\n<p data-score=\"8\"><b>Mejor Actor de reparto<\/b><\/p>\n<ul data-score=\"91\">\n<li>Brendan Gleeson, \u201cThe Banshees of Inisherin\u201d<\/li>\n<li>Barry Keoghan, \u201cThe Banshees of Inisherin\u201d<\/li>\n<li>Brad Pitt, \u201cBabylon\u201d<\/li>\n<li><b>Ke Huy Quan, \u201cEverything Everywhere All at Once\u201d GANADOR<\/b><\/li>\n<li>Eddie Redmayne, \u201cThe Good Nurse\u201d<\/li>\n<\/ul>\n<p data-score=\"8\"><b>Mejor Actriz de reparto<\/b><\/p>\n<ul data-score=\"97\">\n<li><b>Angela Bassett, \u201cBlack Panther: Wakanda Forever\u201d GANADOR<\/b><\/li>\n<li>Kerry Condon, \u201cThe Banshees of Inisherin\u201d<\/li>\n<li>Jamie Lee Curtis, \u201cEverything Everywhere All at Once\u201d<\/li>\n<li>Dolly De Leon, \u201cTriangle of Sadness\u201d<\/li>\n<li>Carey Mulligan, \u201cShe Said\u201d<\/li>\n<\/ul>\n<p data-score=\"12\"><b>Mejor Actor de reparto en Comedia o Musical<\/b><\/p>\n<ul data-score=\"84\">\n<li>Diego Calva, \u201cBabylon\u201d<\/li>\n<li>Daniel Craig, \u201cGlass Onion: A Knives Out Mystery\u201d<\/li>\n<li>Adam Driver, \u201cWhite Noise\u201d<\/li>\n<li><b>Colin Farrell, \u201cThe Banshees of Inisherin\u201d GANADOR<\/b><\/li>\n<li>Ralph Fiennes, \u201cThe Menu\u201d<\/li>\n<\/ul>\n<p data-score=\"8\"><b>Mejor Pel\u00edcula animada<\/b><\/p>\n<ul data-score=\"61\">\n<li><b>\u201cGuillermo del Toro\u2019s Pinocchio\u201d GANADOR<\/b><\/li>\n<li>\u201cMarcel the Shell With Shoes On\u201d<\/li>\n<li>\u201cPuss in Boots: The Last Wish\u201d<\/li>\n<li>\u201cTurning Red\u201d<\/li>\n<\/ul>\n<p data-score=\"10\"><b>Mejor Actor de pel\u00edcula &#8211; Drama<\/b><\/p>\n<ul data-score=\"69\">\n<li><b>Austin Butler, \u201cElvis\u201d GANADOR<\/b><\/li>\n<li>Brendan Fraser, \u201cThe Whale\u201d<\/li>\n<li>Hugh Jackman, \u201cThe Son\u201d<\/li>\n<li>Bill Nighy, \u201cLiving\u201d<\/li>\n<li>Jeremy Pope, \u201cThe Inspection\u201d<\/li>\n<\/ul>\n<p data-score=\"10\"><b>Mejor Actriz de pel\u00edcula &#8211; Drama<\/b><\/p>\n<ul data-score=\"75\">\n<li><b>Cate Blanchett, \u201cTAR\u201d GANADOR<\/b><\/li>\n<li>Olivia Colman, \u201cEmpire of Light\u201d<\/li>\n<li>Viola Davis, \u201cThe Woman King\u201d<\/li>\n<li>Ana de Armas, \u201cBlonde\u201d<\/li>\n<li>Michelle Williams, \u201cThe Fabelmans\u201d<\/li>\n<\/ul>\n<p data-score=\"12\"><b>Mejor Actriz de pel\u00edcula &#8211; Musical o comedia<\/b><\/p>\n<ul data-score=\"92\">\n<li>Lesley Manville, \u201cMrs. Harris Goes to Paris\u201d<\/li>\n<li>Margot Robbie, \u201cBabylon\u201d<\/li>\n<li>Anya Taylor-Joy, \u201cThe Menu\u201d<\/li>\n<li>Emma Thompson, \u201cGood Luck to You Leo Grande\u201d<\/li>\n<li><b>Michelle Yeoh, \u201cEverything Everywhere All at Once\u201d GANADOR<\/b><\/li>\n<\/ul>\n<p data-score=\"8\"><b>Mejor Director -pel\u00edcula<\/b><\/p>\n<ul data-score=\"98\">\n<li>James Cameron, \u201cAvatar: The Way of Water\u201d<\/li>\n<li>Daniel Kwan and Daniel Scheinert, \u201cEverything Everywhere All at Once\u201d<\/li>\n<li>Baz Luhrmann, \u201cElvis\u201d<\/li>\n<li>Martin McDonagh, \u201cThe Banshees of Inisherin\u201d<\/li>\n<li><b>Steven Spielberg, \u201cThe Fabelmans\u201d GANADOR<\/b><\/li>\n<\/ul>\n<p data-score=\"7\"><b>Mejor Banda sonora<\/b><\/p>\n<ul data-score=\"92\">\n<li>Alexandre Desplat, \u201cGuillermo del Toro\u2019s Pinocchio\u201d<\/li>\n<li>Hildur Gu\u00f0nad\u00f3ttir, \u201cWomen Talking\u201d<\/li>\n<li><b>Justin Hurwitz, \u201cBabylon\u201d GANADOR<\/b><\/li>\n<li>John Williams, \u201cThe Fabelmans\u201d<\/li>\n<li>Carter Burwell, \u201cThe Banshees of Inisherin\u201d<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Este martes se llev\u00f3 a cabo la 80\u00b0 Entrega de los Golden Globes, la cual premia a lo mejor del cine y la televisi\u00f3n en Estados Unidos, y que en el 2023 regres\u00f3 a la televisi\u00f3n abierta luego de la pol\u00e9mica en la que se vio envuelta hace un par de a\u00f1os. La noche desfil\u00f3 [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1436467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[51],"tags":[65,66,67,68,69],"class_list":["post-1436465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-brad-pitt","tag-eddie-murphy","tag-golden-blobes","tag-guillermo-del-toro","tag-rihanna","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estos fueron todos los ganadores de los Golden Globes 2023 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estos fueron todos los ganadores de los Golden Globes 2023 - Noticias\" \/>\n<meta property=\"og:description\" content=\"Este martes se llev\u00f3 a cabo la 80\u00b0 Entrega de los Golden Globes, la cual premia a lo mejor del cine y la televisi\u00f3n en Estados Unidos, y que en el 2023 regres\u00f3 a la televisi\u00f3n abierta luego de la pol\u00e9mica en la que se vio envuelta hace un par de a\u00f1os. La noche desfil\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-11T23:01:47+00:00\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Estos fueron todos los ganadores de los Golden Globes 2023\",\"datePublished\":\"2023-01-11T23:01:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/\"},\"wordCount\":1150,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Brad Pitt\",\"Eddie Murphy\",\"Golden Blobes\",\"Guillermo del Toro\",\"Rihanna\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/\",\"url\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/\",\"name\":\"Estos fueron todos los ganadores de los Golden Globes 2023 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-01-11T23:01:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estos fueron todos los ganadores de los Golden Globes 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/noticiasya.com\/aspen\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estos fueron todos los ganadores de los Golden Globes 2023 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Estos fueron todos los ganadores de los Golden Globes 2023 - Noticias","og_description":"Este martes se llev\u00f3 a cabo la 80\u00b0 Entrega de los Golden Globes, la cual premia a lo mejor del cine y la televisi\u00f3n en Estados Unidos, y que en el 2023 regres\u00f3 a la televisi\u00f3n abierta luego de la pol\u00e9mica en la que se vio envuelta hace un par de a\u00f1os. La noche desfil\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/","og_site_name":"Noticias","article_published_time":"2023-01-11T23:01:47+00:00","author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Estos fueron todos los ganadores de los Golden Globes 2023","datePublished":"2023-01-11T23:01:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/"},"wordCount":1150,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"image":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#primaryimage"},"thumbnailUrl":"","keywords":["Brad Pitt","Eddie Murphy","Golden Blobes","Guillermo del Toro","Rihanna"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/","url":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/","name":"Estos fueron todos los ganadores de los Golden Globes 2023 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#primaryimage"},"image":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-01-11T23:01:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/nacional\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Estos fueron todos los ganadores de los Golden Globes 2023"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/noticiasya.com\/aspen\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Estos fueron todos los ganadores de los Golden Globes 2023","url":"http:\/\/noticiasya.com\/aspen\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2023\/01\/11\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":["brad pitt","eddie murphy","golden blobes","guillermo del toro","rihanna"],"dateCreated":"2023-01-11T23:01:47Z","datePublished":"2023-01-11T23:01:47Z","dateModified":"2023-01-11T23:01:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Estos fueron todos los ganadores de los Golden Globes 2023\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2023\\\/01\\\/11\\\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2023\\\/01\\\/11\\\/estos-fueron-todos-los-ganadores-de-los-golden-globes-2023\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[\"brad pitt\",\"eddie murphy\",\"golden blobes\",\"guillermo del toro\",\"rihanna\"],\"dateCreated\":\"2023-01-11T23:01:47Z\",\"datePublished\":\"2023-01-11T23:01:47Z\",\"dateModified\":\"2023-01-11T23:01:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451226,"url":"https:\/\/noticiasya.com\/aspen\/2024\/07\/17\/brad-pitt-angelina-jolie-miraval-litigio-divorcio-trax\/","url_meta":{"origin":1436465,"position":0},"title":"Brad Pitt rechaza la petici\u00f3n &#171;opresiva y acosadora&#187; de Angelina Jolie de revelar mensajes en el caso Miraval","author":"Eduardo Salinas","date":"julio 17, 2024","format":false,"excerpt":"(CNN) --\u00a0En el \u00faltimo enfrentamiento del litigio en curso entre Brad Pitt y Angelina Jolie sobre la bodega francesa Ch\u00e2teau Miraval de la expareja, ambos se enfrentan por la solicitud de Jolie para que Pitt entregue comunicaciones de terceros relacionadas con un incidente a\u00e9reo de 2016.\"Jolie, sin embargo, rechaz\u00f3 el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466328,"url":"https:\/\/noticiasya.com\/aspen\/2025\/09\/10\/brad-pitt-comercial-cafe-expreso-taika-waititi-trax\/","url_meta":{"origin":1436465,"position":1},"title":"Brad Pitt protagoniza un anuncio de Taika Waititi para una m\u00e1quina de caf\u00e9 expreso que cuesta casi US$ 1.500","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"Si te encanta el olor del comercialismo por la ma\u00f1ana, aqu\u00ed tienes algo para disfrutar.Brad Pitt, el actor, productor y cultivador de barbas favorito de todos a sus 61 a\u00f1os, es la estrella de un nuevo anuncio de m\u00e1quina de caf\u00e9 expreso de De\u2019Longhi dirigido por el ganador del Oscar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462019,"url":"https:\/\/noticiasya.com\/aspen\/2025\/05\/05\/rihanna-anuncio-embarazo-gala-met-trax\/","url_meta":{"origin":1436465,"position":2},"title":"Rihanna revela su tercer embarazo en la Gala del Met","author":"","date":"mayo 5, 2025","format":false,"excerpt":"Despu\u00e9s de revelar su segundo embarazo de forma dram\u00e1tica durante su actuaci\u00f3n en el descanso de la Super Bowl 2023, Rihanna volvi\u00f3 a hacer lo propio estrenando el tercero en la alfombra roja de la Met Gala.Fue la \u00faltima asistente en llegar al Museo Metropolitano de Arte de Nueva York\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457106,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/31\/brad-pitt-angelina-jolie-acuerdo-divorcio-trax\/","url_meta":{"origin":1436465,"position":3},"title":"Brad Pitt y Angelina Jolie llegan a un acuerdo de divorcio y cierran una disputa legal de 8 a\u00f1os","author":"","date":"diciembre 31, 2024","format":false,"excerpt":"Despu\u00e9s de una batalla legal que dur\u00f3 m\u00e1s de ocho a\u00f1os, Brad Pitt y Angelina Jolie llegaron a un acuerdo de divorcio, seg\u00fan documentos judiciales obtenidos por CNN.El acuerdo se present\u00f3 ante el Tribunal Superior de Los \u00c1ngeles el 30 de diciembre, seg\u00fan muestran los registros judiciales. No se divulgaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443302,"url":"https:\/\/noticiasya.com\/aspen\/2024\/01\/07\/premios-globo-de-oro-2024-presentadores-a-que-hora-empieza-y-como-ver-por-tv-e-internet\/","url_meta":{"origin":1436465,"position":4},"title":"Premios Globo de Oro 2024: presentadores, a qu\u00e9 hora empieza y c\u00f3mo ver por TV e internet","author":"","date":"enero 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Uno de los eventos m\u00e1s importantes de la industria del cine y la televisi\u00f3n se llevar\u00e1 a cabo este domingo 7 de enero: los Globo de Oro 2024.En su edici\u00f3n n\u00famero 81, la gala promete una noche llena de glamur desde la alfombra roja. Este a\u00f1o, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457190,"url":"https:\/\/noticiasya.com\/aspen\/2025\/01\/03\/globo-oro-golden-globes-favoritos-ojo-critico-orix\/","url_meta":{"origin":1436465,"position":5},"title":"Los favoritos para ganar los Globo de Oro 2025, seg\u00fan Ojo Cr\u00edtico","author":"","date":"enero 3, 2025","format":false,"excerpt":"Este domingo es la ceremonia de entrega de los premios Globos de Oro de 2025, que se emitir\u00e1 en directo por CBS y en streaming por Paramount+. Juan Carlos Arciniegas, el Ojo Cr\u00edtico de CNN, analiza los nominados y da sus proyecciones de los posibles ganadores en las categor\u00edas principales.\u201cThe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1436465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1436465"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1436465\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1436465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1436465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1436465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}