{"id":1437048,"date":"2023-02-10T09:59:55","date_gmt":"2023-02-10T17:59:55","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1437048"},"modified":"2023-02-10T09:59:55","modified_gmt":"2023-02-10T17:59:55","slug":"entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/","title":{"rendered":"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico"},"content":{"rendered":"<p>\u00a1Bang, bang! Sonaba la tarola de una banda callejera en la azotea de una vecindad. Las aves sobrevolaban entre tendederos con ropa y el llanto de los gatos se escuchaba a la distancia. Cascos de cerveza y un par de amplificadores rotos adornaban el cuadro.<\/p>\n<p>De fondo la radio con la cl\u00e1sica cumbia de lavaderos y por las calles una camioneta vieja que pregonaba por la colonia si ten\u00edan latas, lavadoras, microondas o algo de fierro viejo que vendan.<\/p>\n<p>La magia de un momento hechizante, salido de una pel\u00edcula en blanco y negro. Una pintura neocl\u00e1sica de la que imaginas cientos de historias pero todas culminan en el mismo final. Cuatro libertinos en la edad de lo desconocido utilizaban su magia \u00fanica para dejar el mundo y conectarse al mismo tiempo en el un\u00edsono infinito.<\/p>\n<p>El pelo enmara\u00f1ado, la mezclilla gastada de sus jeans, las u\u00f1as mal pintadas de negro y una resaca de m\u00e1s de dos d\u00edas. Todo era parte de su m\u00edstica. Todo estaba en su lugar.<\/p>\n<p>Me situ\u00e9 en ese momento. Imagin\u00e9 que los acompa\u00f1aba en su ensayo y que los chillidos de la guitarra me recorr\u00edan la espalda. Me sent\u00e9 junto a ellos en un tinaco mientras reflexionaba la profundidad de las letras. Las frases iban y ven\u00edan, rebotaban todo el tiempo en mi cabeza.<\/p>\n<p>\u00bfQu\u00e9 pensaban? \u00bfC\u00f3mo se sobreviv\u00eda a un momento as\u00ed de ins\u00f3lito en la m\u00fasica? \u00bfQu\u00e9 se sent\u00eda haber creado la mejor banda de rock y ni siquiera saberlo? Me acerqu\u00e9 a Diego y despu\u00e9s de hacer un ligero solo de teclado, lo dej\u00f3 por un momento para sentarse conmigo a beber y a charlar&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1329499 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/02\/f1280x720-24250_155925_5050.jpg?w=1024\" alt=\"\" width=\"1024\" height=\"576\" \/><\/p>\n<p><em>&#171;Lo nuestro era hacer m\u00fasica. Nunca pensamos en nada, simplemente nos ca\u00edmos bien y dijimos &#8216;yo toc\u00f3 esto, yo toco lo otro&#8217; y pues chido, de esa forma se dio, nunca pensamos en hacer una banda, al menos ni Sa\u00fal ni yo pensamos en hacer un grupo que llenara lugares o tuviera rolas legendarias. Solo quer\u00edamos tocar.<\/em><\/p>\n<p><em>Me parec\u00eda interesante compartir con un &#171;broder&#187; diferente, porque yo ven\u00eda de la salsa y de tocar jazz, entonces dije &#171;vamos a ver de qu\u00e9 se trata este rollo&#8217;. A la fecha yo me considero mucho m\u00e1s jazzero o folcl\u00f3rico o salsero que rocanrolero, porque tiene que ver no solo la m\u00fasica que tocas si no el c\u00f3mo vives.<\/em><\/p>\n<p><em>Despu\u00e9s sali\u00f3 la idea de irnos a Espa\u00f1a en un barco que te daba avent\u00f3n. Te sub\u00edas a chambear haciendo lo que fuera y a cambio de eso te llevaban. Ya casi nos \u00edbamos para all\u00e1 y de pronto apareci\u00f3 Juan Manuel Aceves, un amigo que nos consigui\u00f3 un estudio de grabaci\u00f3n como de 10 de la noche a 5 de la ma\u00f1ana que era cuando estaba libre y ah\u00ed nos metimos a hacer los demos.<\/em><\/p>\n<p><em>Uno de nuestros amigos le llev\u00f3 el demo a un cuate de la radio y programaron la rola en Espacio 59, una estaci\u00f3n bastante chida para bandas nuevas, entonces eso nos volte\u00f3 completamente la jugada porque est\u00e1bamos casi por irnos. No s\u00e9 qu\u00e9 hubiera pasado en Espa\u00f1a la verdad.<\/em><\/p>\n<p><em>No ten\u00edamos idea, quer\u00edamos tocar y punto. Me pareci\u00f3 interesante hacer algo con este g\u00fcey y la verdad yo no hab\u00eda escuchado nada, me empez\u00f3 a poner rolas y dije &#8216;\u00f3rale qu\u00e9 chido est\u00e1&#8217; y le empezamos a meter. Ahora m\u00edranos, aqu\u00ed estamos 37 a\u00f1os despu\u00e9s&#187;.<\/em><\/p>\n<p><strong>Su apariencia era oscura, desalineada y hasta andr\u00f3gina. Parec\u00edan salidos de una pel\u00edcula de Burton, \u00bffue coincidencia?<\/strong><\/p>\n<p><em>Sa\u00fal tra\u00eda mucho esa onda para m\u00ed era algo nuevo. Esa onda de pintarse los ojos y pararnos los pelos antes de tocar, la ropa negra y todo ese pedo era una novedad y de alguna manera estos g\u00fceyes ya lo tra\u00edan m\u00e1s en la sangre, Alfonso y Sa\u00fal. Yo me adapt\u00e9 a su mundo. Historias muy diferentes a la m\u00eda. Yo empec\u00e9 a descubrir muchas cosas en t\u00e9rminos musicales porque hab\u00eda algo en m\u00ed que ninguneaba al rock en muchos sentidos y hasta a ciertas bandas. Yo dec\u00eda &#8216;necesito m\u00e1s armon\u00eda, m\u00e1s acordes, cosas m\u00e1s complejas&#8217;, me hac\u00eda falta m\u00e1s<\/em><em>. La parte oscura la fui agarrando poco a poco y me fui metiendo a la onda que tra\u00edan ellos&#187;.<\/em><\/p>\n<p><strong>Despu\u00e9s el sonido hizo historia&#8230;<\/strong><\/p>\n<p><em>&#171;No fue una cosa racional ni consciente, fue algo que se dio. Un d\u00eda me preguntaban de d\u00f3nde hab\u00edan salido los sonidos tan caracter\u00edsticos del primer disco, pero lo que pasa es que yo solo ten\u00eda un sintetizador que <\/em><em>ten\u00eda ocho sonidos (risas), entonces o usaba la marimba o usaba las cuerdas. A veces ped\u00edamos prestado equipo pero eran m\u00e1s las condiciones en las que toc\u00e1bamos. Yo hab\u00eda escuchado poco rock, escuchaba cosas m\u00e1s progresivas como Yes, Genesis, m\u00e1s rock progresivo, ven\u00eda de la salsa y el jazz, as\u00ed que supongo que las ideas se mezclaron. Lo que tra\u00eda Sa\u00fal con lo m\u00edo. <\/em><\/p>\n<p><em>No s\u00e9 bien c\u00f3mo fue el proceso. <\/em><em>De repente me dijo &#8216;g\u00fcey ah\u00ed tengo una rola&#8217; le dije &#8216;ah\u00ed tengo una grabadora y unos sintes, vamos a juntar las canicas&#8217; y nos sentamos en un cuartito de azotea a empezar a chambear. &#8216;C\u00f3mo ves si le metemos esto&#8217;, &#8216;Ah suena ching\u00f3n b\u00fascale ac\u00e1&#8217;, y as\u00ed fue. Ya despu\u00e9s lleg\u00f3 el productor del primer disco y empez\u00f3 a jalar hilos de cosas interesantes que le sonaban a \u00e9l, de usar esto y lo otro. <\/em><\/p>\n<p><em>En &#8216;Viento&#8217; por ejemplo, nos faltaba una rola para el disco y Sa\u00fal lleg\u00f3 con esa secuencia de acordes y empez\u00f3 a tocar y luego pas\u00f3 la historia de la servilleta. Un se\u00f1or que nos ve\u00eda en La Veiga, un restaurante que ya no existe, nos pas\u00f3 una servilleta con la frase de la rola. Nos ve\u00eda y escrib\u00eda cosas y ese d\u00eda tra\u00edamos los pelos parados, entonces escribi\u00f3 &#171;Pr\u00e9stame tu peine y p\u00e9iname el alma&#187; y ya de ah\u00ed Sa\u00fal se encarrer\u00f3 con la letra pero esta rola era para rellenar el disco.\u00a0<\/em><\/p>\n<p><em>Fue muy chido porque era un proyecto en el que no quer\u00edamos rendirle cuentas a nadie m\u00e1s que a nosotros mismos. Si lo que yo estaba haciendo le gustaba a este g\u00fcey y al otro, ya est\u00e1bamos del otro lado. \u00c9ramos nosotros y lo seguimos siendo hasta la fecha. Nuestros propios jueces.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1329622 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/02\/Caifanes.jpg?w=1024\" alt=\"\" width=\"1024\" height=\"640\" \/><\/p>\n<p><strong>La m\u00edstica siempre fue parte de Caifanes&#8230;<\/strong><\/p>\n<p><em>La m\u00fasica tiene la virtud y la capacidad de saltarse la parte racional. Eso explica que de repente est\u00e9s cantando a todo pulm\u00f3n en un concierto con un g\u00fcey que no pelar\u00edas nunca en la calle, pero cuando tocan tu rola favorita hasta lo abrazas. La m\u00fasica es m\u00edstica completamente, ten\u00eda un maestro que dec\u00eda que la m\u00fasica era el mejor veh\u00edculo para acercarse a Dios, y s\u00ed, hay muy pocas cosas que evocan sentimientos o sensaciones como la m\u00fasica. Es como el olfato de pronto hueles algo y te regresa todos esos recuerdos.<\/em><\/p>\n<p><em>Sa\u00fal siempre tuvo una forma muy m\u00edstica y particular de escribir. Todo iba junto con pegado, por lo menos en mi caso siempre he sido mucho de v\u00edscera y es algo que ha pasado con las nuevas rolas que de repente todo cae en su lugar.\u00a0<\/em><\/p>\n<p><em>Mucho de ello es dictado no es nuestra creaci\u00f3n. Hay ciertas rolas y ciertos momentos en donde eres solo un camino, lo dem\u00e1s te lo dictan de all\u00e1 arriba.<\/em><\/p>\n<p><strong>Cuando buscas Caifanes en Internet, los primeros 100 resultados te arrojan la misma frase: Caifanes, la mejor banda de rock en espa\u00f1ol&#8230; \u00bfEst\u00e1s bien con el t\u00edtulo que se les ha dado?<\/strong><\/p>\n<p><em>Creo que s\u00ed somos una banda con una propuesta muy particular. Nos abrimos paso a chingadazos y logramos entrar a lugares donde nadie hab\u00eda entrado. Medios masivos, radio y en ese sentido s\u00ed fue un parte aguas. <\/em><\/p>\n<p><em>\u00bfLa mejor banda? No s\u00e9. Creo que no hay que buscar ser la mejor banda, le rompes la madre al asunto. Luego escuchas rolas que dices, &#8216;estos g\u00fceyes la quieren pegar a huevo&#8217;. Hay que hacer m\u00fasica por necesidad. Tiene que ver con eso, con hacer m\u00fasica por las ganas de hacer m\u00fasica, no por buscar fama. Hacerlo por el dinero y la fama es exactamente la forma para no lograrlo.<\/em><\/p>\n<p><em>Si t\u00fa haces las cosas con gusto y coraz\u00f3n, se oye y se siente. Es como t\u00fa, si quieres hacer un reportaje ching\u00f3n est\u00e1s ah\u00ed con alma y cuerpo puesto en ello y se siente y lleva esa energ\u00eda.\u00a0<\/em><\/p>\n<p><em>Creo que hay muchos caminos, el nuestro fue este y nos fue bien y quiero pensar que es por que somos honestos con lo que estamos haciendo.<\/em><\/p>\n<p><strong>Cuando terminan una canci\u00f3n deja de ser suya y pasa a ser de qui\u00e9n la escucha. Cuando escuch\u00e9 &#8216;Sombras En Tiempos Perdidos&#8217; por primera vez, sent\u00ed un abrazo profundo en el momento en el que m\u00e1s lo necesitaba. \u00bfC\u00f3mo es hacer estas canciones y qu\u00e9 pasa cuando alguien m\u00e1s se adue\u00f1a de ellas y les da un nuevo significado?<\/strong><\/p>\n<p><em>Cuando llegas al estudio ya le diste a cada rola mil vueltas por todos lados. &#8216;Sombras En Tiempos Perdidos&#8217; me gusta mucho, es de mis rolas favoritas de Caifanes. La armon\u00eda y la melod\u00eda y c\u00f3mo fue hecha. Esa est\u00e1 en el Diablito y en ese disco hubo dos rolas que hicimos con Daniel Freiberg, un m\u00fasico y un s\u00faper productor argentino, &#8216;La Celula&#8217; y &#8216;Sombras&#8217;.\u00a0<\/em><\/p>\n<p><em>Me acuerdo que para &#8216;La C\u00e9lula&#8217; necesit\u00e1bamos una trompeta para el final y Daniel me dice &#8216;\u00bfA qui\u00e9n quieres?&#8217; le dije &#8216;j\u00e1late a Randy Brecker&#8217;, de broma porque lo admiraba mucho. Me dijo &#8216;s\u00ed le hablamos ahorita&#8217;, y de pronto lleg\u00f3 sac\u00f3 su trompeta y nos pusimos de acuerdo para ver qu\u00e9 iba a tocar. Entr\u00f3 y en exactamente 15 segundos hab\u00eda captado lo que quer\u00edamos. Le dije &#8216;falta un solo en esta parte&#8217; y se lo ech\u00f3 y solo estuvo 10 minutos con nosotros a lo mucho. <\/em><\/p>\n<p><em>Este disco fue muy particular porque Gustavo Santaolalla hizo un pedazo, el Cachorro hizo otro y Freiberg otro. Creo que la elecci\u00f3n de las canciones fue muy atinada. No s\u00e9 qui\u00e9n eligi\u00f3 a Dani para hacer esas dos o que Gustavo hiciera &#8216;El Elefante&#8217;, que es muy teatral, pero muy buena elecci\u00f3n. <\/em><\/p>\n<p><em>Hay experiencias muy bonitas e interesantes de producci\u00f3n y de arte.<\/em><\/p>\n<p><strong>\u00bfCu\u00e1l es la mejor y cu\u00e1l es la peor rola de Caifanes?<\/strong><\/p>\n<p><em>No s\u00e9 porque las puedo ver como las ves t\u00fa. Yo las toco un chingo pero las concebimos juntos entonces no creo que haya una mala canci\u00f3n.<\/em><\/p>\n<p><em>Hay rolas que me conmueven mucho por la historia que significan en m\u00ed vida, como lo ser\u00e1n en la tuya. Una novia de la secundaria con la que quer\u00edas desde hace meses y de pronto pusieron &#8216;Antes De Que Nos Olviden&#8217; y pues esa rola se convierte en un himno para ti.<\/em><\/p>\n<p><em>No hay una rola mala de Caifanes no porque seamos unos genios, sino porque no la dejamos pasar. La detuvimos antes de que saliera. Y no por sonar a una junta que evaluaba la canci\u00f3n y la calificaba, porque el rock es mucho m\u00e1s emp\u00edrico, de decir &#8216;est\u00e1 ching\u00f3n eso&#8217; o &#8216;suena poca madre&#8217;, m\u00e1s que pensar en una buena rola y una mala.\u00a0<\/em><\/p>\n<p><em>Tengo mis consentidas porque en algunas quiz\u00e1 hago un solo de sax que me gusta mucho o cuando la grabamos algo pas\u00f3 ah\u00ed y eso. Tenemos nuestras consentidas y nuestras obligadas, porque hay rolas que dejar\u00eda de tocar pero la gente las quiere y nosotros estamos para ellos.\u00a0<\/em><\/p>\n<p><iframe loading=\"lazy\" title=\"Caifanes Antes de que nos olviden (Palacio de los deportes 2011) Me\u0301xico Suena 2012 6 de 11\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/2pxPMvaAkGI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>\u00bfRecuerdas la primera vez que tocaron en Estados Unidos? \u00bfC\u00f3mo se sintieron de llegar y de encontrarse a miles de fan\u00e1ticos del otro lado?<\/strong><\/p>\n<p><em>La primera vez que tocamos fue en Los \u00c1ngeles. Est\u00e1bamos en un camerino como con una ventanita chiquita y ah\u00ed Sa\u00fal y yo nos asom\u00e1bamos como pod\u00edamos para ver. Nos asom\u00e1bamos para ver c\u00f3mo estaba todo y Sa\u00fal me dec\u00eda &#8216;hay un chingo de gente&#8217;.\u00a0Lleg\u00f3 un chingo de gente y se llen\u00f3 para nuestra sorpresa. Fue parecido a lo que pas\u00f3 aqu\u00ed en M\u00e9xico. De hecho me cambi\u00e9 de casa hace poco y me encontr\u00e9 el cartel y te estoy hablando del 89 por all\u00e1. <\/em><\/p>\n<p><em>Esa fue la primera vez que tocamos en Estados Unidos y creo que ahora tocamos m\u00e1s all\u00e1 que ac\u00e1. Siempre ha sido una plaza muy buena, vamos a Ontario ahora y aunque los boletos ya est\u00e1n agotados es todo un placer tocar en este lugar.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Bang, bang! Sonaba la tarola de una banda callejera en la azotea de una vecindad. Las aves sobrevolaban entre tendederos con ropa y el llanto de los gatos se escuchaba a la distancia. Cascos de cerveza y un par de amplificadores rotos adornaban el cuadro. De fondo la radio con la cl\u00e1sica cumbia de lavaderos [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1437253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[51],"tags":[126,127,128,129,89,130],"class_list":["post-1437048","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-entretenimiento","tag-alfonso-andre","tag-caifanes","tag-diego-herrera","tag-el-diablito","tag-entrevista","tag-saul-hernandez","post_format-post-format-video","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u00a1Bang, bang! Sonaba la tarola de una banda callejera en la azotea de una vecindad. Las aves sobrevolaban entre tendederos con ropa y el llanto de los gatos se escuchaba a la distancia. Cascos de cerveza y un par de amplificadores rotos adornaban el cuadro. De fondo la radio con la cl\u00e1sica cumbia de lavaderos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-10T17:59:55+00:00\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico\",\"datePublished\":\"2023-02-10T17:59:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/\"},\"wordCount\":2238,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Alfonso Andr\u00e9\",\"Caifanes\",\"Diego Herrera\",\"El Diablito\",\"Entrevista\",\"Sa\u00fal Hern\u00e1ndez\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/\",\"url\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/\",\"name\":\"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-02-10T17:59:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/noticiasya.com\/aspen\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico - Noticias","og_description":"\u00a1Bang, bang! Sonaba la tarola de una banda callejera en la azotea de una vecindad. Las aves sobrevolaban entre tendederos con ropa y el llanto de los gatos se escuchaba a la distancia. Cascos de cerveza y un par de amplificadores rotos adornaban el cuadro. De fondo la radio con la cl\u00e1sica cumbia de lavaderos [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/","og_site_name":"Noticias","article_published_time":"2023-02-10T17:59:55+00:00","author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico","datePublished":"2023-02-10T17:59:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/"},"wordCount":2238,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"image":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#primaryimage"},"thumbnailUrl":"","keywords":["Alfonso Andr\u00e9","Caifanes","Diego Herrera","El Diablito","Entrevista","Sa\u00fal Hern\u00e1ndez"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/","url":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/","name":"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#primaryimage"},"image":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-02-10T17:59:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-valle\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/noticiasya.com\/aspen\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\u00e9tico","url":"http:\/\/noticiasya.com\/aspen\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2023\/02\/10\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":["alfonso andr\u00e9","caifanes","diego herrera","el diablito","entrevista","sa\u00fal hern\u00e1ndez"],"dateCreated":"2023-02-10T17:59:55Z","datePublished":"2023-02-10T17:59:55Z","dateModified":"2023-02-10T17:59:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Entrevista con Caifanes: Habitar la tristeza no es del todo pat\\u00e9tico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2023\\\/02\\\/10\\\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2023\\\/02\\\/10\\\/entrevista-con-caifanes-habitar-la-tristeza-no-es-del-todo-patetico\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[\"alfonso andr\\u00e9\",\"caifanes\",\"diego herrera\",\"el diablito\",\"entrevista\",\"sa\\u00fal hern\\u00e1ndez\"],\"dateCreated\":\"2023-02-10T17:59:55Z\",\"datePublished\":\"2023-02-10T17:59:55Z\",\"dateModified\":\"2023-02-10T17:59:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456465,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/11\/cien-anos-soledad-suicidio-historia-garcia-marquez-orix\/","url_meta":{"origin":1437048,"position":0},"title":"El suicidio que no fue: la historia de c\u00f3mo Garc\u00eda M\u00e1rquez escribi\u00f3 &#8216;Cien a\u00f1os de soledad&#8217;","author":"Eduardo Salinas","date":"diciembre 11, 2024","format":false,"excerpt":"De Cien a\u00f1os de soledad, considerada por muchos como la novela en espa\u00f1ol m\u00e1s grande desde Don Quijote de la Mancha, se han contado numerosas historias y an\u00e9cdotas a veces dotadas de la magia que el libro inspira. La m\u00e1s famosa, quiz\u00e1, es la epifan\u00eda de Gabriel Garc\u00eda M\u00e1rquez mientras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467980,"url":"https:\/\/noticiasya.com\/aspen\/2025\/11\/03\/entrevista-trump-60-minutes-cbs-trax\/","url_meta":{"origin":1437048,"position":1},"title":"Trump pas\u00f3 90 minutos con &#171;60 Minutes&#187;: esto fue lo que sucedi\u00f3","author":"","date":"noviembre 3, 2025","format":false,"excerpt":"El presidente Trump apareci\u00f3 en \u201c60 Minutes\u201d el domingo por la noche, un a\u00f1o despu\u00e9s de demandar al programa de CBS por la edici\u00f3n de una entrevista con Kamala Harris, y plenamente consciente de que sus respuestas tambi\u00e9n ser\u00edan recortadas por cuestiones de tiempo.\u201cNo tienes que usar esa\u201d, coment\u00f3 Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452261,"url":"https:\/\/noticiasya.com\/aspen\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/","url_meta":{"origin":1437048,"position":2},"title":"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial","author":"","date":"agosto 29, 2024","format":false,"excerpt":"(CNN) -- La vicepresidenta Kamala Harris se enfrenta este jueves a la siguiente prueba en su carrera presidencial con su primera entrevista sin guion con un importante medio de comunicaci\u00f3n desde que se convirti\u00f3 en la candidata dem\u00f3crata.Harris aspira a extender el impulso que ha conjurado en el inicio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451490,"url":"https:\/\/noticiasya.com\/aspen\/2024\/07\/29\/haiti-disparos-cobertura-entrevista-cnn-puerto-principe-trax\/","url_meta":{"origin":1437048,"position":3},"title":"Las fuerzas de seguridad que protegen al l\u00edder de Hait\u00ed hacen disparos de &#171;cobertura&#187; tras abandonar una entrevista con CNN","author":"","date":"julio 29, 2024","format":false,"excerpt":"(CNN) -- Las fuerzas de seguridad que proteg\u00edan al l\u00edder de Hait\u00ed lo cubrieron mientras abandonaba un hospital de Puerto Pr\u00edncipe tras una entrevista con CNN, en un claro ejemplo de la violencia que sigue asolando a este pa\u00eds por parte de bandas criminales.CNN hab\u00eda estado entrevistando al primer ministro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1437538,"url":"https:\/\/noticiasya.com\/aspen\/2023\/02\/22\/lo-bueno-lo-malo-y-lo-feo-del-festival-besame-mucho-2023\/","url_meta":{"origin":1437048,"position":4},"title":"Lo bueno, lo malo y lo feo del festival B\u00e9same Mucho 2023","author":"Eduardo Salinas","date":"febrero 22, 2023","format":false,"excerpt":"El festival B\u00e9same Mucho es uno de los m\u00e1s esperados desde su creaci\u00f3n en el 2022. Se trata de un evento que re\u00fane lo mejor de la m\u00fasica latina e hispanohablante en el Dodger Stadium de Los \u00c1ngeles, siendo este su segundo a\u00f1o y teniendo en su cartel a bandas\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/aspen\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466692,"url":"https:\/\/noticiasya.com\/aspen\/2025\/09\/22\/lamine-yamal-barcelona-balon-oro-2025-orix\/","url_meta":{"origin":1437048,"position":5},"title":"Los n\u00fameros, m\u00e9ritos y t\u00edtulos de Lamine Yamal para optar al Bal\u00f3n de Oro 2025","author":"Eduardo Salinas","date":"septiembre 22, 2025","format":false,"excerpt":"La joya m\u00e1s joven del Barcelona, Lamine Yamal, es una estrella emergente y en camino a la consolidaci\u00f3n, con s\u00f3lidos argumentos para competir por el Bal\u00f3n de Oro.Debut\u00f3 el 29 de abril de 2023 siendo un adolescente de tan solo 15 a\u00f1os, 9 meses y 16 d\u00edas, el m\u00e1s joven\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1437048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1437048"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1437048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1437048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1437048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1437048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}