{"id":1438687,"date":"2023-04-12T15:05:40","date_gmt":"2023-04-12T22:05:40","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1438687"},"modified":"2023-04-12T15:05:40","modified_gmt":"2023-04-12T22:05:40","slug":"las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/","title":{"rendered":"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa"},"content":{"rendered":"<p>Tras la repentina muerte de su hijo Juli\u00e1n Figueroa, la actriz Maribel Guardia tuvo un encuentro con la prensa en el que luego de varios d\u00edas ofreci\u00f3 las primeras palabras acerca de lo que sucedi\u00f3 con su hijo quien perdiera la vida el pasado domingo por la noche.<\/p>\n<p>Fue durante la tarde del martes que la actriz, acompa\u00f1ada de su nuera Imelda Garza Tu\u00f1\u00f3n, ofrecieron algunas palabras para los medios de comunicaci\u00f3n que a\u00fan se encontraban rondando su propiedad para obtener un poco de informaci\u00f3n acerca del deceso.<\/p>\n<p>Fue entonces que la actriz se\u00f1al\u00f3 porqu\u00e9 hab\u00eda realizado el funeral de su hijo a puerta cerrada en el que solo pudieron asistir familiares y amigos cercanos, ya que seg\u00fan sus palabras, deb\u00edan vivir ese dolor en familia con la gente que realmente hab\u00eda conocido al joven de 28 a\u00f1os.<\/p>\n<p>&#171;Necesit\u00e1bamos vivir este dolor en familia con gente que realmente conoci\u00f3 y am\u00f3 a Juli\u00e1n y realmente el d\u00eda de ayer fue muy importante para nosotros\u00a0 vivir este duelo que yo s\u00e9 que apenas est\u00e1 empezando. Nos falta mucho camino por recorrer pero Dios es grande&#187;, coment\u00f3 la actriz.<\/p>\n<p>Maribel tambi\u00e9n habl\u00f3 sobre las cenizas de su hijo las cuales a\u00fan conserva y no ha pensado en donde depositarlas. &#171;Yo ahorita no quiero deshacerme de sus cenizas, las tengo ah\u00ed. Lo tengo tan lindo con su San Miguel de Arc\u00e1ngel, con la Virgen de Guadalupe que yo se lo ofrec\u00ed cuando naci\u00f3&#187;, coment\u00f3.<\/p>\n<p>La tambi\u00e9n cantante coment\u00f3 que el pasado lunes 10 de abril, asisti\u00f3 a su casa un cura para ofrecer una misa para despedirlo junto a sus seres queridos, y es por estas razones que no han compartido nada con los medios pues se trata de algo bastante especial y delicado para la familia.<\/p>\n<p>&#171;Era mi amor, el ni\u00f1o de mis ojos y ha sido muy duro perderlo. Dios me lo dio, Dios me lo quit\u00f3, lo entrego en sus manos. Ten\u00eda tanto por recorrer, estaba empezando su carrera, pero as\u00ed fue&#187;, concluy\u00f3 la actriz entre l\u00e1grimas y lamentos frente a las c\u00e1maras.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Maribel Guardia, qu\u00e9 mensaje tan poderoso ante la muerte repentina de tu amado hijo Juli\u00e1n Figueroa. \u201cle pido a todos que recen por mi hijo, le pido a Dios, a todos, que sus hijos los vean crecer, casarse, tener nietos, los vean triunfar, y que sus hijos los entierren a ustedes\u201d <a href=\"https:\/\/t.co\/MCaYYvxUb0\">pic.twitter.com\/MCaYYvxUb0<\/a><\/p>\n<p>&mdash; javi (@javierperamz) <a href=\"https:\/\/twitter.com\/javierperamz\/status\/1645964708279640064?ref_src=twsrc%5Etfw\">April 12, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la repentina muerte de su hijo Juli\u00e1n Figueroa, la actriz Maribel Guardia tuvo un encuentro con la prensa en el que luego de varios d\u00edas ofreci\u00f3 las primeras palabras acerca de lo que sucedi\u00f3 con su hijo quien perdiera la vida el pasado domingo por la noche. Fue durante la tarde del martes que [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1438689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[51],"tags":[194,195,196,197,198,199],"class_list":["post-1438687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-declaraciones","tag-fallecimiento","tag-imelda-garza-tunon","tag-julian-figueroa","tag-maribel-guardia","tag-palabras","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa - Noticias\" \/>\n<meta property=\"og:description\" content=\"Tras la repentina muerte de su hijo Juli\u00e1n Figueroa, la actriz Maribel Guardia tuvo un encuentro con la prensa en el que luego de varios d\u00edas ofreci\u00f3 las primeras palabras acerca de lo que sucedi\u00f3 con su hijo quien perdiera la vida el pasado domingo por la noche. Fue durante la tarde del martes que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-12T22:05:40+00:00\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa\",\"datePublished\":\"2023-04-12T22:05:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/\"},\"wordCount\":382,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Declaraciones\",\"Fallecimiento\",\"Imelda Garza Tu\u00f1\u00f3n\",\"Juli\u00e1n Figueroa\",\"Maribel Guardia\",\"Palabras\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/\",\"url\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/\",\"name\":\"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-04-12T22:05:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/noticiasya.com\/aspen\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/","og_locale":"es_ES","og_type":"article","og_title":"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa - Noticias","og_description":"Tras la repentina muerte de su hijo Juli\u00e1n Figueroa, la actriz Maribel Guardia tuvo un encuentro con la prensa en el que luego de varios d\u00edas ofreci\u00f3 las primeras palabras acerca de lo que sucedi\u00f3 con su hijo quien perdiera la vida el pasado domingo por la noche. Fue durante la tarde del martes que [&hellip;]","og_url":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/","og_site_name":"Noticias","article_published_time":"2023-04-12T22:05:40+00:00","author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa","datePublished":"2023-04-12T22:05:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/"},"wordCount":382,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"image":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#primaryimage"},"thumbnailUrl":"","keywords":["Declaraciones","Fallecimiento","Imelda Garza Tu\u00f1\u00f3n","Juli\u00e1n Figueroa","Maribel Guardia","Palabras"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/","url":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/","name":"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#primaryimage"},"image":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-04-12T22:05:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/noticiasya.com\/aspen\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las declaraciones de Maribel Guardia tras la muerte de Juli\u00e1n Figueroa","url":"http:\/\/noticiasya.com\/aspen\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2023\/04\/12\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":["declaraciones","fallecimiento","imelda garza tu\u00f1\u00f3n","juli\u00e1n figueroa","maribel guardia","palabras"],"dateCreated":"2023-04-12T22:05:40Z","datePublished":"2023-04-12T22:05:40Z","dateModified":"2023-04-12T22:05:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las declaraciones de Maribel Guardia tras la muerte de Juli\\u00e1n Figueroa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2023\\\/04\\\/12\\\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2023\\\/04\\\/12\\\/las-declaraciones-de-maribel-guardia-tras-la-muerte-de-julian-figueroa\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[\"declaraciones\",\"fallecimiento\",\"imelda garza tu\\u00f1\\u00f3n\",\"juli\\u00e1n figueroa\",\"maribel guardia\",\"palabras\"],\"dateCreated\":\"2023-04-12T22:05:40Z\",\"datePublished\":\"2023-04-12T22:05:40Z\",\"dateModified\":\"2023-04-12T22:05:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463538,"url":"https:\/\/noticiasya.com\/aspen\/2025\/06\/13\/ianina-tunon-uno-de-cada-diez-ninos-en-la-argentina-vive-en-indigencia-con-multiples-privaciones\/","url_meta":{"origin":1438687,"position":0},"title":"Ianina Tu\u00f1\u00f3n: &#171;Uno de cada diez ni\u00f1os en la Argentina vive en indigencia con m\u00faltiples privaciones&#187;","author":"Eduardo Salinas","date":"junio 13, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Ianina Tu\u00f1\u00f3n, investigadora en Ciencias Sociales del Observatorio de la Deuda Social Argentina de la UCA, dialog\u00f3 este viernes con Regreso CNN, conducido por Mariana Arias y Pepe Gil Vidal, sobre los \u00faltimos datos de indigencia infantil y su impacto en el desarrollo integral de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452295,"url":"https:\/\/noticiasya.com\/aspen\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/","url_meta":{"origin":1438687,"position":1},"title":"Fallece Juli\u00e1n Ortega, actor de la serie &#171;\u00c9lite&#187; de Netflix, a los 41 a\u00f1os","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) -- El actor espa\u00f1ol Juli\u00e1n Ortega, conocido por aparecer en la popular serie dram\u00e1tica en espa\u00f1ol de Netflix \"\u00c9lite\", falleci\u00f3, seg\u00fan anunci\u00f3 el sindicato de actores y actrices del pa\u00eds. Ten\u00eda 41 a\u00f1os.\"Nuestro m\u00e1s sentido p\u00e9same a su familia y amigos\", escribi\u00f3 el sindicato en un comunicado el lunes.Ortega,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472769,"url":"https:\/\/noticiasya.com\/aspen\/2026\/04\/01\/mexico-deja-atras-ee-uu-presidenta-mujer-meryl-streep-claudia-sheinbaum-orix\/","url_meta":{"origin":1438687,"position":2},"title":"Meryl Streep elogi\u00f3 a Sheinbaum y la presidenta de M\u00e9xico respondi\u00f3: &#171;Es la mejor actriz del mundo&#187;","author":"","date":"abril 1, 2026","format":false,"excerpt":"La actriz estadounidense Meryl Streep reconoci\u00f3 el rol de la presidenta de M\u00e9xico, Claudia Sheinbaum, y consider\u00f3 que el pa\u00eds \u201cha dejado atr\u00e1s\u201d a Estados Unidos al tener una presidenta mujer, la primera en m\u00e1s de 200 a\u00f1os de historia.\u201cClaro que M\u00e9xico ha dejado atr\u00e1s a los Estados Unidos teniendo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469614,"url":"https:\/\/noticiasya.com\/aspen\/2025\/12\/27\/actriz-rey-leon-broadway-apunalada-trax\/","url_meta":{"origin":1438687,"position":3},"title":"Ex actriz infantil de &#171;El Rey Le\u00f3n&#187; en Broadway muere apu\u00f1alada en Nueva Jersey","author":"","date":"diciembre 27, 2025","format":false,"excerpt":"Imani Smith, quien interpret\u00f3 a la joven Nala en \u201cEl Rey Le\u00f3n\u201d de Disney en Broadway, falleci\u00f3 el domingo tras ser encontrada con heridas de arma blanca en una vivienda, seg\u00fan la Fiscal\u00eda del Condado de Middlesex, Nueva Jersey.Ten\u00eda toda la vida por delante, seg\u00fan una cuenta de GoFundMe creada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472003,"url":"https:\/\/noticiasya.com\/aspen\/2026\/03\/08\/mojtaba-jamenei-nuevo-lider-supremo-iran-sucesion-trax\/","url_meta":{"origin":1438687,"position":4},"title":"Mojtaba Jamenei, hijo del fallecido l\u00edder supremo, asume el control de Ir\u00e1n","author":"","date":"marzo 8, 2026","format":false,"excerpt":"En 1979, millones de iran\u00edes se volcaron a las calles derrocar al antiguo Sha y poner fin a la pr\u00e1ctica de transferir el poder de padre a hijo. Sin embargo, d\u00e9cadas despu\u00e9s, la historia parece repetirse.Mojtaba Jamenei, el segundo hijo del exl\u00edder supremo Al\u00ed Jamenei, fue elevado al cargo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458649,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/12\/audio-implosion-sumergible-titan-trax\/","url_meta":{"origin":1438687,"position":5},"title":"La Guardia Costera de EE.UU. publica un supuesto audio de la implosi\u00f3n del sumergible Tit\u00e1n","author":"","date":"febrero 12, 2025","format":false,"excerpt":"La Guardia Costera de Estados Unidos public\u00f3 este martes un audio inquietante de lo que se cree que es la firma ac\u00fastica de la implosi\u00f3n del sumergible Tit\u00e1n 2023.El audio fue capturado por una grabadora ac\u00fastica pasiva amarrada por la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica, aproximadamente a 1.450 kil\u00f3metros del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1438687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1438687"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1438687\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1438687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1438687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1438687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}