{"id":1439762,"date":"2023-07-03T17:22:47","date_gmt":"2023-07-04T00:22:47","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1439762"},"modified":"2024-01-16T14:26:16","modified_gmt":"2024-01-16T22:26:16","slug":"entrevista-con-raymix-la-gente-quiere-bailar","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/","title":{"rendered":"Entrevista con Raymix: La gente quiere bailar"},"content":{"rendered":"<p>Hacer una canci\u00f3n que suene en cada rinc\u00f3n del continente no es cosa f\u00e1cil, mucho menos hacer que esa canci\u00f3n de inicio a un nuevo g\u00e9nero musical y que ponga a bailar a todo aquel que la escuche en fiestas, bares, conciertos, tocadas y hasta en el transporte p\u00fablico.<\/p>\n<p>Eso hizo Raymix, un mexicano bastante sobresaliente que con su visi\u00f3n de mezclar la m\u00fasica electr\u00f3nica y la cumbia, cre\u00f3 un sonido sin precedentes al que bautiz\u00f3 como electro cumbia. &#8216;Oye Mujer&#8217; es el tema que lo inici\u00f3 todo y que le dio un nombre en la escena mexicana.<\/p>\n<p>Gracias a un ritmo que mezclaba lo mejor de ambos mundos y que llam\u00f3 la atenci\u00f3n de la gente, el nacido en el Estado de M\u00e9xico dej\u00f3 claro que nuestra cumbia era aut\u00e9ntica y que los mexicanos sab\u00edamos dejarlo todo en la pista. Y es que desde que se populariz\u00f3 su rola, Raymix se dedic\u00f3 a crear los mejores tracks en su estudio y a experimentar con ritmos, efectos y hasta con otros artistas, code\u00e1ndose con la crema y nata de la escena como lo ha sido Paulina Rubio, Paty Manterola, Mar\u00eda Le\u00f3n, Aczino, Gepe, Esteman, Celso Pi\u00f1a y Horacio Palencia, por mencionar algunos.<\/p>\n<p>Raymix siempre est\u00e1 innovando y una prueba de ello es la estad\u00eda que hizo en la NASA cuando fue invitado a participar en un programa espacial siendo seleccionado entre cientos de participantes, lo que nos da un indicios sobre la mente brillante que hay detr\u00e1s del artista. Sin embargo, Edmundo le fue fiel a su pasi\u00f3n m\u00e1s grande y dej\u00f3 la ingenier\u00eda de lado para convertirse en m\u00fasico y seguir haciendo temas que hicieran feliz a la gente.<\/p>\n<p>Este a\u00f1o, Raymix lanz\u00f3 su esperado \u00e1lbum Mi Otra Mitad (2023), un material de 13 canciones que muestra el lado m\u00e1s maduro de su m\u00fasica y que se manifiesta en cortes rom\u00e1nticos creados bajo la premisa de ser uno mismo y amar sin importar nada. Nos sorprende la evoluci\u00f3n art\u00edstica de un joven que comenz\u00f3 siguiendo un sue\u00f1o y que hoy hace m\u00fasica desde un rinc\u00f3n m\u00e1s humano y real a sus convicciones.<\/p>\n<p>Platicamos con \u00e9l en v\u00edsperas de su gira por Estados Unidos que pasar\u00e1 por ciudades como Chicago, Nueva York, Nueva Jersey, Los \u00c1ngeles, Las Vegas y Tracy, California y que comenz\u00f3 este fin de semana.<\/p>\n<p><iframe loading=\"lazy\" title=\"Raymix - Mi Otra Mitad\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/0xDhJMJ4gVA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>Muchos te reconocen como el creador de la electro cumbia, \u00bfEst\u00e1s de acuerdo con ese t\u00edtulo?<\/strong><\/p>\n<p><em>Lo que pasa es que cuando empec\u00e9 esta idea de la electro cumbia, no hab\u00eda el t\u00e9rmino electro cumbia, no estaba como que bien definido, entonces se me ocurri\u00f3 acu\u00f1arlo as\u00ed como existe el electro pop, el electro house, dije &#8216;puede existir una electro cumbia&#8217;. Entonces s\u00ed, fui uno de los primeros que empez\u00f3 a emplear el t\u00e9rmino y pues a la fecha varios artistas me han seguido, entonces me siento bien por ello.<\/em><\/p>\n<p><strong>\u00bfRecuerdas c\u00f3mo surgi\u00f3 el sonido o c\u00f3mo lo descubriste?<\/strong><\/p>\n<p><em>Yo antes de la m\u00fasica me dediqu\u00e9 a mi carrera e hice una pasant\u00eda en la NASA en el 2013 y siempre escuchaba mis canciones all\u00e1 y fue cuando dije &#8216;\u00bfPor qu\u00e9 no hacer una cumbia que sea un poco m\u00e1s electr\u00f3nica, m\u00e1s house o m\u00e1s trance&#8217;? Y as\u00ed fue como se me ocurri\u00f3 hacer este estilo.\u00a0<\/em><\/p>\n<p><strong>\u00bfCreciste rodeado de mucha m\u00fasica ya sea con tus pap\u00e1s o tu familia?<\/strong><\/p>\n<p><em>Tengo un entorno de m\u00fasicos, mi pap\u00e1 es m\u00fasico, mis t\u00edos, mi abuela.<\/em><\/p>\n<p><strong>\u00bfCu\u00e1l crees que es la importancia de la cumbia en un pa\u00eds como M\u00e9xico.<\/strong><\/p>\n<p><em>Absoluta, porque no hay una sola fiesta en la que no se ponga una cumbia para bailar. La gente quiere bailar y eso es una parte de la cultura, es tradici\u00f3n en M\u00e9xico y se est\u00e1 exportando, es como por ejemplo la m\u00fasica pop, es una m\u00fasica que se baila, todo se baila lento, r\u00e1pido, pero se baila. Entonces la cumbia pues es mucho m\u00e1s bailable y eso yo creo que es la importancia, es absoluta, forma parte de la de la sangre de los mexicanos.<\/em><\/p>\n<p><strong>Estamos en un punto donde el regional mexicano ha evolucionado a tal grado que ahora es la m\u00fasica mainstream que nos representa en el mundo y pas\u00f3 de ser la m\u00fasica de sombrero y botas a convertirse en los actuales rockstars nacionales. \u00bfCrees que en alg\u00fan punto la cumbia evolucione al grado de generar este cambio?<\/strong><\/p>\n<p><em>Yo creo que tiene el potencial, pero creo que tambi\u00e9n tiene mucho que ver hasta con factores que uno no puede controlar, destino, la suerte, no s\u00e9 c\u00f3mo llamarle. Creo que hay el potencial, hay mucha gente trabajando en el g\u00e9nero y ojal\u00e1 alg\u00fan d\u00eda suceda. Es un sue\u00f1o que todos los que nos dedicamos al g\u00e9nero nos gustar\u00eda y no perdemos la esperanza de que alg\u00fan d\u00eda suceda. Mientras tanto, pues nos ha ido muy bien a pesar de que no es un g\u00e9nero mainstream, se han conectado muchos \u00e9xitos que han logrado n\u00fameros impresionantes que el pop y el reguet\u00f3n tienen. Ha dado se\u00f1ales de que puede suceder.<\/em><\/p>\n<p><strong>Y es que ya hay festivales s\u00faper hipsters que empiezan a buscar a grupos como Los \u00c1ngeles Azules y eran eventos que jam\u00e1s pensar\u00edas que har\u00edan esto&#8230;<\/strong><\/p>\n<p><em>Yo quisiera que ellos fueran un poquito m\u00e1s abiertos en apoyar a las promesas que vienen atr\u00e1s de ellos, cosa que la verdad hasta el momento no se ha visto y es muy lamentable, porque si no hay esa uni\u00f3n y ese apoyo para el mismo g\u00e9nero musical, pues entonces \u00bfDe qu\u00e9 sirve? Un tsunami no lo hace una sola ola, tiene que ser mucha agua, muchas olas juntas, entonces ojal\u00e1 y y haya m\u00e1s apoyo en ese aspecto.\u00a0<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1346868 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/07\/f1280x720-90723_222398_5050.jpg?w=1024\" alt=\"\" width=\"1024\" height=\"576\" \/><\/p>\n<p><strong>&#8216;Oye Mujer&#8217; tiene 850 millones de reproducciones en YouTube pero es imposible que contabilicemos las reproducciones no oficiales que ha tenido en discos, MP3 cuando exist\u00edan, \u00bfQu\u00e9 se siente tener un tema tan conocido por todos?<\/strong><\/p>\n<p><em>Es una bendici\u00f3n muy grande, es algo gigantesco y me siento muy afortunado de haber logrado semejante \u00e9xito musical. Tambi\u00e9n me siento contento con lo dem\u00e1s que he logrado, por ejemplo, para mi segundo disco tenemos una canci\u00f3n que se llama &#8216;Todo Lo Encuentro En Ti&#8217;, que tambi\u00e9n nos ha dado buenos resultados, tiene 75 millones de visualizaciones el video, tambi\u00e9n por ejemplo en mi tercer disco lanc\u00e9 una canci\u00f3n con Paulina Rubio que acabamos de certificar en diamante y que fue una canci\u00f3n muy muy gustada, ya vamos a llegar a 80 millones de reproducciones. A pesar de que se nos atraves\u00f3 la pandemia cuando sali\u00f3 esta canci\u00f3n, afortunadamente hemos estado ah\u00ed y eso es lo m\u00e1s importante. <\/em><\/p>\n<p><em>Creo que una carrera cuando es de una canci\u00f3n, pues no es tanto una carrera, pero cuando uno trabaja para generar un concepto creo que ah\u00ed est\u00e1 el verdadero valor y de eso es de lo que yo me siento muy afortunado.<\/em><\/p>\n<p><strong>Claro, conozco muy bien tu carrera pero mencion\u00e9 esta canci\u00f3n porque es un tema m\u00edtico para la cultura mexicana&#8230;<\/strong><\/p>\n<p><em>Afortunadamente as\u00ed es. Esa es la bandera de la electro cumbia, es mi carta de presentaci\u00f3n y pues muy satisfecho de que es una canci\u00f3n m\u00eda 100%, composici\u00f3n, canto, idea, m\u00fasica, producci\u00f3n, masterizaci\u00f3n, video, todo, todo lo hice yo y los resultados est\u00e1n ah\u00ed. Afortunadamente la gente la tom\u00f3 como un cl\u00e1sico y casi me atrevo a decir que no hay fiesta donde no toquen esa canci\u00f3n.<\/em><\/p>\n<p><strong>Hablando un poco de tu nuevo \u00e1lbum, plat\u00edcame \u00bfC\u00f3mo surgen las colaboraciones que tienes? \u00bfC\u00f3mo decides si esta canci\u00f3n ser\u00e1 para ti solo o si sumar\u00e1s a alg\u00fan artista a que colabore?<\/strong><\/p>\n<p><em>La misma canci\u00f3n te va diciendo hacia d\u00f3nde va, entonces dices &#8216;creo que esta canci\u00f3n va a estar buena con alguien&#8217; y vas empezando ideas. \u00bfHombre o mujer? Y as\u00ed poco a poco vas haciendo los filtros hasta que dices ya tengo a la candidata o al candidato ideal.<\/em><\/p>\n<p><em>Ahorita no estoy tan motivado en buscar colaboraciones, sino si alguien tiene una canci\u00f3n y quiere que yo participe o que hagamos algo juntos, yo siempre tengo las ganas de hacerlo, siempre y cuando la canci\u00f3n nos guste, pero se ha dado mucho de que se ponen un poco complicados los artistas, o no tanto los artistas sino los managers, y como que hay mucho elitismo en la industria, en donde si no tienes los millones de millones y no eres el artista caliente del momento, no te quieren ni escuchar. Por eso ahorita no estoy motivado sobre colaborar m\u00e1s que con quienes quieran hacerlo conmigo.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1346869 size-large\" src=\"https:\/\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/07\/electrocumbia-raymix-PHOTO04.png?w=1024\" alt=\"Electrocumbia Raymix Photo04\" width=\"1024\" height=\"576\" \/><\/p>\n<p><strong>La gente tiene la creencia de que trabajabas en la NASA pero m\u00e1s bien fue un programa en el que participaste \u00bfCierto? \u00bfMe puedes contar un poquito de c\u00f3mo fue tu paso por esta instituci\u00f3n?<\/strong><\/p>\n<p><em>Efectivamente, s\u00ed. Esto fue en 2013, cuando llevamos a cabo el desarrollo de uno de los sat\u00e9lites. Tambi\u00e9n trabajamos un poquito de cohetes educativos y para m\u00ed fue algo muy importante en mi carrera acad\u00e9mica. Aprend\u00ed muchas cosas y tambi\u00e9n pude desarrollar habilidades que ya ten\u00eda pero que pude colocar para expandir un poquito m\u00e1s mi conocimiento.<\/em><\/p>\n<p><strong>\u00bfPrefieres las cumbias o el espacio?<\/strong><\/p>\n<p><em>Las dos cosas, me gusta la m\u00fasica y la academia.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hacer una canci\u00f3n que suene en cada rinc\u00f3n del continente no es cosa f\u00e1cil, mucho menos hacer que esa canci\u00f3n de inicio a un nuevo g\u00e9nero musical y que ponga a bailar a todo aquel que la escuche en fiestas, bares, conciertos, tocadas y hasta en el transporte p\u00fablico. Eso hizo Raymix, un mexicano bastante [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1443964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[51],"tags":[249,89,250,251,252],"class_list":["post-1439762","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-entretenimiento","tag-electro-cumbia","tag-entrevista","tag-lgbt","tag-oye-mujer","tag-raymix","post_format-post-format-video","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entrevista con Raymix: La gente quiere bailar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista con Raymix: La gente quiere bailar - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hacer una canci\u00f3n que suene en cada rinc\u00f3n del continente no es cosa f\u00e1cil, mucho menos hacer que esa canci\u00f3n de inicio a un nuevo g\u00e9nero musical y que ponga a bailar a todo aquel que la escuche en fiestas, bares, conciertos, tocadas y hasta en el transporte p\u00fablico. Eso hizo Raymix, un mexicano bastante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-04T00:22:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-16T22:26:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2667\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Entrevista con Raymix: La gente quiere bailar\",\"datePublished\":\"2023-07-04T00:22:47+00:00\",\"dateModified\":\"2024-01-16T22:26:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/\"},\"wordCount\":1661,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg\",\"keywords\":[\"Electro Cumbia\",\"Entrevista\",\"LGBT\",\"Oye Mujer\",\"Raymix\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/\",\"url\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/\",\"name\":\"Entrevista con Raymix: La gente quiere bailar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg\",\"datePublished\":\"2023-07-04T00:22:47+00:00\",\"dateModified\":\"2024-01-16T22:26:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#primaryimage\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg\",\"width\":2667,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista con Raymix: La gente quiere bailar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/noticiasya.com\/aspen\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista con Raymix: La gente quiere bailar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista con Raymix: La gente quiere bailar - Noticias","og_description":"Hacer una canci\u00f3n que suene en cada rinc\u00f3n del continente no es cosa f\u00e1cil, mucho menos hacer que esa canci\u00f3n de inicio a un nuevo g\u00e9nero musical y que ponga a bailar a todo aquel que la escuche en fiestas, bares, conciertos, tocadas y hasta en el transporte p\u00fablico. Eso hizo Raymix, un mexicano bastante [&hellip;]","og_url":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/","og_site_name":"Noticias","article_published_time":"2023-07-04T00:22:47+00:00","article_modified_time":"2024-01-16T22:26:16+00:00","og_image":[{"width":2667,"height":1500,"url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg","type":"image\/jpeg"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Entrevista con Raymix: La gente quiere bailar","datePublished":"2023-07-04T00:22:47+00:00","dateModified":"2024-01-16T22:26:16+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/"},"wordCount":1661,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"image":{"@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg","keywords":["Electro Cumbia","Entrevista","LGBT","Oye Mujer","Raymix"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/","url":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/","name":"Entrevista con Raymix: La gente quiere bailar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#primaryimage"},"image":{"@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg","datePublished":"2023-07-04T00:22:47+00:00","dateModified":"2024-01-16T22:26:16+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#primaryimage","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg","width":2667,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Entrevista con Raymix: La gente quiere bailar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/noticiasya.com\/aspen\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Entrevista con Raymix: La gente quiere bailar","url":"http:\/\/noticiasya.com\/aspen\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2023\/07\/03\/entrevista-con-raymix-la-gente-quiere-bailar\/"},"thumbnailUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg"},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":["electro cumbia","entrevista","lgbt","oye mujer","raymix"],"dateCreated":"2023-07-04T00:22:47Z","datePublished":"2023-07-04T00:22:47Z","dateModified":"2024-01-16T22:26:16Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Entrevista con Raymix: La gente quiere bailar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2023\\\/07\\\/03\\\/entrevista-con-raymix-la-gente-quiere-bailar\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2023\\\/07\\\/03\\\/entrevista-con-raymix-la-gente-quiere-bailar\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasya.com\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/07\\\/img15.jpg?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/noticiasya.com\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/07\\\/img15.jpg\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[\"electro cumbia\",\"entrevista\",\"lgbt\",\"oye mujer\",\"raymix\"],\"dateCreated\":\"2023-07-04T00:22:47Z\",\"datePublished\":\"2023-07-04T00:22:47Z\",\"dateModified\":\"2024-01-16T22:26:16Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/07\/img15.jpg","jetpack-related-posts":[{"id":1472844,"url":"https:\/\/noticiasya.com\/aspen\/2026\/04\/03\/sonideros-mexicanos-cumbia-inmigrantes-orix\/","url_meta":{"origin":1439762,"position":0},"title":"El barrio mexicano tambi\u00e9n suena en Estados Unidos: la cultura de los sonideros cruza la frontera","author":"Eduardo Salinas","date":"abril 3, 2026","format":false,"excerpt":"Luces de colores destellan sobre la pista mientras la cumbia sonidera marca el ritmo: bocinas repartidas por todo el lugar, personas que se mueven al un\u00edsono y, por encima de la canci\u00f3n, la voz de un hombre env\u00eda saludos, repite lo que dice la m\u00fasica o dedica el tema. En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445487,"url":"https:\/\/noticiasya.com\/aspen\/2024\/02\/15\/entrevista-con-instituto-mexicano-del-sonido-20-anos-haciendo-musica-de-barrio\/","url_meta":{"origin":1439762,"position":1},"title":"Entrevista con Instituto Mexicano del Sonido: 20 a\u00f1os haciendo m\u00fasica de barrio","author":"","date":"febrero 15, 2024","format":false,"excerpt":"El sonido de I.M.S. ha estado resonando durante dos d\u00e9cadas en M\u00e9xico y el mundo, llevando consigo la esencia vibrante y ecl\u00e9ctica de su creador: Camilo Lara. Camilo no solo es reconocido por su talento como m\u00fasico, sino tambi\u00e9n por su versatilidad como productor y sus contribuciones a la industria\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/aspen\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/02\/Instituto-Mexicano-del-Sonido-web-jpg-a837vv.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/02\/Instituto-Mexicano-del-Sonido-web-jpg-a837vv.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/02\/Instituto-Mexicano-del-Sonido-web-jpg-a837vv.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/02\/Instituto-Mexicano-del-Sonido-web-jpg-a837vv.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1446998,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/15\/entrevista-con-fiah-lo-que-siempre-quisiste-ser-pero-nunca-te-atreviste\/","url_meta":{"origin":1439762,"position":2},"title":"Entrevista con FIAH: Lo que siempre quisiste ser pero nunca te atreviste","author":"Eduardo Salinas","date":"marzo 15, 2024","format":false,"excerpt":"Fiah Miau es todo lo que siempre quisiste ser pero nunca te atreviste. Irreverente, rebelde y \u00fanica. Perreo oscuro que parece prohibido. Su esencia disruptiva, su sonido exc\u00e9ntrico y su estilo visual impactante. Todo esta irreverencia con tan pocos a\u00f1os en la escena. Fiah lleg\u00f3 a derribar los castillos y\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/aspen\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/03\/entretenimiento.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/03\/entretenimiento.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/03\/entretenimiento.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2024\/03\/entretenimiento.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1460176,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/20\/shakira-reencuentro-loba-concierto-mexico-orix\/","url_meta":{"origin":1439762,"position":3},"title":"Shakira: &#171;No hay mejor reencuentro de una loba con su manada mexicana&#187;","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Shakira abri\u00f3 el primero de los siete conciertos que ofrece en la capital mexicana ante m\u00e1s de 60.000 personas reunidas en el Estadio GNP en la Ciudad de Mexico la noche de este mi\u00e9rcoles.Con las canciones \u201cLa Fuerte\u201d, \u201cGirl like Me\u201d y \u201cLatinas\u201d, la cantante colombiana subi\u00f3 al escenario a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467231,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/09\/peru-banda-cumbia-ataque-concierto-efe\/","url_meta":{"origin":1439762,"position":4},"title":"Cuatro miembros de una famosa banda de cumbia peruana heridos por disparos en su concierto","author":"","date":"octubre 9, 2025","format":false,"excerpt":"La Polic\u00eda Nacional del Per\u00fa (PNP) confirm\u00f3 que cuatro integrantes de la agrupaci\u00f3n de cumbia Agua Marina, una de las m\u00e1s famosas del pa\u00eds, resultaron heridos durante la noche de este mi\u00e9rcoles despu\u00e9s de que fuera atacada con disparos de armas de fuego mientras ofrec\u00eda un concierto en un local\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467345,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/13\/agua-marina-atentado-peru-destitucion-boluarte-orix\/","url_meta":{"origin":1439762,"position":5},"title":"C\u00f3mo el atentado contra la banda peruana de cumbia Agua Marina fue un catalizador de la ca\u00edda de Dina Boluarte","author":"","date":"octubre 13, 2025","format":false,"excerpt":"Al filo de la madrugada del viernes, la presidenta de Per\u00fa, Dina Boluarte, fue destituida por el congreso por permanente incapacidad moral. Y en el centro de esta nueva crisis pol\u00edtica en el pa\u00eds aparece el ataque contra una popular orquesta de cumbia.M\u00e1s de 120 votos la declararon no apta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1439762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1439762"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1439762\/revisions"}],"predecessor-version":[{"id":1443965,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1439762\/revisions\/1443965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media\/1443964"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1439762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1439762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1439762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}