{"id":1441415,"date":"2023-11-29T15:05:48","date_gmt":"2023-11-29T23:05:48","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1441415"},"modified":"2024-01-16T08:41:33","modified_gmt":"2024-01-16T16:41:33","slug":"los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/","title":{"rendered":"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros"},"content":{"rendered":"<h2>Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros<\/h2>\n<p>\u00a1Ay Shakira! \u00bfCu\u00e1ndo aprender\u00e1s? El d\u00eda de ayer la colombiana se dijo a s\u00ed misma culpable del delito de evasi\u00f3n de impuestos en Espa\u00f1a a cambio de pagar solo una parte de la deuda y no ir a la c\u00e1rcel.<\/p>\n<p>Y es que la fiscal\u00eda espa\u00f1ola no se la dej\u00f3 f\u00e1cil a la cantante de 46 a\u00f1os, pues luego de hacer una evaluaci\u00f3n y descubrir que la colombiana hab\u00eda evadido su responsabilidad fiscal por la cantidad de 14.5 millones de euros, le perdonaron la mitad de la deuda y adem\u00e1s le ayudaron a no caer tras las rejas.<\/p>\n<p>La int\u00e9rprete de &#8216;Acr\u00f3stico&#8217; deber\u00e1 pagar una indemnizaci\u00f3n por 7.3 millones de euros, un precio bastante justo para seguir con su vida y no tener una mancha en su historial.<\/p>\n<p>Al salir de la corte y haber perdido tal cantidad de dinero, la gente not\u00f3 que se ve\u00eda tranquila y en paz con lo que hab\u00eda &#171;soltado&#187;, as\u00ed que los memes no esperaron ni por un segundo, \u00a1Ya hab\u00edan miles!<\/p>\n<p>Aqu\u00ed una peque\u00f1a selecci\u00f3n con algunos de los m\u00e1s divertidos:<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/C0P2EnJr3yd\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:500px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/C0P2EnJr3yd\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/C0P2EnJr3yd\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by El Bot\u00f3n (@elbotonradio)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros \u00a1Ay Shakira! \u00bfCu\u00e1ndo aprender\u00e1s? El d\u00eda de ayer la colombiana se dijo a s\u00ed misma culpable del delito de evasi\u00f3n de impuestos en Espa\u00f1a a cambio de pagar solo una parte de la deuda y no ir a la c\u00e1rcel. Y [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1443868,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[51],"tags":[],"class_list":["post-1441415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros \u00a1Ay Shakira! \u00bfCu\u00e1ndo aprender\u00e1s? El d\u00eda de ayer la colombiana se dijo a s\u00ed misma culpable del delito de evasi\u00f3n de impuestos en Espa\u00f1a a cambio de pagar solo una parte de la deuda y no ir a la c\u00e1rcel. Y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-29T23:05:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-16T16:41:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros\",\"datePublished\":\"2023-11-29T23:05:48+00:00\",\"dateModified\":\"2024-01-16T16:41:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/\"},\"wordCount\":236,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png\",\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/\",\"url\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/\",\"name\":\"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png\",\"datePublished\":\"2023-11-29T23:05:48+00:00\",\"dateModified\":\"2024-01-16T16:41:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#primaryimage\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png\",\"width\":1280,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/noticiasya.com\/aspen\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/","og_locale":"es_ES","og_type":"article","og_title":"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros - Noticias","og_description":"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros \u00a1Ay Shakira! \u00bfCu\u00e1ndo aprender\u00e1s? El d\u00eda de ayer la colombiana se dijo a s\u00ed misma culpable del delito de evasi\u00f3n de impuestos en Espa\u00f1a a cambio de pagar solo una parte de la deuda y no ir a la c\u00e1rcel. Y [&hellip;]","og_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/","og_site_name":"Noticias","article_published_time":"2023-11-29T23:05:48+00:00","article_modified_time":"2024-01-16T16:41:33+00:00","og_image":[{"width":1280,"height":640,"url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png","type":"image\/png"}],"author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros","datePublished":"2023-11-29T23:05:48+00:00","dateModified":"2024-01-16T16:41:33+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/"},"wordCount":236,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"image":{"@id":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png","articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/","url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/","name":"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#primaryimage"},"image":{"@id":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png","datePublished":"2023-11-29T23:05:48+00:00","dateModified":"2024-01-16T16:41:33+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#primaryimage","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png","width":1280,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/nueva-inglaterra\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/noticiasya.com\/aspen\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los memes m\u00e1s divertidos de Shakira y su deuda de 7 millones de euros","url":"http:\/\/noticiasya.com\/aspen\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2023\/11\/29\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\/"},"thumbnailUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png?w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png"},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-11-29T23:05:48Z","datePublished":"2023-11-29T23:05:48Z","dateModified":"2024-01-16T16:41:33Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los memes m\\u00e1s divertidos de Shakira y su deuda de 7 millones de euros\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2023\\\/11\\\/29\\\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2023\\\/11\\\/29\\\/los-memes-mas-divertidos-de-shakira-y-su-deuda-de-7-millones-de-euros\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasya.com\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/11\\\/PORTADA-DOBLE-3.png?w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/noticiasya.com\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2023\\\/11\\\/PORTADA-DOBLE-3.png\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-11-29T23:05:48Z\",\"datePublished\":\"2023-11-29T23:05:48Z\",\"dateModified\":\"2024-01-16T16:41:33Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1436459,"url":"https:\/\/noticiasya.com\/aspen\/2023\/01\/12\/los-mejores-memes-tras-la-sesion-de-bizarrap-y-shakira\/","url_meta":{"origin":1441415,"position":0},"title":"Los mejores memes tras la sesi\u00f3n de Bizarrap y Shakira","author":"Eduardo Salinas","date":"enero 12, 2023","format":false,"excerpt":"Apenas nos estamos reponiendo de la golpiza lirica que Shakira le propin\u00f3 a Piqu\u00e9 en la nueva sesi\u00f3n junto a Bizarrap, cuando la web ya est\u00e1 a full de memes y burlas para ambas personalidades. Desde Shakira convirti\u00e9ndose en Paquita la del Barrio, hasta la embarrada del due\u00f1o de los\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/aspen\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457301,"url":"https:\/\/noticiasya.com\/aspen\/2025\/01\/07\/deudas-medicas-eliminaran-informes-crediticios-trax\/","url_meta":{"origin":1441415,"position":1},"title":"Las deudas m\u00e9dicas dejar\u00e1n de aparecer en los historiales crediticios","author":"Eduardo Salinas","date":"enero 7, 2025","format":false,"excerpt":"Los estadounidenses ya no tendr\u00e1n que preocuparse por facturas m\u00e9dicas impagas que da\u00f1en sus informes y puntuaciones crediticias.El Gobierno de Biden est\u00e1 ultimando una medida que pondr\u00e1 fin a la inclusi\u00f3n de la deuda m\u00e9dica en los informes crediticios y prohibir\u00e1 a los prestamistas utilizar cierta informaci\u00f3n m\u00e9dica en las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459127,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/24\/shakira-cancela-concierto-medellin\/","url_meta":{"origin":1441415,"position":2},"title":"Cancelan concierto de Shakira en Medell\u00edn y la cantante dice que buscar\u00e1n reprogramarlo","author":"","date":"febrero 24, 2025","format":false,"excerpt":"El concierto de la cantante Shakira que estaba programado para este lunes en la ciudad colombiana de Medell\u00edn fue cancelado, anunci\u00f3 la int\u00e9rprete el s\u00e1bado en una publicaci\u00f3n en redes sociales en la que lament\u00f3 el inconveniente.\u201cMis hijos estaban emocionados por conocer Medell\u00edn, y yo por reencontrarme con ustedes y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447223,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/22\/shakira-estrena-las-mujeres-ya-no-lloran-duodecimo-album-estudio-orix\/","url_meta":{"origin":1441415,"position":3},"title":"Shakira estrena &#171;Las mujeres ya no lloran&#187;, su duod\u00e9cimo \u00e1lbum de estudio","author":"","date":"marzo 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Shakira lanz\u00f3 su nuevo \u00e1lbum llamado \"Las mujeres ya no lloran\", con una playlist que incluyen algunos de los \u00e9xitos m\u00e1s populares de los \u00faltimos a\u00f1os en colaboraci\u00f3n con algunos artistas latinos.Este es el duod\u00e9cimo \u00e1lbum de estudio de la artista colombiana que recorre 17 canciones, entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447194,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/21\/shakira-enciende-redes-nuevas-fotos-cancion-punteria-nuevo-disco-orix\/","url_meta":{"origin":1441415,"position":4},"title":"Shakira &#8216;enciende&#8217; las redes con fotos para la canci\u00f3n &#171;Punter\u00eda&#187; de su nuevo disco","author":"","date":"marzo 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- A unas horas del lanzamiento de su nuevo disco, Shakira 'encendi\u00f3' las redes sociales con nuevas fotos que muestran parte de lo que podremos ver en la canci\u00f3n \"Punter\u00eda\".La cantante colombiana subi\u00f3 cinco fotograf\u00edas a su cuenta de Instagram, y en tres de ellas aparece abrazada junto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1437689,"url":"https:\/\/noticiasya.com\/aspen\/2023\/02\/28\/shakira-hablo-por-primera-vez-de-su-divorcio-con-pique-y-la-sesion-con-bzrp\/","url_meta":{"origin":1441415,"position":5},"title":"Shakira habl\u00f3 por primera vez de su divorcio con Piqu\u00e9 y la Sesi\u00f3n con BZRP","author":"Eduardo Salinas","date":"febrero 28, 2023","format":false,"excerpt":"\"Yo tambi\u00e9n compraba esa historia de que una mujer necesita un hombre para completarse\". Shakira y su separaci\u00f3n de Gerard Piqu\u00e9 sigue dando mucho de qu\u00e9 hablar. Tras el lanzamiento de su colaboraci\u00f3n con Bizarrap, en la Music Session #53, la cantante colombiana dio una entrevista con Enrique Acevedo para\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/aspen\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/11\/PORTADA-DOBLE-3.png","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1441415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1441415"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1441415\/revisions"}],"predecessor-version":[{"id":1443869,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1441415\/revisions\/1443869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media\/1443868"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1441415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1441415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1441415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}