{"id":1447276,"date":"2024-03-23T14:03:52","date_gmt":"2024-03-23T21:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/"},"modified":"2024-03-23T14:03:52","modified_gmt":"2024-03-23T21:03:52","slug":"osos-pandas-color-marrones-genes-endogamia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/","title":{"rendered":"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9"},"content":{"rendered":"<p>(CNN) &#8212; Con su distinguido color de pelaje, el panda gigante es una especie reconocible al instante.<\/p>\n<p>Sin embargo, existen pandas gigantes que no son blancos y negros. Estas majestuosas criaturas de pelaje marr\u00f3n y blanco habitan en una \u00fanica cadena monta\u00f1osa en China. Y ahora, los cient\u00edficos pueden haber desentra\u00f1ado el misterio del pelaje inusual de estos pandas extremadamente raros, seg\u00fan una nueva investigaci\u00f3n.<\/p>\n<p>El trabajo, que implic\u00f3 estudiar la gen\u00e9tica de m\u00faltiples pandas en estado salvaje y en cautiverio, ha sugerido que los pandas con pelaje marr\u00f3n y blanco son el resultado de una variaci\u00f3n natural, m\u00e1s que un signo de endogamia en una poblaci\u00f3n cada vez menor.<\/p>\n<p>Mira las travesuras de dos pandas gemelos colgados de un \u00e1rbol<\/p>\n<p>El primer panda marr\u00f3n conocido por la ciencia fue una hembra llamada Dandan. Un guardabosques local encontr\u00f3 a la osa enferma en el condado de Foping, en las monta\u00f1as Qinling de la provincia de Shaanxi, en marzo de 1985. La osa estuvo mantenida en cautiverio hasta su muerte en 2000.<\/p>\n<p>Desde el descubrimiento de Dandan hace d\u00e9cadas, se han reportado 11 avistamientos documentados a trav\u00e9s de fuentes de noticias oficiales o cuentas personales compartidas con los autores de este estudio que apareci\u00f3 en la revista PNAS el 4 de marzo.<\/p>\n<p>\u201cLos casos recurrentes de pandas marrones implican que este rasgo puede ser heredable. Sin embargo, hasta la fecha, la base gen\u00e9tica que subyace al color del pelaje marr\u00f3n y blanco sigue sin estar clara\u201d, escribieron los autores.<\/p>\n<p>Comprender mejor la coloraci\u00f3n distintiva podr\u00eda ayudar a fundamentar los esfuerzos para criar pandas marrones y blancos en cautiverio, dijo el autor principal, el Dr. Fuwen Wei, profesor de ecolog\u00eda de la vida silvestre y biolog\u00eda de la conservaci\u00f3n en el Instituto de Zoolog\u00eda de la Academia China de Ciencias en Beijing. El estatus del panda gigante como especie es vulnerable, seg\u00fan la Lista Roja de Especies Amenazadas de la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza.<\/p>\n<p>Un panda gigante salvaje en las monta\u00f1as Qinling de China mira a la c\u00e1mara en marzo de 2016. (Xinhua\/Shutterstock)<\/p>\n<p>Un \u00e1rbol geneal\u00f3gico de los pandas<\/p>\n<p>Para comprender qu\u00e9 hay detr\u00e1s de este rasgo, los investigadores estudiaron a Qizai, un panda marr\u00f3n macho rescatado cuando era un cachorro en 2009 de la Reserva Natural Nacional Foping en Hanzhong. Actualmente es el \u00fanico panda marr\u00f3n en cautiverio.<\/p>\n<p>Cuando se compar\u00f3 bajo un microscopio con muestras de cabello de tres pandas blancos y negros, el pelaje marr\u00f3n de Qizai ten\u00eda menos y m\u00e1s peque\u00f1os melanosomas, estructuras diminutas que se encuentran en las c\u00e9lulas responsables del pigmento de la piel y el cabello en los mam\u00edferos. Es m\u00e1s, era m\u00e1s probable que los melanosomas tuvieran una forma irregular, descubri\u00f3 el equipo del estudio.<\/p>\n<p>Luego, los investigadores reunieron informaci\u00f3n gen\u00e9tica sobre Qizai y reconstruyeron su \u00e1rbol geneal\u00f3gico. Las heces frescas, o caca de oso, recolectadas en la reserva natural revelaron la identidad de su madre salvaje, una panda hembra blanca y negra que lleva un collar de rastreo y es conocida como Niuniu.<\/p>\n<p>Los investigadores tambi\u00e9n identificaron al hijo de Qizai, un panda blanco y negro nacido en cautiverio en 2020. (El equipo de estudio identific\u00f3 m\u00e1s tarde al padre de Qizai, Xiyue, un panda blanco y negro salvaje pero rastreado, mediante el estudio de la gen\u00e9tica de una poblaci\u00f3n m\u00e1s amplia de pandas.)<\/p>\n<p>Los cient\u00edficos estudiaron la informaci\u00f3n gen\u00e9tica de los miembros de la familia de Qizai y la compararon con la informaci\u00f3n gen\u00e9tica de 12 pandas blancos y negros de las monta\u00f1as Qinling y 17 pandas blancos y negros de otras regiones de China utilizando informaci\u00f3n extra\u00edda de muestras de sangre y excrementos. .<\/p>\n<p>Si bien ninguno de los familiares inmediatos de Qizai ten\u00eda pelaje marr\u00f3n, los investigadores pudieron demostrar que sus padres y su hijo ten\u00edan todos una copia del rasgo recesivo en un gen conocido como Bace2, mientras que Qizai ten\u00eda dos copias.<\/p>\n<p>Los genes de un individuo pueden portar rasgos recesivos, como ojos azules o cabello rojo en los humanos, sin que aparezcan como una caracter\u00edstica f\u00edsica. Cada padre debe poseer una copia de la variante gen\u00e9tica y transmitirla para que el rasgo aparezca en la descendencia, como es el caso del Qizai.<\/p>\n<p>El an\u00e1lisis gen\u00e9tico resuelve un enigma<\/p>\n<p>Gracias a un an\u00e1lisis de una muestra de tejido almacenada durante m\u00e1s de dos d\u00e9cadas en etanol, los cient\u00edficos tambi\u00e9n pudieron secuenciar el genoma de Dandan, el primer panda marr\u00f3n conocido. Dandan ten\u00eda el mismo rasgo recesivo, encontraron los investigadores.<\/p>\n<p>Luego, los cient\u00edficos realizaron un an\u00e1lisis m\u00e1s amplio de 192 pandas gigantes blancos y negros para verificar que el gen responsable era Bace2. La mutaci\u00f3n que causa el pelaje marr\u00f3n s\u00f3lo estuvo presente en dos pandas provenientes de las monta\u00f1as Qinling en Shaanxi, no de la provincia de Sichuan, donde vive la mayor\u00eda de los pandas gigantes de China.<\/p>\n<p>Un cachorro de oso panda cautiva a turistas en China con sus acrobacias<\/p>\n<p>Para confirmar los hallazgos, los cient\u00edficos utilizaron la herramienta de edici\u00f3n de genes CRISPR-Cas9 para eliminar la secuencia gen\u00e9tica que hab\u00edan identificado como causante de la mutaci\u00f3n en el gen Bace2 en 78 ratones de laboratorio. El cambio redujo la cantidad y el tama\u00f1o de los melanosomas en los ratones.<\/p>\n<p>&#171;El color del pelaje de los ratones knockout (con genes desactivados) es marr\u00f3n claro&#187;, dijo Wei, quien tambi\u00e9n es presidente de la Universidad Agr\u00edcola de Jiangxi en Nanchang, en la provincia china de Jiangxi.<\/p>\n<p>\u201cEsto demuestra que esta eliminaci\u00f3n tiene el potencial de alterar el color del pelaje de un rat\u00f3n, ya que la v\u00eda de pigmentaci\u00f3n est\u00e1 relativamente conservada (compartida) entre los mam\u00edferos. Por lo tanto, es muy probable que esta mutaci\u00f3n influya en el color del pelaje de un panda marr\u00f3n\u201d.<\/p>\n<p>Variaci\u00f3n natural vs. endogamia<\/p>\n<p>No est\u00e1 claro qu\u00e9 caus\u00f3 la mutaci\u00f3n gen\u00e9tica. Wei dijo que debe estar relacionado con el entorno espec\u00edfico de las monta\u00f1as Qinling, que tienen un clima diferente al de Sichuan. La mutaci\u00f3n gen\u00e9tica no parec\u00eda ser el resultado de la endogamia, como alguna vez se sospech\u00f3, dijo.<\/p>\n<p>\u201cEs m\u00e1s probable que sea el resultado de una variaci\u00f3n natural que de la endogamia. Nuestro an\u00e1lisis de parentesco indica que los padres de Qizai no est\u00e1n estrechamente relacionados\u201d, a\u00f1adi\u00f3 Wei.<\/p>\n<p>Tiejun Wang, profesor asociado en el departamento de recursos naturales de la Universidad de Twente en los Pa\u00edses Bajos, dijo que era una buena noticia que la coloraci\u00f3n \u00fanica no pareciera ser el resultado de la endogamia. Wang, que ha estudiado los pandas marrones, no particip\u00f3 en el estudio.<\/p>\n<p>&#171;Para aquellos que est\u00e1n preocupados por esta especie, este es un avance positivo&#187;, dijo Wang, quien dijo que trabaj\u00f3 como guardabosques en las monta\u00f1as durante 10 a\u00f1os.<\/p>\n<p>Wang dijo que aplaudi\u00f3 al equipo &#171;por sus tremendos esfuerzos al tratar de arrojar luz sobre esta cuesti\u00f3n cient\u00edfica&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Con su distinguido color de pelaje, el panda gigante es una especie reconocible al instante. Sin embargo, existen pandas gigantes que no son blancos y negros. Estas majestuosas criaturas de pelaje marr\u00f3n y blanco habitan en una \u00fanica cadena monta\u00f1osa en China. Y ahora, los cient\u00edficos pueden haber desentra\u00f1ado el misterio del pelaje [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447276","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Con su distinguido color de pelaje, el panda gigante es una especie reconocible al instante. Sin embargo, existen pandas gigantes que no son blancos y negros. Estas majestuosas criaturas de pelaje marr\u00f3n y blanco habitan en una \u00fanica cadena monta\u00f1osa en China. Y ahora, los cient\u00edficos pueden haber desentra\u00f1ado el misterio del pelaje [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-23T21:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9\",\"datePublished\":\"2024-03-23T21:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/\"},\"wordCount\":1269,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/\",\"name\":\"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-23T21:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9 - Noticias","og_description":"(CNN) &#8212; Con su distinguido color de pelaje, el panda gigante es una especie reconocible al instante. Sin embargo, existen pandas gigantes que no son blancos y negros. Estas majestuosas criaturas de pelaje marr\u00f3n y blanco habitan en una \u00fanica cadena monta\u00f1osa en China. Y ahora, los cient\u00edficos pueden haber desentra\u00f1ado el misterio del pelaje [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-23T21:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/"},"author":{"name":"","@id":""},"headline":"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9","datePublished":"2024-03-23T21:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/"},"wordCount":1269,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/","name":"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-23T21:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\u00edficos ahora entienden por qu\u00e9","url":"http:\/\/noticiasya.com\/aspen\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2024\/03\/23\/osos-pandas-color-marrones-genes-endogamia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-23T21:03:52Z","datePublished":"2024-03-23T21:03:52Z","dateModified":"2024-03-23T21:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"No todos los pandas son blancos y negros. Algunos tienen un tono diferente y los cient\\u00edficos ahora entienden por qu\\u00e9\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/23\\\/osos-pandas-color-marrones-genes-endogamia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/23\\\/osos-pandas-color-marrones-genes-endogamia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-23T21:03:52Z\",\"datePublished\":\"2024-03-23T21:03:52Z\",\"dateModified\":\"2024-03-23T21:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452875,"url":"https:\/\/noticiasya.com\/aspen\/2024\/09\/20\/perros-panda-zoo-china-viral-trax\/","url_meta":{"origin":1447276,"position":0},"title":"&#171;Perros panda&#187;: un zoo chino se hace viral por atraer a los visitantes con cachorros pintados","author":"","date":"septiembre 20, 2024","format":false,"excerpt":"(CNN) -- Un zoo chino admiti\u00f3 que su atracci\u00f3n estrella, dos supuestos pandas, no son m\u00e1s que perros pintados.Los esponjosos Chow Chow, pintados para parecerse al amado animal nacional del pa\u00eds, aparecieron en un v\u00eddeo grabado por un visitante del zoo, situado en la provincia meridional de Guangdong. El video,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464389,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/10\/apon-pandas-regresaron-china-trax\/","url_meta":{"origin":1447276,"position":1},"title":"La capital japonesa de los pandas est\u00e1 perdiendo sus ejemplares. \u00bfQu\u00e9 suceder\u00e1?","author":"","date":"julio 10, 2025","format":false,"excerpt":"Llegaron vestidos de blanco y negro, con gorros de piel, pancartas y peluches en la mano. Con l\u00e1grimas en los ojos y sollozos en la garganta, esperaron pacientemente en fila bajo el sol abrasador para echar un \u00faltimo vistazo antes de que todo terminara.Los pandas se han convertido en grandes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456213,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/02\/hong-kong-esculturas-de-pandas-arte-ap\/","url_meta":{"origin":1447276,"position":2},"title":"Hong Kong expondr\u00e1 2.500 esculturas de pandas para aprovechar la fiebre local por los osos","author":"","date":"diciembre 2, 2024","format":false,"excerpt":"(AP) -- Miles de esculturas de pandas gigantes dar\u00e1n la bienvenida a residentes y turistas a partir de este s\u00e1bado en Hong Kong, donde el entusiasmo por estos osos creci\u00f3 desde que nacieron dos cachorros en un parque tem\u00e1tico local.\u00a1Las 2.500 esculturas se presentaron en la ceremonia de inauguraci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450401,"url":"https:\/\/noticiasya.com\/aspen\/2024\/06\/16\/china-enviara-una-nueva-pareja-de-pandas-gigantes-a-australia-en-senal-estrechamiento-de-lazos-trax\/","url_meta":{"origin":1447276,"position":3},"title":"China enviar\u00e1 una nueva pareja de pandas gigantes a Australia en se\u00f1al de estrechamiento de lazos","author":"","date":"junio 16, 2024","format":false,"excerpt":"(CNN) -- China enviar\u00e1 una nueva pareja de pandas gigantes a Australia, seg\u00fan anunci\u00f3 este domingo el primer ministro Li Qiang, en la \u00faltima se\u00f1al del estrechamiento de las relaciones entre ambos pa\u00edses.Li hizo el anuncio en el zoo de Adelaida al iniciar un viaje de cuatro d\u00edas al pa\u00eds,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1411514,"url":"https:\/\/noticiasya.com\/aspen\/2022\/07\/07\/shuan-shuan-fallece-a-los-35-anos-la-panda-mas-longeva-de-mexico\/","url_meta":{"origin":1447276,"position":4},"title":"Shuan Shuan fallece a los 35 a\u00f1os, la panda m\u00e1s longeva de M\u00e9xico","author":"agomez","date":"julio 7, 2022","format":false,"excerpt":"Shuan super\u00f3 la expectativa de vida de su especie cuando est\u00e1n en su h\u00e1bitat natural, que es de 15 a\u00f1os.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/aspen\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470548,"url":"https:\/\/noticiasya.com\/aspen\/2026\/01\/28\/5-cosas-28-de-enero-orix\/","url_meta":{"origin":1447276,"position":5},"title":"Las 5 cosas que debes saber este 28 de enero","author":"agomez","date":"enero 28, 2026","format":false,"excerpt":"La confrontaci\u00f3n previa de Alex Pretti con agentes federales. Espa\u00f1a podr\u00eda legalizar a medio mill\u00f3n de inmigrantes. \u00bfC\u00f3mo fue el ataque armado en Salamanca, Guanajuato? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1447276"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447276\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1447276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1447276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1447276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}