{"id":1447296,"date":"2024-03-24T15:03:56","date_gmt":"2024-03-24T22:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/"},"modified":"2024-03-24T15:03:56","modified_gmt":"2024-03-24T22:03:56","slug":"amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/","title":{"rendered":"AMLO: Trump no construir\u00e1 el muro &#171;porque nos entendemos muy bien&#187;"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo que el expresidente de Estados Unidos Donald Trump no construir\u00e1 el muro en caso de ganar un segundo mandato en las elecciones de noviembre.<\/p>\n<p>En una entrevista con el programa &#171;60 Minutes&#187; de CBS, que se emite la noche de este domingo, L\u00f3pez Obrador coment\u00f3 que Trump no construir\u00e1 el muro &#171;porque nos entendemos muy bien&#187;.<\/p>\n<p>&#171;No (va a construir el muro) porque nos entendemos muy bien. Firmamos un tratado comercial y econ\u00f3mico que ha sido favorable para los dos pueblos, para los dos pa\u00edses. \u00c9l lo sabe. Y el presidente Biden tambi\u00e9n&#187;, dijo L\u00f3pez Obrador en un avance de la entrevista.<\/p>\n<p>El tema del muro apareci\u00f3 en la conversaci\u00f3n luego de que el presidente mexicano fuera cuestionado sobre la renovada promesa en campa\u00f1a de Trump de acabar con los vac\u00edos en el muro fronterizo que divide a Estados Unidos y M\u00e9xico.<\/p>\n<p>L\u00f3pez Obrador reitera que M\u00e9xico no aceptar\u00e1 migrantes deportados bajo la pol\u00e9mica ley de inmigraci\u00f3n de Texas<\/p>\n<p>En su campa\u00f1a a la presidencia de 2016, Trump prometi\u00f3 terminar de construir el muro fronterizo entre ambos pa\u00edses e incluso dijo que M\u00e9xico pagar\u00eda por ello, pero ninguna de las dos cosas ocurri\u00f3, seg\u00fan una verificaci\u00f3n de informaci\u00f3n realizada por CNN.<\/p>\n<p>Trump dijo en varias ocasiones en esa campa\u00f1a que EE.UU. necesitaba alrededor de 1.600 kil\u00f3metros de muro fronterizo con M\u00e9xico; sin embargo, en su gobierno se terminaron construyendo solo 737 km, y gran parte de esta cantidad fue para reemplazar estructura existente.<\/p>\n<p>Cuando termin\u00f3 su mandato, el Gobierno de Trump ten\u00eda planeados otros 280 kil\u00f3metros de muro, pero no fueron ejecutados.<\/p>\n<p>La frontera de Estados Unidos con M\u00e9xico tiene m\u00e1s de 3.057 kil\u00f3metros de largo. Como se\u00f1al\u00f3 Trump durante su campa\u00f1a de 2016, las barreras naturales dificultan el cruce en algunos tramos incluso sin muro.<\/p>\n<p>Con informaci\u00f3n de Daniel Dale, de CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo que el expresidente de Estados Unidos Donald Trump no construir\u00e1 el muro en caso de ganar un segundo mandato en las elecciones de noviembre. En una entrevista con el programa &#171;60 Minutes&#187; de CBS, que se emite la noche de este domingo, L\u00f3pez [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447296","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AMLO: Trump no construir\u00e1 el muro &quot;porque nos entendemos muy bien&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMLO: Trump no construir\u00e1 el muro &quot;porque nos entendemos muy bien&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo que el expresidente de Estados Unidos Donald Trump no construir\u00e1 el muro en caso de ganar un segundo mandato en las elecciones de noviembre. En una entrevista con el programa &#171;60 Minutes&#187; de CBS, que se emite la noche de este domingo, L\u00f3pez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-24T22:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AMLO: Trump no construir\u00e1 el muro &#171;porque nos entendemos muy bien&#187;\",\"datePublished\":\"2024-03-24T22:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/\"},\"wordCount\":371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/\",\"name\":\"AMLO: Trump no construir\u00e1 el muro \\\"porque nos entendemos muy bien\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-24T22:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMLO: Trump no construir\u00e1 el muro &#171;porque nos entendemos muy bien&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMLO: Trump no construir\u00e1 el muro \"porque nos entendemos muy bien\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/","og_locale":"es_ES","og_type":"article","og_title":"AMLO: Trump no construir\u00e1 el muro \"porque nos entendemos muy bien\" - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo que el expresidente de Estados Unidos Donald Trump no construir\u00e1 el muro en caso de ganar un segundo mandato en las elecciones de noviembre. En una entrevista con el programa &#171;60 Minutes&#187; de CBS, que se emite la noche de este domingo, L\u00f3pez [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-24T22:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/"},"author":{"name":"","@id":""},"headline":"AMLO: Trump no construir\u00e1 el muro &#171;porque nos entendemos muy bien&#187;","datePublished":"2024-03-24T22:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/"},"wordCount":371,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/","url":"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/","name":"AMLO: Trump no construir\u00e1 el muro \"porque nos entendemos muy bien\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-24T22:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AMLO: Trump no construir\u00e1 el muro &#171;porque nos entendemos muy bien&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AMLO: Trump no construir\u00e1 el muro &#171;porque nos entendemos muy bien&#187;","url":"http:\/\/noticiasya.com\/aspen\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-24T22:03:56Z","datePublished":"2024-03-24T22:03:56Z","dateModified":"2024-03-24T22:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AMLO: Trump no construir\\u00e1 el muro &#171;porque nos entendemos muy bien&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/24\\\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/24\\\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-24T22:03:56Z\",\"datePublished\":\"2024-03-24T22:03:56Z\",\"dateModified\":\"2024-03-24T22:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451267,"url":"https:\/\/noticiasya.com\/aspen\/2024\/07\/19\/amlo-carta-trump-rebatirle-argumentos-migracion-orix\/","url_meta":{"origin":1447296,"position":0},"title":"L\u00f3pez Obrador enviar\u00e1 una carta a su \u201camigo\u201d Trump para rebatirle argumentos sobre migraci\u00f3n e integraci\u00f3n econ\u00f3mica","author":"","date":"julio 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, anunci\u00f3 este viernes que la semana pr\u00f3xima le escribir\u00e1 al candidato presidencial republicano Donald Trump para exponer sus argumentos sobre inmigraci\u00f3n.\u201cLe voy a enviar una carta, lo anuncio, a mi amigo Donald Trump, porque pienso que no le est\u00e1n informando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465595,"url":"https:\/\/noticiasya.com\/aspen\/2025\/08\/18\/trump-mexico-hace-nosotros-decimos-que-tan-cierto-es-orix\/","url_meta":{"origin":1447296,"position":1},"title":"Trump dice que M\u00e9xico &#171;hace lo que nosotros le decimos que haga&#187;. \u00bfQu\u00e9 tan cierto es?","author":"","date":"agosto 18, 2025","format":false,"excerpt":"Las negociaciones entre M\u00e9xico y Estados Unidos han sido un sello caracter\u00edstico desde que Donald Trump regres\u00f3 al poder en enero de este a\u00f1o. Desde entonces, el presidente de EE.UU. y la presidenta de M\u00e9xico, Claudia Sheinbaum, se han centrado en negociar, pero tambi\u00e9n en cruzar declaraciones que tensan la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456660,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/","url_meta":{"origin":1447296,"position":2},"title":"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales","author":"","date":"diciembre 16, 2024","format":false,"excerpt":"El presidente electo de EE.UU. Donald Trump critic\u00f3 al presidente Joe Biden luego de un par de acciones que la administraci\u00f3n de Biden tom\u00f3 despu\u00e9s de la elecci\u00f3n de Trump en noviembre, incluidos informes de que la administraci\u00f3n vendi\u00f3 materiales de construcci\u00f3n del muro fronterizo entre Estados Unidos y M\u00e9xico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465685,"url":"https:\/\/noticiasya.com\/aspen\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/","url_meta":{"origin":1447296,"position":3},"title":"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido","author":"","date":"agosto 20, 2025","format":false,"excerpt":"El muro a lo largo de la frontera sur ser\u00e1 pintado de negro en un esfuerzo por hacer que la estructura sea demasiado caliente para escalarla, anunci\u00f3 este martes la secretaria del Departamento de Seguridad Nacional, Kristi Noem, diciendo que la sugerencia vino del presidente Donald Trump.\u201cEs alto, lo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453222,"url":"https:\/\/noticiasya.com\/aspen\/2024\/09\/30\/amlo-ultima-mananera-mexico-orix\/","url_meta":{"origin":1447296,"position":4},"title":"AMLO brinda su \u00faltima ma\u00f1anera: &#171;Me voy muy contento porque voy a entregar la banda presidencial a una mujer excepcional&#187;","author":"","date":"septiembre 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Este lunes, el presidente saliente, Andr\u00e9s Manuel L\u00f3pez Obrador (AMLO), brind\u00f3 su \u00faltima conferencia de prensa diaria.En sus seis a\u00f1os en el cargo, ha realizado m\u00e1s de mil sesiones informativas matutinas televisadas que duran un promedio de dos horas y media cada una. La llamada \"ma\u00f1anera\" ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448027,"url":"https:\/\/noticiasya.com\/aspen\/2024\/04\/12\/agentes-fronterizos-temen-migrantes-mexico-trax\/","url_meta":{"origin":1447296,"position":5},"title":"Estos son los agentes fronterizos a los que temen los migrantes y no son los estadounidenses","author":"","date":"abril 12, 2024","format":false,"excerpt":"Ejido Jacum\u00e9, Baja California, M\u00e9xico (CNN) -- La barrera de color \u00f3xido se eleva en el cielo azul sin nubes, un marcador s\u00f3lido y casi infranqueable de la frontera entre M\u00e9xico y Estados Unidos. Pero entonces se detiene, cuando el terreno accidentado se convierte en una monta\u00f1a, o una gran\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1447296"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447296\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1447296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1447296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1447296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}