{"id":1447305,"date":"2024-03-24T19:03:44","date_gmt":"2024-03-25T02:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/"},"modified":"2024-03-24T19:03:44","modified_gmt":"2024-03-25T02:03:44","slug":"trump-consigue-fianza-464-millones-nueva-york-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/","title":{"rendered":"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones"},"content":{"rendered":"<p>(CNN) &#8212; El equipo legal de Donald Trump y la oficina del fiscal general de Nueva York trabajan duro antes de que este lunes venza el plazo para que el expresidente obtenga una fianza por la multimillonaria sentencia por fraude civil que pesa en su contra.<\/p>\n<p>Trump debe personalmente m\u00e1s de US$ 454 millones derivados de la sentencia dictada por el juez Arthur Engoron en febrero. La cifra se dispara hasta los US$ 463,9 millones si se incluye el dinero que le deben sus hijos Eric y Donald Jr, la Organizaci\u00f3n Trump y los intereses devengados desde la fecha de la sentencia.<\/p>\n<p>Donald Trump est\u00e1 a punto de enriquecerse US$ 3.000 millones, pero eso probablemente no resolver\u00e1 su crisis de liquidez<\/p>\n<p>Los expertos que hablaron con CNN dicen que la fiscal general Letitia James y su personal deber\u00edan estar preparados para comenzar el complicado laberinto legal de confiscar los activos de Trump si el expresidente no asegura los bonos necesarios para cubrir el fallo de Engoron mientras apela.<\/p>\n<p>Est\u00e1n en juego activos como edificios, casas, coches, helic\u00f3pteros y su avi\u00f3n. El principal foco de atenci\u00f3n podr\u00edan ser sus cuentas bancarias, que seg\u00fan los expertos ser\u00e1n m\u00e1s f\u00e1ciles de embargar, y las propiedades, que ser\u00edan m\u00e1s dif\u00edciles.<\/p>\n<p>Trump pidi\u00f3 a un tribunal estatal de apelaciones que le permita depositar una fianza menor \u2013o ninguna en absoluto\u2013 al afirmar que se enfrentar\u00eda a un da\u00f1o irreparable si se viera obligado a vender propiedades en una venta forzosa que no podr\u00eda deshacerse si finalmente gana su apelaci\u00f3n. El tribunal a\u00fan no se ha pronunciado.<\/p>\n<p>Esto es lo que pasar\u00eda si Trump no puede asegurar la fianza:<\/p>\n<p>Incautaci\u00f3n de cuentas bancarias y dinero en efectivo<\/p>\n<p>En teor\u00eda, los funcionarios pueden comenzar el complicado proceso legal de tomar sus activos, a falta de cualquier otra maniobra legal estrat\u00e9gica de los fiscales del Estado y la lucha contra el equipo legal de Trump. Los funcionarios tendr\u00e1n que sopesar qu\u00e9 activos quieren tomar, si sus cuentas bancarias o sus propiedades. Los expertos creen que la primera acci\u00f3n deber\u00eda ser embargar sus cuentas bancarias.<\/p>\n<p>&#171;Los bancos son la parte m\u00e1s f\u00e1cil, recibir\u00e1n la sentencia del Fiscal General -la orden judicial- y luego los bancos la ejecutar\u00e1n&#187;, dijo el abogado Peter Katz, ex fiscal federal del Distrito Este de Nueva York que ha llevado casos de fraude. &#171;Retiran los fondos de la cuenta y los ingresan en las cuentas del Fiscal General. Lo otro es un poco m\u00e1s dif\u00edcil&#187;.<\/p>\n<p>Sacar dinero de las cuentas de Trump requiere que los fiscales estatales pidan al sheriff de Nueva York o a un US Marshall que entren en la sucursal principal del banco en el que Trump tenga su dinero, armados con una orden judicial.<\/p>\n<p>Truth Social hizo m\u00e1s rico a Trump y le dio un nuevo meg\u00e1fono, pero est\u00e1 teniendo problemas como red social.<\/p>\n<p>&#171;Entran y se lo dan al gerente&#187;, dijo Adam Pollock, un exasistente de la fiscal general del Estado de Nueva York que ahora se especializa en ejecuci\u00f3n de sentencias en Pollock Cohen LLP. &#171;Se supone que el gerente debe abonar el importe de inmediato. Debe ser un cheque al portador&#187;.<\/p>\n<p>Cualquier tiempo extra que perciba la oficina de la fiscal general podr\u00eda ser solo parte de la determinaci\u00f3n de la estrategia correcta.<\/p>\n<p>&#171;Est\u00e1n intentando ponerse las pilas. Quieren encontrar el m\u00e1s l\u00edquido de los activos que pueden restringir de inmediato. Una cuenta bancaria es la forma m\u00e1s eficaz de hacerlo&#187;, dijo el abogado Alden B. Smith, especializado en el cobro de deudas. &#171;Probablemente est\u00e9n decidiendo cu\u00e1l es el mejor curso de acci\u00f3n&#187;.<\/p>\n<p>\u00bfQu\u00e9 ocurre con los edificios y las empresas?<\/p>\n<p>La incautaci\u00f3n de propiedades lleva mucho m\u00e1s tiempo.<\/p>\n<p>Una vez que los fiscales estatales deciden qu\u00e9 propiedad quieren tomar, dan a la oficina del sheriff la orden de ejecuci\u00f3n, junto con una tasa de US$ 350, dijo Pollock. A continuaci\u00f3n, el sheriff publica el anuncio de la propiedad en tres lugares y la oficina de la fiscal general debe anunciarlo cuatro veces, dijo Pollack. A continuaci\u00f3n, en 63 d\u00edas a partir de cuando la orden de ejecuci\u00f3n se da al sheriff, una subasta p\u00fablica se lleva a cabo para la propiedad, de acuerdo con Pollock.<\/p>\n<p>&#171;Podr\u00edan decir &#8216;entreguen la propiedad de estas 500 corporaciones y LLC al sheriff para subasta p\u00fablica&#8217; o s\u00f3lo lo suficiente para que puedan satisfacer la sentencia o U$ 455 millones&#187;, dijo Pollock.<\/p>\n<p>AN\u00c1LISIS | Trump necesita US$ 500 millones, y r\u00e1pido<\/p>\n<p>El proceso de embargo ser\u00e1 m\u00e1s dif\u00edcil con las propiedades de Trump fuera del estado, por lo que los fiscales estatales ya han hecho algunos movimientos legales para poner la pelota en marcha en Nueva York.<\/p>\n<p>La oficina de la fiscal general present\u00f3 sentencias en el condado de Westchester, al norte de la ciudad de Nueva York, en lo que algunos dicen que es la primera se\u00f1al de que el Estado est\u00e1 sentando las bases para incautar el campo de golf del expresidente en Briarcliff Manor, as\u00ed como su finca privada conocida como Seven Springs.<\/p>\n<p>Los abogados del Estado registraron las sentencias en la oficina del secretario del condado de Westchester el 6 de marzo, justo una semana despu\u00e9s de la sentencia de Engoron.<\/p>\n<p>\u00bfQu\u00e9 pasa con Mar-a-Lago?<\/p>\n<p>No se han presentado otros juicios, pero el proceso podr\u00eda desarrollarse en otros estados donde Trump tiene activos, sobre todo Mar-a-Lago en Florida, aunque otras propiedades podr\u00edan ser menos dif\u00edciles de tomar.<\/p>\n<p>&#171;La oficina de la fiscal general es la empresa m\u00e1s grande del estado de Nueva York, si se piensa en ella como un bufete de abogados. La oficina tiene cero abogados en Florida. Yo ver\u00eda la ejecuci\u00f3n de propiedades en Nueva York antes de ver nada en Florida&#187;, dijo Pollack.<\/p>\n<p>Una batalla legal clave podr\u00eda ser qu\u00e9 parte de Mar-a-Lago se considera la casa de Trump, que podr\u00eda estar protegida por la ley.<\/p>\n<p>&#171;En el centro podr\u00eda estar la extensi\u00f3n de homestead. Pero eso tendr\u00eda que desarrollarse en los tribunales&#187;, dijo Pollock.<\/p>\n<p>\u00bfPuede Trump salir de esta?<\/p>\n<p>Trump sigue a la espera de que un tribunal de apelaciones reduzca la cantidad que debe pagar como parte de la sentencia o suspenda la sentencia mientras se estudia su apelaci\u00f3n.<\/p>\n<p>Si no gana su apelaci\u00f3n, la bancarrota sigue siendo una opci\u00f3n, aunque una que el expresidente no quiere tomar.<\/p>\n<p>&#171;No quiere que se declare en quiebra, ya que entonces la deuda ser\u00eda condonada&#187;, dijo Smith. &#171;Si se declara en quiebra, la sentencia se suspende autom\u00e1ticamente. La quiebra es la mayor n\u00e9mesis de la ejecuci\u00f3n de cobros para los abogados&#187;.<\/p>\n<p>Si Trump no consigue el dinero, sus opciones se reducen considerablemente.<\/p>\n<p>&#171;No veo ninguna otra forma de que pueda detener el proceso sin declararse en bancarrota o conseguir una fianza&#187;, dijo Smith.<\/p>\n<p>La Fiscal\u00eda de Nueva York da el primer paso para preparar el embargo de bienes de Trump<\/p>\n<p>Trump y su equipo podr\u00edan vender propiedades m\u00e1s peque\u00f1as como forma de intentar satisfacer la deuda.<\/p>\n<p>&#171;A fin de cuentas, har\u00e1 cualquier cosa antes de dejar que Tish James ponga un candado metaf\u00f3rico en el 40 de Wall Street&#187;, dijo el viernes a CNN Harry Litman, ex ayudante del fiscal general.<\/p>\n<p>Mientras el reloj est\u00e1 a punto de agotarse, algunos expertos se preguntan por qu\u00e9 se dio siquiera un periodo de gracia.<\/p>\n<p>&#171;No hay raz\u00f3n para la cortes\u00eda cuando debe US$ 455 millones al pueblo del estado de Nueva York despu\u00e9s de haber sido declarado persistentemente responsable de fraude&#187;, dijo Pollock. &#171;No es alguien con quien se suele tener cortes\u00eda&#187;.<\/p>\n<p>\u00bfTiene Trump el dinero en efectivo?<\/p>\n<p>El expresidente public\u00f3 en Truth Social este viernes que actualmente tiene casi US$ 500 millones en efectivo que ten\u00eda la intenci\u00f3n de utilizar para su campa\u00f1a y dijo que James &#171;quiere quit\u00e1rselo&#187;.<\/p>\n<p>&#171;A TRAV\u00c9S DEL TRABAJO DURO, EL TALENTO Y LA SUERTE, ACTUALMENTE TENGO CASI QUINIENTOS MILLONES DE D\u00d3LARES EN EFECTIVO, UNA CANTIDAD SUSTANCIAL DE LOS CUALES TEN\u00cdA LA INTENCI\u00d3N DE UTILIZAR EN MI CAMPA\u00d1A PARA PRESIDENTE. EL JUEZ POL\u00cdTICO HIP\u00d3CRITA EN EL CASO AMA\u00d1ADO Y CORRUPTO DE A.G., DONDE NO HICE NADA MAL, SAB\u00cdA ESTO, QUISO QUIT\u00c1RMELO&#187;, public\u00f3 Trump en may\u00fasculas.<\/p>\n<p>Su abogado, Chris Kise dijo a CNN que Trump no se refer\u00eda a dinero en efectivo que tiene en la mano, sin embargo.<\/p>\n<p>&#171;De lo que est\u00e1 hablando es del dinero que aparece en los formularios de divulgaci\u00f3n de su campa\u00f1a y que ha acumulado a lo largo de a\u00f1os de poseer y gestionar negocios de \u00e9xito&#187;, dijo Kise a CNN este viernes. Ese es precisamente el dinero en efectivo que Letitia James y los dem\u00f3cratas tienen en la mira&#187;.<\/p>\n<p>Trump tambi\u00e9n ha tenido que pagar recientemente una fianza de casi US$ 92 millones para satisfacer la sentencia en su contra en el caso de difamaci\u00f3n de E. Jean Carroll, mientras recurre.<\/p>\n<p>Litman dijo a CNN que es probable que haya menos dinero del que dice Trump debido a la sentencia por fraude. De cualquier manera, agreg\u00f3, es un golpe devastador para el ex presidente.<\/p>\n<p>&#171;Es como una empresa que de repente no tiene sillas, muebles, cuentas por cobrar ni nada. Ese es realmente el final del d\u00eda, creo, para la organizaci\u00f3n Trump en Nueva York&#187;, dijo Litman. &#171;Es una situaci\u00f3n fea, fea para \u00e9l, incluso si es medianamente exacta&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El equipo legal de Donald Trump y la oficina del fiscal general de Nueva York trabajan duro antes de que este lunes venza el plazo para que el expresidente obtenga una fianza por la multimillonaria sentencia por fraude civil que pesa en su contra. Trump debe personalmente m\u00e1s de US$ 454 millones derivados [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447305","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El equipo legal de Donald Trump y la oficina del fiscal general de Nueva York trabajan duro antes de que este lunes venza el plazo para que el expresidente obtenga una fianza por la multimillonaria sentencia por fraude civil que pesa en su contra. Trump debe personalmente m\u00e1s de US$ 454 millones derivados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-25T02:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones\",\"datePublished\":\"2024-03-25T02:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/\"},\"wordCount\":1665,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/\",\"name\":\"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-25T02:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones - Noticias","og_description":"(CNN) &#8212; El equipo legal de Donald Trump y la oficina del fiscal general de Nueva York trabajan duro antes de que este lunes venza el plazo para que el expresidente obtenga una fianza por la multimillonaria sentencia por fraude civil que pesa en su contra. Trump debe personalmente m\u00e1s de US$ 454 millones derivados [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-25T02:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/"},"author":{"name":"","@id":""},"headline":"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones","datePublished":"2024-03-25T02:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/"},"wordCount":1665,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/","name":"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-25T02:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones","url":"http:\/\/noticiasya.com\/aspen\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-25T02:03:44Z","datePublished":"2024-03-25T02:03:44Z","dateModified":"2024-03-25T02:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/24\\\/trump-consigue-fianza-464-millones-nueva-york-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/24\\\/trump-consigue-fianza-464-millones-nueva-york-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-25T02:03:44Z\",\"datePublished\":\"2024-03-25T02:03:44Z\",\"dateModified\":\"2024-03-25T02:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447620,"url":"https:\/\/noticiasya.com\/aspen\/2024\/04\/01\/trump-fianza-fraude-nueva-york-millones-trax\/","url_meta":{"origin":1447305,"position":0},"title":"Trump paga la fianza de US$ 175 millones para apelar caso de fraude civil en Nueva York","author":"","date":"abril 1, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El expresidente de Estados Unidos Donald Trump pag\u00f3 una fianza de 175 millones de d\u00f3lares para apelar el fallo en su contra en un caso de fraude civil en Nueva York, el cual present\u00f3 la fiscal general del estado Letitia James.Esto es lo que puede pasar si Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445813,"url":"https:\/\/noticiasya.com\/aspen\/2024\/02\/21\/trump-juez-retrase-sentencia-fraude-trax\/","url_meta":{"origin":1447305,"position":1},"title":"Trump solicita al juez que retrase un mes la ejecuci\u00f3n de la sentencia por fraude civil de US$ 355 millones","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- El expresidente Donald Trump pidi\u00f3 al juez que supervisa el caso de fraude civil que retrase un mes la ejecuci\u00f3n de la sentencia de US$ 355 millones en su contra.En una carta al juez Arthur Engoron, los abogados de Trump acusan a la fiscal general de Nueva York,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447208,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/21\/fiscal-general-nueva-york-embargo-bienes-trump-trax\/","url_meta":{"origin":1447305,"position":2},"title":"La Fiscal\u00eda de Nueva York da el primer paso para preparar el embargo de bienes de Trump","author":"","date":"marzo 21, 2024","format":false,"excerpt":"(CNN) \u2013\u2013\u00a0La Fiscal\u00eda General de Nueva York present\u00f3 sentencias en el condado de Westchester, en lo que representa la primera se\u00f1al de que el estado se prepara para intentar embargar el campo de golf y la finca privada de Donald Trump al norte de Manhattan, conocidos como Seven Springs.Los abogados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446020,"url":"https:\/\/noticiasya.com\/aspen\/2024\/02\/26\/trump-hijos-organizacion-apelacion-nueva-york-fraude-trax\/","url_meta":{"origin":1447305,"position":3},"title":"Trump, sus hijos Donald Jr. y Eric, y exfuncionarios de la Organizaci\u00f3n Trump apelan la sentencia de fraude civil en Nueva York","author":"","date":"febrero 26, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El expresidente Donald Trump, sus hijos adultos Donald Jr. y Eric, adem\u00e1s de dos exfuncionarios de la Organizaci\u00f3n Trump apelaron la sentencia de US$ 464 millones dictada en su contra en el caso de fraude civil en Nueva York.Juez le ordena formalmente a Trump pagar US$ 454 millones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446475,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/04\/trump-liquidez-sentencias-500-trax-2\/","url_meta":{"origin":1447305,"position":4},"title":"\u00bfC\u00f3mo Trump (de repente sin liquidez) podr\u00eda recaudar m\u00e1s de US$ 500 millones para cumplir sentencias en su contra?","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) --\u00a0Donald Trump se enfrenta a una crisis de liquidez a medida que se acercan r\u00e1pidamente los plazos para liquidar los m\u00e1s de US$ 500 millones que debe en sentencias.Ahora puedes seguirnos en\u00a0WhatsApp ChannelEl mi\u00e9rcoles, un juez de la corte de apelaciones de Nueva York se neg\u00f3 a darle al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446153,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/01\/trump-liquidez-sentencias-500-trax\/","url_meta":{"origin":1447305,"position":5},"title":"\u00bfC\u00f3mo Trump (de repente sin liquidez) podr\u00eda recaudar m\u00e1s de US$ 500 millones para cumplir sentencias en su contra?","author":"","date":"marzo 1, 2024","format":false,"excerpt":"(CNN) --\u00a0Donald Trump se enfrenta a una crisis de liquidez a medida que se acercan r\u00e1pidamente los plazos para liquidar los m\u00e1s de US$ 500 millones que debe en sentencias.El mi\u00e9rcoles, un juez de la corte de apelaciones de Nueva York se neg\u00f3 a darle al expresidente tiempo adicional para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1447305"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447305\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1447305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1447305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1447305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}