{"id":1447317,"date":"2024-03-25T00:03:46","date_gmt":"2024-03-25T07:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/"},"modified":"2024-03-25T00:03:46","modified_gmt":"2024-03-25T07:03:46","slug":"analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/","title":{"rendered":"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro?"},"content":{"rendered":"<p>(CNN) &#8212; Los informes de incidentes aterradores y a veces tr\u00e1gicos a bordo de aviones se aceleraron este a\u00f1o, llevando a muchos a preguntarse si todav\u00eda es seguro volar.<\/p>\n<p>Un tap\u00f3n de puerta se desprendi\u00f3 en un vuelo de Alaska Airlines dejando un agujero enorme en el fuselaje del Boeing 737 Max. Los tel\u00e9fonos y la ropa de los pasajeros fueron arrancados de sus cuerpos y lanzados hacia la noche mientras ca\u00edan las m\u00e1scaras de ox\u00edgeno y el avi\u00f3n se dirig\u00eda hacia el suelo, afortunadamente sin causar lesiones graves.<\/p>\n<p>Otro avi\u00f3n Boeing se precipit\u00f3 tan severamente que los pasajeros fueron arrojados al techo de la cabina, dejando a docenas tan heridos que necesitaron ser hospitalizados al aterrizar.<\/p>\n<p>Un avi\u00f3n de pasajeros choc\u00f3 con un avi\u00f3n militar en un aeropuerto de Tokio, matando a cinco miembros de la Guardia Costera japonesa que estaban respondiendo a un terremoto.<\/p>\n<p>Y ocurrieron incidentes m\u00e1s menores, como cuando una rueda de 200 libras se desprendi\u00f3 de un avi\u00f3n al despegar, aplastando veh\u00edculos estacionados en el suelo. El motor de otro avi\u00f3n se incendi\u00f3. Un jet lleg\u00f3 a un aeropuerto solo para descubrir que faltaba un panel. Estos incidentes todos ganaron la atenci\u00f3n digna de una Kardashian en las redes sociales.<\/p>\n<p>Pero responder a la pregunta de si todav\u00eda es seguro volar no es tan sencillo.<\/p>\n<p>Vuelo de United Airlines descubre falta de panel externo despu\u00e9s de aterrizar de manera segura en Oreg\u00f3n<\/p>\n<p>La respuesta r\u00e1pida es que volar es seguro, m\u00e1s seguro que la mayor\u00eda de las formas de viaje, y mucho, mucho m\u00e1s seguro que el viaje en autom\u00f3vil que la mayor\u00eda de las personas hacen todos los d\u00edas sin pensarlo dos veces.<\/p>\n<p>&#171;Cuando llegas al aeropuerto y subes al tubo presurizado, esa es la parte m\u00e1s segura del viaje&#187;, dijo Anthony Brickhouse, investigador de accidentes y profesor de seguridad a\u00e9rea en la Universidad Aeron\u00e1utica Embry-Riddle. &#171;Estabas m\u00e1s en riesgo conduciendo hacia el aeropuerto&#187;.<\/p>\n<p>Pero tambi\u00e9n es cierto que es solo pura suerte que la industria de la aviaci\u00f3n estadounidense haya mantenido intacto su casi perfecto historial de seguridad.<\/p>\n<p>15 a\u00f1os casi perfectos<\/p>\n<p>Desde que un avi\u00f3n de pasajeros regional se estrell\u00f3 en Buffalo, Nueva York, en enero de 2009, matando a 49 personas a bordo y una en tierra, solo otras cinco personas han muerto en accidentes en vuelos comerciales programados en los Estados Unidos:<\/p>\n<p>Tres pasajeros murieron en 2013 cuando un avi\u00f3n de Asiana Airlines se desintegr\u00f3 al estrellarse antes de la pista en San Francisco.<br \/>\nUn pasajero en un vuelo de Southwest en 2018 muri\u00f3 cuando una cubierta del motor se rompi\u00f3 y estall\u00f3 la ventana junto a donde estaba sentado.<br \/>\nUn pasajero muri\u00f3 en 2019 cuando un avi\u00f3n peque\u00f1o se sali\u00f3 de la pista en Alaska rural.<\/p>\n<p>En comparaci\u00f3n, un promedio de m\u00e1s de 100 personas al d\u00eda murieron en las carreteras de Estados Unidos entre 2003 y 2022, el a\u00f1o m\u00e1s reciente para el cual est\u00e1n disponibles las cifras de muertes en accidentes de tr\u00e1fico de todo el a\u00f1o. Eso significa que casi tantas personas murieron en carreteras y autopistas cada hora, en promedio, como la cantidad de personas que murieron en accidentes de aviaci\u00f3n comercial en Estados Unidos en 15 a\u00f1os.<\/p>\n<p>El fuselaje destruido del vuelo 214 de Asiana Airlines es visible en la pista del Aeropuerto Internacional de San Francisco despu\u00e9s de que se estrell\u00f3 al aterrizar y se incendiara el s\u00e1bado 6 de julio de 2013. Carlos Avila Gonzalez\/The San Francisco. (Cr\u00e9dito: Chronicle\/Getty Images\/Archivo)<\/p>\n<p>Sin embargo, otras formas de vuelo no son ni de lejos tan seguras.<\/p>\n<p>Casi 300 personas han muerto desde 2009 mientras viajaban en servicios a\u00e9reos &#171;a pedido&#187;, como jets privados. Y cerca de 5.500 personas han muerto en aviaci\u00f3n general, que suelen ser aviones peque\u00f1os operados a menudo por pilotos aficionados.<\/p>\n<p>Si bien la aviaci\u00f3n comercial tiene el registro m\u00e1s seguro entre las opciones de tr\u00e1nsito, los ferrocarriles son la segunda forma m\u00e1s segura de viajar.<\/p>\n<p>Los ferrocarriles tuvieron 71 muertes de pasajeros en trenes de cercan\u00edas y Amtrak desde 2009 hasta el a\u00f1o pasado. Pero los trenes de pasajeros registraron muchas menos millas recorridas que aviones o veh\u00edculos de motor.<\/p>\n<p>Ed Pierson, director de la Fundaci\u00f3n para la Seguridad de la Aviaci\u00f3n y cr\u00edtico severo de Boeing, dijo que conoce las estad\u00edsticas, pero debido a preocupaciones sobre los controles de calidad en el acosado fabricante de aeronaves, a\u00fan se negar\u00eda a volar en el Boeing 737 Max o permitir\u00eda que un miembro de su familia lo hiciera. Incluso se baj\u00f3 de un Max justo antes de la salida despu\u00e9s de sorprenderse al descubrir que estaba en ese modelo de avi\u00f3n en particular.<\/p>\n<p>Sin embargo, Pierson dijo que est\u00e1 dispuesto a volar en la mayor\u00eda de los aviones, incluso muchos modelos antiguos de Boeing.<\/p>\n<p>&#171;Quitando el Max de la ecuaci\u00f3n, (volar ha) demostrado ser bastante seguro&#187;, dijo.<\/p>\n<p>Regresan a Chile algunos pasajeros del vuelo de Latam Airlines a Nueva Zelandia que sufri\u00f3 un &#171;evento t\u00e9cnico&#187; y termin\u00f3 con decenas de lesionados<\/p>\n<p>Apenas se evit\u00f3 un desastre<\/p>\n<p>Desafortunadamente, el historial de seguridad de los \u00faltimos a\u00f1os no es una garant\u00eda de seguridad en el futuro.<\/p>\n<p>El r\u00e9cord de casi ausencia de fatalidades en la industria de viajes en avi\u00f3n de Estados Unidos se debe en parte a los esfuerzos de las autoridades de aviaci\u00f3n, las aerol\u00edneas y los fabricantes de aeronaves, a pesar de las cr\u00edticas dirigidas a los tres grupos recientemente.<\/p>\n<p>Pero principalmente ha sido pura suerte. En cada caso, si las cosas hubieran sido un poco diferentes, los resultados podr\u00edan haber sido mucho peores.<\/p>\n<p>El avi\u00f3n de Alaska Air que perdi\u00f3 el tap\u00f3n de la puerta hab\u00eda volado durante m\u00e1s de dos meses sin los cuatro pernos necesarios para mantener el tap\u00f3n de la puerta en su lugar, seg\u00fan la Junta Nacional de Seguridad en el Transporte.<\/p>\n<p>Hab\u00eda realizado 153 vuelos antes de que el tap\u00f3n de la puerta se desprendiera a 16.000 pies de altura. Veintid\u00f3s de esos vuelos fueron entre Haw\u00e1i y el continente.<\/p>\n<p>Si la puerta hubiera estallado a la altitud normal de crucero de 35.000 pies, o a horas del aeropuerto m\u00e1s cercano sobre el vasto Oc\u00e9ano Pac\u00edfico, o si el tap\u00f3n hubiera golpeado directamente hacia atr\u00e1s y golpeado la cola del avi\u00f3n y causado da\u00f1os, probablemente podr\u00eda haber causado la p\u00e9rdida de la aeronave y las 177 personas a bordo.<\/p>\n<p>Y eso no es lo m\u00e1s importante. Hace un a\u00f1o, la discusi\u00f3n sobre la seguridad a\u00e9rea no se centraba en aviones Boeing. Se trataba de una serie de incidentes casi catastr\u00f3ficos en pistas de los aeropuertos de la naci\u00f3n con informes de incidente tras incidente de colisiones evitadas por poco.<\/p>\n<p>Pasajero del vuelo de LATAM a Auckland afirma que el piloto le dijo que perdi\u00f3 el control despu\u00e9s de una falla en un instrumento<\/p>\n<p>Casi desastres para aviones en tierra<\/p>\n<p>El 4 de febrero de 2023, un avi\u00f3n de FedEx estuvo a 45 metros de la pista antes de que sus pilotos se dieran cuenta de que un avi\u00f3n de Southwest estaba en proceso de despegar en la misma pista. Fue uno de los cinco incidentes de este tipo en los que solo se evit\u00f3 un accidente por poco en un per\u00edodo de solo siete semanas al comienzo del a\u00f1o pasado.<\/p>\n<p>Y ninguno de esos fue tan potencialmente grave como otro incidente en julio de 2017, cuando un avi\u00f3n de Air Canada pilotado por un capit\u00e1n que hab\u00eda estado despierto durante m\u00e1s de 19 horas casi aterriza en una pista de rodaje en el Aeropuerto Internacional de San Francisco donde tres aviones de fuselaje ancho llenos de pasajeros esperaban para despegar.<\/p>\n<p>La Junta Nacional de Seguridad en el Transporte determin\u00f3 m\u00e1s tarde que el avi\u00f3n de Air Canada estuvo a 30 metros del suelo antes de despegar nuevamente sin entrar en contacto con ninguno de los aviones de pasajeros en tierra. El regulador de seguridad dijo que m\u00e1s de 1.000 personas en los cuatro aviones podr\u00edan haber muerto si el accidente no se hubiera evitado en el \u00faltimo momento.<\/p>\n<p>&#171;Habr\u00eda sido el peor desastre en la historia de la aviaci\u00f3n&#187;, dijo Brickhouse. &#171;Los pilotos, los controladores de tr\u00e1fico a\u00e9reo, los mec\u00e1nicos, todos son humanos, y los humanos cometen errores. Hemos estado trabajando para dise\u00f1ar el sistema para que cuando se cometan errores, podamos recuperarnos de ellos sin que sea una tragedia&#187;.<\/p>\n<p>Pero Pierson dijo que el sistema est\u00e1 bajo un estr\u00e9s sin precedentes, y los reguladores, las aerol\u00edneas y los fabricantes de aeronaves como Boeing necesitan hacer cambios.<\/p>\n<p>&#171;Creo que el sistema est\u00e1 bajo un tremendo estr\u00e9s&#187;, dijo. &#171;Hay escasez de personal, en control de tr\u00e1fico a\u00e9reo, escasez de pilotos, de personal de mantenimiento, de personal de fabricaci\u00f3n&#187;.<\/p>\n<p>AN\u00c1LISIS | Dave Calhoun fue el director ejecutivo contratado para arreglar Boeing, pero desde que asumi\u00f3 el poder la empresa est\u00e1 en crisis<\/p>\n<p>\u00bfAfectado por la sobreconfianza?<\/p>\n<p>Lo que m\u00e1s preocupa a Pierson es la actitud de que la aparente seguridad del sistema de aviaci\u00f3n estadounidense significa que no se necesita mejorar nada.<\/p>\n<p>&#171;Hay un sentido de exceso de confianza&#187;, dijo. &#171;El est\u00e1ndar de oro se est\u00e1 derritiendo, porque seguimos tratando de minimizar todo y hablar sobre lo seguro que es el sistema. Esa no es la mentalidad correcta. Esa es la mentalidad que mata a las personas&#187;.<\/p>\n<p>Brickhouse cree que los aviones en uso actualmente son seguros. Dijo que el drama del incidente de Alaska Air llam\u00f3 la atenci\u00f3n sobre una serie de otros eventos que en s\u00ed mismos no representan una amenaza seria, incluso si no deber\u00edan haber ocurrido.<\/p>\n<p>&#171;Tuvimos eventos de seguridad en la aviaci\u00f3n todo el tiempo. Eso no es un indicio de la industria de la aviaci\u00f3n&#187;, dijo. &#171;Pero despu\u00e9s de Alaska Air, se convirti\u00f3 en un evento en cadena y todos se volvieron hiper sensibles&#187;.<\/p>\n<p>A pesar de tener m\u00e1s confianza en la seguridad del sistema que Pierson, Brickhouse dijo que tampoco desestimar\u00eda a nadie que tenga miedo de volar en este momento o que quiera evitar un avi\u00f3n como el 737 Max. Y \u00e9l tiene sus propias preocupaciones sobre cosas como el n\u00famero de accidentes evitados por poco en los aeropuertos de la naci\u00f3n.<\/p>\n<p>&#171;No creo en la suerte, pero tenemos la suerte de que estos incidentes no se convirtieron en desastres&#187;, dijo. &#171;Cuando tienes una tendencia que sigue ocurriendo, necesitas concentrarte en solucionarlo&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los informes de incidentes aterradores y a veces tr\u00e1gicos a bordo de aviones se aceleraron este a\u00f1o, llevando a muchos a preguntarse si todav\u00eda es seguro volar. Un tap\u00f3n de puerta se desprendi\u00f3 en un vuelo de Alaska Airlines dejando un agujero enorme en el fuselaje del Boeing 737 Max. Los tel\u00e9fonos y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447317","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los informes de incidentes aterradores y a veces tr\u00e1gicos a bordo de aviones se aceleraron este a\u00f1o, llevando a muchos a preguntarse si todav\u00eda es seguro volar. Un tap\u00f3n de puerta se desprendi\u00f3 en un vuelo de Alaska Airlines dejando un agujero enorme en el fuselaje del Boeing 737 Max. Los tel\u00e9fonos y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-25T07:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro?\",\"datePublished\":\"2024-03-25T07:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/\"},\"wordCount\":1855,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/\",\"name\":\"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-25T07:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro? - Noticias","og_description":"(CNN) &#8212; Los informes de incidentes aterradores y a veces tr\u00e1gicos a bordo de aviones se aceleraron este a\u00f1o, llevando a muchos a preguntarse si todav\u00eda es seguro volar. Un tap\u00f3n de puerta se desprendi\u00f3 en un vuelo de Alaska Airlines dejando un agujero enorme en el fuselaje del Boeing 737 Max. Los tel\u00e9fonos y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-25T07:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro?","datePublished":"2024-03-25T07:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/"},"wordCount":1855,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/","name":"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-25T07:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | Volar se est\u00e1 volviendo aterrador. \u00bfPero sigue siendo seguro?","url":"http:\/\/noticiasya.com\/aspen\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2024\/03\/25\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-25T07:03:46Z","datePublished":"2024-03-25T07:03:46Z","dateModified":"2024-03-25T07:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | Volar se est\\u00e1 volviendo aterrador. \\u00bfPero sigue siendo seguro?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/25\\\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/25\\\/analisis-volar-se-esta-volviendo-aterrador-pero-sigue-siendo-seguro-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-25T07:03:46Z\",\"datePublished\":\"2024-03-25T07:03:46Z\",\"dateModified\":\"2024-03-25T07:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450835,"url":"https:\/\/noticiasya.com\/aspen\/2024\/07\/01\/turbulencia-heridos-boeing-air-europa-madrid-montevideo-trax\/","url_meta":{"origin":1447317,"position":0},"title":"Al menos 30 pasajeros heridos despu\u00e9s de que una \u201cfuerte turbulencia\u201d obligara a un avi\u00f3n Boeing de Air Europa a aterrizar en Brasil","author":"","date":"julio 1, 2024","format":false,"excerpt":"(CNN) -- Al menos treinta pasajeros resultaron heridos despu\u00e9s de que un vuelo de Madrid a Uruguay sufriera \"fuertes turbulencias\" y tuviera que realizar un aterrizaje de emergencia en Brasil, inform\u00f3 el lunes la aerol\u00ednea espa\u00f1ola Air Europa.\u201cNuestro vuelo UX045 con destino Montevideo fue desviado al aeropuerto de Natal (Brasil)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446883,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/12\/problemas-boeing-no-paran-7-incidentes-con-aviones-meses-orix\/","url_meta":{"origin":1447317,"position":1},"title":"Los problemas de Boeing no paran: al menos 7 incidentes con aviones en menos de tres meses de 2024","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- De nueva cuenta, Boeing se encuentra bajo los reflectores medi\u00e1ticos por otro problema en uno de sus aviones, lo cual resalta a\u00fan m\u00e1s el desastroso 2024 que ha tenido el gigante de la aviaci\u00f3n.En apenas poco menos de tres meses este a\u00f1o, la compa\u00f1\u00eda se ha visto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447808,"url":"https:\/\/noticiasya.com\/aspen\/2024\/04\/06\/supervivientes-accidentes-aereos-victimas-miedo-volar-trax\/","url_meta":{"origin":1447317,"position":2},"title":"Estos sobrevivientes de accidentes a\u00e9reos y los seres queridos de las v\u00edctimas tienen miedo, tras a\u00f1os de vuelos. No est\u00e1n solos","author":"","date":"abril 6, 2024","format":false,"excerpt":"(CNN) -- Una repugnante sensaci\u00f3n de deja vu inund\u00f3 a Barb Handley y a sus hermanos cuando en enero surgi\u00f3 la noticia del desprendimiento de una pieza del fuselaje de un avi\u00f3n de Alaska Airlines en pleno vuelo, y dejando un enorme agujero en el avi\u00f3n.Las im\u00e1genes del agujero al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457857,"url":"https:\/\/noticiasya.com\/aspen\/2025\/01\/24\/heridos-sacudida-vuelo-aterrizaje-emergencia-nigeria-trax\/","url_meta":{"origin":1447317,"position":3},"title":"Seis personas resultaron heridas tras sacudida en pleno vuelo que oblig\u00f3 a un avi\u00f3n a aterrizar de emergencia en Nigeria","author":"","date":"enero 24, 2025","format":false,"excerpt":"Cuatro pasajeros y dos tripulantes resultaron heridos el viernes cuando un vuelo de United Airlines de Lagos, Nigeria, al Aeropuerto Internacional Dulles de Washington experiment\u00f3 un movimiento repentino en el aire, seg\u00fan United Airlines.Un video tomado por pasajeros muestra el caos a bordo, con bandejas, comida y otros objetos esparcidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444450,"url":"https:\/\/noticiasya.com\/aspen\/2024\/01\/26\/los-boeing-737-max-9-volveran-a-volar-esto-es-lo-que-deben-saber-los-viajeros\/","url_meta":{"origin":1447317,"position":4},"title":"Los Boeing 737 Max 9 volver\u00e1n a volar: esto es lo que deben saber los viajeros","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN) -- El incidente de Alaska Airlines del 5 de enero, que dej\u00f3 un agujero en el fuselaje de un Boeing 737 Max 9 poco despu\u00e9s de despegar de Portland, Oregon, plante\u00f3 importantes cuestiones de seguridad, dio lugar a investigaciones y dej\u00f3 en vilo a algunos pasajeros.Tras el incidente, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1454934,"url":"https:\/\/noticiasya.com\/aspen\/2024\/10\/04\/china-comac-c919-experiencia-trax\/","url_meta":{"origin":1447317,"position":5},"title":"El C919 es la respuesta china al A320. Pero, \u00bfc\u00f3mo es a bordo?","author":"","date":"octubre 4, 2024","format":false,"excerpt":"(CNN) --Vol\u00e9 m\u00e1s de un mill\u00f3n de millas con docenas de aerol\u00edneas de todo el mundo, y perd\u00ed la cuenta de cu\u00e1ntas veces me sub\u00ed a un avi\u00f3n de Air China para hacer el corto trayecto de Beijing a Shanghai.Durante la semana, las aerol\u00edneas programan m\u00e1s de 60 vuelos diarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1447317"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447317\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1447317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1447317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1447317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}