{"id":1447319,"date":"2024-03-25T01:03:41","date_gmt":"2024-03-25T08:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/"},"modified":"2024-03-25T01:03:41","modified_gmt":"2024-03-25T08:03:41","slug":"bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/","title":{"rendered":"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de El Salvador, Nayib Bukele anunci\u00f3 este domingo en sus redes sociales la instalaci\u00f3n de un cerco de 5 mil soldados y polic\u00edas en 4 distritos del norte del pa\u00eds para desarticular el accionar de la pandillas.<\/p>\n<p>&#171;Hace unos d\u00edas, hubo dos homicidios en la zona norte de nuestro pa\u00eds. Ya capturamos a los dos culpables, miembros de la pandilla 18 Sure\u00f1os. No nos vamos a detener hasta erradicar lo poco que a\u00fan queda de las pandillas&#187;, destac\u00f3 el mandatario en sus redes sociales.<\/p>\n<p>El cerco de seguridad comprender\u00e1 los distritos de San Jos\u00e9 Cancasque, San Antonio Los Ranchos, Potonico y San Isidro Labrador.<\/p>\n<p>Hace unos d\u00edas, hubo dos homicidios en la zona norte de nuestro pa\u00eds. Ya capturamos a los dos culpables, miembros de la pandilla 18 Sure\u00f1os.<br \/>\nEn este momento, 5 mil soldados y mil polic\u00edas han cercado los distritos de San Jos\u00e9 Cancasque, San Antonio Los Ranchos, Potonico y San\u2026 pic.twitter.com\/Nhx2bL6k6R<br \/>\n\u2014 Nayib Bukele (@nayibbukele) March 25, 2024<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de El Salvador, Nayib Bukele anunci\u00f3 este domingo en sus redes sociales la instalaci\u00f3n de un cerco de 5 mil soldados y polic\u00edas en 4 distritos del norte del pa\u00eds para desarticular el accionar de la pandillas. &#171;Hace unos d\u00edas, hubo dos homicidios en la zona norte de nuestro pa\u00eds. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447319","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de El Salvador, Nayib Bukele anunci\u00f3 este domingo en sus redes sociales la instalaci\u00f3n de un cerco de 5 mil soldados y polic\u00edas en 4 distritos del norte del pa\u00eds para desarticular el accionar de la pandillas. &#171;Hace unos d\u00edas, hubo dos homicidios en la zona norte de nuestro pa\u00eds. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-25T08:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador\",\"datePublished\":\"2024-03-25T08:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/\"},\"wordCount\":210,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/\",\"name\":\"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-25T08:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de El Salvador, Nayib Bukele anunci\u00f3 este domingo en sus redes sociales la instalaci\u00f3n de un cerco de 5 mil soldados y polic\u00edas en 4 distritos del norte del pa\u00eds para desarticular el accionar de la pandillas. &#171;Hace unos d\u00edas, hubo dos homicidios en la zona norte de nuestro pa\u00eds. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-25T08:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/"},"author":{"name":"","@id":""},"headline":"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador","datePublished":"2024-03-25T08:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/"},"wordCount":210,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/","url":"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/","name":"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-25T08:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Bukele anuncia un cerco con mil soldados y polic\u00edas en cuatro distritos en el norte El Salvador","url":"http:\/\/noticiasya.com\/aspen\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2024\/03\/25\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-25T08:03:41Z","datePublished":"2024-03-25T08:03:41Z","dateModified":"2024-03-25T08:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Bukele anuncia un cerco con mil soldados y polic\\u00edas en cuatro distritos en el norte El Salvador\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/25\\\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/25\\\/bukele-cerco-militar-soldados-policias-distritos-norte-el-salvador-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-25T08:03:41Z\",\"datePublished\":\"2024-03-25T08:03:41Z\",\"dateModified\":\"2024-03-25T08:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466805,"url":"https:\/\/noticiasya.com\/aspen\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/","url_meta":{"origin":1447319,"position":0},"title":"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista","author":"","date":"septiembre 25, 2025","format":false,"excerpt":"El presidente de El Salvador, Nayib Bukele, agradeci\u00f3 el martes a Donald Trump por los elogios durante su discurso ante la ONU y celebr\u00f3 la decisi\u00f3n de la Casa Blanca de declarar organizaci\u00f3n terrorista extranjera a la pandilla Barrio 18.\u201cEn El Salvador, ya hab\u00edamos dado este paso al designarlos formalmente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460327,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/24\/lider-pandilla-ms13-eeuu-deportacion-salvador-trax\/","url_meta":{"origin":1447319,"position":1},"title":"&#171;P\u00e9rdida hist\u00f3rica&#187;: presunto l\u00edder de pandilla MS-13 evade la justicia de EE.UU. con deportaci\u00f3n a El Salvador","author":"","date":"marzo 24, 2025","format":false,"excerpt":"Como parte de los vuelos de deportaci\u00f3n de presuntos terroristas, que se encuentran en el centro de una tormenta legal y pol\u00edtica, Estados Unidos retir\u00f3 en silencio los cargos contra un presunto l\u00edder clave de la pandilla MS-13 y lo devolvi\u00f3 al presidente pro-Trump de El Salvador, Nayib Bukele.C\u00e9sar Humberto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459994,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/16\/el-salvador-miembros-tren-aragua-megaprision-bukele-orix\/","url_meta":{"origin":1447319,"position":2},"title":"El Salvador recibe a 238 supuestos miembros del Tren de Aragua y los env\u00eda a la megaprisi\u00f3n de Bukele","author":"","date":"marzo 16, 2025","format":false,"excerpt":"El presidente de El Salvador, Nayib Bukele, anunci\u00f3 este domingo que su pa\u00eds ha recibido a 238 supuestos miembros de la organizaci\u00f3n criminal Tren de Aragua, quienes fueron trasladados desde Estados Unidos bajo \u00f3rdenes del presidente Donald Trump.\u201cQuiero expresar mi sincero agradecimiento al presidente Nayib Bukele de El Salvador por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470264,"url":"https:\/\/noticiasya.com\/aspen\/2026\/01\/20\/barrio-18-mara-salvatrucha-pandillas-guatemala-orix\/","url_meta":{"origin":1447319,"position":3},"title":"\u00bfQu\u00e9 son y c\u00f3mo operan Barrio 18 y la Mara Salvatrucha, las dos pandillas con mayor presencia en Guatemala?","author":"","date":"enero 20, 2026","format":false,"excerpt":"Guatemala vive el segundo de los 30 d\u00edas de estado de sitio declarados por el presidente Bernardo Ar\u00e9valo tras el asesinato de nueve polic\u00edas. Desde hace varios a\u00f1os, el pa\u00eds centroamericano es escenario de las operaciones criminales de dos principales pandillas, la Mara Salvatrucha (MS-13) y Barrio 18, que a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452607,"url":"https:\/\/noticiasya.com\/aspen\/2024\/09\/12\/nayiv-bukele-criticos-dictadura-libres-trax\/","url_meta":{"origin":1447319,"position":4},"title":"Los cr\u00edticos denuncian que el gobierno de Nayib Bukele es una dictadura. Pero estas personas dicen que nunca se han sentido tan libres.","author":"","date":"septiembre 12, 2024","format":false,"excerpt":"San Salvador, El Salvador (CNN)--Durante d\u00e9cadas, las opciones de vida para muchos en El Salvador fueron sombr\u00edas: irse o morir. Apodada la \u201ccapital mundial del asesinato\u201d, hubo un promedio de un homicidio por hora a principios de 2016, en este pa\u00eds de solo 6 millones de habitantes, dos millones menos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458084,"url":"https:\/\/noticiasya.com\/aspen\/2025\/01\/31\/rubio-bukele-el-salvador-tren-de-aragua-trax\/","url_meta":{"origin":1447319,"position":5},"title":"Rubio y Bukele discutir\u00e1n el env\u00edo a El Salvador de presuntos pandilleros del Tren de Aragua","author":"","date":"enero 31, 2025","format":false,"excerpt":"El secretario de Estado de Estados Unidos, Marco Rubio, discutir\u00e1 la posibilidad de deportar a El Salvador a presuntos pandilleros del Tren de Aragua, en una reuni\u00f3n a celebrarse con el presidente de El Salvador, Nayib Bukele, seg\u00fan el enviado especial del Departamento de Estado para Am\u00e9rica Latina, Mauricio Claver-Carone.\u201cEstamos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1447319"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447319\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1447319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1447319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1447319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}