{"id":1447333,"date":"2024-03-25T09:03:38","date_gmt":"2024-03-25T16:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/"},"modified":"2024-03-25T09:03:38","modified_gmt":"2024-03-25T16:03:38","slug":"semana-santa-de-turismo-uruguay-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/","title":{"rendered":"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el &#171;santa&#187; a la semana clave de los cristianos"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; &#171;\u00bfQu\u00e9 planes ten\u00e9s para Semana Santa?&#187;, le pregunt\u00e9 d\u00edas atr\u00e1s a una amiga. &#171;Semana de Turismo, dir\u00e1s&#187;, me corrigi\u00f3 r\u00e1pidamente, en tono medio broma, medio serio. Y es que en Uruguay \u2013oficialmente\u2013 la semana clave del calendario de los cristianos qued\u00f3 despojada del adjetivo &#171;santa&#187; hace m\u00e1s de 100 a\u00f1os. En las leyes, es la Semana de Turismo. Y tambi\u00e9n se ha hecho de otros nombres populares, como Semana Criolla y hasta Semana de la Cerveza, dependiendo del lugar en el que te encuentres.<\/p>\n<p>No hay que confundirse: en Uruguay, el cristianismo \u2013la fe mayoritaria\u2013 celebra libremente la Semana Santa (aunque, eso s\u00ed, con una visibilidad menor a la de pa\u00edses como Espa\u00f1a). Y los huevos y los conejos de Pascua son ultrapopulares. Sin embargo, desde comienzos del siglo XX, las leyes no la reconocen a esa semana como tal, sino como la Semana de Turismo, que cada a\u00f1o coincide en fechas con la Semana Santa de los cristianos.<\/p>\n<p>El cambio se remonta a 1919, cuando se secularizaron los feriados religiosos: la Semana Santa pas\u00f3 a ser la Semana de Turismo, la Navidad se convirti\u00f3 en el D\u00eda de la Familia, al D\u00eda de Reyes se lo design\u00f3 como D\u00eda de los Ni\u00f1os y al D\u00eda de la Virgen como D\u00eda de las Playas.<\/p>\n<p>El cambio de los nombres de los feriados es apenas una de las m\u00faltiples acciones que llev\u00f3 adelante el pa\u00eds entre fines del siglo XIX y principios del siglo XX, para separar completamente al Estado de la Iglesia cat\u00f3lica, algo que ya hab\u00eda quedado garantizado en la Constituci\u00f3n de 1919. Se trata de un proceso tan singular en la regi\u00f3n que se ha convertido en caso de estudio para los acad\u00e9micos.<\/p>\n<p>De los cementerios a los feriados: \u00bfc\u00f3mo se deshizo Uruguay de los s\u00edmbolos religiosos?<\/p>\n<p>El primer hito significativo que marc\u00f3 este proceso de secularizaci\u00f3n del pa\u00eds sucedi\u00f3 tan pronto como en 1861, apenas unos 30 a\u00f1os despu\u00e9s de que el pa\u00eds aprobara su primera Constituci\u00f3n. Ese a\u00f1o, los cementerios, que estaban bajo el control de la Iglesia, pasaron a estar bajo la \u00f3rbita del Estado. De all\u00ed en adelante, hasta que en 1917 se aprob\u00f3 una constituci\u00f3n que separ\u00f3 formalmente a la Iglesia del Estado y garantiz\u00f3 la libertad de culto, la instituci\u00f3n cat\u00f3lica fue perdiendo cada vez m\u00e1s poder real y simb\u00f3lico.<\/p>\n<p>En 1885, por ejemplo, se volvi\u00f3 obligatorio el matrimonio civil antes del religioso. Y pocos a\u00f1os despu\u00e9s, en 1907, se aprob\u00f3 la ley de divorcio y se suprimieron las referencia a Dios y los evangelios en el juramento de los parlamentarios. Un a\u00f1o antes, se hab\u00eda definido remover todos los crucifijos de los hospitales p\u00fablicos.<\/p>\n<p>Uno de las decisiones m\u00e1s significativas lleg\u00f3 en 1909, cuando se suprimi\u00f3 la ense\u00f1anza de la religi\u00f3n en las escuelas p\u00fablicas. Jos\u00e9 Pedro Varela, el impulsor de la educaci\u00f3n laica, gratuita y obligatoria en el pa\u00eds, resum\u00eda a\u00f1os antes en estas palabras el esp\u00edritu que gui\u00f3 las decisiones de los pol\u00edticos de la \u00e9poca: \u201cNo profesemos ning\u00fan culto, pero tengamos la religi\u00f3n del porvenir, con la mirada fija en la estrella de la justicia, que nos alumbre; marchemos incesantemente preparando el establecimiento de la democracia, en la que el pueblo, convertido en sacerdote y en rey, tendr\u00e1 por gu\u00eda y por Dios a la libertad\u201d.<\/p>\n<p>El proceso, no obstante, no fue uniforme. Las primeras decisiones, seg\u00fan acad\u00e9micos como Roger Gaymonat, no necesariamente ten\u00edan como intenci\u00f3n volver laico al pa\u00eds. Sin embrago, a partir de 1885 s\u00ed se desat\u00f3 una \u201ctormenta anticlerical\u201d y desde los primeros a\u00f1os del siglo XX ya hubo una ofensiva de la mano del presidente que moldear\u00eda el Uruguay moderno: Jos\u00e9 Batlle y Ord\u00f3\u00f1ez, quien gobern\u00f3 entre 1903 y 1907, y 1911 y 1915.<\/p>\n<p>De Turismo, Criolla, de la Cerveza&#8230;<\/p>\n<p>Despojada de su santidad, la Semana de Turismo en Uruguay se hizo de m\u00faltiples nombres vinculados a las fiestas que se celebran a lo largo y ancho del peque\u00f1o pa\u00eds sudamericano. En Montevideo, por ejemplo, destaca la Semana Criolla, un evento organizado por el Gobierno de la ciudad que tiene como espect\u00e1culo central las populares y tambi\u00e9n pol\u00e9micas jineteadas, en las que los jinetes muestran su habilidad para mantenerse montando caballos salvajes por el mayor tiempo posible en un ruedo (una pr\u00e1ctica que ha sido fuertemente cuestionada por organizaciones de activistas por el bienestar animal).<\/p>\n<p>En Paysand\u00fa, departamento ubicado en el norte del pa\u00eds, la Semana Santa se ha convertido en Semana de la Cerveza. Hace m\u00e1s de 50 a\u00f1os, un trabajador de una industria cervecera del lugar propuso la organizaci\u00f3n de un festival que coincidiera con los festivos de Turismo y desde entonces la fiesta ha crecido. Adem\u00e1s de cerveza, por supuesto, hay ofertas de espect\u00e1culos, gastronom\u00eda y artesan\u00edas, entre otros.<\/p>\n<p>\u00bfEn qu\u00e9 creen los uruguayos?<\/p>\n<p>Una investigaci\u00f3n del Pew Research Center de 2014, que se sigue utilizando como referencia en estudios acad\u00e9micos, situaba a Uruguay en la c\u00faspide de pa\u00edses latinoamericanos con m\u00e1s personas sin filiaci\u00f3n religiosa: un 37 % en total, dividido entre aquellos que no tienen una religi\u00f3n particular (24 %), los ateos (10 %) y los que se definen como agn\u00f3sticos (3 %).<\/p>\n<p>El Pew califica a Uruguay como un caso \u201cat\u00edpico\u201d. \u201cEn ning\u00fan otro pa\u00eds de Latinoam\u00e9rica encuestado las personas sin filiaci\u00f3n religiosa llegan incluso al 20 %\u201d de la poblaci\u00f3n\u201d, afirma. Para ponerlo en contexto, en los pa\u00edses vecinos estos porcentajes ascienden a 11 %, en el caso de Argentina, y 8 %, en el caso de Brasil. En el otro extremo de la lista regional est\u00e1 Paraguay, donde apenas un 1 % entra en estas categor\u00edas.<\/p>\n<p>En cuanto a la filiaci\u00f3n religiosa de quienes s\u00ed se declaran como parte de una religi\u00f3n, el estudio del Pew Research Center registra un 42 % de cat\u00f3licos, 15 % de protestantes y 6 % pertenecientes a \u201cotras\u201d religiones.<\/p>\n<p>Nota del editor: este art\u00edculo fue publicado originalmente en 2023.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; &#171;\u00bfQu\u00e9 planes ten\u00e9s para Semana Santa?&#187;, le pregunt\u00e9 d\u00edas atr\u00e1s a una amiga. &#171;Semana de Turismo, dir\u00e1s&#187;, me corrigi\u00f3 r\u00e1pidamente, en tono medio broma, medio serio. Y es que en Uruguay \u2013oficialmente\u2013 la semana clave del calendario de los cristianos qued\u00f3 despojada del adjetivo &#171;santa&#187; hace m\u00e1s de 100 a\u00f1os. En las [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447333","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el &quot;santa&quot; a la semana clave de los cristianos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el &quot;santa&quot; a la semana clave de los cristianos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; &#171;\u00bfQu\u00e9 planes ten\u00e9s para Semana Santa?&#187;, le pregunt\u00e9 d\u00edas atr\u00e1s a una amiga. &#171;Semana de Turismo, dir\u00e1s&#187;, me corrigi\u00f3 r\u00e1pidamente, en tono medio broma, medio serio. Y es que en Uruguay \u2013oficialmente\u2013 la semana clave del calendario de los cristianos qued\u00f3 despojada del adjetivo &#171;santa&#187; hace m\u00e1s de 100 a\u00f1os. En las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-25T16:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el &#171;santa&#187; a la semana clave de los cristianos\",\"datePublished\":\"2024-03-25T16:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/\"},\"wordCount\":1083,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/\",\"name\":\"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el \\\"santa\\\" a la semana clave de los cristianos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-25T16:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el &#171;santa&#187; a la semana clave de los cristianos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el \"santa\" a la semana clave de los cristianos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el \"santa\" a la semana clave de los cristianos - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; &#171;\u00bfQu\u00e9 planes ten\u00e9s para Semana Santa?&#187;, le pregunt\u00e9 d\u00edas atr\u00e1s a una amiga. &#171;Semana de Turismo, dir\u00e1s&#187;, me corrigi\u00f3 r\u00e1pidamente, en tono medio broma, medio serio. Y es que en Uruguay \u2013oficialmente\u2013 la semana clave del calendario de los cristianos qued\u00f3 despojada del adjetivo &#171;santa&#187; hace m\u00e1s de 100 a\u00f1os. En las [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-25T16:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/"},"author":{"name":"","@id":""},"headline":"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el &#171;santa&#187; a la semana clave de los cristianos","datePublished":"2024-03-25T16:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/"},"wordCount":1083,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/","url":"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/","name":"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el \"santa\" a la semana clave de los cristianos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-25T16:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el &#171;santa&#187; a la semana clave de los cristianos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el &#171;santa&#187; a la semana clave de los cristianos","url":"http:\/\/noticiasya.com\/aspen\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2024\/03\/25\/semana-santa-de-turismo-uruguay-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-25T16:03:38Z","datePublished":"2024-03-25T16:03:38Z","dateModified":"2024-03-25T16:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\\u00eds que le quit\\u00f3 el &#171;santa&#187; a la semana clave de los cristianos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/25\\\/semana-santa-de-turismo-uruguay-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/25\\\/semana-santa-de-turismo-uruguay-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-25T16:03:38Z\",\"datePublished\":\"2024-03-25T16:03:38Z\",\"dateModified\":\"2024-03-25T16:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472710,"url":"https:\/\/noticiasya.com\/aspen\/2026\/03\/30\/semana-turismo-uruguay-que-santa-semana-orix\/","url_meta":{"origin":1447333,"position":0},"title":"Semana de Turismo, Criolla y hasta de la Cerveza: el pa\u00eds que le quit\u00f3 el &#171;santa&#187; a la semana clave de los cristianos","author":"","date":"marzo 30, 2026","format":false,"excerpt":"\u201c\u00bfQu\u00e9 planes ten\u00e9s para Semana Santa?\u201d, le pregunt\u00e9 d\u00edas atr\u00e1s a una amiga. \u201cSemana de Turismo, dir\u00e1s\u201d, me corrigi\u00f3 r\u00e1pidamente, en tono medio broma, medio serio.Y es que en Uruguay \u2013oficialmente\u2013 la semana clave del calendario de los cristianos qued\u00f3 despojada del adjetivo \u201csanta\u201d hace m\u00e1s de 100 a\u00f1os. En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447360,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/26\/5-cosas-26-marzo-corina-yoris-orix\/","url_meta":{"origin":1447333,"position":1},"title":"Las 5 cosas que debes saber este 26 de marzo: Corina Yoris: \u201cSon horas muy oscuras\u201d","author":"","date":"marzo 26, 2024","format":false,"excerpt":"As\u00ed comparecieron sospechosos del ataque en Rusia: \u00bffueron torturados? Parte nueva caravana migrante con 2.000 personas desde sur de M\u00e9xico. Dani Alves sale en libertad provisional con fianza.\u00a0Esto es lo que debes saber para comenzar el d\u00eda.\u00a0Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo1. Corina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447335,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/25\/semana-santa-pascua-significa-que-es-orix\/","url_meta":{"origin":1447333,"position":2},"title":"\u00bfQu\u00e9 significan los ramos, los huevos de pascua y por qu\u00e9 se hace ayuno en Semana Santa? Algunas claves de la semana mayor de los cristianos","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN) -- D\u00e9mosle un vistazo a la tradici\u00f3n de Pascua y de Semana Santa.El domingo de Pascua, los cristianos celebran la resurrecci\u00f3n de Jesucristo al tercer d\u00eda despu\u00e9s de su crucifixi\u00f3n. Tambi\u00e9n marca el final del per\u00edodo de penitencia de 40 d\u00edas llamado Cuaresma. La Pascua es considerada como una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472697,"url":"https:\/\/noticiasya.com\/aspen\/2026\/03\/30\/que-significa-semana-santa-ramos-pascua-ayuno-orix\/","url_meta":{"origin":1447333,"position":3},"title":"\u00bfQu\u00e9 significan los ramos, los huevos de pascua y por qu\u00e9 se hace ayuno en Semana Santa?","author":"","date":"marzo 30, 2026","format":false,"excerpt":"D\u00e9mosle un vistazo a la tradici\u00f3n de Pascua y de Semana Santa.El domingo de Pascua, los cristianos celebran la resurrecci\u00f3n de Jesucristo al tercer d\u00eda despu\u00e9s de su crucifixi\u00f3n. Tambi\u00e9n marca el final del per\u00edodo de penitencia de 40 d\u00edas llamado Cuaresma. La Pascua es considerada como una de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461362,"url":"https:\/\/noticiasya.com\/aspen\/2025\/04\/18\/semana-santa-catolica-que-es-trax\/","url_meta":{"origin":1447333,"position":4},"title":"Viernes Santo para los cristianos: qu\u00e9 se conmemora en Semana Santa","author":"","date":"abril 18, 2025","format":false,"excerpt":"En Semana Santa, los cristianos conmemoran la pasi\u00f3n, muerte y resurrecci\u00f3n de Jesucristo al tercer d\u00eda despu\u00e9s de su crucifixi\u00f3n. Tambi\u00e9n marca el final del per\u00edodo de penitencia de 40 d\u00edas llamado Cuaresma. La Pascua se considera la \u00e9poca m\u00e1s importante del a\u00f1o cristiano.Para los cristianos, el Domingo de Ramos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456877,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/23\/uruguay-navidad-historia-orix\/","url_meta":{"origin":1447333,"position":5},"title":"Ni China ni Corea del Norte: la historia del pa\u00eds de Am\u00e9rica Latina que &#171;elimin\u00f3&#187; la Navidad del calendario oficial hace m\u00e1s de 100 a\u00f1os","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Las listas de los pa\u00edses que no reconocen la celebraci\u00f3n de la Navidad \u2014o incluso la proh\u00edben\u2014 suelen estar dominadas por reg\u00edmenes autoritarios o naciones que profesan de manera oficial religiones diferentes a la cat\u00f3lica. Sin embargo, hay un pa\u00eds laico de Latinoam\u00e9rica que hace m\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1447333"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447333\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1447333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1447333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1447333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}