{"id":1447398,"date":"2024-03-26T16:03:51","date_gmt":"2024-03-26T23:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/"},"modified":"2024-03-26T16:03:51","modified_gmt":"2024-03-26T23:03:51","slug":"lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/","title":{"rendered":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?"},"content":{"rendered":"<p>(CNN) &#8212; Durante los \u00faltimos d\u00edas, cientos de documentos de una demanda relacionada con Jeffrey Epstein se hicieron p\u00fablicos por primera vez. El conjunto m\u00e1s reciente de esos documentos se revel\u00f3 este martes.<\/p>\n<p>El alcance total de la supuesta actividad criminal de Jeffrey Epstein sigue envuelto en un velo de misterio despu\u00e9s de que el delincuente sexual convicto muriera en la c\u00e1rcel antes de poder enfrentar un juicio por cargos federales de tr\u00e1fico sexual.<\/p>\n<p>CNN revis\u00f3 los documentos reci\u00e9n revelados, que se publicaron poco a poco a partir del mi\u00e9rcoles pasado y sumaban m\u00e1s de 4.500 p\u00e1ginas. Los archivos inclu\u00edan los nombres y la informaci\u00f3n de muchas decenas de personas que fueron editados previamente, incluidos algunos de los acusadores de Epstein, destacados empresarios, pol\u00edticos y m\u00e1s.<\/p>\n<p>As\u00ed era la isla de Jeffrey Epstein 1:53<\/p>\n<p>La inclusi\u00f3n de un individuo en los documentos no indica que esa persona haya sido acusada de ning\u00fan delito, y gran parte de la informaci\u00f3n encontrada en los documentos ha sido reportada en varios medios de comunicaci\u00f3n en los a\u00f1os transcurridos desde que fueron sellados originalmente.<\/p>\n<p>Sin embargo, los documentos reci\u00e9n revelados tambi\u00e9n dejaron informaci\u00f3n por fuera.<\/p>\n<p>\u00bfEn qu\u00e9 consiste el caso de Jeffrey Epstein? Pederastia, tr\u00e1fico de menores y nombres famosos<\/p>\n<p>As\u00ed era la isla de Jeffrey Epstein 1:53<\/p>\n<p>No hab\u00eda una lista completa de nombres sin editar<\/p>\n<p>Durante su vida, Epstein, un financiero bien relacionado, se mov\u00eda en c\u00edrculos de \u00e9lite, code\u00e1ndose con l\u00edderes mundiales y empresarios prominentes, incluso despu\u00e9s de declararse culpable en 2008 de solicitar una prostituta menor de edad y registrarse como delincuente sexual.<\/p>\n<p>La cuesti\u00f3n de qui\u00e9n del acaudalado c\u00edrculo \u00edntimo de Epstein conoc\u00eda \u2014o participaba en\u2014 sus presuntas actividades ilegales ha sido fuente de ira e inter\u00e9s entre los defensores de las v\u00edctimas, los funcionarios encargados de hacer cumplir la ley y los miembros del p\u00fablico en los a\u00f1os posteriores a que el alcance de los delitos de Epstein se haya hecho m\u00e1s conocido.<\/p>\n<p>Los documentos forman parte de una demanda civil por difamaci\u00f3n presentada en 2015 por Virginia Roberts Giuffre contra la exnovia de Epstein, Ghislaine Maxwell, alegando que Epstein abus\u00f3 sexualmente de ella cuando era menor de edad con la ayuda de Maxwell.<\/p>\n<p>Giuffre y Maxwell llegaron a un acuerdo sobre la demanda en 2017, y la mayor\u00eda de los archivos judiciales fueron desclasificados en 2019, un d\u00eda antes de que Epstein se suicidara en la c\u00e1rcel. Maxwell fue declarada culpable de tr\u00e1fico sexual en 2021 y condenada a 20 a\u00f1os de prisi\u00f3n.<\/p>\n<p>Sin embargo, cientos de documentos siguieron sin estar disponibles para el p\u00fablico hasta que el juez que supervisa el caso orden\u00f3 que muchos de ellos fueran revelados y no editados en una orden del 18 de diciembre.<\/p>\n<p>Y aunque muchos documentos fueron desclasificados en su totalidad, otros todav\u00eda conten\u00edan p\u00e1ginas editadas, lo que significa que todav\u00eda hay un mont\u00f3n de inc\u00f3gnitas sobre el caso.<\/p>\n<p>Publican la cuarta ronda de documentos de una demanda relacionada con Jeffrey Epstein<\/p>\n<p>\u00bfQui\u00e9nes aparecen en los documentos del caso Epstein? 4:20<\/p>\n<p>Las conexiones de alto poder de Epstein<\/p>\n<p>Muchas de las personas reveladas en los documentos ya ten\u00edan v\u00ednculos conocidos con Epstein, incluidos los ex presidentes Bill Clinton y Donald Trump, el pr\u00edncipe Andr\u00e9s de Gran Breta\u00f1a, el exgobernador de Nuevo M\u00e9xico Bill Richardson, el cazatalentos de modelos franc\u00e9s Jean-Luc Brunel y Leslie Wexner, fundadora de Victoria&#8217;s Secret, quienes negaron haber actuado mal en relaci\u00f3n con Epstein.<\/p>\n<p>Trump y Clinton no est\u00e1n acusados directamente de irregularidades en los documentos, y en una declaraci\u00f3n no sellada de 2016, Giuffre neg\u00f3 tener conocimiento de que participaran en alg\u00fan delito de abuso sexual.<\/p>\n<p>Sobre Trump, Giuffre dijo que \u201cnunca vio ni fue testigo de la participaci\u00f3n de Donald Trump en esos actos, pero \u00bfestaba \u00e9l en la casa de Jeffrey Epstein? He o\u00eddo que s\u00ed, pero no lo he visto personalmente, as\u00ed que no lo s\u00e9\u201d.<\/p>\n<p>Cuando se le pregunt\u00f3 a principios de esta semana sobre el nombre de Trump que aparece en los documentos recientemente revelados, un portavoz de Trump reaccion\u00f3 atacando a los medios. En el pasado, Trump trat\u00f3 de distanciarse de Epstein.<\/p>\n<p>El nombre de Clinton fue mencionado muchas veces en los documentos judiciales no sellados y en las declaraciones de varias personas que trabajaron para Epstein, incluidas acusaciones de que a Clinton \u201cle gustan las j\u00f3venes\u201d y que el expresidente supuestamente presion\u00f3 a Vanity Fair para que no escribiera sobre el financiero ca\u00eddo en desgracia. El exeditor de Vanity Fair, Graydon Carter, que supervisaba la revista en ese momento, dijo a CNN la semana pasada que la supuesta presi\u00f3n de Clinton &#171;categ\u00f3ricamente no ocurri\u00f3&#187;.<\/p>\n<p>Giuffre relat\u00f3 haber conocido a Clinton m\u00e1s de una vez, incluso en una cena en la isla de Epstein en 2002, pero dijo que no tuvo ninguna relaci\u00f3n sexual con \u00e9l.<\/p>\n<p>\u201cNo tuve que hacer nada con Bill Clinton, \u00e9l nunca tuvo una relaci\u00f3n sexual conmigo. Nunca lo he visto involucrado sexualmente con nadie m\u00e1s\u201d, dijo.<\/p>\n<p>Sin embargo, Giuffre dijo que cre\u00eda que Clinton fue testigo del abuso sexual de menores \u201cporque sab\u00eda cu\u00e1l era mi prop\u00f3sito all\u00ed para Jeffrey y visit\u00f3 la isla de Jeffrey\u201d.<\/p>\n<p>En una transcripci\u00f3n de la declaraci\u00f3n de Jeffrey Epstein de 2016 hecha p\u00fablica este martes, Epstein no respondi\u00f3 ninguna pregunta sustancial, invocando su derecho de la Quinta Enmienda cientos de veces durante las m\u00e1s de cinco horas que permaneci\u00f3 sentado para ser interrogado.<\/p>\n<p>Epstein no respondi\u00f3 a decenas de preguntas sobre su relaci\u00f3n con Bill Clinton y si el expresidente hab\u00eda estado en la isla privada del financiero.<\/p>\n<p>&#171;Cuando Bill Clinton lleg\u00f3 a su isla, iba acompa\u00f1ado de dos mujeres j\u00f3venes que ten\u00edan aproximadamente 18 a\u00f1os, \u00bfverdad?&#187;, le pregunt\u00f3 el abogado Paul Cassell a Epstein.<\/p>\n<p>&#171;Quinta&#187;, respondi\u00f3 Epstein.<\/p>\n<p>Un portavoz de Clinton confirm\u00f3 en 2019 que el expresidente hab\u00eda volado en el avi\u00f3n privado de Epstein, pero dijo que Clinton no sab\u00eda nada de los \u201cterribles cr\u00edmenes\u201d del financiero y que nunca hab\u00eda visitado la isla Little St. James ni las residencias de Epstein en Nuevo M\u00e9xico o Florida.<\/p>\n<p>Un portavoz de Clinton reiter\u00f3 este martes esa negaci\u00f3n de 2019 y le dijo a CNN que nunca estuvo en la isla de Epstein. El portavoz tambi\u00e9n se\u00f1al\u00f3 que varias personas testificaron que Clinton no visit\u00f3 la isla. La semana pasada, el portavoz se\u00f1al\u00f3 que \u201chan pasado casi 20 a\u00f1os desde la \u00faltima vez que el presidente Clinton tuvo contacto con Epstein\u201d.<\/p>\n<p>Caso Jeffrey Epstein: las claves de los documentos y nombres revelados<\/p>\n<p>Desclasifican documentos vinculados al juicio de Jeffrey Epstein 0:36<\/p>\n<p>Las t\u00e1cticas de Epstein<\/p>\n<p>Los documentos tambi\u00e9n inclu\u00edan algunas acusaciones inquietantes.<\/p>\n<p>En un extracto no sellado de una declaraci\u00f3n de Nadia Marcinkova, asociada de Epstein, un abogado le pregunt\u00f3 a Marcinkova si estaba \u201ccon Jeffrey Epstein en su cumplea\u00f1os cuando uno de sus amigos le envi\u00f3 12 \u2013 lo siento, tres ni\u00f1as de 12 a\u00f1os con el prop\u00f3sito de que Jeffrey Epstein abusara sexualmente de ellas.<\/p>\n<p>Luego pregunt\u00f3 si \u201cestas tres ni\u00f1as de 12 a\u00f1os eran de Francia. \u00bfSe los envi\u00f3 el d\u00eda de su cumplea\u00f1os Jean Luc Brunel o alguien m\u00e1s?&#187;.<\/p>\n<p>Brunel, un buscador de modelos franc\u00e9s, muri\u00f3 en una celda en 2022 mientras era investigado por las autoridades francesas por sus v\u00ednculos con Epstein.<\/p>\n<p>Marcinkova invoc\u00f3 la Quinta Enmienda y no respondi\u00f3 a la pregunta. Giuffre tambi\u00e9n cont\u00f3 la historia de ni\u00f1as de 12 a\u00f1os que fueron enviadas a Epstein en sus propias declaraciones judiciales.<\/p>\n<p>Los documentos tambi\u00e9n inclu\u00edan informes policiales de las autoridades locales de Palm Beach que investigaron a Epstein durante a\u00f1os. Las acusaciones fueron ampliamente difundidas, pero los documentos recientemente revelados detallan las entrevistas de un detective con docenas de ni\u00f1as que ilustran un patr\u00f3n de los m\u00e9todos de Epstein para conseguir ni\u00f1as vulnerables para abusar de ellas.<\/p>\n<p>En una declaraci\u00f3n no sellada, el detective de Palm Beach, Joseph Recarey, expuso un proceso que, seg\u00fan dijo, Epstein y Maxwell usaban para encontrar y reclutar ni\u00f1as para &#171;realizar masajes y trabajar en la casa de Epstein&#187;. Recarey testific\u00f3 que estos masajes se volver\u00edan sexuales.<\/p>\n<p>Otra acusadora, cuyo nombre permanece oculto en los documentos abiertos, dijo que ten\u00eda entre 15 y 17 a\u00f1os cuando le pagaron por darle masajes a Epstein, que pens\u00f3 que no implicar\u00edan actividad sexual.<\/p>\n<p>&#171;Estaba all\u00ed y, de repente, me pas\u00f3 algo horrible&#187;, dijo sobre su experiencia con Epstein, y agreg\u00f3 que \u201cno se supon\u00eda que fuera sexual, pero lo fue&#187;.<\/p>\n<p>Alessi, exempleada de Epstein, testific\u00f3 que una v\u00edctima menor de 18 a\u00f1os ocasionalmente llevaba a su madre a la casa de Epstein.<\/p>\n<p>En t\u00e9rminos de pago, \u201ctodo el mundo recib\u00eda 100 d\u00f3lares la hora\u201d, dijo Alessi.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Durante los \u00faltimos d\u00edas, cientos de documentos de una demanda relacionada con Jeffrey Epstein se hicieron p\u00fablicos por primera vez. El conjunto m\u00e1s reciente de esos documentos se revel\u00f3 este martes. El alcance total de la supuesta actividad criminal de Jeffrey Epstein sigue envuelto en un velo de misterio despu\u00e9s de que el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447398","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Durante los \u00faltimos d\u00edas, cientos de documentos de una demanda relacionada con Jeffrey Epstein se hicieron p\u00fablicos por primera vez. El conjunto m\u00e1s reciente de esos documentos se revel\u00f3 este martes. El alcance total de la supuesta actividad criminal de Jeffrey Epstein sigue envuelto en un velo de misterio despu\u00e9s de que el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-26T23:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?\",\"datePublished\":\"2024-03-26T23:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/\"},\"wordCount\":1562,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/\",\"name\":\"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-26T23:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein? - Noticias","og_description":"(CNN) &#8212; Durante los \u00faltimos d\u00edas, cientos de documentos de una demanda relacionada con Jeffrey Epstein se hicieron p\u00fablicos por primera vez. El conjunto m\u00e1s reciente de esos documentos se revel\u00f3 este martes. El alcance total de la supuesta actividad criminal de Jeffrey Epstein sigue envuelto en un velo de misterio despu\u00e9s de que el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-26T23:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?","datePublished":"2024-03-26T23:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/"},"wordCount":1562,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/","name":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-26T23:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?","url":"http:\/\/noticiasya.com\/aspen\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-26T23:03:51Z","datePublished":"2024-03-26T23:03:51Z","dateModified":"2024-03-26T23:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 revelaron (y qu\\u00e9 no) los documentos sobre Jeffrey Epstein?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/26\\\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/03\\\/26\\\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-26T23:03:51Z\",\"datePublished\":\"2024-03-26T23:03:51Z\",\"dateModified\":\"2024-03-26T23:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443507,"url":"https:\/\/noticiasya.com\/aspen\/2024\/01\/11\/que-revelaron-y-que-no-los-documentos-sobre-jeffrey-epstein\/","url_meta":{"origin":1447398,"position":0},"title":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?","author":"","date":"enero 11, 2024","format":false,"excerpt":"(CNN) -- Durante los \u00faltimos d\u00edas, cientos de documentos de una demanda relacionada con Jeffrey Epstein se hicieron p\u00fablicos por primera vez. El conjunto m\u00e1s reciente de esos documentos se revel\u00f3 este martes.El alcance total de la supuesta actividad criminal de Jeffrey Epstein sigue envuelto en un velo de misterio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443217,"url":"https:\/\/noticiasya.com\/aspen\/2024\/01\/05\/publican-la-tercera-ronda-de-documentos-relacionados-a-jeffrey-epstein\/","url_meta":{"origin":1447398,"position":1},"title":"Publican la tercera ronda de documentos relacionados a Jeffrey Epstein","author":"","date":"enero 5, 2024","format":false,"excerpt":"(CNN) --\u00a0La tercera ronda de documentos de una demanda relacionada con Jeffrey Epstein, el ped\u00f3filo convicto que muri\u00f3 en la c\u00e1rcel antes de poder enfrentar un juicio por cargos federales de tr\u00e1fico sexual, se hizo p\u00fablica este viernes.La publicaci\u00f3n de este viernes le sigue a cientos de p\u00e1ginas de documentos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443219,"url":"https:\/\/noticiasya.com\/aspen\/2024\/01\/05\/publican-la-tercera-ronda-de-documentos-relacionados-a-jeffrey-epstein-2\/","url_meta":{"origin":1447398,"position":2},"title":"Publican la tercera ronda de documentos relacionados a Jeffrey Epstein","author":"","date":"enero 5, 2024","format":false,"excerpt":"(CNN) --\u00a0La tercera ronda de documentos de una demanda relacionada con Jeffrey Epstein, el ped\u00f3filo convicto que muri\u00f3 en la c\u00e1rcel antes de poder enfrentar un juicio por cargos federales de tr\u00e1fico sexual, se hizo p\u00fablica este viernes.La publicaci\u00f3n de este viernes ten\u00eda m\u00e1s de mil p\u00e1ginas, y llega despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447397,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/26\/jeffrey-epstein-quinta-ronda-documentos-trax\/","url_meta":{"origin":1447398,"position":3},"title":"Publican la quinta ronda de documentos relacionados con Jeffrey Epstein","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Se hizo p\u00fablica este martes la quinta ronda de documentos de una demanda relacionada con Jeffrey Epstein, el delincuente sexual convicto que muri\u00f3 en la c\u00e1rcel antes de poder enfrentar un juicio por cargos federales de tr\u00e1fico sexual.La publicaci\u00f3n sigue a miles de p\u00e1ginas de documentos ya divulgados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447394,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/26\/jeffrey-epstein-revelan-mas-documentos-demanda-trax\/","url_meta":{"origin":1447398,"position":4},"title":"En documentos revelados sobre Jeffrey Epstein, un detective describe el reclutamiento de decenas de ni\u00f1as","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Otros 19 documentos de una demanda relacionada a Jeffrey Epstein, pederasta convicto que muri\u00f3 en prisi\u00f3n antes de enfrentar un juicio por\u00a0 tr\u00e1fico sexual, se hicieron p\u00fablicos este jueves.Caso Jeffrey Epstein: las claves de los documentos y nombres reveladosSe trata del segundo lote de documentos que se revelan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443187,"url":"https:\/\/noticiasya.com\/aspen\/2024\/01\/05\/en-documentos-revelados-sobre-jeffrey-epstein-un-detective-describe-el-reclutamiento-de-decenas-de-ninas\/","url_meta":{"origin":1447398,"position":5},"title":"En documentos revelados sobre Jeffrey Epstein, un detective describe el reclutamiento de decenas de ni\u00f1as","author":"","date":"enero 5, 2024","format":false,"excerpt":"(CNN) -- Otros 19 documentos de una demanda relacionada a Jeffrey Epstein, ped\u00f3filo convicto que muri\u00f3 en prisi\u00f3n antes de enfrentar un juicio por\u00a0 tr\u00e1fico sexual, se hicieron p\u00fablicos este jueves.Caso Jeffrey Epstein: las claves de los documentos y nombres reveladosSe trata del segundo lote de documentos que se revelan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1447398"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1447398\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1447398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1447398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1447398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}