{"id":1448784,"date":"2024-05-02T15:03:41","date_gmt":"2024-05-02T22:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/"},"modified":"2024-05-02T15:03:41","modified_gmt":"2024-05-02T22:03:41","slug":"servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/","title":{"rendered":"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos"},"content":{"rendered":"<p>(CNN) &#8212; El Servicio de Impuestos Internos de EE.UU. (IRS, por sus siglas en ingl\u00e9s) detall\u00f3 este jueves sus planes para aumentar significativamente las tasas de auditor\u00eda de los contribuyentes ricos y las grandes corporaciones, utilizando fondos proporcionados por la Ley de Reducci\u00f3n de la Inflaci\u00f3n respaldada por los dem\u00f3cratas que se aprob\u00f3 en 2022.<\/p>\n<p>Se espera que la tasa de auditor\u00eda de los contribuyentes que ganan m\u00e1s de US$ 10 millones aumente en un 50%, pasando del 11% en 2019 al 16,5% en 2026.<\/p>\n<p>El IRS tambi\u00e9n planea triplicar las tasas de auditor\u00eda de las grandes empresas con activos superiores a US$ 250 millones, as\u00ed como multiplicar por diez las tasas de auditor\u00eda de las sociedades comerciales con activos superiores a US$ 10 millones durante el per\u00edodo de siete a\u00f1os.<\/p>\n<p>A pesar de los aumentos previstos, los \u00edndices de auditor\u00eda no superar\u00e1n los alcanzados en 2010 porque el n\u00famero de declaraciones de grandes empresas, sociedades y personas adineradas ha crecido y se ha vuelto m\u00e1s complejo, seg\u00fan el IRS.<\/p>\n<p>\u00bfQu\u00e9 pasa si no declaraste tus impuestos en EE.UU. el 15 de abril o si lo hiciste tarde?<\/p>\n<p>El fisco est\u00e1 utilizando la afluencia de dinero proporcionada por la Ley de Reducci\u00f3n de la Inflaci\u00f3n para modernizar la agencia, mejorar los servicios para los contribuyentes y recaudar m\u00e1s ingresos fiscales de aquellos que no han estado pagando lo que deben. Pero los republicanos, preocupados por la posibilidad de que las peque\u00f1as empresas y la clase media se conviertan en objetivo de los auditores del IRS, han hecho varios esfuerzos para reducir la financiaci\u00f3n de la agencia.<\/p>\n<p>El comisionado del IRS, Danny Werfel, ha dicho en repetidas ocasiones que la agencia se ha comprometido a proteger a los hogares estadounidenses que ganan menos de US$ 400.000 al a\u00f1o de un aumento en las tasas de auditor\u00eda. Espec\u00edficamente, las tasas de auditor\u00eda de esos estadounidenses no exceder\u00e1n lo que fueron en 2018, un a\u00f1o r\u00e9cord m\u00ednimo, dijo este jueves en una llamada con periodistas.<\/p>\n<p>&#171;Como he dicho una y otra vez, no hay una nueva ola de auditor\u00edas para los contribuyentes de ingresos medios y bajos. Eso no est\u00e1 en nuestros planes de ninguna manera&#187;, dijo Werfel.<\/p>\n<p>Nuevas auditor\u00edas con m\u00e1s personal e inteligencia artificial<\/p>\n<p>Debido a a\u00f1os de escasez de fondos, las auditor\u00edas del IRS a grandes empresas y multimillonarios cayeron entre 2010 y 2021. La plantilla total de las oficinas de cumplimiento de la agencia se redujo un 30% durante ese periodo.<\/p>\n<p>Para aumentar las auditor\u00edas, el IRS est\u00e1 contratando a los contadores, ingenieros, economistas, cient\u00edficos de datos, abogados y expertos fiscales necesarios para llevar a cabo auditor\u00edas complejas.<\/p>\n<p>Desde 2022, el IRS ha a\u00f1adido alrededor de 11.000 puestos a tiempo completo, incluyendo el personal que trabaja en las auditor\u00edas, as\u00ed como los encargados de servicio al cliente y otros puestos de trabajo. La agencia planea agregar otros 14.000 puestos a tiempo completo con fondos de la Ley de Reducci\u00f3n de la Inflaci\u00f3n para el a\u00f1o fiscal 2029, dijo Werfel este jueves.<\/p>\n<p>\u00bfCu\u00e1ndo empieza el IRS a mandar los reembolsos de impuestos en 2024?<\/p>\n<p>Algunas de las nuevas contrataciones sustituir\u00e1n a personas que se jubilen o abandonen el servicio. Los aumentos llevar\u00edan el n\u00famero total de empleados del IRS a 102.500, agreg\u00f3 Werfel.<\/p>\n<p>El IRS tambi\u00e9n est\u00e1 invirtiendo dinero en la mejora de su tecnolog\u00eda. La agencia est\u00e1 utilizando inteligencia artificial para ayudar a seleccionar qu\u00e9 empresas auditar.<\/p>\n<p>Los esfuerzos de la agencia han recuperado hasta ahora US$520 millones de millonarios que no declararon sus impuestos o no pagaron su deuda tributaria.<\/p>\n<p>Cambios en los servicios al contribuyente<br \/>\nEl IRS tambi\u00e9n est\u00e1 utilizando los fondos de la Ley de Reducci\u00f3n de la Inflaci\u00f3n para modernizar los servicios al contribuyente. Como resultado, este a\u00f1o la agencia ha podido responder a un mill\u00f3n de llamadas m\u00e1s que en la temporada de impuestos anterior.<\/p>\n<p>La agencia tambi\u00e9n atendi\u00f3 a m\u00e1s personas en persona en los Centros de Asistencia al Contribuyente de todo el pa\u00eds.<\/p>\n<p>Se est\u00e1n realizando esfuerzos para digitalizar los 1.000 millones de documentos en papel de la agencia y se han introducido mejoras en la herramienta en l\u00ednea conocida como &#187; Where&#8217;s My Refund&#187; (\u00bfD\u00f3nde est\u00e1 mi reembolso?) para que los contribuyentes puedan obtener m\u00e1s informaci\u00f3n en tiempo real sobre el estado de sus declaraciones de impuestos.<\/p>\n<p>A principios de este a\u00f1o, el IRS puso en marcha una versi\u00f3n piloto de su propio servicio de declaraci\u00f3n de la renta que permit\u00eda a los estadounidenses presentar sus declaraciones de forma gratuita directamente al IRS. M\u00e1s de 140.000 personas utilizaron el programa, conocido como Direct File, para presentar con \u00e9xito sus declaraciones de la renta este a\u00f1o. El IRS a\u00fan no ha decidido si continuar\u00e1 con el proyecto piloto el a\u00f1o que viene.<\/p>\n<p>Batallas por la financiaci\u00f3n<\/p>\n<p>La Ley de Reducci\u00f3n de la Inflaci\u00f3n, que se aprob\u00f3 sin ning\u00fan voto republicano, aprob\u00f3 unos US$ 80.000 millones para el IRS en un periodo de 10 a\u00f1os.<\/p>\n<p>Pero los republicanos han hecho varios esfuerzos por recuperar el dinero. En junio pasado, en un acuerdo sobre el techo de la deuda para evitar el impago, los dem\u00f3cratas aceptaron rescindir US$ 20.000 millones de los fondos de la Ley de Reducci\u00f3n de la Inflaci\u00f3n.<\/p>\n<p>En enero, los dem\u00f3cratas concedieron una aceleraci\u00f3n del recorte de 20.000 millones en un esfuerzo por aprobar una ley de gasto federal para todo el a\u00f1o a tiempo de evitar un cierre parcial del Gobierno.<\/p>\n<p>Werfel advirti\u00f3 este jueves de lo que est\u00e1 en riesgo si se producen nuevos recortes en la financiaci\u00f3n del IRS.<\/p>\n<p>Bajo la actual estructura de financiaci\u00f3n, la agencia espera quedarse sin dinero de la Ley de Reducci\u00f3n de la Inflaci\u00f3n asignado espec\u00edficamente para la modernizaci\u00f3n de sus sistemas para el a\u00f1o fiscal 2026. Eso significar\u00eda que el IRS no podr\u00eda mantener su nivel actual de servicio telef\u00f3nico y \u00e9ste retroceder\u00eda hasta el punto de que 7 de cada 10 llamadas de contribuyentes no ser\u00edan atendidas, dijo la agencia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El Servicio de Impuestos Internos de EE.UU. (IRS, por sus siglas en ingl\u00e9s) detall\u00f3 este jueves sus planes para aumentar significativamente las tasas de auditor\u00eda de los contribuyentes ricos y las grandes corporaciones, utilizando fondos proporcionados por la Ley de Reducci\u00f3n de la Inflaci\u00f3n respaldada por los dem\u00f3cratas que se aprob\u00f3 en 2022. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448784","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El Servicio de Impuestos Internos de EE.UU. (IRS, por sus siglas en ingl\u00e9s) detall\u00f3 este jueves sus planes para aumentar significativamente las tasas de auditor\u00eda de los contribuyentes ricos y las grandes corporaciones, utilizando fondos proporcionados por la Ley de Reducci\u00f3n de la Inflaci\u00f3n respaldada por los dem\u00f3cratas que se aprob\u00f3 en 2022. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T22:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos\",\"datePublished\":\"2024-05-02T22:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/\"},\"wordCount\":1087,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/\",\"name\":\"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-02T22:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos - Noticias","og_description":"(CNN) &#8212; El Servicio de Impuestos Internos de EE.UU. (IRS, por sus siglas en ingl\u00e9s) detall\u00f3 este jueves sus planes para aumentar significativamente las tasas de auditor\u00eda de los contribuyentes ricos y las grandes corporaciones, utilizando fondos proporcionados por la Ley de Reducci\u00f3n de la Inflaci\u00f3n respaldada por los dem\u00f3cratas que se aprob\u00f3 en 2022. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-02T22:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/"},"author":{"name":"","@id":""},"headline":"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos","datePublished":"2024-05-02T22:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/"},"wordCount":1087,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/","name":"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-02T22:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El IRS planea aumentar en un 50% el n\u00famero de auditor\u00edas a los contribuyentes ricos","url":"http:\/\/noticiasya.com\/aspen\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2024\/05\/02\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-02T22:03:41Z","datePublished":"2024-05-02T22:03:41Z","dateModified":"2024-05-02T22:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El IRS planea aumentar en un 50% el n\\u00famero de auditor\\u00edas a los contribuyentes ricos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/05\\\/02\\\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/05\\\/02\\\/servicio-impuestos-aumenta-auditorias-contribuyentes-ricos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-02T22:03:41Z\",\"datePublished\":\"2024-05-02T22:03:41Z\",\"dateModified\":\"2024-05-02T22:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449876,"url":"https:\/\/noticiasya.com\/aspen\/2024\/05\/30\/irs-permanente-programa-presentacion-impuestos-trax\/","url_meta":{"origin":1448784,"position":0},"title":"El IRS planea hacer permanente su programa gratuito para la presentaci\u00f3n de impuestos en EE.UU.","author":"","date":"mayo 30, 2024","format":false,"excerpt":"(CNN) -- El Servicio de Impuestos Internos de EE.UU. (IRS, por sus siglas en ingl\u00e9s) dijo este jueves que continuar\u00e1 y ampliar\u00e1 su programa gratuito de presentaci\u00f3n de impuestos en 2025.A principios de este a\u00f1o se lanz\u00f3 una versi\u00f3n piloto del programa online, conocido como Direct File. Proporciona orientaci\u00f3n paso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461641,"url":"https:\/\/noticiasya.com\/aspen\/2025\/04\/25\/cambios-irs-que-tan-probable-auditado-trax\/","url_meta":{"origin":1448784,"position":1},"title":"Con todos los cambios que ha habido en el IRS, \u00bfqu\u00e9 tan probable es que seas auditado?","author":"","date":"abril 25, 2025","format":false,"excerpt":"Nadie quiere ser auditado por el Servicio de Impuestos Internos (IRS, por sus siglas en ingl\u00e9s). Y, de hecho, muy pocos contribuyentes estadounidenses lo han sido en los \u00faltimos a\u00f1os.Menos del 1 % de todas las declaraciones presentadas entre 2013 y 2021 hab\u00edan sido auditadas al final del a\u00f1o fiscal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456722,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/18\/tramos-impuesto-federal-sobre-renta-ee-uu-2025-orix\/","url_meta":{"origin":1448784,"position":2},"title":"Estos son los rangos para el impuesto federal sobre la renta en EE.UU. para el a\u00f1o tributario 2025","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"El Servicio de Impuestos Internos de Estados Unidos (IRS, por sus siglas en ingl\u00e9s) tiene definidos los nuevos rangos fiscales del impuesto sobre la renta ajustados a la inflaci\u00f3n, as\u00ed como los importes de la deducci\u00f3n est\u00e1ndar que entrar\u00e1n en vigor para el a\u00f1o tributario 2025.Se trata de los n\u00fameros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471139,"url":"https:\/\/noticiasya.com\/aspen\/2026\/02\/12\/usted-podria-elegible-servicios-gratuitos-presentacion-impuestos-trax\/","url_meta":{"origin":1448784,"position":3},"title":"Usted podr\u00eda ser elegible para servicios gratuitos de preparaci\u00f3n y presentaci\u00f3n de impuestos en EE.UU.","author":"","date":"febrero 12, 2026","format":false,"excerpt":"En lo que respecta a sus declaraciones de impuestos federales, decenas de millones de hogares estadounidenses pagan por la preparaci\u00f3n y presentaci\u00f3n de sus impuestos. Sin embargo, muchos podr\u00edan calificar para programas gratis aprobados por el IRS.Entonces \u00bfpor qu\u00e9 no los utilizan?Una raz\u00f3n podr\u00eda ser la complejidad del c\u00f3digo tributario.\u201cNuestra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465273,"url":"https:\/\/noticiasya.com\/aspen\/2025\/08\/08\/irs-comparte-datos-contribuyentes-inmigrantes-indocumentados-trax\/","url_meta":{"origin":1448784,"position":4},"title":"IRS comparte datos confidenciales de contribuyentes con autoridades de inmigraci\u00f3n para encontrar inmigrantes indocumentados","author":"","date":"agosto 8, 2025","format":false,"excerpt":"El Servicio de Impuestos Internos (IRS, por sus siglas en ingl\u00e9s) comenz\u00f3 a compartir datos confidenciales de los contribuyentes esta semana con las autoridades de inmigraci\u00f3n que buscan inmigrantes indocumentados, seg\u00fan dos fuentes familiarizadas con el asunto.Como parte del masivo impulso de deportaci\u00f3n del presidente Donald Trump, el Departamento del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460659,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/31\/isr-licencia-funcionarios-ti-intercambio-datos-inmigracion-trax\/","url_meta":{"origin":1448784,"position":5},"title":"El IRS pone bajo licencia a altos funcionarios de TI que &#171;bloquear\u00edan&#187; intercambio de datos con autoridades de inmigraci\u00f3n","author":"","date":"marzo 31, 2025","format":false,"excerpt":"Hasta 50 profesionales s\u00e9nior de Tecnolog\u00edas de Informaci\u00f3n (TI) en el Servicio de Impuestos Internos (IRS, por sus siglas en ingl\u00e9s), incluidos algunos de los principales expertos en ciberseguridad de la agencia, fueron puestos en licencia administrativa el viernes mientras la administraci\u00f3n de Trump finaliza planes controvertidos para compartir datos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1448784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1448784"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1448784\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1448784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1448784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1448784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}