{"id":1448797,"date":"2024-05-02T16:03:49","date_gmt":"2024-05-02T23:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/"},"modified":"2024-05-02T16:03:49","modified_gmt":"2024-05-02T23:03:49","slug":"arizona-firma-ley-deroga-prohibicion-aborto-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/","title":{"rendered":"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864"},"content":{"rendered":"<p>(CNN) &#8212; La gobernadora de Arizona, Katie Hobbs, firm\u00f3 este jueves una legislaci\u00f3n que deroga la prohibici\u00f3n casi total del aborto en el estado desde hace 160 a\u00f1os, que sienta las bases para que una restricci\u00f3n de 15 semanas siga siendo ley.<\/p>\n<p>La gobernadora dem\u00f3crata firm\u00f3 el proyecto de ley un d\u00eda despu\u00e9s de que fuera aprobado en el Senado controlado por el Partido Republicano, donde dos republicanos se unieron a los 14 dem\u00f3cratas de la C\u00e1mara para impulsar la medida. El debate de una hora sobre el proyecto de ley se volvi\u00f3 pol\u00e9mico cuando los republicanos criticaron a los dos desertores, a los dem\u00f3cratas y a una posible iniciativa electoral de oto\u00f1o que consagrar\u00eda el derecho al aborto en la constituci\u00f3n estatal.<\/p>\n<p>En una ceremonia de firma este jueves, Hobbs y otros l\u00edderes dem\u00f3cratas enmarcaron la derogaci\u00f3n como el primer paso en una lucha m\u00e1s amplia por los derechos reproductivos.<\/p>\n<p>Esta es la\u00a0reacci\u00f3n\u00a0de Trump ante la prohibici\u00f3n del aborto en Arizona<\/p>\n<p>\u201cHoy no debemos descansar\u201d, dijo la gobernadora. &#171;Debemos volver a comprometernos a proteger la autonom\u00eda corporal de las mujeres, su capacidad para tomar sus propias decisiones sobre atenci\u00f3n m\u00e9dica y su capacidad para controlar sus vidas&#187;.<\/p>\n<p>La derogaci\u00f3n es una victoria para los defensores del derecho al aborto, que durante a\u00f1os han intentado revocar la ley de 1864 que prohib\u00eda el aborto en todas las etapas del embarazo, excepto para salvar la vida de la madre, y amenazaba a los proveedores con penas de prisi\u00f3n de dos a cinco a\u00f1os.<\/p>\n<p>Pero el futuro inmediato del acceso al aborto en el estado no est\u00e1 claro.<\/p>\n<p>El fallo de la Corte Suprema de Arizona del 9 de abril, que determin\u00f3 que el estado ten\u00eda que cumplir con la ley centenaria, no iba a ser ejecutable hasta el 27 de junio como muy pronto, seg\u00fan la fiscal general dem\u00f3crata de Arizona, Kris Mayes.<\/p>\n<p>Mientras tanto, la medida de derogaci\u00f3n no entrar\u00e1 en vigor hasta 90 d\u00edas despu\u00e9s de que la Legislatura de Arizona levante su sesi\u00f3n a finales de este a\u00f1o, lo que significa que la prohibici\u00f3n del aborto de la \u00e9poca de la Guerra Civil por este tema podr\u00eda entrar en vigor por alg\u00fan tiempo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La gobernadora de Arizona, Katie Hobbs, firm\u00f3 este jueves una legislaci\u00f3n que deroga la prohibici\u00f3n casi total del aborto en el estado desde hace 160 a\u00f1os, que sienta las bases para que una restricci\u00f3n de 15 semanas siga siendo ley. La gobernadora dem\u00f3crata firm\u00f3 el proyecto de ley un d\u00eda despu\u00e9s de que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448797","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La gobernadora de Arizona, Katie Hobbs, firm\u00f3 este jueves una legislaci\u00f3n que deroga la prohibici\u00f3n casi total del aborto en el estado desde hace 160 a\u00f1os, que sienta las bases para que una restricci\u00f3n de 15 semanas siga siendo ley. La gobernadora dem\u00f3crata firm\u00f3 el proyecto de ley un d\u00eda despu\u00e9s de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T23:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864\",\"datePublished\":\"2024-05-02T23:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/\"},\"wordCount\":431,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/\",\"name\":\"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-02T23:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864 - Noticias","og_description":"(CNN) &#8212; La gobernadora de Arizona, Katie Hobbs, firm\u00f3 este jueves una legislaci\u00f3n que deroga la prohibici\u00f3n casi total del aborto en el estado desde hace 160 a\u00f1os, que sienta las bases para que una restricci\u00f3n de 15 semanas siga siendo ley. La gobernadora dem\u00f3crata firm\u00f3 el proyecto de ley un d\u00eda despu\u00e9s de que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-02T23:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/"},"author":{"name":"","@id":""},"headline":"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864","datePublished":"2024-05-02T23:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/"},"wordCount":431,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/","name":"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-02T23:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864","url":"http:\/\/noticiasya.com\/aspen\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-02T23:03:49Z","datePublished":"2024-05-02T23:03:49Z","dateModified":"2024-05-02T23:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\\u00f3n del aborto establecida en 1864\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/05\\\/02\\\/arizona-firma-ley-deroga-prohibicion-aborto-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/05\\\/02\\\/arizona-firma-ley-deroga-prohibicion-aborto-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-02T23:03:49Z\",\"datePublished\":\"2024-05-02T23:03:49Z\",\"dateModified\":\"2024-05-02T23:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447905,"url":"https:\/\/noticiasya.com\/aspen\/2024\/04\/09\/corte-suprema-arizona-dictamina-estado-adherirse-ley-hace-mas-100-anios-prohibe-casi-todos-abortos-trax\/","url_meta":{"origin":1448797,"position":0},"title":"Corte Suprema de Arizona determina que el estado debe seguir una ley de 123 a\u00f1os que proh\u00edbe el aborto en casi todos los casos","author":"","date":"abril 9, 2024","format":false,"excerpt":"(CNN) -- En una decisi\u00f3n hist\u00f3rica, la Corte Suprema de Arizona determin\u00f3 este martes que el estado debe adherirse a una ley de 123 a\u00f1os de antig\u00fcedad que proh\u00edbe los abortos en su totalidad excepto en los casos en que \"sea necesario para salvar\" la vida de una persona embarazada.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451811,"url":"https:\/\/noticiasya.com\/aspen\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/","url_meta":{"origin":1448797,"position":1},"title":"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre","author":"","date":"agosto 13, 2024","format":false,"excerpt":"(CNN) -- La propuesta de enmienda constitucional de Arizona que establecer\u00eda un \"derecho fundamental al aborto\" obtuvo suficientes firmas para figurar en la boleta electoral del estado.La Ley de Acceso al Aborto de Arizona recibi\u00f3 577.971 firmas certificadas, seg\u00fan confirm\u00f3 este lunes la oficina del secretario de Estado de Arizona,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447926,"url":"https:\/\/noticiasya.com\/aspen\/2024\/04\/10\/analisis-trump-aborto-arizona-elecciones-2024-trax\/","url_meta":{"origin":1448797,"position":2},"title":"AN\u00c1LISIS | Arizona demuestra que dejar el aborto en manos de los estados en EE.UU. no aliviar\u00e1 el problema que significa para Trump","author":"","date":"abril 10, 2024","format":false,"excerpt":"(CNN) -- Solo hizo falta un d\u00eda \u2014y una sorprendente sentencia judicial que revive una prohibici\u00f3n del aborto de la \u00e9poca de la Guerra Civil en un vital estado indeciso\u2014 para desmentir la afirmaci\u00f3n que hizo Donald Trump de que la cuesti\u00f3n del aborto hab\u00eda quedado \"pr\u00e1cticamente fuera de juego\"\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448019,"url":"https:\/\/noticiasya.com\/aspen\/2024\/04\/12\/iowa-ley-ilegaliza-algunos-inmigrantes-indocumentados-trax\/","url_meta":{"origin":1448797,"position":3},"title":"Gobernadora de Iowa firma proyecto de ley que ilegaliza la estad\u00eda de algunos inmigrantes indocumentados en el estado","author":"","date":"abril 12, 2024","format":false,"excerpt":"(CNN) -- Iowa sigui\u00f3 el ejemplo de Texas cuando su gobernadora promulg\u00f3 un proyecto de ley esta semana que permite a los agentes del orden arrestar a algunos inmigrantes indocumentados.La gobernadora republicana de Iowa, Kim Reynolds, promulg\u00f3 este mi\u00e9rcoles un proyecto de ley que tipifica como delito estar en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455124,"url":"https:\/\/noticiasya.com\/aspen\/2024\/10\/15\/trump-declaraciones-fiv-aborto-trax\/","url_meta":{"origin":1448797,"position":4},"title":"Trump se declara &#171;padre de la FIV&#187; en un evento con una audiencia exclusivamente femenina","author":"","date":"octubre 15, 2024","format":false,"excerpt":"(CNN) -- Donald Trump se declar\u00f3 este martes \"padre de la fecundaci\u00f3n in vitro\", un tratamiento de fertilidad que se vio amenazado tras la decisi\u00f3n de la Corte Suprema de Justicia de 2022 de anular el caso Roe contra Wade.No est\u00e1 claro qu\u00e9 quiso decir exactamente el expresidente cuando hizo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464632,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/17\/camara-representantes-historica-ley-criptomonedas-trump-trax\/","url_meta":{"origin":1448797,"position":5},"title":"C\u00e1mara de Representantes aprueba hist\u00f3rica ley de criptomonedas y la env\u00eda a Trump tras una breve revuelta de conservadores","author":"","date":"julio 17, 2025","format":false,"excerpt":"La C\u00e1mara de Representantes de EE.UU. aprob\u00f3 este jueves una importante legislaci\u00f3n bipartidista que busca regular un tipo de criptomoneda conocida como stablecoins, y envi\u00f3 el proyecto de ley al escritorio del presidente para su firma.Los legisladores dieron la aprobaci\u00f3n final a la Ley GENIUS, la primera legislaci\u00f3n de su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1448797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1448797"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1448797\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1448797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1448797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1448797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}