{"id":1448843,"date":"2024-05-03T18:03:50","date_gmt":"2024-05-04T01:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/"},"modified":"2024-05-03T18:03:50","modified_gmt":"2024-05-04T01:03:50","slug":"migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/","title":{"rendered":"Cientos de migrantes quedan varados en tren de carga conocido como &#171;La Bestia&#187;, al norte de M\u00e9xico"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Cientos de migrantes se encuentran varados a bordo de un tren de carga de la red conocida como &#171;La Bestia&#187; en Ceballos, en el estado mexicano de Durango, desde hace cinco d\u00edas, luego de que el operador detuviera el curso de la m\u00e1quina y abandonara a ni\u00f1os, mujeres, embarazadas y hombres, desconcertados y con pocas provisiones, seg\u00fan denunciaron varios de los extranjeros a CNN.<\/p>\n<p>Por a\u00f1os, cientos de migrantes han arriesgado sus vidas intentando llegar a Estados Unidos encima de los vagones de esta red de trenes, conocida como tambi\u00e9n como el &#171;tren de la muerte&#187;, por los peligros a los que se enfrentan los extranjeros en su largo viaje desde el sur de M\u00e9xico hacia el norte.<\/p>\n<p>&#171;No somos delincuentes, venimos buscando el sue\u00f1o americano&#187;, dice migrante que viaja en &#171;la Bestia&#187;<\/p>\n<p>De acuerdo con algunos testimonios de migrantes que viajaban en el tren, partieron el lunes pasado del municipio de G\u00f3mez Palacio, Durango, con rumbo al fronterizo estado mexicano de Chihuahua cuando el conductor detuvo la m\u00e1quina y huy\u00f3.<\/p>\n<p>\u201cSupuestamente lo que hab\u00eda pasado es que da\u00f1aron una parte de adelante, no s\u00e9 si las ventanas, los vidrios los hab\u00edan da\u00f1ado los mismos migrantes, no s\u00e9 por qu\u00e9. Por eso dicen que nos han castigado as\u00ed\u201d, dijo a CNN Juan Carlos Tumba, migrante ecuatoriano.<\/p>\n<p>La angustia crece cada d\u00eda entre los migrantes varados en Ceballos, municipio de Mapim\u00ed, ya que entre ellos viajan muchos ni\u00f1os y mujeres embarazadas. Algunos se niegan a bajar del tren por temor a ser deportados.<\/p>\n<p>\u201cYa casi sin nada de comida, sin agua, nos tienen al borde de la locura a todos. No hallamos qu\u00e9 hacer\u201d, dijo a CNN Kimberli Andreina Murina, con ocho meses de embarazo y quien es acompa\u00f1ada por su esposo.<\/p>\n<p>Migrantes a bordo del tren conocido como &#171;La Bestia&#187;, cerca de la frontera entre M\u00e9xico y Estados Unidos. (Foto de John Moore\/Getty Images)<\/p>\n<p>De acuerdo con Francis Mar Carmona, otra migrante que tambi\u00e9n viajaba en el tren junto con su hija y esposo, lo \u00fanico que quieren es llegar a la frontera, sin embargo, la ayuda no llega.<\/p>\n<p>\u201cNo sabemos hasta cu\u00e1ndo vaya a arrancar este tren, ac\u00e1 esperando en la lucha, ya no aguantamos el fr\u00edo, el calor, lo ni\u00f1os se desesperan, queremos llegar\u201d, dijo Carmona, que lleva en la traves\u00eda seis meses.<\/p>\n<p>Los migrantes varados en Ceballos refirieron que, hasta este viernes, las autoridades locales no han tenido ning\u00fan acercamiento con ellos para conocer su condici\u00f3n o brindar el apoyo a las personas m\u00e1s vulnerables.<\/p>\n<p>CNN ha intentado contactar al gobierno municipal de Mapim\u00ed y al estatal, pero sin respuesta hasta el momento. Tambi\u00e9n ha solicitado al Instituto Nacional de Migraci\u00f3n de M\u00e9xico (INM) m\u00e1s informaci\u00f3n sobre este caso, pero no hemos obtenido respuesta.<\/p>\n<p>Hallan a migrantes &#171;abandonados&#187; en Veracruz<\/p>\n<p>A la par de este grupo de migrantes varados en Durango, el INM inform\u00f3 este jueves que sus agentes hallaron a 407 personas extranjeras \u201cabandonadas\u201d, repartidas en autobuses en el estado de Veracruz.<\/p>\n<p>En un comunicado publicado en su cuenta de X, el instituto precis\u00f3 que los autobuses fueron encontrados el martes pasado en la autopista Minatitl\u00e1n-Acayucan.<\/p>\n<p>Encuentran a unos 400 migrantes en autobuses abandonados en una carretera de M\u00e9xico<\/p>\n<p>Este lunes, el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, inform\u00f3 durante su conferencia de prensa matutina, que sostuvo una llamada con su hom\u00f3logo de Estados Unidos, Joe Biden, en la que conversaron principalmente sobre temas migratorios.<\/p>\n<p>Los dos l\u00edderes discutieron sobre \u201cc\u00f3mo gestionar eficazmente la migraci\u00f3n hemisf\u00e9rica, fortalecer la eficiencia operativa en la frontera compartida y as\u00ed mejorar la seguridad y prosperidad de los ciudadanos de ambos pa\u00edses&#187;, seg\u00fan un comunicado emitido en conjunto.<\/p>\n<p>El mandatario mexicano dijo este jueves que la migraci\u00f3n es un tema relevante a nivel pol\u00edtico porque este a\u00f1o M\u00e9xico y Estados Unidos tendr\u00e1n elecciones tras un flujo migratorio r\u00e9cord en 2023.<\/p>\n<p>L\u00f3pez Obrador insisti\u00f3 en que la migraci\u00f3n irregular ha disminuido en m\u00e1s de 50% en la frontera norte de M\u00e9xico con Estados Unidos, que reportaba unos 12.000 migrantes sin documentos en diciembre y en abril 5.812, seg\u00fan datos exhibidos por el presidente mexicano, en su habitual conferencia matutina este jueves.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Cientos de migrantes se encuentran varados a bordo de un tren de carga de la red conocida como &#171;La Bestia&#187; en Ceballos, en el estado mexicano de Durango, desde hace cinco d\u00edas, luego de que el operador detuviera el curso de la m\u00e1quina y abandonara a ni\u00f1os, mujeres, embarazadas y hombres, desconcertados [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448843","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cientos de migrantes quedan varados en tren de carga conocido como &quot;La Bestia&quot;, al norte de M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cientos de migrantes quedan varados en tren de carga conocido como &quot;La Bestia&quot;, al norte de M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Cientos de migrantes se encuentran varados a bordo de un tren de carga de la red conocida como &#171;La Bestia&#187; en Ceballos, en el estado mexicano de Durango, desde hace cinco d\u00edas, luego de que el operador detuviera el curso de la m\u00e1quina y abandonara a ni\u00f1os, mujeres, embarazadas y hombres, desconcertados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-04T01:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cientos de migrantes quedan varados en tren de carga conocido como &#171;La Bestia&#187;, al norte de M\u00e9xico\",\"datePublished\":\"2024-05-04T01:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/\"},\"wordCount\":777,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/\",\"name\":\"Cientos de migrantes quedan varados en tren de carga conocido como \\\"La Bestia\\\", al norte de M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-04T01:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cientos de migrantes quedan varados en tren de carga conocido como &#171;La Bestia&#187;, al norte de M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cientos de migrantes quedan varados en tren de carga conocido como \"La Bestia\", al norte de M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Cientos de migrantes quedan varados en tren de carga conocido como \"La Bestia\", al norte de M\u00e9xico - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Cientos de migrantes se encuentran varados a bordo de un tren de carga de la red conocida como &#171;La Bestia&#187; en Ceballos, en el estado mexicano de Durango, desde hace cinco d\u00edas, luego de que el operador detuviera el curso de la m\u00e1quina y abandonara a ni\u00f1os, mujeres, embarazadas y hombres, desconcertados [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-04T01:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/"},"author":{"name":"","@id":""},"headline":"Cientos de migrantes quedan varados en tren de carga conocido como &#171;La Bestia&#187;, al norte de M\u00e9xico","datePublished":"2024-05-04T01:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/"},"wordCount":777,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/","name":"Cientos de migrantes quedan varados en tren de carga conocido como \"La Bestia\", al norte de M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-04T01:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cientos de migrantes quedan varados en tren de carga conocido como &#171;La Bestia&#187;, al norte de M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cientos de migrantes quedan varados en tren de carga conocido como &#171;La Bestia&#187;, al norte de M\u00e9xico","url":"http:\/\/noticiasya.com\/aspen\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2024\/05\/03\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-04T01:03:50Z","datePublished":"2024-05-04T01:03:50Z","dateModified":"2024-05-04T01:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cientos de migrantes quedan varados en tren de carga conocido como &#171;La Bestia&#187;, al norte de M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/05\\\/03\\\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2024\\\/05\\\/03\\\/migrantes-varados-tren-de-carga-la-bestia-norte-mexico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-04T01:03:50Z\",\"datePublished\":\"2024-05-04T01:03:50Z\",\"dateModified\":\"2024-05-04T01:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1460235,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/21\/migrantes-deportados-el-salvador-investigacion-trump-trax\/","url_meta":{"origin":1448843,"position":0},"title":"Los migrantes deportados a El Salvador pasaron por un riguroso proceso de investigaci\u00f3n, afirma Trump","author":"","date":"marzo 21, 2025","format":false,"excerpt":"El presidente Donald Trump descart\u00f3 este viernes las afirmaciones de que hay personas indebidamente enviadas a El Salvador, tras invocar la semana pasada una amplia autoridad en tiempos de guerra para identificar y deportar a cientos de migrantes bajo la Ley de Enemigos Extranjeros.\u201cBueno, me dijeron que pasaron por un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459989,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/16\/trump-deporta-ley-enemigos-extranjeros-juez-trax\/","url_meta":{"origin":1448843,"position":1},"title":"Gobierno de Trump deporta a cientos de personas bajo la Ley de Enemigos Extranjeros a pesar de prohibici\u00f3n de juez","author":"","date":"marzo 16, 2025","format":false,"excerpt":"El Gobierno de Trump anunci\u00f3 este domingo que cientos de personas fueron deportadas del pa\u00eds despu\u00e9s de que el presidente Donald Trump invocara la Ley de Enemigos Extranjeros, una amplia facultad para tiempos de guerra que solo se ha utilizado en tres ocasiones anteriores, para acelerar las deportaciones de migrantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470304,"url":"https:\/\/noticiasya.com\/aspen\/2026\/01\/20\/varados-frontera-trump-peticionarios-asilo-orix\/","url_meta":{"origin":1448843,"position":2},"title":"Varados en la frontera: el d\u00eda que el regreso de Trump a la Casa Blanca cambi\u00f3 el panorama de miles de peticionarios de asilo","author":"","date":"enero 20, 2026","format":false,"excerpt":"La madrugada del 20 de enero de 2025, en Ciudad Ju\u00e1rez, Chihuahua, al norte de M\u00e9xico, el clima congelante no deten\u00eda al grupo de peticionarios de asilo formados en el puente fronterizo que conecta con El Paso, Texas. Ese era uno de los puntos donde ser\u00edan procesados para ingresar legalmente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457743,"url":"https:\/\/noticiasya.com\/aspen\/2025\/01\/22\/juarez-migrantes-frontera-mexico-eeuu-app-cbp-trax\/","url_meta":{"origin":1448843,"position":3},"title":"Varados en la frontera: migrantes quedan en el limbo luego de que Trump cancel\u00f3 la aplicaci\u00f3n CBP One de citas en la frontera","author":"","date":"enero 22, 2025","format":false,"excerpt":"Cuando Jos\u00e9 Guillermo Cabrera lleg\u00f3 el fin de semana pasado a Ciudad Ju\u00e1rez, una ciudad a lo largo de la frontera entre M\u00e9xico y Estados Unidos, estaba lleno de esperanza. \u201cMe sent\u00eda como todo migrante, emocionado, despu\u00e9s de tanto tiempo esperando\u201d, dijo Cabrera, de 33 a\u00f1os, a CNN.Ciudad Ju\u00e1rez estaba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460020,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/17\/tren-de-aragua-que-es-lider-miembros-donde-opera-orix\/","url_meta":{"origin":1448843,"position":4},"title":"\u00bfQu\u00e9 es el Tren de Aragua, qui\u00e9n lo lidera, cu\u00e1ntos miembros tiene y d\u00f3nde opera?","author":"","date":"marzo 17, 2025","format":false,"excerpt":"La banda delincuencial Tren de Aragua est\u00e1 en el centro de atenci\u00f3n en medio de la ola de redadas antiinmigratorias y deportaciones del Gobierno de Donald Trump en Estados Unidos. El grupo delincuencial fue declarado en febrero por el Departamento de Estado de EE.UU. como una organizaci\u00f3n terrorista y supuestos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462327,"url":"https:\/\/noticiasya.com\/aspen\/2025\/05\/14\/ley-enemigos-extranjeros-trump-deportar-tren-de-aragua-orix\/","url_meta":{"origin":1448843,"position":5},"title":"Jueza avala que Trump use Ley de Enemigos Extranjeros para deportar a venezolanos ligados al Tren de Aragua","author":"","date":"mayo 14, 2025","format":false,"excerpt":"Una jueza federal en Pensilvania dio una victoria para el presidente Donald Trump, quien busca usar una amplia autoridad en tiempos de guerra para acelerar las deportaciones de inmigrantes acusados \u200b\u200bde pertenecer a la pandilla venezolana Tren de Aragua.La jueza federal de distrito Stephanie Haines, designada por Trump, y quien\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1448843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1448843"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1448843\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1448843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1448843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1448843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}