{"id":1464915,"date":"2025-07-28T07:03:39","date_gmt":"2025-07-28T14:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/"},"modified":"2025-07-28T07:03:39","modified_gmt":"2025-07-28T14:03:39","slug":"bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/","title":{"rendered":"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas"},"content":{"rendered":"<p>Sacar cad\u00e1veres de migrantes y sus hijos de las embravecidas aguas del r\u00edo Grande a lo largo de la frontera entre Estados Unidos y M\u00e9xico es algo a lo que un grupo de bomberos mexicanos de la ciudad fronteriza de Ciudad Acu\u00f1a est\u00e1 acostumbrado.<\/p>\n<p>Las t\u00e9cnicas perfeccionadas durante las b\u00fasquedas de rutina, como introducir un tubo de PVC en un mont\u00f3n de escombros para sentir el olor de la descomposici\u00f3n de los cuerpos, resultaron invaluables despu\u00e9s de las devastadoras inundaciones del 4 de julio en el centro de Texas, a lo largo del r\u00edo Guadalupe.<\/p>\n<p>Cristopher Herrera y Jorge Fuentes, miembros del grupo de rescate Fundaci\u00f3n 911, fueron de los primeros en llegar para ayudar en las labores de b\u00fasqueda y rescate. Su grupo est\u00e1 capacitado para situaciones especializadas de b\u00fasqueda y rescate a lo largo del r\u00edo Grande, un r\u00edo que cruzan migrantes de Centroam\u00e9rica y Sudam\u00e9rica con la esperanza de comenzar una nueva vida en Estados Unidos.<\/p>\n<p>El grupo de rescate intervino para ayudar en Texas a pesar del dif\u00edcil clima inmigratorio en Estados Unidos, marcado por vuelos de deportaci\u00f3n, redadas del ICE y casos judiciales que se desarrollan en todo el pa\u00eds.<\/p>\n<p>\u201cNo se trata de pol\u00edtica ni de fronteras ni nada por el estilo\u201d, declar\u00f3 Fuentes a CNN. \u201cSe trata de personas que ayudan a otras, y de una comunidad que ayuda a otra comunidad. La pol\u00edtica [\u2026] no entra en juego cuando hay vidas humanas en juego\u201d.<\/p>\n<p>Herrera ten\u00eda un d\u00eda libre el 4 de julio hasta que se conoci\u00f3 la magnitud de las inundaciones en Texas. Cuando su grupo de bomberos del Departamento de Bomberos de Ciudad de Acu\u00f1a se enter\u00f3 de lo que estaba sucediendo en el condado de Kerr, inmediatamente comenzaron a coordinar planes para ayudar en su grupo de WhatsApp.<\/p>\n<p>Aproximadamente un mes antes de la catastr\u00f3fica inundaci\u00f3n, algunos bomberos de la Fundaci\u00f3n 911 realizaron ejercicios de entrenamiento con el Departamento de Bomberos Voluntarios de Mountain Home, en el centro de Texas. Cuando empezaron a comprender la magnitud de la devastaci\u00f3n, uno de los l\u00edderes de la Fundaci\u00f3n 911 llam\u00f3 al Departamento de Bomberos de Texas para preguntar si necesitaban ayuda.<\/p>\n<p>A la ma\u00f1ana siguiente, el Departamento de Bomberos mexicano comenz\u00f3 a reunir equipos, veh\u00edculos y suministros, dijo Fuentes.<\/p>\n<p>Los bomberos de Acu\u00f1a pudieron ingresar al pa\u00eds legalmente, pero tres de ellos necesitaron un permiso provisional para trabajar como empleados de ayuda humanitaria, dijo Herrera.<\/p>\n<p>Menos de dos d\u00edas despu\u00e9s de la crecida del r\u00edo Guadalupe, estos bomberos mexicanos llegaron a Texas para ayudar en las labores de rescate y recuperaci\u00f3n. Estaban compuestos por dos grupos: Fundaci\u00f3n 911 y bomberos del Departamento de Bomberos de Ciudad de Acu\u00f1a.<\/p>\n<p>Fundaci\u00f3n 911 es un grupo sin fines de lucro de bomberos unidos para reunir donativos de materiales y equipo de estaciones de bomberos y otros puestos de respuesta a emergencias para entregarlos a diferentes cuerpos en M\u00e9xico que no cuentan con el dinero para adquirirlos.<\/p>\n<p>Muchos miembros del grupo ten\u00edan familiares en la regi\u00f3n, lo que les ayud\u00f3 a comprender el nivel y la escala de las inundaciones, dijo Herrera.<\/p>\n<p>Al menos 136 personas murieron en el centro de Texas durante las hist\u00f3ricas inundaciones del 4 de julio. Entre ellas, se encontraban ni\u00f1as del campamento Mystic, a orillas del r\u00edo Guadalupe. Esa noche cay\u00f3 en la zona una lluvia equivalente a la de todo un verano, y sumi\u00f3 la zona en el caos.<\/p>\n<p>Cruzar las aguas turbulentas del r\u00edo Guadalupe tras la inundaci\u00f3n represent\u00f3 un nuevo reto para el grupo de bomberos de M\u00e9xico. Los bomberos de la Fundaci\u00f3n 911 trabajaron en colaboraci\u00f3n con el Departamento de Bomberos Voluntarios de Mountain Home en todo el condado de Kerr, buscando se\u00f1ales de vida a lo largo del r\u00edo Guadalupe.<\/p>\n<p>\u201cCuando vimos la situaci\u00f3n en el condado de Kerr, fue totalmente diferente. Es un desastre natural, una emergencia\u201d, dijo Herrera. \u201cFue completamente distinto a un rescate en el r\u00edo Bravo\u201d, dijo en referencia al nombre del r\u00edo en M\u00e9xico.<\/p>\n<p>A diferencia del r\u00edo Grande, que tiene importantes secciones de corrientes furiosas, adem\u00e1s de aguas estancadas, los bomberos tuvieron que enfrentarse a un r\u00edo lleno de \u00e1rboles ca\u00eddos, autom\u00f3viles, casas y otras formas de escombros, dijo Fuentes.<\/p>\n<p>\u201cLa cantidad de agua que baj\u00f3 por el r\u00edo Guadalupe fue completamente desproporcionada a lo que ten\u00edamos previsto\u201d, dijo Herrera. \u201cNo solo se trat\u00f3 de una b\u00fasqueda en el agua, sino tambi\u00e9n de la remoci\u00f3n de escombros y un poco de investigaci\u00f3n\u201d.<\/p>\n<p>El r\u00edo Guadalupe puso a prueba el conocimiento y la experiencia de estos bomberos con t\u00e1cticas de b\u00fasqueda y rescate, coment\u00f3.<\/p>\n<p>Las cuadrillas permanecieron seis d\u00edas en el pa\u00eds, y la mayor\u00eda de las operaciones de b\u00fasqueda y rescate se llevaron a cabo durante los primeros d\u00edas de la inundaci\u00f3n. A medida que las operaciones de rescate se reduc\u00edan, la prioridad se centr\u00f3 en una misi\u00f3n de recuperaci\u00f3n a favor del viento a lo largo del r\u00edo.<\/p>\n<p>Mientras buscaban cad\u00e1veres, el grupo de bomberos comenz\u00f3 a utilizar una t\u00e9cnica que usa a lo largo del r\u00edo Grande, donde introducen un tubo de PVC entre los escombros para ver si pueden oler un cuerpo en descomposici\u00f3n, dijo Fuentes.<\/p>\n<p>La decisi\u00f3n de ayudar en las inundaciones de Texas fue personal para Fuentes, quien se puso en el lugar de los padres preocupados por el paradero y la seguridad de sus hijos perdidos en las inundaciones.<\/p>\n<p>Como padre de dos hijos, Fuentes enfatiz\u00f3 que hubiera querido toda la ayuda posible en las misiones de b\u00fasqueda y rescate.<\/p>\n<p>Cuando Ismael Aldaba, presidente de la Fundaci\u00f3n 911, llam\u00f3, \u201cno lo dud\u00e9\u201d, dijo Fuentes. \u201cDecid\u00ed ir inmediatamente a ayudar\u201d.<\/p>\n<p>La devastaci\u00f3n y los recuerdos de todo lo que se perdi\u00f3 tambi\u00e9n impactaron a Aldaba.<\/p>\n<p>\u201cMuchos de los desaf\u00edos que hemos visto aqu\u00ed nunca los hab\u00edamos visto en ninguna emergencia anterior, no de esta magnitud\u201d, declar\u00f3 Aldaba a CNN. \u201cEs asombroso ver objetos personales, ropa, atascados a entre 6 y 7,5 metros, en los \u00e1rboles\u201d.<\/p>\n<p>Una de las principales motivaciones del grupo de bomberos durante sus misiones de recuperaci\u00f3n fue localizar a las ni\u00f1as desaparecidas del campamento Mystic durante sus seis d\u00edas a lo largo del Guadalupe, dijo Herrera.<\/p>\n<p>\u201cSi hubiera sido mi hija, estar\u00eda aqu\u00ed d\u00eda, tarde y noche hasta encontrarla\u201d, dijo Herrera.<\/p>\n<p>Ayudar en Texas con estos esfuerzos de b\u00fasqueda y rescate fue una experiencia inolvidable, especialmente por la calidez de los lugare\u00f1os, dijo Herrera.<\/p>\n<p>La comunidad latina del condado de Kerr recibi\u00f3 a las tripulaciones mexicanas con los brazos abiertos, ofreci\u00e9ndoles casas, lugares para dormir y ba\u00f1arse, dijo Herrera. Cada d\u00eda, los lugare\u00f1os les daban comida, agua fresca y postres.<\/p>\n<p>Nos llevaron con una persona que nos cort\u00f3 el cabello gratis, nos llevaron con enfermeras que nos pusieron sueros y otras cosas. Tuvimos una persona que nos dio un masaje para relajarnos debido al alto estr\u00e9s que ten\u00edamos por la inundaci\u00f3n, dijo.<\/p>\n<p>\u201cPensar que toda la comunidad estaba agradecida de que estuvi\u00e9ramos ah\u00ed, y no solamente la comunidad latina, sino toda la gente que llegaba a dondequiera que par\u00e1bamos, nos agradec\u00edan\u201d, dijo Herrera.<\/p>\n<p>Los Departamentos de Bomberos de todo el estado de diferentes condados y ciudades, incluidos Dallas, Arlington, Plano y Corpus Christi, extendieron sus manos para recibirlos personalmente, dijo Herrera.<\/p>\n<p>El grupo mexicano intercambi\u00f3 t\u00e9cnicas y experiencias mientras trabajaba con el Departamento de Bomberos Voluntarios de Mountain Home, ense\u00f1\u00e1ndose mutuamente nuevas habilidades, incluida la t\u00e9cnica de la tuber\u00eda de PVC para encontrar cuerpos.<\/p>\n<p>El v\u00ednculo que forjaron los dos grupos de bomberos surge de un llamado mutuo a servir al bien com\u00fan, dijo Herrera.<\/p>\n<p>\u201cSi llegas a una estaci\u00f3n de bomberos en Estados Unidos y quieres hablar con alguien, siempre te recibir\u00e1n con los brazos abiertos\u201d, dijo. \u201cEsa vocaci\u00f3n de servir en todos los servicios de emergencia, especialmente en el Departamento de Bomberos, es algo muy hermoso. Te llena de alegr\u00eda; te adoptan como si fueras uno de ellos\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sacar cad\u00e1veres de migrantes y sus hijos de las embravecidas aguas del r\u00edo Grande a lo largo de la frontera entre Estados Unidos y M\u00e9xico es algo a lo que un grupo de bomberos mexicanos de la ciudad fronteriza de Ciudad Acu\u00f1a est\u00e1 acostumbrado. Las t\u00e9cnicas perfeccionadas durante las b\u00fasquedas de rutina, como introducir un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1464915","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Sacar cad\u00e1veres de migrantes y sus hijos de las embravecidas aguas del r\u00edo Grande a lo largo de la frontera entre Estados Unidos y M\u00e9xico es algo a lo que un grupo de bomberos mexicanos de la ciudad fronteriza de Ciudad Acu\u00f1a est\u00e1 acostumbrado. Las t\u00e9cnicas perfeccionadas durante las b\u00fasquedas de rutina, como introducir un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-28T14:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas\",\"datePublished\":\"2025-07-28T14:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/\"},\"wordCount\":1451,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/\",\"name\":\"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-28T14:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas - Noticias","og_description":"Sacar cad\u00e1veres de migrantes y sus hijos de las embravecidas aguas del r\u00edo Grande a lo largo de la frontera entre Estados Unidos y M\u00e9xico es algo a lo que un grupo de bomberos mexicanos de la ciudad fronteriza de Ciudad Acu\u00f1a est\u00e1 acostumbrado. Las t\u00e9cnicas perfeccionadas durante las b\u00fasquedas de rutina, como introducir un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/","og_site_name":"Noticias","article_published_time":"2025-07-28T14:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/"},"author":{"name":"","@id":""},"headline":"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas","datePublished":"2025-07-28T14:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/"},"wordCount":1451,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/","url":"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/","name":"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-28T14:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Para estos bomberos mexicanos, encontrar cad\u00e1veres de migrantes en la frontera los prepar\u00f3 para las inundaciones de Texas","url":"http:\/\/noticiasya.com\/aspen\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/07\/28\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-28T14:03:39Z","datePublished":"2025-07-28T14:03:39Z","dateModified":"2025-07-28T14:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Para estos bomberos mexicanos, encontrar cad\\u00e1veres de migrantes en la frontera los prepar\\u00f3 para las inundaciones de Texas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/07\\\/28\\\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/07\\\/28\\\/bomberos-mexicanos-cuerpos-migrantes-inundaciones-texas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-28T14:03:39Z\",\"datePublished\":\"2025-07-28T14:03:39Z\",\"dateModified\":\"2025-07-28T14:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464317,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/08\/mexicano-murio-desaparecido-inundaciones-texas-orix\/","url_meta":{"origin":1464915,"position":0},"title":"Un ciudadano mexicano muri\u00f3 y otro est\u00e1 desaparecido tras las inundaciones en Texas, confirm\u00f3 Sheinbaum","author":"","date":"julio 8, 2025","format":false,"excerpt":"Este martes, la presidenta de M\u00e9xico, Claudia Sheinbaum, inform\u00f3 durante su conferencia de prensa matutina que un ciudadano mexicano muri\u00f3 y otro est\u00e1 desaparecido en las inundaciones en Texas, Estados Unidos, donde se han registrado m\u00e1s de 100 muertes.La presidenta tambi\u00e9n aprovech\u00f3 la oportunidad para felicitar a Protecci\u00f3n Civil y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451017,"url":"https:\/\/noticiasya.com\/aspen\/2024\/07\/10\/patrulla-fronteriza-reporta-rescate-54-migrantes-rio-grande-orix\/","url_meta":{"origin":1464915,"position":1},"title":"Patrulla Fronteriza reporta rescate de 54 migrantes en el R\u00edo Grande","author":"","date":"julio 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Agentes migratorios de Estados Unidos y bomberos de Sunland Park, Nuevo M\u00e9xico, asistieron y pusieron a salvo a un grupo de 54 migrantes que cruzaban el R\u00edo Bravo, inform\u00f3 este mi\u00e9rcoles la Oficina de Aduanas y Patrulla Fronteriza (CBP por sus siglas en ingl\u00e9s).Mueren dos militares y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464738,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/21\/renuncia-jefe-busqueda-rescate-fema-inundaciones-texas-trax\/","url_meta":{"origin":1464915,"position":2},"title":"Renuncia el jefe de b\u00fasqueda y rescate de FEMA tras frustraci\u00f3n por respuesta a inundaciones en Texas","author":"","date":"julio 21, 2025","format":false,"excerpt":"El jefe de la rama de B\u00fasqueda y Rescate Urbano de la Agencia Federal de Gesti\u00f3n de Emergencias (FEMA, por sus siglas en ingl\u00e9s), que dirige una red de equipos en todo el pa\u00eds para responder r\u00e1pidamente a desastres naturales, renunci\u00f3 el lunes.La salida de Ken Pagurek ocurre menos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457821,"url":"https:\/\/noticiasya.com\/aspen\/2025\/01\/23\/decenas-migrantes-vistos-deportados-estados-unidos-a-juarez-mexico-trax\/","url_meta":{"origin":1464915,"position":3},"title":"&#171;Intentarlo de nuevo&#187;: CNN habl\u00f3 con deportados en la frontera sur de EE.UU. mientras se endurecen las pol\u00edticas migratorias","author":"","date":"enero 23, 2025","format":false,"excerpt":"Decenas de inmigrantes fueron deportados a M\u00e9xico desde Estados Unidos el jueves, seg\u00fan pudo comprobar un equipo de CNN en Ciudad Ju\u00e1rez.Los inmigrantes, que parec\u00edan ser todos hombres, fueron vistos cruzando a pie el puente Paso del Norte, que conecta El Paso, Texas, con Ciudad Ju\u00e1rez, Chihuahua. Fueron escoltados por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443847,"url":"https:\/\/noticiasya.com\/aspen\/2024\/01\/16\/gobierno-de-biden-dice-a-la-corte-suprema-que-texas-hizo-imposible-que-los-federales-ayudaran-potencialmente-a-3-inmigrantes-mexicanos-que-se-ahogaron-en-el-rio-grande\/","url_meta":{"origin":1464915,"position":4},"title":"Gobierno de Biden dice a la Corte Suprema que Texas hizo \u201cimposible\u201d que los federales ayudaran potencialmente a 3 inmigrantes mexicanos que se ahogaron en el r\u00edo Grande","author":"","date":"enero 16, 2024","format":false,"excerpt":"(CNN) -- El Gobierno de Joe Biden dijo a la Corte Suprema el lunes por la noche que Texas hizo \u201cimposible\u201d que los agentes de la Patrulla Fronteriza pudieran brindar ayuda a tres inmigrantes mexicanos que se ahogaron en el r\u00edo Grande la semana pasada.En una nueva presentaci\u00f3n ante el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464521,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/15\/inundaciones-repentinas-areas-metropolitanas-trax\/","url_meta":{"origin":1464915,"position":5},"title":"Inundaciones repentinas afectan importantes \u00e1reas metropolitanas del noreste mientras lluvias extremas amenazan a millones","author":"","date":"julio 15, 2025","format":false,"excerpt":"Decenas de advertencias de inundaciones repentinas est\u00e1n vigentes para millones de personas en varios estados y ciudades importantes del noreste de Estados Unidos, mientras tormentas de verano de movimiento lento impactan la costa este el lunes por la noche.Se han reportado inundaciones cerca de Newark, Nueva Jersey, la ciudad de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1464915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1464915"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1464915\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1464915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1464915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1464915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}