{"id":1464929,"date":"2025-07-28T15:03:43","date_gmt":"2025-07-28T22:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/"},"modified":"2025-07-28T15:03:43","modified_gmt":"2025-07-28T22:03:43","slug":"declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/","title":{"rendered":"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia"},"content":{"rendered":"<p>\u00c1lvaro Uribe, presidente de Colombia de 2002 a 2010, fue declarado culpable este lunes del delito de soborno en un caso de manipulaci\u00f3n de testigos. Es el primer exmandatario del pa\u00eds sudamericano en ser condenado penalmente.<\/p>\n<p>El <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/28\/colombia\/fallo-juicio-alvaro-uribe-manipulacion-testigos-orix\">fallo fue dictado<\/a> por la jueza 44 penal de Bogot\u00e1, Sandra Heredia, quien concluy\u00f3 que hay elementos suficientes para condenar al exmandatario, miembro del opositor partido Centro Democr\u00e1tico.<\/p>\n<p>La jurista sigue la lectura de la sentencia.<\/p>\n<p>Desde que la investigaci\u00f3n en su contra comenz\u00f3 en 2018, Uribe se declar\u00f3 inocente de todos los cargos. Mantuvo esa postura a lo largo del juicio, que dur\u00f3 67 d\u00edas y en el que se confront\u00f3 con el senador Iv\u00e1n Cepeda, del partido oficialista Pacto Hist\u00f3rico. En 2012, Uribe hab\u00eda acusado a Cepeda de querer vincularlo con la creaci\u00f3n de un grupo paramilitar \u2014se\u00f1alamiento que Cepeda rechaz\u00f3\u2014, pero la Corte Suprema de Colombia determin\u00f3 que era Uribe quien deb\u00eda ser investigado por la presunta manipulaci\u00f3n de testigos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1lvaro Uribe, presidente de Colombia de 2002 a 2010, fue declarado culpable este lunes del delito de soborno en un caso de manipulaci\u00f3n de testigos. Es el primer exmandatario del pa\u00eds sudamericano en ser condenado penalmente. El fallo fue dictado por la jueza 44 penal de Bogot\u00e1, Sandra Heredia, quien concluy\u00f3 que hay elementos suficientes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1464929","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u00c1lvaro Uribe, presidente de Colombia de 2002 a 2010, fue declarado culpable este lunes del delito de soborno en un caso de manipulaci\u00f3n de testigos. Es el primer exmandatario del pa\u00eds sudamericano en ser condenado penalmente. El fallo fue dictado por la jueza 44 penal de Bogot\u00e1, Sandra Heredia, quien concluy\u00f3 que hay elementos suficientes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-28T22:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia\",\"datePublished\":\"2025-07-28T22:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/\"},\"wordCount\":199,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/\",\"name\":\"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-28T22:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia - Noticias","og_description":"\u00c1lvaro Uribe, presidente de Colombia de 2002 a 2010, fue declarado culpable este lunes del delito de soborno en un caso de manipulaci\u00f3n de testigos. Es el primer exmandatario del pa\u00eds sudamericano en ser condenado penalmente. El fallo fue dictado por la jueza 44 penal de Bogot\u00e1, Sandra Heredia, quien concluy\u00f3 que hay elementos suficientes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/","og_site_name":"Noticias","article_published_time":"2025-07-28T22:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/"},"author":{"name":"","@id":""},"headline":"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia","datePublished":"2025-07-28T22:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/"},"wordCount":199,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/","url":"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/","name":"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-28T22:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Declaran culpable a \u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia","url":"http:\/\/noticiasya.com\/aspen\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/07\/28\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-28T22:03:43Z","datePublished":"2025-07-28T22:03:43Z","dateModified":"2025-07-28T22:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Declaran culpable a \\u00c1lvaro Uribe: es la primera vez que un expresidente es condenado penalmente en Colombia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/07\\\/28\\\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/07\\\/28\\\/declaran-culpable-expresidente-alvaro-uribe-caso-manipulacion-testigos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-28T22:03:43Z\",\"datePublished\":\"2025-07-28T22:03:43Z\",\"dateModified\":\"2025-07-28T22:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465042,"url":"https:\/\/noticiasya.com\/aspen\/2025\/08\/01\/sentencian-alvaro-uribe12-anios-prision-domiciliaria-orix\/","url_meta":{"origin":1464929,"position":0},"title":"Sentencian al expresidente de Colombia \u00c1lvaro Uribe a 12 a\u00f1os de prisi\u00f3n domiciliaria","author":"","date":"agosto 1, 2025","format":false,"excerpt":"El expresidente de Colombia \u00c1lvaro Uribe fue sentenciado este viernes a 12 a\u00f1os de prisi\u00f3n domiciliaria tras haber sido declarado culpable de fraude procesal y soborno a testigos. Uribe se declar\u00f3 inocente y su defensa ya hab\u00eda anticipado que presentar\u00e1 un recurso de apelaci\u00f3n.La sentencia se dio a conocer este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464963,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/29\/ivan-cepeda-conclusiones-rechaza-plan-politico-condena-uribe-orix\/","url_meta":{"origin":1464929,"position":1},"title":"Iv\u00e1n Cepeda rechaza que condena de Uribe sea un &#171;plan pol\u00edtico&#187; o impulso a su candidatura","author":"","date":"julio 29, 2025","format":false,"excerpt":"El senador Iv\u00e1n Cepeda, del partido de gobierno Pacto Hist\u00f3rico, rechaz\u00f3 en entrevista con CNN que la condena contra el expresidente de Colombia \u00c1lvaro Uribe sea alg\u00fan \u201cplan pol\u00edtico\u201d o impulso a una posible candidatura presidencial.El lunes, el expresidente \u00c1lvaro Uribe fue encontrado culpable de dos de los tres cargos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464339,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/08\/juicio-expresidente-alvaro-uribe-colombia-fallo-28-julio-orix\/","url_meta":{"origin":1464929,"position":2},"title":"Termina juicio contra el expresidente \u00c1lvaro Uribe en Colombia y el fallo se dar\u00e1 el 28 de julio","author":"","date":"julio 8, 2025","format":false,"excerpt":"Con los alegatos de conclusi\u00f3n, este martes termin\u00f3 la etapa de juicio penal contra el exmandatario de Colombia \u00c1lvaro Uribe, por su presunta participaci\u00f3n en los delitos de fraude procesal, soborno en actuaci\u00f3n penal y soborno de testigo, en el juzgado 44 penal de Bogot\u00e1. Uribe rechaza los cargos.En esa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464909,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/28\/fallo-juicio-alvaro-uribe-manipulacion-testigos-orix\/","url_meta":{"origin":1464929,"position":3},"title":"Llega el fallo en el juicio a \u00c1lvaro Uribe por manipulaci\u00f3n de testigos: as\u00ed pas\u00f3 de acusador a acusado","author":"","date":"julio 28, 2025","format":false,"excerpt":"Ha sido un largo y complejo litigio judicial entre el expresidente de Colombia \u00c1lvaro Uribe, del partido de oposici\u00f3n Centro Democr\u00e1tico, y el senador Iv\u00e1n Cepeda, del partido de gobierno, Pacto Hist\u00f3rico. Todo se remonta a 13 a\u00f1os atr\u00e1s, cuando, en medio de un debate sobre el origen y las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467575,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/21\/tribunal-revoca-condena-alvaro-uribe-orix\/","url_meta":{"origin":1464929,"position":4},"title":"Tribunal Superior de Bogot\u00e1 revoca condena al expresidente \u00c1lvaro Uribe","author":"","date":"octubre 21, 2025","format":false,"excerpt":"El Tribunal Superior de Bogot\u00e1 admiti\u00f3 este martes la apelaci\u00f3n del expresidente de Colombia \u00c1lvaro Uribe V\u00e9lez y revoc\u00f3 la condena en primera instancia a 12 a\u00f1os de prisi\u00f3n domiciliaria por los delitos de manipulaci\u00f3n de testigos y fraude.La Fiscal\u00eda puede presentar un recurso contra la absoluci\u00f3n ante la Sala\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447937,"url":"https:\/\/noticiasya.com\/aspen\/2024\/04\/10\/alvaro-uribe-responde-llamado-a-juicio-caso-manipulacion-testigos-orix\/","url_meta":{"origin":1464929,"position":5},"title":"\u00c1lvaro Uribe afirma que la promoci\u00f3n de un juicio en su contra obedece a \u201cvenganzas pol\u00edticas\u201d","author":"","date":"abril 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El expresidente de Colombia \u00c1lvaro Uribe\u00a0respondi\u00f3 este mi\u00e9rcoles al pedido de la Fiscal\u00eda General\u00a0para que llamarlo a juicio por los presuntos delitos de fraude judicial y manipulaci\u00f3n de testigos.A trav\u00e9s de un mensaje en sus redes sociales, Uribe dijo que\u00a0la iniciativa no obedece a delito alguno: \u201cEste\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1464929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1464929"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1464929\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1464929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1464929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1464929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}