{"id":1464931,"date":"2025-07-28T17:03:55","date_gmt":"2025-07-29T00:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/"},"modified":"2025-07-28T17:03:55","modified_gmt":"2025-07-29T00:03:55","slug":"tiroteo-nueva-york-manhattan-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/","title":{"rendered":"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes"},"content":{"rendered":"<p>Se cree que un hombre armado muri\u00f3 despu\u00e9s de disparar a un agente del Departamento de Polic\u00eda de Nueva York (NYPD) y al menos a dos civiles cerca de un edificio de oficinas corporativas en el centro de Manhattan este lunes por la tarde, seg\u00fan dijeron a CNN varias fuentes de las fuerzas del orden.<\/p>\n<p>Seg\u00fan una fuente, se vio a un hombre con un rifle largo entrar al edificio.<\/p>\n<p>Un civil que result\u00f3 herido est\u00e1 en estado cr\u00edtico, seg\u00fan un funcionario de las fuerzas del orden. Otro civil y el agente del NYPD, que recibi\u00f3 un disparo en la espalda, se espera que sobrevivan, dijo el funcionario a CNN. El escuadr\u00f3n antibombas del NYPD est\u00e1 en la escena.<\/p>\n<p>El agente que result\u00f3 herido pertenece a una comisar\u00eda del Bronx y estaba en un puesto cerca del edificio cuando ocurri\u00f3 el tiroteo, seg\u00fan el funcionario.<\/p>\n<p>El FBI respondi\u00f3 al incidente \u201cpara brindar apoyo\u201d en la \u201cescena activa del crimen\u201d, seg\u00fan<a href=\"https:\/\/x.com\/FBIDDBongino\/status\/1949970080294449243\"> una publicaci\u00f3n en X <\/a>del subdirector Dan Bongino.<\/p>\n<p>El alcalde de la ciudad de Nueva York, Eric Adams, confirm\u00f3 en <a href=\"https:\/\/x.com\/nycmayor\/status\/1949971560330059818?s=46\">una publicaci\u00f3n en X<\/a> que \u201cactualmente se est\u00e1 llevando a cabo una investigaci\u00f3n por un atacante activo en Midtown\u201d. \u201cPor favor, tomen las precauciones de seguridad necesarias si est\u00e1n en la zona y no salgan si se encuentran cerca de Park Avenue y la calle 51 Este\u201d, escribi\u00f3.<\/p>\n<p>La gobernadora Kathy Hochul dijo <a href=\"https:\/\/x.com\/GovKathyHochul\/status\/1949976340146302991\">en una publicaci\u00f3n en X<\/a> que fue informada sobre el tiroteo y pidi\u00f3 a las personas que eviten la zona.<\/p>\n<p>Un equipo de CNN en el lugar observ\u00f3 que los agentes de la ley en la escena est\u00e1n actuando con cautela y resguard\u00e1ndose.<\/p>\n<p>Un video muestra una fuerte presencia de fuerzas del orden alrededor del edificio. El departamento de polic\u00eda le dijo a CNN que la situaci\u00f3n sigue \u201cmuy activa\u201d.<\/p>\n<p>El edificio, ubicado en el 345 de Park Avenue, alberga oficinas corporativas de la Liga Nacional de F\u00fatbol Americano (NFL) y de la firma Blackstone. El edificio ocupa toda una manzana y es uno de los 41 edificios en la ciudad de Nueva York que tiene su propio c\u00f3digo postal.<\/p>\n<p>CNN contact\u00f3 al NYPD para solicitar m\u00e1s informaci\u00f3n.<\/p>\n<p><em>Noticia en desarrollo\u2026<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se cree que un hombre armado muri\u00f3 despu\u00e9s de disparar a un agente del Departamento de Polic\u00eda de Nueva York (NYPD) y al menos a dos civiles cerca de un edificio de oficinas corporativas en el centro de Manhattan este lunes por la tarde, seg\u00fan dijeron a CNN varias fuentes de las fuerzas del orden. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1464931","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes - Noticias\" \/>\n<meta property=\"og:description\" content=\"Se cree que un hombre armado muri\u00f3 despu\u00e9s de disparar a un agente del Departamento de Polic\u00eda de Nueva York (NYPD) y al menos a dos civiles cerca de un edificio de oficinas corporativas en el centro de Manhattan este lunes por la tarde, seg\u00fan dijeron a CNN varias fuentes de las fuerzas del orden. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T00:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes\",\"datePublished\":\"2025-07-29T00:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/\"},\"wordCount\":425,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/\",\"name\":\"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-29T00:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes - Noticias","og_description":"Se cree que un hombre armado muri\u00f3 despu\u00e9s de disparar a un agente del Departamento de Polic\u00eda de Nueva York (NYPD) y al menos a dos civiles cerca de un edificio de oficinas corporativas en el centro de Manhattan este lunes por la tarde, seg\u00fan dijeron a CNN varias fuentes de las fuerzas del orden. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/","og_site_name":"Noticias","article_published_time":"2025-07-29T00:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/"},"author":{"name":"","@id":""},"headline":"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes","datePublished":"2025-07-29T00:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/"},"wordCount":425,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/","url":"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/","name":"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-29T00:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes","url":"http:\/\/noticiasya.com\/aspen\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-29T00:03:55Z","datePublished":"2025-07-29T00:03:55Z","dateModified":"2025-07-29T00:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se cree que el sospechoso muri\\u00f3 tras tiroteo que dej\\u00f3 heridos a un polic\\u00eda de Nueva York y a dos civiles, seg\\u00fan fuentes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/07\\\/28\\\/tiroteo-nueva-york-manhattan-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/07\\\/28\\\/tiroteo-nueva-york-manhattan-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-29T00:03:55Z\",\"datePublished\":\"2025-07-29T00:03:55Z\",\"dateModified\":\"2025-07-29T00:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456322,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/06\/pistas-asesinato-ceo-unitedhealthcare-trax\/","url_meta":{"origin":1464931,"position":0},"title":"Un coqueteo, municiones escritas y una botella ofrecen pistas sobre el atacante del CEO de UnitedHealthcare","author":"","date":"diciembre 6, 2024","format":false,"excerpt":"Una foto que muestra a un hombre encapuchado sonriendo puede proporcionar pistas importantes que podr\u00edan ayudar a conducir al sospechoso en el tiroteo mortal del CEO de UnitedHealthcare, Brian Thompson.Una imagen publicada por el Departamento de Polic\u00eda de Nueva York muestra a un hombre al que las autoridades califican de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456865,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/22\/muere-pasajera-hombre-fuego-metro-nueva-york-trax\/","url_meta":{"origin":1464931,"position":1},"title":"Detienen a un sospechoso por la muerte de una mujer a quien le prendieron fuego en el metro de Nueva York","author":"","date":"diciembre 22, 2024","format":false,"excerpt":"La Polic\u00eda arrest\u00f3 a un sospechoso de la muerte de una mujer tras prenderle fuego en el metro de la ciudad de Nueva York este domingo por la ma\u00f1ana, informaron las autoridades.Alrededor de las 7:30 a.m., un hombre, que la Polic\u00eda cree que tiene entre 25 y 30 a\u00f1os, se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473507,"url":"https:\/\/noticiasya.com\/aspen\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/","url_meta":{"origin":1464931,"position":2},"title":"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades","author":"","date":"abril 25, 2026","format":false,"excerpt":"Un agente de polic\u00eda de Chicago muri\u00f3 por disparos y otro result\u00f3 gravemente herido este s\u00e1bado por un sospechoso de robo al que escoltaban dentro de un hospital, inform\u00f3 el superintendente de la polic\u00eda de Chicago, Larry Snelling.No est\u00e1 claro c\u00f3mo el sospechoso \u2014quien, seg\u00fan el hospital, fue sometido a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467004,"url":"https:\/\/noticiasya.com\/aspen\/2025\/09\/30\/agentes-ice-empujaron-periodistas-tribunal-nueva-york-trax\/","url_meta":{"origin":1464931,"position":3},"title":"Agentes de ICE forcejearon y empujaron a periodistas en un tribunal de inmigraci\u00f3n de Nueva York, muestra video","author":"","date":"septiembre 30, 2025","format":false,"excerpt":"Al menos un periodista pareci\u00f3 resultar herido despu\u00e9s de que un reportero fue agarrado y otro empujado por agentes enmascarados del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en un tribunal de inmigraci\u00f3n de la ciudad de Nueva York la ma\u00f1ana del martes, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466399,"url":"https:\/\/noticiasya.com\/aspen\/2025\/09\/12\/ice-muerto-herido-trafico-chicago-trax\/","url_meta":{"origin":1464931,"position":4},"title":"Una persona muri\u00f3 y un agente del ICE result\u00f3 herido en una parada de tr\u00e1fico en Chicago, dice el DHS","author":"","date":"septiembre 12, 2025","format":false,"excerpt":"Una persona que fue detenida en una parada de tr\u00e1fico organizado por Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) arrastr\u00f3 a un agente con su veh\u00edculo para resistirse al arresto. El episodio ocurri\u00f3 en un suburbio de Chicago en la ma\u00f1ana del viernes, y llev\u00f3 al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459081,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/22\/mueren-policia-hombre-armado-tiroteo-hospital-pensilvania-trax\/","url_meta":{"origin":1464931,"position":5},"title":"Mueren un polic\u00eda y un hombre armado en un tiroteo en un hospital de Pensilvania","author":"","date":"febrero 22, 2025","format":false,"excerpt":"Un agente de polic\u00eda muri\u00f3 mientras respond\u00eda a un tiroteo en un hospital de York, Pensilvania, este s\u00e1bado por la ma\u00f1ana, confirm\u00f3 su departamento en Facebook.El hombre armado tambi\u00e9n muri\u00f3, dijo el Hospital UPMC Memorial en un comunicado en Facebook.\u201cNing\u00fan paciente result\u00f3 herido. El hospital es ahora seguro\u201d, dijo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1464931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1464931"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1464931\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1464931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1464931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1464931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}