{"id":1464951,"date":"2025-07-29T11:03:50","date_gmt":"2025-07-29T18:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/"},"modified":"2025-07-29T11:03:50","modified_gmt":"2025-07-29T18:03:50","slug":"eeuu-quemara-anticonceptivos-usaid-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/","title":{"rendered":"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero"},"content":{"rendered":"<p>El Gobierno de Trump est\u00e1 listo para destruir anticonceptivos adquiridos por EE.UU. por un valor de US$ 9,7 millones en lugar de entregarlos a mujeres en el extranjero. Esto sucede tras el desmantelamiento de los programas de asistencia exterior llevados a cabo por la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID, por sus siglas en ingl\u00e9s).<\/p>\n<p>La \u201cdecisi\u00f3n preliminar\u201d de destruir los anticonceptivos adquiridos por USAID fue confirmada por un portavoz del Departamento de Estado, quien dijo que el costo de incinerarlos ser\u00eda de US$ 167.000.<\/p>\n<p>Los anticonceptivos han estado almacenados en Geel, B\u00e9lgica. El Ministerio de Asuntos Exteriores belga dijo que estaba participando en conversaciones diplom\u00e1ticas con la embajada de EE.UU. para encontrar soluciones alternativas para los suministros.<\/p>\n<p>La mayor\u00eda de los anticonceptivos son m\u00e9todos de larga duraci\u00f3n, como dispositivos intrauterinos (DIU) e inyectables, dijo un asistente del Congreso de EE.UU. a CNN. Se desconoce exactamente cu\u00e1ndo se destruir\u00e1n los suministros, seg\u00fan el asistente.<\/p>\n<p>\u201cTienen que incinerar dos veces los productos porque contienen altos niveles de hormonas y no quieren arriesgarse a que los subproductos se filtren al medio ambiente, lo cual probablemente aumente el costo\u201d, dijo el asistente del Congreso. \u201cEl Gobierno de Trump est\u00e1 literalmente quemando el dinero de los contribuyentes\u201d.<\/p>\n<p>Una lista de los suministros, compartida con CNN por otra fuente con conocimiento del inventario del almac\u00e9n, muestra que los anticonceptivos incluyen DIU de cobre, implantes en varilla, inyecciones anticonceptivas y tabletas de levonorgestrel y etinilestradiol. Algunos tienen la marca de USAID, pero la mayor\u00eda no, seg\u00fan la lista aportada por la fuente.<\/p>\n<p>La mayor\u00eda de los productos vencen en 2028 o 2029, siendo la fecha de caducidad m\u00e1s temprana entre los productos la de abril de 2027, seg\u00fan la lista que detalla los casi 5 millones de art\u00edculos.<\/p>\n<p>El portavoz del Departamento de Estado de EE.UU. se refiri\u00f3 a los anticonceptivos que ser\u00e1n destruidos como \u201cciertos anticonceptivos abortivos provenientes de contratos de USAID de la era Biden que han sido terminados\u201d.<\/p>\n<p>Existe controversia sobre si describir ciertos anticonceptivos como abortivos, o causantes de aborto, debido al debate sobre si la vida comienza en el momento en que un \u00f3vulo es fertilizado o en una etapa posterior. Algunos m\u00e9todos anticonceptivos, incluidos los DIU, pueden funcionar evitando la implantaci\u00f3n de un \u00f3vulo fertilizado. Sin embargo, los DIU funcionan principalmente suprimiendo la liberaci\u00f3n de \u00f3vulos o impidiendo que los espermatozoides lleguen a un \u00f3vulo.<\/p>\n<p>CNN ha contactado al Colegio Estadounidense de Obstetras y Ginec\u00f3logos para obtener comentarios al respecto, pero hasta el momento no ha obtenido respuestas.<\/p>\n<p>\u201cSolo un n\u00famero limitado de productos ha sido aprobado para su eliminaci\u00f3n. No se destruir\u00e1n medicamentos para el VIH ni condones\u201d, agreg\u00f3 el portavoz. \u201cUSAID evit\u00f3 un costo adicional de US$ 34,1 millones a los contribuyentes negociando cancelaciones sin costo de pedidos pendientes realizados bajo el Gobierno de Biden\u201d.<\/p>\n<p>En respuesta a los informes de los medios de que los anticonceptivos ser\u00edan transferidos a una instalaci\u00f3n francesa de desechos m\u00e9dicos para ser destruidos a finales de julio, una fuente diplom\u00e1tica en Francia dijo a CNN que los anticonceptivos estaban siendo gestionados por entidades privadas y que \u201cno ten\u00edan informaci\u00f3n sobre ning\u00fan traslado\u201d, hasta el jueves de la semana pasada.<\/p>\n<p>\u201cApoyamos firmemente el compromiso de las autoridades belgas de encontrar una soluci\u00f3n para evitar la destrucci\u00f3n de estos anticonceptivos, para que puedan llegar a mujeres y hombres de todo el mundo que los necesitan y los esperan\u201d, agreg\u00f3 la fuente diplom\u00e1tica. \u201cEl acceso a servicios y productos de salud sexual y reproductiva de calidad es tanto un tema de derechos humanos como de salud p\u00fablica\u201d.<\/p>\n<p>La senadora estadounidense Jeanne Shaheen envi\u00f3 a un miembro de su personal al almac\u00e9n en B\u00e9lgica como parte de un intento por presentar una iniciativa legal que proh\u00edba \u201cla destrucci\u00f3n de dichos productos a menos que se hayan agotado todos los esfuerzos para venderlos o donarlos\u201d. Dicho miembro del personal confirm\u00f3 que la fecha de caducidad m\u00e1s temprana de los anticonceptivos era 2027, y que algunos suministros no venc\u00edan hasta 2031, lo que significa que a\u00fan podr\u00edan usarse durante a\u00f1os.<\/p>\n<p>\u201cEn un momento en que el Gobierno de Trump ha realizado recortes devastadores a la asistencia exterior, es decepcionante que el Departamento de Estado apruebe gastar dinero para destruir productos ya pagados que salvar\u00edan vidas y est\u00e1n listos para ser distribuidos\u201d, dijo Shaheen en un comunicado. \u201cLos alimentos y los productos para la planificaci\u00f3n familiar son desesperadamente necesarios en pa\u00edses afectados por conflictos, como Sud\u00e1n y la Rep\u00fablica Democr\u00e1tica del Congo, donde la hambruna est\u00e1 comenzando a arraigarse\u201d.<\/p>\n<p>La portavoz del ministerio de Asuntos Exteriores belga, Florinda Baleci, dijo a CNN que el pa\u00eds estaba \u201cexplorando todas las v\u00edas posibles para evitar la destrucci\u00f3n de estos stocks, incluida su reubicaci\u00f3n temporal\u201d.<\/p>\n<p>Una organizaci\u00f3n llamada MSI Reproductive Choices dijo que, junto con otros socios financistas, hab\u00eda ofrecido pagar el env\u00edo y el reempaquetado de los suministros con la marca USAID, pero que el gobierno estadounidense rechaz\u00f3 la oferta.<\/p>\n<p>\u201cNo se nos dio una raz\u00f3n de por la qua esta oferta no fue aceptada, pero qued\u00f3 claro en las conversaciones que no lo ser\u00eda y que nuestros esfuerzos estar\u00edan mejor enfocados en encontrar soluciones alternativas a la escasez de suministros anticonceptivos\u201d, dijo Grace Dunne, portavoz de MSI, que trabaja en 36 pa\u00edses para proveer atenci\u00f3n de salud reproductiva, incluyendo servicios de aborto, anticoncepci\u00f3n y atenci\u00f3n materna.<\/p>\n<p>En respuesta a preguntas de CNN sobre la oferta, el Departamento de Estado destac\u00f3 la llamada \u201c<a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2021%2F01%2F30%2Fworld%2Fbiden-abortion-mexico-city-policy-intl&#038;data=05%7C02%7CHannah.Strange%40cnn.com%7C9f267587b83b4b8f693908ddcea3a4be%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638893924436409832%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=MIHRyYMI9Ux57KtqLc9GgLIkL0L%2B7nTaGM7sDH5yt%2B8%3D&#038;reserved=0\">pol\u00edtica de la Ciudad de M\u00e9xico<\/a>\u201d, que \u201cproh\u00edbe proporcionar cierta asistencia \u2014directa o indirectamente\u2014 a organizaciones no gubernamentales extranjeras que realicen o promuevan activamente el aborto como m\u00e9todo de planificaci\u00f3n familiar\u201d.<\/p>\n<p>Esa pol\u00edtica, a la que los opositores llaman la \u201cregla mordaza global\u201d, impide que las organizaciones no gubernamentales que proporcionan abortos, ofrecen consejer\u00eda sobre abortos o abogan por el acceso seguro al aborto reciban fondos estadounidenses.<\/p>\n<p>La destrucci\u00f3n planeada de los anticonceptivos ha provocado protestas de otras organizaciones, como M\u00e9dicos Sin Fronteras (MSF), que expres\u00f3 su preocupaci\u00f3n por la escasez de anticonceptivos en pa\u00edses que antes depend\u00edan de los suministros donados por USAID.<\/p>\n<p>\u201cEn las comunidades atendidas por MSF \u2014ya sea afectadas por conflictos, brotes de enfermedades, desastres naturales o provocados por el hombre, o exclusi\u00f3n de la atenci\u00f3n m\u00e9dica\u2014 el acceso a anticonceptivos ya est\u00e1 restringido\u201d, dijo la organizaci\u00f3n en un comunicado. \u201cLos contextos que previamente depend\u00edan de suministros anticonceptivos financiados por USAID est\u00e1n en mayor riesgo de interrupciones en la cadena de suministro y quiebres de stock\u201d.<\/p>\n<p>\u201cMSF ha visto de primera mano los beneficios positivos para la salud cuando las mujeres y ni\u00f1as pueden tomar libremente sus propias decisiones de salud eligiendo prevenir o retrasar el embarazo, y las peligrosas consecuencias cuando no pueden\u201d, agreg\u00f3 Avril Beno\u00eet, directora ejecutiva de MSF USA.<\/p>\n<p>MSF tambi\u00e9n cit\u00f3 informes que dicen que m\u00e1s anticonceptivos con la marca USAID se encuentran almacenados en un dep\u00f3sito en los Emiratos \u00c1rabes Unidos, pero la organizaci\u00f3n dijo que se desconoce el plan del gobierno estadounidense para esos suministros.<\/p>\n<p>Un portavoz del Departamento de Estado no respondi\u00f3 una pregunta sobre los anticonceptivos almacenados en los EAU. CNN se ha puesto en contacto con el gobierno de los EAU para obtener comentarios, pero hasta ahora no obtuvo respuesta.<\/p>\n<p>A principios de julio, el secretario de Estado de EE.UU., Marco Rubio, celebr\u00f3 el fin de USAID, diciendo que los futuros programas de asistencia exterior se alinear\u00edan con las pol\u00edticas de la administraci\u00f3n y ser\u00edan administrados por el Departamento de Estado. El r\u00e1pido desmantelamiento de USAID, liderado por el Departamento de Eficiencia Gubernamental (DOGE), ha supuesto la eliminaci\u00f3n de miles de programas de asistencia exterior, incluyendo muchos que se centraban en trabajos para salvar vidas.<\/p>\n<p>Un estudio publicado a principios de este mes por una destacada revista m\u00e9dica, The Lancet, estim\u00f3 que los recortes de fondos de USAID podr\u00edan resultar en m\u00e1s de 14 millones de muertes adicionales para 2030. Seg\u00fan el estudio, la financiaci\u00f3n de USAID era m\u00e1s probable que redujera la mortalidad relacionada con el VIH\/SIDA, seguida por la malaria.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Trump est\u00e1 listo para destruir anticonceptivos adquiridos por EE.UU. por un valor de US$ 9,7 millones en lugar de entregarlos a mujeres en el extranjero. Esto sucede tras el desmantelamiento de los programas de asistencia exterior llevados a cabo por la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID, por [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1464951","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Trump est\u00e1 listo para destruir anticonceptivos adquiridos por EE.UU. por un valor de US$ 9,7 millones en lugar de entregarlos a mujeres en el extranjero. Esto sucede tras el desmantelamiento de los programas de asistencia exterior llevados a cabo por la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID, por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T18:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero\",\"datePublished\":\"2025-07-29T18:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/\"},\"wordCount\":1463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/\",\"name\":\"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-29T18:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero - Noticias","og_description":"El Gobierno de Trump est\u00e1 listo para destruir anticonceptivos adquiridos por EE.UU. por un valor de US$ 9,7 millones en lugar de entregarlos a mujeres en el extranjero. Esto sucede tras el desmantelamiento de los programas de asistencia exterior llevados a cabo por la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID, por [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/","og_site_name":"Noticias","article_published_time":"2025-07-29T18:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero","datePublished":"2025-07-29T18:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/"},"wordCount":1463,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/","url":"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/","name":"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-29T18:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. quemar\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero","url":"http:\/\/noticiasya.com\/aspen\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/07\/29\/eeuu-quemara-anticonceptivos-usaid-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-29T18:03:50Z","datePublished":"2025-07-29T18:03:50Z","dateModified":"2025-07-29T18:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. quemar\\u00e1 US$ 9,7 millones en anticonceptivos comprados por USAID en lugar de entregarlos a mujeres en el extranjero\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/07\\\/29\\\/eeuu-quemara-anticonceptivos-usaid-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/07\\\/29\\\/eeuu-quemara-anticonceptivos-usaid-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-29T18:03:50Z\",\"datePublished\":\"2025-07-29T18:03:50Z\",\"dateModified\":\"2025-07-29T18:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464965,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/30\/5-cosas-30-julio-orix\/","url_meta":{"origin":1464951,"position":0},"title":"Las 5 cosas que debes saber este 30 de julio: olas de tsunami, atacante de Nueva York y venezolanos en EE.UU.","author":"","date":"julio 30, 2025","format":false,"excerpt":"Fuerte sismo activa alerta de tsunami en pa\u00edses del Pac\u00edfico. Miles de venezolanos en EE.UU. se enfrentan al temor de volver a su pa\u00eds. El Reino Unido reconocer\u00e1 un Estado palestino si Israel no acepta un cese del fuego en Gaza. Las condiciones de Maxwell para testificar ante el Congreso.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446978,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/14\/olivia-rodrigo-reparte-anticonceptivos-de-emergencia-gratuitos-trax\/","url_meta":{"origin":1464951,"position":1},"title":"Olivia Rodrigo reparte anticonceptivos de emergencia gratuitos en un concierto en EE.UU.","author":"","date":"marzo 14, 2024","format":false,"excerpt":"(CNN) -- Olivia Rodrigo puso anticonceptivos de emergencia a disposici\u00f3n de quienes asistieron al concierto de su gira \"Guts\" en Missouri el martes, como parte de su iniciativa Fund 4 Good.Como se pudo ver en las redes sociales, en el interior del local de St. Louis donde actu\u00f3 Rodrigo se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458321,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/05\/exdirigentes-usaid-carta-trump-trax\/","url_meta":{"origin":1464951,"position":2},"title":"Primero en CNN: exdirigentes de USAID se pronuncian contra los intentos de Trump de desmantelar la agencia","author":"","date":"febrero 5, 2025","format":false,"excerpt":"Cinco exdirigentes de la Agencia de los Estados Unidos para el Desarrollo Internacional (USAID) de todas las administraciones republicanas y dem\u00f3cratas se pronunciaron contra los intentos de la administraci\u00f3n Trump de desmantelar la agencia humanitaria y pidieron al Congreso \u201cque proteja r\u00e1pidamente el papel estatutario de la agencia\u201d.En una declaraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458461,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/08\/trump-desmantelando-usaid-hija-ivanka-defendio-trax\/","url_meta":{"origin":1464951,"position":3},"title":"Trump est\u00e1 desmantelando una agencia que su hija Ivanka una vez defendi\u00f3","author":"","date":"febrero 8, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, est\u00e1 desmantelando con entusiasmo una agencia que una vez fue defendida por su hija y asesora principal, Ivanka Trump.El trabajo de la Agencia de Estados Unidos para el Desarrollo Internacional (USAID) fue lo suficientemente importante para el presidente que, durante su discurso sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459084,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/22\/trump-agentes-inmigracion-espacios-oficinas-usaid-trax\/","url_meta":{"origin":1464951,"position":4},"title":"Trump dice que los agentes de aplicaci\u00f3n de la ley de inmigraci\u00f3n ocupar\u00e1n ahora los espacios de oficinas de USAID","author":"","date":"febrero 22, 2025","format":false,"excerpt":"El presidente Donald Trump anunci\u00f3 que funcionarios de la Oficina de Aduanas y Protecci\u00f3n Fronteriza de EE.UU. ahora trabajar\u00e1n en la antigua sede de la Agencia de Estados Unidos para el Desarrollo Internacional (USAID), mientras la administraci\u00f3n reduce la ayuda exterior y refuerza la aplicaci\u00f3n de la ley de inmigraci\u00f3n.\u201cTambi\u00e9n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460998,"url":"https:\/\/noticiasya.com\/aspen\/2025\/04\/09\/usaid-despedira-personal-extranjero-agosto-trax\/","url_meta":{"origin":1464951,"position":5},"title":"USAID informa a su personal extranjero que ser\u00e1 despedido a mediados de agosto","author":"","date":"abril 9, 2025","format":false,"excerpt":"La Agencia de Estados Unidos para el Desarrollo Internacional (USAID, en ingl\u00e9s) inform\u00f3 el mi\u00e9rcoles a todo su personal extranjero que ser\u00e1 despedido a mediados de agosto, seg\u00fan un correo electr\u00f3nico interno visto por CNN.Esta decisi\u00f3n se produce en un momento en que la administraci\u00f3n de Trump busca abolir por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1464951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1464951"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1464951\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1464951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1464951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1464951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}