{"id":1467260,"date":"2025-10-10T08:03:46","date_gmt":"2025-10-10T15:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/"},"modified":"2025-10-10T08:03:46","modified_gmt":"2025-10-10T15:03:46","slug":"jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/","title":{"rendered":"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte?"},"content":{"rendered":"<p>Con su veloz y s\u00fabita destituci\u00f3n por \u201cpermanente incapacidad moral\u201d, la ahora exmandataria de Per\u00fa, Dina Boluarte, se suma a la lista de personas con un breve paso por la Presidencia de Per\u00fa en las \u00faltimas d\u00e9cadas. El pa\u00eds tuvo seis presidentes, entre destituciones, renuncias e interinatos, en los \u00faltimos siete a\u00f1os. Boluarte adem\u00e1s es la cuarta jefa de Estado en ser desplazada por el Congreso en este siglo, luego de Alberto Fujimori, Mart\u00edn Vizcarra y Pedro Castillo.<\/p>\n<p>Este cap\u00edtulo de sucesi\u00f3n acelerada de presidente, que ubica a Per\u00fa entre los pa\u00edses con mayor inestabilidad institucional de Am\u00e9rica latina, comenz\u00f3 cuando Pedro Pablo Kuczynski <a href=\"https:\/\/cnnespanol.cnn.com\/2018\/03\/21\/kuczynski-renuncia-escandalos-odebrecht-vacancia-indulto\/\">renunci\u00f3<\/a> en 2018 tras dos a\u00f1os de gobierno. Su dimisi\u00f3n se produjo en medio de cr\u00edticas por el caso Odebrecht y el indulto que concedi\u00f3 al expresidente Alberto Fujimori, condenado por violaciones a los derechos humanos en su mandato. Mart\u00edn Vizcarra le sucedi\u00f3 y fue presidente desde 2018 hasta 2020, <a href=\"https:\/\/cnnespanol.cnn.com\/video\/vizcarra-martin-peru-vacancia-cogreso-lima-perspectivas-buenos-aires\/\">cuando lo destituy\u00f3 el Congreso<\/a>. Manuel Merino y Francisco Sagasti le siguieron entonces como presidentes interinos. Despu\u00e9s, Pedro Castillo ocup\u00f3 el cargo desde 2021 hasta 2022, <a href=\"https:\/\/cnnespanol.cnn.com\/2022\/12\/07\/congreso-aprueba-vacancia-pedro-castillo-peru-orix\/\">cuando el Congreso lo vac\u00f3<\/a> mientras \u00e9l intentaba disolver al \u00f3rgano legislativo.<\/p>\n<p>Boluarte, quien era la vicepresidenta de Castillo, lo sucedi\u00f3 en el poder durante casi tres a\u00f1os. Y ahora, tras su destituci\u00f3n, el presidente del Congreso, Jos\u00e9 Enrique Jer\u00ed Or\u00e9, asumi\u00f3 como nuevo presidente de la Rep\u00fablica, durante una ceremonia realizada durante esta madrugada.<\/p>\n<p>Ahora Per\u00fa, que realizar\u00e1 elecciones presidenciales en abril pr\u00f3ximo, inaugura otro cap\u00edtulo institucional lleno de preguntas. Estas son las claves que explican los interrogantes que est\u00e1n detr\u00e1s de la remoci\u00f3n de Boluarte y de los desaf\u00edos que le esperan ahora a Jer\u00ed Or\u00e9.<\/p>\n<p>A lo largo de su mandato, Boluarte ya hab\u00eda enfrentado mociones de vacancia, pero hab\u00eda conseguido los suficientes apoyos pol\u00edticos para evitar la destituci\u00f3n.<\/p>\n<p>Eso cambi\u00f3 esta vez. Por la tarde del jueves, el partido opositor Fuerza Popular, dirigido por Keiko Fujimori, hija del expresidente Alberto Fujimori, anunci\u00f3 que apoyar\u00eda la moci\u00f3n para destituirla. Durante el resto de la jornada, otras fuerzas tambi\u00e9n se sumaron.<\/p>\n<p>Al final de la jornada, la moci\u00f3n de vacancia se aprob\u00f3 por un amplio margen: 121 votos de 130 posibles, la mayor cantidad de sufragios obtenida por una medida as\u00ed, por encima de las de Fujimori, Vizcarra y Castillo.<\/p>\n<p>Boluarte acept\u00f3 la decisi\u00f3n, aunque ella y su abogado, Juan Carlos Portugal, dijeron que el Congreso viol\u00f3 el debido proceso porque no dio un tiempo adecuado para que prepararan una defensa frente a las mociones en su contra. Durante la sesi\u00f3n, por el contrario, los congresistas argumentaron que actuaron con apego al reglamento, que permite acelerar los procesos si se re\u00fanen los votos suficientes.<\/p>\n<p>Analistas consultados por CNN consideraron que Boluarte perdi\u00f3 apoyos principalmente debido a dos factores: su baja popularidad y los recientes problemas de inseguridad en Per\u00fa, que han motivado protestas tanto en Lima como en otras ciudades.<\/p>\n<p>X\u00f3chtil Pimienta, profesora del Tecnol\u00f3gico de Monterrey, record\u00f3 que la desaprobaci\u00f3n de Boluarte <a href=\"https:\/\/www.cnn.com\/2025\/05\/18\/americas\/boluarte-nose-surgery-rolex-peru-presidency-intl-latam\">es superior al 90%<\/a>, algo que atribuye a los presuntos casos de corrupci\u00f3n en los que la ahora exmandataria se ha visto involucrada.<\/p>\n<p>\u201cTodo se detona por <a href=\"https:\/\/www.cnn.com\/2024\/03\/30\/world\/boluarte-peru-rolex-police-raid-intl\/\">el esc\u00e1ndalo del \u2018Rolexgate\u2019<\/a>\u201d, dijo Pimienta, en referencia a las investigaciones judiciales abiertas contra Boluarte por presuntamente haber aceptado relojes lujosos y otras joyas como pago por un soborno. Boluarte rechaza estos se\u00f1alamientos, as\u00ed como otros que la implican en posibles actos de corrupci\u00f3n.<\/p>\n<p>El internacionalista Fausto Pretelin consider\u00f3 que la baja popularidad de Boluarte no solo afect\u00f3 su imagen frente a la ciudadan\u00eda, sino tambi\u00e9n su capacidad para tomar decisiones y formar mayor\u00edas pol\u00edticas, un aspecto clave para los presidentes de Per\u00fa debido al poder con el que cuenta el Congreso.<\/p>\n<p>En cuanto a la inseguridad, los analistas destacaron el creciente descontento social por los homicidios y las extorsiones, delitos que a lo largo del a\u00f1o han generado varias protestas. Esta inconformidad se aviv\u00f3 durante las \u00faltimas horas, luego de que el grupo musical Agua Marina fuera atacado a disparos la noche del mi\u00e9rcoles mientras daba un concierto en Lima. Por estos hechos \u2014ampliamente difundidos en redes sociales\u2014, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/09\/latinoamerica\/peru-banda-cumbia-ataque-concierto-efe\">cuatro de sus integrantes resultaron heridos<\/a>.<\/p>\n<p>Boluarte asegura que su Gobierno estaba trabajando para contener a los grupos delictivos. Sin embargo, algunos ciudadanos consideran que no hab\u00eda resultados y que la expresidenta no era emp\u00e1tica con la situaci\u00f3n.<\/p>\n<p>\u201cLo que pas\u00f3 en un concierto donde fueron heridos de bala integrantes de un grupo muy famoso, en un concierto abierto a todo el p\u00fablico, se vuelve s\u00edmbolo de desconexi\u00f3n con la ciudadan\u00eda y, por supuesto, lo aprovecha la oposici\u00f3n y la no oposici\u00f3n para impulsar este proceso, esta figura de la vacancia\u201d, dijo Pimienta.<\/p>\n<p>Algunos reportes de organismos internacionales respaldan la preocupaci\u00f3n ciudadana por la inseguridad en Per\u00fa.<\/p>\n<p>El informe sobre drogas publicado este a\u00f1o por la Oficina de las Naciones Unidas contra la Droga y el Delito (ONUDC) indica que toda Am\u00e9rica Latina \u201ccontin\u00faa sufriendo los niveles m\u00e1s elevados de violencia delictiva de todo el mundo\u201d, derivados principalmente de la actividad de narcotraficantes.<\/p>\n<p>Precisamente contener esa inseguridad creciente, que adem\u00e1s llev\u00f3 a miles de j\u00f3venes de la Generaci\u00f3n Z y a sindicatos a las calles recientemente, ser\u00e1 el gran desaf\u00edo para los pocos meses de gobierno que tiene Jer\u00ed Or\u00e9 por delante.<\/p>\n<p>Minutos despu\u00e9s de que el Congreso aprob\u00f3 destituirla, Boluarte dio un mensaje al pa\u00eds. Acompa\u00f1ada de su Gabinete en el Palacio de Gobierno, defendi\u00f3 su gesti\u00f3n, se describi\u00f3 como una dem\u00f3crata y dijo que el pa\u00eds merece, entre otras cosas, \u201cun crecimiento con estabilidad democr\u00e1tica y un Gobierno que trabaje sin corrupci\u00f3n, como lo hemos venido haciendo\u201d.<\/p>\n<p>Pretelin consider\u00f3 que, debido a su baja popularidad, Boluarte \u201cno tiene ninguna posibilidad de sobrevivencia pol\u00edticamente hablando\u201d, por lo que descart\u00f3 que m\u00e1s adelante pueda tomar otro rol relevante en la vida p\u00fablica de Per\u00fa.<\/p>\n<p>Con ella fuera del cargo, Jer\u00ed Or\u00e9 asumi\u00f3 una Presidencia que tendr\u00e1 entre sus principales tareas, precisamente, crear las condiciones para la pr\u00f3xima sucesi\u00f3n presidencial.<\/p>\n<p>En marzo, la propia Boluarte <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/25\/latinoamerica\/peru-dina-boluarte-convoca-elecciones-generales-orix\">convoc\u00f3 a elecciones para el 12 de abril de 2026<\/a>, una contienda en la cual, a decir de Pimienta, \u201clas fuerzas pol\u00edticas deben estar pensando en qu\u00e9 persona, qu\u00e9 candidato puede generar la unidad que se necesita para devolver la estabilidad al pa\u00eds\u201d.<\/p>\n<p>Al asumir, Jer\u00ed Or\u00e9 tom\u00f3 nota de los reclamos de las calles y de las pol\u00edtica. \u201cEl principal enemigo est\u00e1 afuera, en las calles, las bandas criminales y las organizaciones criminales y como enemigos debemos declararles la guerra\u201d, dijo y asegur\u00f3 que va \u201ca ganar esa guerra\u201d.<\/p>\n<p>La promesa de Jer\u00ed Or\u00e9 ser\u00e1 desafiada por la inseguridad, el malestar en las calles, que no da se\u00f1ales de ceder, y por la inestabilidad de d\u00e9cadas de la pol\u00edtica peruana.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con su veloz y s\u00fabita destituci\u00f3n por \u201cpermanente incapacidad moral\u201d, la ahora exmandataria de Per\u00fa, Dina Boluarte, se suma a la lista de personas con un breve paso por la Presidencia de Per\u00fa en las \u00faltimas d\u00e9cadas. El pa\u00eds tuvo seis presidentes, entre destituciones, renuncias e interinatos, en los \u00faltimos siete a\u00f1os. Boluarte adem\u00e1s es [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467260","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Con su veloz y s\u00fabita destituci\u00f3n por \u201cpermanente incapacidad moral\u201d, la ahora exmandataria de Per\u00fa, Dina Boluarte, se suma a la lista de personas con un breve paso por la Presidencia de Per\u00fa en las \u00faltimas d\u00e9cadas. El pa\u00eds tuvo seis presidentes, entre destituciones, renuncias e interinatos, en los \u00faltimos siete a\u00f1os. Boluarte adem\u00e1s es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T15:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte?\",\"datePublished\":\"2025-10-10T15:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/\"},\"wordCount\":1228,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/\",\"name\":\"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-10T15:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte? - Noticias","og_description":"Con su veloz y s\u00fabita destituci\u00f3n por \u201cpermanente incapacidad moral\u201d, la ahora exmandataria de Per\u00fa, Dina Boluarte, se suma a la lista de personas con un breve paso por la Presidencia de Per\u00fa en las \u00faltimas d\u00e9cadas. El pa\u00eds tuvo seis presidentes, entre destituciones, renuncias e interinatos, en los \u00faltimos siete a\u00f1os. Boluarte adem\u00e1s es [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-10T15:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/"},"author":{"name":"","@id":""},"headline":"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte?","datePublished":"2025-10-10T15:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/"},"wordCount":1228,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/","name":"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-10T15:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Jos\u00e9 Jer\u00ed es el s\u00e9ptimo presidente de Per\u00fa en 7 a\u00f1os. \u00bfQu\u00e9 le espera y por qu\u00e9 cay\u00f3 Boluarte?","url":"http:\/\/noticiasya.com\/aspen\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/10\/10\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-10T15:03:46Z","datePublished":"2025-10-10T15:03:46Z","dateModified":"2025-10-10T15:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Jos\\u00e9 Jer\\u00ed es el s\\u00e9ptimo presidente de Per\\u00fa en 7 a\\u00f1os. \\u00bfQu\\u00e9 le espera y por qu\\u00e9 cay\\u00f3 Boluarte?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/10\\\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/10\\\/jose-jeri-dina-boluarte-destitucion-peru-claves-que-sigue-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-10T15:03:46Z\",\"datePublished\":\"2025-10-10T15:03:46Z\",\"dateModified\":\"2025-10-10T15:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467247,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/09\/dina-boluarte-peru-quien-es-orix\/","url_meta":{"origin":1467260,"position":0},"title":"Qui\u00e9n es Dina Boluarte, la presidenta de Per\u00fa bajo presi\u00f3n por una moci\u00f3n de vacancia en el Congreso","author":"","date":"octubre 9, 2025","format":false,"excerpt":"Cuando Dina Boluarte jur\u00f3 como presidenta de Per\u00fa en diciembre de 2022, hizo historia al convertirse en la primera mujer en ocupar el cargo, con la promesa de poner fin a la corrupci\u00f3n y devolver la estabilidad a un pa\u00eds en crisis.Sin embargo, su mandato, marcado por la represi\u00f3n en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447708,"url":"https:\/\/noticiasya.com\/aspen\/2024\/04\/03\/congreso-peru-voto-confianza-gabinete-crisis-caso-rolex-orix\/","url_meta":{"origin":1467260,"position":1},"title":"El Congreso de Per\u00fa da voto de confianza al gabinete, en medio de crisis por el caso Rolex","author":"","date":"abril 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El gabinete del presidente del Consejo de Ministros de Per\u00fa, Gustavo Adrianz\u00e9n, obtuvo el voto de investidura o voto de confianza de parte del Congreso, gracias al respaldo de 70 parlamentarios. 38 lo rechazaron y 17 se abstuvieron.La mayor\u00eda de votos a favor provino del llamado bloque de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445394,"url":"https:\/\/noticiasya.com\/aspen\/2024\/02\/14\/la-presidenta-boluarte-realiza-4-cambios-en-el-gabinete-de-ministros-de-peru\/","url_meta":{"origin":1467260,"position":2},"title":"La presidenta Boluarte realiza 4 cambios en el gabinete de ministros de Per\u00fa","author":"","date":"febrero 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La presidenta de Per\u00fa, Dina Boluarte, anunci\u00f3 este martes desde el Palacio de Gobierno cambios de sus ministros de Econom\u00eda y Finanzas, Defensa, Ambiente, y Energ\u00eda y Minas.En el Ministerio de Defensa, Walter Astudillo toma el lugar que deja Jorge Luis Ch\u00e1vez; en Econom\u00eda y Finanzas, Jos\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465247,"url":"https:\/\/noticiasya.com\/aspen\/2025\/08\/08\/petro-boluarte-escalan-tensiones-soberania-isla-santa-rosa-orix\/","url_meta":{"origin":1467260,"position":3},"title":"Boluarte y Petro suben la apuesta y se enfrentan por la soberan\u00eda de la isla de Santa Rosa","author":"","date":"agosto 8, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, y la presidenta de Per\u00fa, Dina Boluarte, han escalado en las \u00faltimas horas las tensiones sobre la peque\u00f1a isla de Santa Rosa, que est\u00e1 ubicada en el r\u00edo Amazonas y es el centro de una disputa entre ambos gobiernos.La disputa \u2014en la que Per\u00fa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450730,"url":"https:\/\/noticiasya.com\/aspen\/2024\/06\/26\/peru-jurado-nacional-eleccione-boluarte-2021-orix\/","url_meta":{"origin":1467260,"position":4},"title":"\u201cNo he tenido ning\u00fan acercamiento de ninguna clase\u201d, dice presidente del Jurado Nacional de Elecciones sobre supuesto contacto entre presidenta Boluarte y su instituci\u00f3n durante elecciones de 2021","author":"","date":"junio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Jorge Luis Salas Arenas, presidente del Jurado Nacional de Elecciones (JNE), neg\u00f3 que durante los comicios de 2021 haya tenido contacto con el expresidente Pedro Castillo, la actual presidenta Dina Boluarte o alguna persona vinculada a estos o a Per\u00fa Libre, el partido por el que ambos se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456572,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/13\/boluarte-denuncia-acoso-desestabilizar-orden-peru-orix\/","url_meta":{"origin":1467260,"position":5},"title":"Boluarte denuncia que la acosan para desestabilizar el orden constitucional en Per\u00fa y plantear la vacancia presidencial","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"La presidenta de Per\u00fa, Dina Boluarte, dijo el jueves que lamentaba que dos casos \u201cvinculados a su entorno personal\u201d sean los temas que \u201cmarquen la agenda de un pa\u00eds\u201d. En un mensaje a la naci\u00f3n y acompa\u00f1ada de su gabinete, la mandataria se\u00f1al\u00f3 que estos casos son \u201cutilizados como escenarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1467260"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467260\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1467260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1467260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1467260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}