{"id":1467275,"date":"2025-10-10T15:03:40","date_gmt":"2025-10-10T22:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/"},"modified":"2025-10-10T15:03:40","modified_gmt":"2025-10-10T22:03:40","slug":"consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/","title":{"rendered":"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione"},"content":{"rendered":"<p>El Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas (ONU) <a href=\"https:\/\/webtv.un.org\/es\/asset\/k1l\/k1lamex2ys\">se reuni\u00f3<\/a> este viernes en una sesi\u00f3n de urgencia <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/09\/venezuela\/venezuela-pide-onu-reunion-urgencia-posible-ataque-armado-ee-uu-efe\">a pedido de Venezuela<\/a> en medio de las crecientes tensiones militares en el Caribe.<\/p>\n<p>Caracas anunci\u00f3 el jueves que solicitaba esta reuni\u00f3n por el \u201cataque armado\u201d que se pudiera dar, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/09\/venezuela\/venezuela-pide-onu-reunion-urgencia-posible-ataque-armado-ee-uu-efe\">seg\u00fan dijo<\/a>, por parte de EE.UU. \u201cen un muy corto plazo\u201d.<\/p>\n<p>En la reuni\u00f3n de este viernes, que comenz\u00f3 a las 3 pm ET, Samuel Moncada, representante permanente de Venezuela ante la ONU, dijo que su pa\u00eds \u201cviene hoy aqu\u00ed a exigir al gobierno de Estados Unidos que cumpla con sus obligaciones internacionales\u201d.<\/p>\n<p>Agreg\u00f3 que existen los medios para superar las diferencias entre ambos pa\u00edses y que Venezuela \u201cha estado y estar\u00e1 dispuesto a dialogar con el objeto de superar por la v\u00eda pol\u00edtica y diplom\u00e1tica cualquier dificultad para preservar a nuestra regi\u00f3n como una zona de paz\u201d.<\/p>\n<p>La zona del Caribe cercana a <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/08\/venezuela\/encienden-luces-navidad-venezuela-sombra-conflicto-eeuu-orix\">Venezuela<\/a> ha sido un punto de tensi\u00f3n por los despliegues militares de EE.UU. y los recientes ataques a cuatro botes que, seg\u00fan el gobierno estadounidense, transportaban drogas. El Gobierno de Venezuela ve estas acciones como <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/09\/venezuela\/trump-guerra-carteles-venezuela-siria-iran-orix\">un intento de cambio de r\u00e9gimen de parte de Washington.<\/a><\/p>\n<p>\u201cEstados Unidos cree que el Caribe le pertenece porque tiene m\u00e1s de 100 a\u00f1os usando la expansionista doctrina Monroe, que no es m\u00e1s que un lastre del colonialismo\u201d, agreg\u00f3 Moncada en su mensaje.<\/p>\n<p>En este contexto, Moncada propuso al Consejo de Seguridad de la ONU tres acciones para controlar la situaci\u00f3n entre ambos pa\u00edses:<\/p>\n<ul>\n<li>\u201cQue se determine la existencia de una amenaza a la paz y a la seguridad internacionales por la actual escalada militar del Gobierno de EE.UU. en el Caribe\u201d.<\/li>\n<li>\u201cQue se adopten medidas necesarias para evitar que la situaci\u00f3n sobre el terreno se agrave a\u00fan m\u00e1s\u201d.<\/li>\n<li>\u201cQue se apruebe una resoluci\u00f3n del Consejo de Seguridad en que todos su miembros, incluyendo Estados Unidos, se comprometan a respetar la soberan\u00eda, la independencia y la integralidad territorial\u201d de Venezuela.<\/li>\n<\/ul>\n<p>Por su parte, John Kelley, representante interino de Estados Unidos ante la ONU, dijo que su pa\u00eds \u201cno est\u00e1 en contra del pueblo de Venezuela, que tiene el derecho a estar representado por un gobierno leg\u00edtimo\u201d.<\/p>\n<p>Kelley repiti\u00f3 la acusaci\u00f3n que ha hecho el Gobierno de Donald Trump previamente: que el presidente de Venezuela, Nicol\u00e1s Maduro, \u201ces el l\u00edder de un grupo narcoterrorista, el Cartel de los Soles, y es responsable del tr\u00e1fico de drogas que llegan a Estados Unidos y a Europa\u201d.<\/p>\n<p>Se\u00f1al\u00f3 que Maduro corrompi\u00f3 las instituciones para sacar adelante la operaci\u00f3n de ese cartel.<\/p>\n<p>Moncada coment\u00f3 que esas acusaciones se han hecho \u201csin ninguna evidencia\u201d.<\/p>\n<p>\u201cNunca hemos visto una evidencia ante las acusaciones contra todas nuestras fuerzas armadas, contra todo nuestro pueblo; declaran que hay una invasi\u00f3n, que somos una amenaza sin ninguna evidencia\u201d, dijo el representante venezolano.<\/p>\n<p>El Consejo de Seguridad es<a href=\"https:\/\/cnnespanol.cnn.com\/2023\/03\/31\/analisis-rusia-presidencia-consejo-seguridad-onu-orix\"> uno de los \u00f3rganos m\u00e1s importantes de la ONU, <\/a>creado en 1946 en un intento de contar con las herramientas diplom\u00e1ticas y militares para mantener la paz de una manera asertiva.<\/p>\n<p>Tiene 15 miembros, cinco de los cuales \u2014EE.UU., China, Francia, Reino Unido y Rusia\u2014 son permanentes y poseen poder de veto, mientas los restantes 10 rotan cada dos a\u00f1os.<\/p>\n<p>Pero debido precisamente a esta composici\u00f3n el Consejo de Seguridad<a href=\"https:\/\/cnnespanol.cnn.com\/2023\/03\/31\/analisis-rusia-presidencia-consejo-seguridad-onu-orix\"> no ha tenido los efectos esperados,<\/a> ya que no se pueden tomar decisiones contundentes sin el apoyo de los 5 miembros permanentes, que pueden vetarse mutuamente las resoluciones.<\/p>\n<p>Y considerando que<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/08\/13\/analisis-rusia-china-maduro-elecciones-intereses-venezuela-orix\"> China y Rusia son aliados del Gobierno de Venezuela,<\/a> que enfrenta ahora a Estados Unidos, es muy dif\u00edcil que el Consejo de Seguridad pueda rompar la inercia esta vez.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas (ONU) se reuni\u00f3 este viernes en una sesi\u00f3n de urgencia a pedido de Venezuela en medio de las crecientes tensiones militares en el Caribe. Caracas anunci\u00f3 el jueves que solicitaba esta reuni\u00f3n por el \u201cataque armado\u201d que se pudiera dar, seg\u00fan dijo, por parte [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467275","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas (ONU) se reuni\u00f3 este viernes en una sesi\u00f3n de urgencia a pedido de Venezuela en medio de las crecientes tensiones militares en el Caribe. Caracas anunci\u00f3 el jueves que solicitaba esta reuni\u00f3n por el \u201cataque armado\u201d que se pudiera dar, seg\u00fan dijo, por parte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T22:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione\",\"datePublished\":\"2025-10-10T22:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/\"},\"wordCount\":681,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/\",\"name\":\"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-10T22:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione - Noticias","og_description":"El Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas (ONU) se reuni\u00f3 este viernes en una sesi\u00f3n de urgencia a pedido de Venezuela en medio de las crecientes tensiones militares en el Caribe. Caracas anunci\u00f3 el jueves que solicitaba esta reuni\u00f3n por el \u201cataque armado\u201d que se pudiera dar, seg\u00fan dijo, por parte [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-10T22:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/"},"author":{"name":"","@id":""},"headline":"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione","datePublished":"2025-10-10T22:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/"},"wordCount":681,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/","name":"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-10T22:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione","url":"http:\/\/noticiasya.com\/aspen\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/10\/10\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-10T22:03:40Z","datePublished":"2025-10-10T22:03:40Z","dateModified":"2025-10-10T22:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Venezuela apela al Consejo de Seguridad de la ONU para intentar frenar a EE.UU. en el Caribe. Es poco probable que funcione\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/10\\\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/10\\\/consejo-seguridad-onu-sesion-urgencia-eeuu-caribe-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-10T22:03:40Z\",\"datePublished\":\"2025-10-10T22:03:40Z\",\"dateModified\":\"2025-10-10T22:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467452,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/16\/venezuela-pide-consejo-seguridad-onu-investigue-ataques-ee-uu-caribe-orix\/","url_meta":{"origin":1467275,"position":0},"title":"Venezuela pide a Consejo de Seguridad de ONU que investigue ataques de EE.UU. en el Caribe &#171;y determine su car\u00e1cter ilegal&#187;","author":"","date":"octubre 16, 2025","format":false,"excerpt":"El Gobierno de Venezuela pidi\u00f3 este jueves al Consejo de Seguridad de la ONU que investigue los recientes ataques que Estados Unidos ha realizado contra embarcaciones en el mar Caribe \u201cy determine su car\u00e1cter ilegal\u201d, as\u00ed como se\u00f1alar que estas y otras acciones estadounidenses son una \u201camenaza\u201d para la paz\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458408,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/07\/deportaciones-venezuela-orix\/","url_meta":{"origin":1467275,"position":1},"title":"Deportaciones de EE.UU. a Venezuela empezar\u00e1n dentro de los pr\u00f3ximos 30 d\u00edas, seg\u00fan Homan","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Una semana despu\u00e9s del encuentro del presidente Nicol\u00e1s Maduro con Richard Grenell, enviado del presidente Donald Trump, en el que se discutieron temas migratorios, entre otras cosas, el \u201czar de la frontera\u201d, Tom Homan, ofreci\u00f3 la primera l\u00ednea de tiempo sobre el plan de deportaciones a Venezuela.En una entrevista con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469344,"url":"https:\/\/noticiasya.com\/aspen\/2025\/12\/17\/sheinbaum-punto-negociacion-reunion-evitar-conflicto-eeuu-venezuela-orix\/","url_meta":{"origin":1467275,"position":2},"title":"Sheinbaum dice que M\u00e9xico podr\u00eda ser &#171;punto de negociaci\u00f3n y reuni\u00f3n&#187; para evitar un conflicto entre EE.UU. y Venezuela","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este mi\u00e9rcoles que su pa\u00eds y los dem\u00e1s que integran Am\u00e9rica Latina podr\u00edan buscar un di\u00e1logo que evite \u201ccualquier conflicto en la regi\u00f3n\u201d, en medio de la escalada en las tensiones entre Estados Unidos y Venezuela.Asimismo, la mandataria coment\u00f3 que, si las partes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456582,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","url_meta":{"origin":1467275,"position":3},"title":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"El Alto Comisionado para los Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas (ONU), Volker T\u00fcrk, dijo estar \u201cprofundamente preocupado\u201d por la situaci\u00f3n pol\u00edtica en Venezuela, a cuatro meses y medio de las controvertidas elecciones presidenciales del 28 de julio y a menos de un mes del comienzo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467130,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/05\/venezuela-rusia-ataques-estados-unidos-efe\/","url_meta":{"origin":1467275,"position":4},"title":"Venezuela expone a Rusia la situaci\u00f3n de seguridad en el Caribe ante &#171;amenazas&#187; de EE.UU.","author":"","date":"octubre 5, 2025","format":false,"excerpt":"El canciller de Venezuela, Yv\u00e1n Gil, expuso este domingo a su hom\u00f3logo de Rusia, Sergu\u00e9i Lavrov, la situaci\u00f3n de seguridad en el Caribe ante las \u201camenazas\u201d que, dijo, representa el despliegue naval de Estados Unidos, que mantiene al menos ocho buques de guerra y un submarino de ataque r\u00e1pido cerca\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452916,"url":"https:\/\/noticiasya.com\/aspen\/2024\/09\/21\/argentina-seis-paises-gobierno-venezolano-fin-represion-onu-orix\/","url_meta":{"origin":1467275,"position":5},"title":"Argentina y otros seis pa\u00edses instan al gobierno venezolano a poner fin a la represi\u00f3n ante el Consejo de DD.HH. de la ONU","author":"","date":"septiembre 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El representante de Argentina ante las Naciones Unidas en Ginebra, Carlos Foradori, inst\u00f3 a Venezuela en el Consejo de Derechos Humanos a liberar a quienes han sido detenidos arbitrariamente y a poner fin a la represi\u00f3n y persecuci\u00f3n por cuestiones pol\u00edticas, inform\u00f3 la Canciller\u00eda argentina este viernes.Ecuador\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1467275"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467275\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1467275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1467275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1467275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}