{"id":1467289,"date":"2025-10-11T05:03:41","date_gmt":"2025-10-11T12:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/"},"modified":"2025-10-11T05:03:41","modified_gmt":"2025-10-11T12:03:41","slug":"espana-alojamiento-turistico-alquiler-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/","title":{"rendered":"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial"},"content":{"rendered":"<p>En Madrid, como en otras ciudades espa\u00f1olas, la poblaci\u00f3n se expresa muchas veces a trav\u00e9s de los balcones. Al pasear por el centro de la ciudad, no es extra\u00f1o apreciar algunas barandillas donde cuelgan banderas LGTBI o de Palestina. Particularmente en el c\u00e9ntrico barrio de Lavapi\u00e9s, donde desde hace un tiempo algunos vecinos tambi\u00e9n han empezado a colgar carteles mostrando su rechazo a los pisos tur\u00edsticos.<\/p>\n<p>\u201cEst\u00e1n echando a los vecinos con el aumento de los precios del alquiler\u201d, reclama ante CNN Manuel Osuna, que lleva 60 a\u00f1os viviendo en este barrio. Tiempo suficiente para presenciar c\u00f3mo una mayor llegada de turismo ha terminado por impactar la vida en el barrio, dado que \u201cantes los vecinos pod\u00edan bajar a un bar a ver el f\u00fatbol, pero ahora la mayor\u00eda de los bares son franquicias y les interesan m\u00e1s los turistas\u201d, asegura.<\/p>\n<p>Lavapi\u00e9s se engloba dentro del distrito centro de Madrid, convertido hoy en d\u00eda en el que mayor n\u00famero de viviendas tur\u00edsticas acoge respecto al total de las censadas, seg\u00fan los datos m\u00e1s recientes del Instituto Nacional de Estad\u00edstica (<a href=\"https:\/\/ine.es\/portalgis\/apps\/webappviewer\/index.html?id=e6350afcd6644e7aa10fdd6dca2e701c\">INE<\/a>). Concretamente, <a href=\"https:\/\/www.ine.es\/jaxiT3\/Tabla.htm?t=39363\">6.146 viviendas <\/a>se destinan a este uso, lo que representa el 7,11 % del total de las censadas en esta divisi\u00f3n administrativa.<\/p>\n<p>As\u00ed las cosas, el malestar expresado por Osuna, plasmado tambi\u00e9n en las manifestaciones masivas contra los efectos nocivos del turismo de masas que se han celebrado en ciudades como Madrid, Barcelona o Palma de Mallorca, ha sido asumido por el propio Gobierno espa\u00f1ol, que ha tomado la iniciativa de limitar la proliferaci\u00f3n de viviendas de uso tur\u00edstico que no cumplan con la legalidad vigente.<\/p>\n<p>A mediados de septiembre, el Ejecutivo liderado por Pedro S\u00e1nchez solicit\u00f3 a las diferentes plataformas digitales <a href=\"https:\/\/www.mivau.gob.es\/el-ministerio\/sala-de-prensa\/noticias\/lun-15092025-0933\">que retiraran 53.876 alojamientos tur\u00edsticos \u201cilegales\u201d de sus portales web<\/a> con el objetivo de que pasen a engrosar las filas de apartamentos destinados al alquiler permanente.<\/p>\n<p>Para detectar estos alojamientos, el Gobierno parti\u00f3 de la medida que obliga desde julio de 2025 a que los arrendadores registren sus viviendas de uso tur\u00edstico ante el Colegio de Registradores con el fin de obtener un c\u00f3digo de registro que les permita operar legalmente.<\/p>\n<p>\u201cQuer\u00edamos poner orden en el desorden que exist\u00eda hasta entonces de las viviendas y apartamentos tur\u00edsticos\u201d, destacaba S\u00e1nchez al respecto de esta normativa.<\/p>\n<p>De esta forma, las solicitudes presentadas ante el Colegio de Registradores que contengan datos incompletos o no acordes a la normativa vigente pierden la capacidad de operar en el mercado.<\/p>\n<p>Airbnb, una de las plataformas situadas en la mira del Gobierno, se\u00f1al\u00f3 poco despu\u00e9s de conocerse esta orden de retirada que la mayor\u00eda de los anuncios que tienen activos en Espa\u00f1a ya muestran un n\u00famero de registro y que menos del 10 % de los alojamientos a los que el Colegio de Registradores les revoc\u00f3 su c\u00f3digo de registro siguen activos en sus listados, aunque proceder\u00e1n a darlos de baja.<\/p>\n<p>\u201cCreemos que nuestra contribucio\u0301n ayudara\u0301 a dar forma a un futuro sostenible para los alquileres a corto plazo en Espan\u0303a y hacemos un llamamiento a otras plataformas para que se unan a los esfuerzos de transparencia que Airbnb esta\u0301 llevando a cabo con las autoridades locales\u201d, sen\u0303alaba en un comunicado Jaime Rodri\u0301guez, director general de marketing de la plataforma en Espan\u0303a.<\/p>\n<p>\u201cLa idea es buena\u201d, valora Osuna, pero mantiene cierto recelo sobre el futuro de estas miles de viviendas, ya que, a pesar de haber perdido su capacidad para anunciarse en plataformas conocidas, teme que \u201cbusquen otras formas de publicitarse\u201d para seguir siendo alquiladas por turistas.<\/p>\n<p>A nivel nacional, el INE <a href=\"https:\/\/ine.es\/portalgis\/apps\/webappviewer\/index.html?id=e6350afcd6644e7aa10fdd6dca2e701c\">contabiliza <\/a><a href=\"https:\/\/www.ine.es\/jaxiT3\/Datos.htm?t=39364\">381.837 viviendas<\/a> tur\u00edsticas, lo que representa 60.000 m\u00e1s que las registradas casi cinco a\u00f1os atr\u00e1s, en agosto de 2020,<a href=\"https:\/\/ine.es\/portalgis\/apps\/webappviewer\/index.html?id=3237ec12bece45d6a6ce24649e40856f\"> suponiendo un 1,43 % de las viviendas censadas en todo el pa\u00eds.<\/a><\/p>\n<p>La queja de muchos vecinos es que la proliferaci\u00f3n de este tipo de viviendas, junto al d\u00e9ficit de hogares que existe en el pa\u00eds \u2014 que el Banco de Espa\u00f1a estima entorno a 400.000 y 450.000 viviendas \u2014 y la especulaci\u00f3n inmobiliaria han complicado el panorama.<\/p>\n<p>Sin ir m\u00e1s lejos, el precio del alquiler se ha casi duplicado a nivel nacional en tan solo una d\u00e9cada, seg\u00fan datos del portal inmobiliario <a href=\"https:\/\/www.idealista.com\/sala-de-prensa\/informes-precio-vivienda\/alquiler\/\">Idealista<\/a>. El precio del metro cuadrado del alquiler ha pasado de los 7,5 euros en septiembre de 2015 a 14,5 euros en septiembre de 2025.<\/p>\n<p>En cuanto a la compra, el precio del metro cuadrado se ha incrementado a nivel nacional un 65 % en 10 a\u00f1os, pasando de los 1.522 euros en septiembre de 2015 a 2.517 euros en septiembre de este a\u00f1o.<\/p>\n<p>Estos datos muestran que cada vez es m\u00e1s dif\u00edcil comprar o alquilar un espacio en Espa\u00f1a al que llamar hogar.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Madrid, como en otras ciudades espa\u00f1olas, la poblaci\u00f3n se expresa muchas veces a trav\u00e9s de los balcones. Al pasear por el centro de la ciudad, no es extra\u00f1o apreciar algunas barandillas donde cuelgan banderas LGTBI o de Palestina. Particularmente en el c\u00e9ntrico barrio de Lavapi\u00e9s, donde desde hace un tiempo algunos vecinos tambi\u00e9n han [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467289","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial - Noticias\" \/>\n<meta property=\"og:description\" content=\"En Madrid, como en otras ciudades espa\u00f1olas, la poblaci\u00f3n se expresa muchas veces a trav\u00e9s de los balcones. Al pasear por el centro de la ciudad, no es extra\u00f1o apreciar algunas barandillas donde cuelgan banderas LGTBI o de Palestina. Particularmente en el c\u00e9ntrico barrio de Lavapi\u00e9s, donde desde hace un tiempo algunos vecinos tambi\u00e9n han [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-11T12:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial\",\"datePublished\":\"2025-10-11T12:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/\"},\"wordCount\":845,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/\",\"name\":\"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-11T12:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial - Noticias","og_description":"En Madrid, como en otras ciudades espa\u00f1olas, la poblaci\u00f3n se expresa muchas veces a trav\u00e9s de los balcones. Al pasear por el centro de la ciudad, no es extra\u00f1o apreciar algunas barandillas donde cuelgan banderas LGTBI o de Palestina. Particularmente en el c\u00e9ntrico barrio de Lavapi\u00e9s, donde desde hace un tiempo algunos vecinos tambi\u00e9n han [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-11T12:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/"},"author":{"name":"","@id":""},"headline":"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial","datePublished":"2025-10-11T12:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/"},"wordCount":845,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/","name":"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-11T12:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El cerco al alojamiento tur\u00edstico: Espa\u00f1a prev\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial","url":"http:\/\/noticiasya.com\/aspen\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/10\/11\/espana-alojamiento-turistico-alquiler-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-11T12:03:41Z","datePublished":"2025-10-11T12:03:41Z","dateModified":"2025-10-11T12:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El cerco al alojamiento tur\\u00edstico: Espa\\u00f1a prev\\u00e9 incorporar 53.000 de estas viviendas al alquiler residencial\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/11\\\/espana-alojamiento-turistico-alquiler-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/11\\\/espana-alojamiento-turistico-alquiler-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-11T12:03:41Z\",\"datePublished\":\"2025-10-11T12:03:41Z\",\"dateModified\":\"2025-10-11T12:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459727,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/10\/cristian-munoz-vecino-de-bahia-blanca-el-agua-supero-el-metro-de-altura\/","url_meta":{"origin":1467289,"position":0},"title":"Cristian Mu\u00f1\u00f3z, vecino de Bah\u00eda Blanca: &#171;El agua super\u00f3 el metro de altura&#187;","author":"","date":"marzo 10, 2025","format":false,"excerpt":"Cristian Mu\u00f1\u00f3z, uno de los vecinos del barrio Boulevard de Bah\u00eda Blanca que perdi\u00f3 todas las cosas de la casa por la inundaci\u00f3n, habl\u00f3 este lunes en CNN Radio con Nacho Gir\u00f3n en La Ma\u00f1ana de CNN sobre\u201cEl agua fue tan r\u00e1pida que no nos dieron las manos para subir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473801,"url":"https:\/\/noticiasya.com\/aspen\/2026\/05\/05\/madrid-gentrificacion-salamaca-latinos-orix\/","url_meta":{"origin":1467289,"position":1},"title":"&#171;Cambian Miami por Madrid&#187;: las fortunas latinoamericanas gentrifican el barrio m\u00e1s exclusivo de la capital de Espa\u00f1a","author":"","date":"mayo 5, 2026","format":false,"excerpt":"Toda gran ciudad que se precie tiene su zona dedicada al lujo. En Nueva York, la Quinta Avenida. En Paris, los Campos El\u00edseos. Y en Madrid, destaca la zona conocida como \u201cMilla de Oro\u201d, un entramado de calles situadas en el distrito de Salamanca donde se concentran algunas de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473467,"url":"https:\/\/noticiasya.com\/aspen\/2026\/04\/24\/viviendas-propietarios-inquilinos-batalla-politica-trax\/","url_meta":{"origin":1467289,"position":2},"title":"Propietarios contra inquilinos: la batalla pol\u00edtica por las viviendas unifamiliares en Estados Unidos","author":"","date":"abril 24, 2026","format":false,"excerpt":"La casa de Mona Gass se encuentra en medio de la compleja pol\u00edtica de la crisis de vivienda en Estados Unidos.Gass, de 72 a\u00f1os, paga US$ 2.500 al mes por una casa unifamiliar de tres habitaciones que comparte con su madre de 94 a\u00f1os. Es una de las decenas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464164,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/02\/turistificacion-auge-turistico-expulsa-residentes-orix\/","url_meta":{"origin":1467289,"position":3},"title":"Turistificaci\u00f3n: c\u00f3mo el auge tur\u00edstico transforma y expulsa a algunos residentes de los destinos","author":"","date":"julio 2, 2025","format":false,"excerpt":"En Donostia-San Sebasti\u00e1n, Espa\u00f1a, ya no es lo mismo caminar por el barrio y es dif\u00edcil encontrar una vivienda a un precio accesible. El turismo, que parec\u00eda una bendici\u00f3n para la econom\u00eda local tras la pandemia de covid-19, ha empezado a sentirse como una invasi\u00f3n.Este fen\u00f3meno tiene nombre: turistificaci\u00f3n. Ocurre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465939,"url":"https:\/\/noticiasya.com\/aspen\/2025\/08\/28\/guardia-nacional-washington-redadas-miedo-orix\/","url_meta":{"origin":1467289,"position":4},"title":"Por miedo a la Guardia Nacional y a las redadas, este vibrante barrio latino de Washington se apaga y sus calles se vac\u00edan","author":"","date":"agosto 28, 2025","format":false,"excerpt":"Hace d\u00edas que el negocio est\u00e1 m\u00e1s lento para Ana, una vendedora de frutas en Columbia Heights que pidi\u00f3 no dar su apellido por seguridad, una de las zonas en Washington D.C. con mayor poblaci\u00f3n hispana. \u201cPues algunas personas pr\u00e1cticamente ni est\u00e1n viniendo\u2019, dice Ana, preocupada por la disminuci\u00f3n en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471587,"url":"https:\/\/noticiasya.com\/aspen\/2026\/02\/24\/respuesta-minnesota-ofensiva-ice-ayuda-mutua-trax\/","url_meta":{"origin":1467289,"position":5},"title":"\u00bfQu\u00e9 pueden aprender otros estados de la respuesta de Minnesota frente a la ofensiva de ICE?","author":"","date":"febrero 24, 2026","format":false,"excerpt":"El aumento de agentes federales de inmigraci\u00f3n en Minnesota durante los \u00faltimos meses dej\u00f3 a muchas personas no solo traumatizadas sino tambi\u00e9n en dificultades econ\u00f3micas.Las personas perdieron ingresos porque ten\u00edan demasiado miedo de ir a trabajar o porque su sost\u00e9n de familia fue secuestrado por agentes del Servicio de Inmigraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1467289"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467289\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1467289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1467289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1467289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}