{"id":1467290,"date":"2025-10-11T06:03:40","date_gmt":"2025-10-11T13:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/"},"modified":"2025-10-11T06:03:40","modified_gmt":"2025-10-11T13:03:40","slug":"explosion-fabrica-municiones-tennessee-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/","title":{"rendered":"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos"},"content":{"rendered":"<p>En la madrugada del viernes, una atronadora explosi\u00f3n en una planta de municiones militares e industriales reson\u00f3 en una comunidad del centro de Tennessee, arrasando con un edificio entero y causando la muerto de un n\u00famero a\u00fan desconocido de personas.<\/p>\n<p>Al menos 18 personas siguen desaparecidas tras la explosi\u00f3n que hizo temblar a las viviendas que se encontraban a kil\u00f3metros de distancia y esparci\u00f3 escombros por al menos 800 metros cuadrados. Las autoridades han reconocido a las v\u00edctimas mortales, pero se negaron a proporcionar una cifra de lo que sigui\u00f3 siendo una escena ca\u00f3tica mucho despu\u00e9s de la explosi\u00f3n.<\/p>\n<p>\u201cNecesitamos que nuestras comunidades se unan y comprendan que hemos perdido a mucha gente. Esto no solo afecta a esas familias, sino que tiene un origen m\u00e1s profundo\u2026 podr\u00edan ser personas con las que crecieron\u201d, declar\u00f3 el sheriff del condado de Humphreys, Chris Davis, al se\u00f1alar que una de las v\u00edctimas era un amigo de su infancia.<\/p>\n<p>La explosi\u00f3n ocurri\u00f3 durante un turno de ma\u00f1ana en <a href=\"https:\/\/www.aesys.biz\/\">Accurate Energetic Systems <\/a>(AES), un fabricante de explosivos militares y de materiales de demolici\u00f3n que emplea a decenas de residentes locales.<\/p>\n<p>\u201cNecesitamos oraciones\u2026 estamos destrozados por las familias y los seres queridos que perdieron la vida\u201d, declar\u00f3 Wendall Stinson, CEO de la f\u00e1brica, junto con las autoridades el viernes.<\/p>\n<p>La explosi\u00f3n desencaden\u00f3 una serie de estallidos menores, seg\u00fan las autoridades, y la causa a\u00fan se encuentra bajo investigaci\u00f3n.<\/p>\n<p>Esto es lo que sabemos mientras la investigaci\u00f3n contin\u00faa:<\/p>\n<p>La explosi\u00f3n ocurri\u00f3 alrededor de las 7:45 a.m., hora local, y despert\u00f3 a residentes a kil\u00f3metros de distancia.<\/p>\n<p>\u201cPens\u00e9 que la casa se hab\u00eda derrumbado conmigo dentro\u201d, declar\u00f3 Gentry Stover a The Associated Press, al explicar el sobresalto.<\/p>\n<p>Solo tard\u00f3 unos instantes en reconstruir lo sucedido. \u201cVivo muy cerca de Accurate (Energetic Systems) y me di cuenta unos 30 segundos despu\u00e9s de despertarme de que ten\u00eda que haber sido eso\u201d.<\/p>\n<p>Las autoridades informaron que la explosi\u00f3n se sinti\u00f3 hasta a 24 kil\u00f3metros de distancia, pero Cody Warren, quien vive a m\u00e1s de 32 kil\u00f3metros de la planta, declar\u00f3 a CNN que el ruido lo despert\u00f3 y que al principio pens\u00f3 que un rayo hab\u00eda ca\u00eddo en su casa.<\/p>\n<p>\u201cSal\u00ed y a\u00fan pod\u00eda o\u00edr el sonido a lo lejos. Pens\u00e9 que tal vez era un terremoto o la explosi\u00f3n de un meteorito\u201d, declar\u00f3 Warren a CNN.<\/p>\n<p>M\u00e1s cerca de la planta, escombros carbonizados y veh\u00edculos destrozados se extend\u00edan por una vasta zona. El sheriff Davis la calific\u00f3 como \u201cla escena m\u00e1s devastadora que he visto en mi carrera\u201d.<\/p>\n<p>Se les ha pedido a los residentes que encuentren escombros que llamen a su sheriff local \u201cpara que personal capacitado pueda intervenir de forma segura\u201d. Las autoridades solicitan a todos que eviten la zona cercana a la planta mientras los equipos de emergencia realizan su trabajo.<\/p>\n<p>M\u00e1s de 300 efectivos de emergencia estuvieron en el lugar en el punto \u00e1lgido de la emergencia del viernes, informaron las autoridades.<\/p>\n<p>Se desconoce cu\u00e1ntas personas hab\u00eda dentro de la planta cuando ocurri\u00f3 la explosi\u00f3n, declar\u00f3 el alcalde del condado de Hickman, Jim Bates.<\/p>\n<p>\u201cSer\u00e1 una investigaci\u00f3n que probablemente durar\u00e1 d\u00edas\u201d, dijo Bates.<\/p>\n<p>La Oficina Federal de Alcohol, Tabaco, Armas de Fuego y Explosivos (ABTF) enviar\u00e1 un equipo de respuesta que se espera llegue este s\u00e1bado, informaron las autoridades locales. La ATF y las oficinas del sheriff de los condados de Hickman y Humphreys codirigir\u00e1n la investigaci\u00f3n, que tambi\u00e9n incluir\u00e1 al FBI, seg\u00fan informaron las autoridades.<\/p>\n<p>En un comunicado emitido el viernes por la noche, AES calific\u00f3 la explosi\u00f3n como un \u201caccidente tr\u00e1gico\u201d y expres\u00f3: \u201cNuestros pensamientos y oraciones est\u00e1n con las familias, compa\u00f1eros de trabajo y miembros de la comunidad afectados por este incidente\u201d.<\/p>\n<p>Hasta el viernes por la noche, las autoridades segu\u00edan trabajando para contactar a algunos de los familiares de los empleados que se cree que estaban dentro del edificio en el momento de la explosi\u00f3n, seg\u00fan inform\u00f3 una fuente policial a CNN.<\/p>\n<p>Como parte de las labores para determinar qu\u00e9 empleados de la compa\u00f1\u00eda podr\u00edan estar entre las v\u00edctimas, la fuente indic\u00f3 que las autoridades tambi\u00e9n est\u00e1n analizando los registros de las torres de telefon\u00eda celular cercanas.<\/p>\n<p>El sofisticado proceso consiste en comparar los n\u00fameros de tel\u00e9fono celular de los empleados con los registros de las torres de telefon\u00eda celular locales para determinar la ubicaci\u00f3n geogr\u00e1fica de un dispositivo en el momento de la explosi\u00f3n.<\/p>\n<p>El sheriff Davis se\u00f1al\u00f3 que los miembros de la comunidad estaban pasando por una profunda crisis emocional, ya que muchos esperaban noticias de sus seres queridos.<\/p>\n<p>\u201cEntiendo que algunas familias se enfaden. Entiendo que algunas personas se alteren\u2026 Estamos haciendo todo lo posible para solucionarlo\u201d, declar\u00f3 Davis.<\/p>\n<p>Accurate Energetic Systems fabrica \u201cdiversas composiciones de alto explosivo y productos especializados\u201d para los mercados militar e industrial de EE.UU., seg\u00fan su p\u00e1gina de Facebook. La planta de AES emplea a unas 80 personas, seg\u00fan el alcalde del condado de Hickman.<\/p>\n<p>Adem\u00e1s, la planta se extiende a lo largo de 527 hect\u00e1reas en una zona rural y boscosa junto a la Interestatal 40, a unos 96 kil\u00f3metros al oeste de Nashville, cerca del l\u00edmite entre los condados de Hickman y Humphreys, seg\u00fan informaron las autoridades.<\/p>\n<p>La zona relativamente remota donde se ubica la planta suele estar patrullada por departamentos policiales m\u00e1s peque\u00f1os, por lo que otras agencias han ofrecido recursos de apoyo, seg\u00fan inform\u00f3 una fuente a CNN.<\/p>\n<p>El sitio consta de cinco edificios de producci\u00f3n y \u201cun laboratorio de calidad para la evaluaci\u00f3n y el an\u00e1lisis de productos\u201d, seg\u00fan un perfil de la empresa publicado por la organizaci\u00f3n no gubernamental Asociaci\u00f3n del Ej\u00e9rcito de Estados Unidos, que incluye a AES como patrocinador.<\/p>\n<p>El mes pasado, el Departamento de Defensa otorg\u00f3 a AES un contrato de casi US$ 120 millones \u201cpara la adquisici\u00f3n de TNT\u201d.<\/p>\n<p>El senador estatal de Tennessee, Kerry Roberts, declar\u00f3 a CNN que el due\u00f1o de la empresa es un empleador muy querido por muchos, y sus trabajadores suelen lucir gorras de b\u00e9isbol con el logotipo de la empresa en eventos comunitarios.<\/p>\n<p>\u201cEs una empresa muy querida en la zona\u201d, afirm\u00f3 Roberts. Esto tendr\u00e1 un impacto devastador en varias familias.<\/p>\n<p>La planta ha sufrido accidentes mortales en el pasado y ha enfrentado multas federales relacionadas con pr\u00e1cticas que incumpl\u00edan normas de seguridad laboral, seg\u00fan informes de prensa y datos federales.<\/p>\n<p>En abril de 2014, una explosi\u00f3n en las instalaciones mat\u00f3 a un trabajador e hiri\u00f3 a otros cuatro, inform\u00f3 WSMV, afiliada de CNN. La explosi\u00f3n, ocurrida en la parte trasera de un edificio utilizado para municiones de escopeta, caus\u00f3 graves da\u00f1os. En ese momento, las autoridades informaron que varias empresas operaban en la propiedad y que la explosi\u00f3n ocurri\u00f3 en un \u00e1rea administrada por R\u00edo Ammunition.<\/p>\n<p>A\u00f1os despu\u00e9s, la Administraci\u00f3n de Seguridad y Salud Ocupacional mult\u00f3 a la empresa con US$ 7.200, despu\u00e9s de que una inspecci\u00f3n de 2019 detectara infracciones relacionadas con el equipo de protecci\u00f3n personal, la exposici\u00f3n de los empleados a contaminantes y una capacitaci\u00f3n inadecuada en seguridad, entre otras citaciones.<\/p>\n<p>La empresa impugn\u00f3 las conclusiones, seg\u00fan consta en los registros de la OSHA, y finalmente lleg\u00f3 a un acuerdo formal. Los detalles sobre la inspecci\u00f3n y sus conclusiones son limitados, y no est\u00e1 claro si la planta se ha enfrentado a revisiones de salud o seguridad m\u00e1s recientes.<\/p>\n<p>Los registros muestran que la empresa ha reportado 46 lesiones laborales desde 2016, el primer a\u00f1o registrado. No se reportaron muertes laborales durante este per\u00edodo. En 2024, el a\u00f1o m\u00e1s reciente con datos disponibles, la empresa report\u00f3 cinco lesiones y una enfermedad.<\/p>\n<p>En 2021, un exempleado demand\u00f3 a la empresa alegando despido injustificado tras ser culpado de un incendio ocurrido en las instalaciones el a\u00f1o anterior. La empresa impugn\u00f3 la demanda y el caso fue desestimado tras una mediaci\u00f3n.<\/p>\n<p>La explosi\u00f3n de Tennessee es un duro recordatorio de la larga historia de accidentes laborales mortales en las peque\u00f1as ciudades estadounidenses. Esta historia incluye el desastre de Texas City en 1947, cuando un barco que transportaba nitrato de amonio explot\u00f3 y mat\u00f3 a casi 600 personas, y la explosi\u00f3n de una planta de fertilizantes en West, Texas, en 2013, que caus\u00f3 la muerte de 15. Una ola de accidentes industriales de alto perfil en la d\u00e9cada de 1960 impuls\u00f3 la acci\u00f3n legislativa, lo que condujo a la creaci\u00f3n de la OSHA, promulgada por el presidente Richard Nixon.<\/p>\n<p>Una peque\u00f1a multitud se reuni\u00f3 para una vigilia el viernes por la noche en un parque cercano, sosteniendo velas mientras oraban por los desaparecidos y sus familias, uniendo sus voces para cantar \u201cAmazing Grace\u201d, inform\u00f3 AP.<\/p>\n<p>El sheriff del condado de Humphreys dijo que el incidente afect\u00f3 directamente a la comunidad.<\/p>\n<p>\u201cHay tres familias involucradas en esto con las que tengo una relaci\u00f3n muy cercana. En condados peque\u00f1os como este, nos conocemos\u2026 nos queremos\u201d, dijo Davis.<\/p>\n<p>Tres personas con \u201cheridas leves\u201d fueron atendidas en las instalaciones m\u00e9dicas TriStar en Dickson, seg\u00fan un portavoz de TriStar Health. Dos fueron dadas de alta, mientras que una permanec\u00eda en observaci\u00f3n en una sala de emergencias hasta la noche del viernes, dijo el portavoz.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la madrugada del viernes, una atronadora explosi\u00f3n en una planta de municiones militares e industriales reson\u00f3 en una comunidad del centro de Tennessee, arrasando con un edificio entero y causando la muerto de un n\u00famero a\u00fan desconocido de personas. Al menos 18 personas siguen desaparecidas tras la explosi\u00f3n que hizo temblar a las viviendas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467290","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos - Noticias\" \/>\n<meta property=\"og:description\" content=\"En la madrugada del viernes, una atronadora explosi\u00f3n en una planta de municiones militares e industriales reson\u00f3 en una comunidad del centro de Tennessee, arrasando con un edificio entero y causando la muerto de un n\u00famero a\u00fan desconocido de personas. Al menos 18 personas siguen desaparecidas tras la explosi\u00f3n que hizo temblar a las viviendas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-11T13:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos\",\"datePublished\":\"2025-10-11T13:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/\"},\"wordCount\":1649,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/\",\"name\":\"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-11T13:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos - Noticias","og_description":"En la madrugada del viernes, una atronadora explosi\u00f3n en una planta de municiones militares e industriales reson\u00f3 en una comunidad del centro de Tennessee, arrasando con un edificio entero y causando la muerto de un n\u00famero a\u00fan desconocido de personas. Al menos 18 personas siguen desaparecidas tras la explosi\u00f3n que hizo temblar a las viviendas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-11T13:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/"},"author":{"name":"","@id":""},"headline":"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos","datePublished":"2025-10-11T13:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/"},"wordCount":1649,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/","name":"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-11T13:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una explosi\u00f3n en una planta de municiones de Tennessee destruy\u00f3 un edificio y dej\u00f3 18 desaparecidos. Esto es lo que sabemos","url":"http:\/\/noticiasya.com\/aspen\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/10\/11\/explosion-fabrica-municiones-tennessee-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-11T13:03:40Z","datePublished":"2025-10-11T13:03:40Z","dateModified":"2025-10-11T13:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una explosi\\u00f3n en una planta de municiones de Tennessee destruy\\u00f3 un edificio y dej\\u00f3 18 desaparecidos. Esto es lo que sabemos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/11\\\/explosion-fabrica-municiones-tennessee-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/11\\\/explosion-fabrica-municiones-tennessee-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-11T13:03:40Z\",\"datePublished\":\"2025-10-11T13:03:40Z\",\"dateModified\":\"2025-10-11T13:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456915,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/24\/explosion-fabrica-explosivos-turquia-trax\/","url_meta":{"origin":1467290,"position":0},"title":"Una explosi\u00f3n en una f\u00e1brica de explosivos en Turqu\u00eda deja m\u00e1s de una decena de muertos","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"Al menos 12 personas murieron este martes en una explosi\u00f3n en una f\u00e1brica de explosivos y municiones en el noroeste de Turqu\u00eda, seg\u00fan ha informado el Ministerio del Interior del pa\u00eds.Las autoridades locales excluyeron la posibilidad de sabotaje, inform\u00f3 la filial de CNN, CNN Turk.Al menos otras cuatro personas resultaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467269,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/10\/explosion-planta-militar-tennessee-muertos-trax\/","url_meta":{"origin":1467290,"position":1},"title":"Enorme explosi\u00f3n en planta militar de Tennessee deja varias personas muertas y desaparecidas","author":"","date":"octubre 10, 2025","format":false,"excerpt":"Varias personas murieron y algunas m\u00e1s est\u00e1n desaparecidas tras una explosi\u00f3n en una empresa militar de municiones en Tennessee, seg\u00fan informaron las autoridades locales.\u201cTenemos algunas personas fallecidas, podemos confirmar que hay algunas fallecidas\u201d, declar\u00f3 el sheriff del condado de Humphreys, Chris Davis, en una conferencia de prensa este viernes.David Stewart,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467338,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/13\/que-paso-explosion-mortal-planta-de-tennessee-trax\/","url_meta":{"origin":1467290,"position":2},"title":"\u00bfQu\u00e9 pas\u00f3 en la explosi\u00f3n mortal en una planta de Tennessee? As\u00ed va la investigaci\u00f3n","author":"","date":"octubre 13, 2025","format":false,"excerpt":"Casi tres d\u00edas despu\u00e9s de una explosi\u00f3n enorme en una instalaci\u00f3n de Tennessee especializada en la fabricaci\u00f3n de explosivos militares, los investigadores siguen revisando el sitio donde 16 personas murieron en una \u201cdetonaci\u00f3n gigante\u201d tan significativa que produjo lecturas s\u00edsmicas a cientos de kil\u00f3metros de distancia, seg\u00fan expertos.Investigadores de varias\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446910,"url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/12\/explosion-china-mata-una-persona-deja-22-heridos-trax\/","url_meta":{"origin":1467290,"position":3},"title":"Gran explosi\u00f3n en un restaurante en China mata al menos a una persona y deja 22 heridos","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN) --\u00a0 Una presunta explosi\u00f3n mortal de gas arras\u00f3 un barrio residencial en el norte de China este mi\u00e9rcoles, dejando escenas de devastaci\u00f3n y varias personas heridas.La potente explosi\u00f3n ocurri\u00f3 justo antes de las 8 a.m. en un restaurante en la planta baja en una zona residencial de la ciudad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456348,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/07\/explosion-edificio-paises-bajos-trax\/","url_meta":{"origin":1467290,"position":4},"title":"Al menos cuatro personas hospitalizadas tras una explosi\u00f3n en un edificio de apartamentos en Pa\u00edses Bajos","author":"","date":"diciembre 7, 2024","format":false,"excerpt":"Al menos cuatro personas fueron trasladadas al hospital tras una explosi\u00f3n en un edificio de apartamentos en La Haya, Pa\u00edses Bajos, este s\u00e1bado, seg\u00fan las autoridades.La explosi\u00f3n tuvo lugar sobre las 6.15 hora local, seg\u00fan los bomberos, y provoc\u00f3 el derrumbe parcial y el incendio de un edificio de apartamentos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455919,"url":"https:\/\/noticiasya.com\/aspen\/2024\/11\/19\/explosion-fabrica-louisville-causada-recipiente-de-coccion-defectuoso-trax\/","url_meta":{"origin":1467290,"position":5},"title":"La explosi\u00f3n de una f\u00e1brica en Louisville fue causada por un recipiente de cocci\u00f3n defectuoso, dicen las autoridades","author":"","date":"noviembre 19, 2024","format":false,"excerpt":"(CNN) -- La explosi\u00f3n de una f\u00e1brica que mat\u00f3 a dos trabajadores en Louisville, Kentucky, la semana pasada fue causada por un recipiente de cocina defectuoso, dijeron funcionarios este lunes.\"Fue un accidente industrial y no hay indicios de que alguien haya hecho algo intencional para provocar la explosi\u00f3n\", dijo Shawn\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1467290"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467290\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1467290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1467290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1467290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}