{"id":1467299,"date":"2025-10-11T17:03:48","date_gmt":"2025-10-12T00:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/"},"modified":"2025-10-11T17:03:48","modified_gmt":"2025-10-12T00:03:48","slug":"cdc-enfrentan-drasticos-recortes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/","title":{"rendered":"&#171;El da\u00f1o es irreparable&#187;: los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal"},"content":{"rendered":"<p>Los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC, por sus siglas en ingl\u00e9s) sufrieron otra ronda de dr\u00e1sticos recortes de personal la noche del viernes, con epidemi\u00f3logos, especialistas previsores de brotes y oficinas de pol\u00edticas y datos entre los afectados, seg\u00fan cuatro fuentes con conocimiento de los despidos.<\/p>\n<p>\u201cLa administraci\u00f3n no quer\u00eda que los datos de los CDC no respaldaran su narrativa, as\u00ed que los despidieron. No les gustaba que los grupos de pol\u00edticas de los CDC no aprobaran sin cuestionar sus ideas no cient\u00edficas, as\u00ed que los despidieron\u201d, dijo un funcionario de la agencia que pidi\u00f3 no ser identificado por temor a perder su empleo.<\/p>\n<p>La nueva ronda de despidos ocurre un mes despu\u00e9s de que el secretario de Salud y Servicios Humanos de EE.UU., Robert F. Kennedy Jr., pidiera \u201csangre nueva\u201d en la agencia.<\/p>\n<p>\u201cEs imperativo que eliminemos a los funcionarios con conflictos de inter\u00e9s, juicios catastr\u00f3ficamente err\u00f3neos y agendas pol\u00edticas\u201d, dijo Kennedy en su testimonio ante el Comit\u00e9 de Finanzas del Senado en septiembre. \u201cNecesitamos ciencia imparcial, libre de pol\u00edtica, transparente y basada en la evidencia en inter\u00e9s p\u00fablico. Esos son los principios rectores detr\u00e1s de los cambios en los CDC, y eso es lo que pueden esperar en toda nuestra agencia durante los pr\u00f3ximos tres a\u00f1os\u201d.<\/p>\n<p>Los avisos se enviaron por correo electr\u00f3nico poco despu\u00e9s de las 9 p.m. de un fin de semana festivo, siguiendo un patr\u00f3n favorecido por el Gobierno Trump de realizar despidos de empleados federales fuera del horario laboral normal. Los empleados afectados dijeron que la medida fue especialmente cruel durante un cierre del Gobierno, lo que dificult\u00f3 a\u00fan m\u00e1s obtener informaci\u00f3n sobre la indemnizaci\u00f3n, ya que muchos empleados federales no estaban en sus oficinas ni pod\u00edan responder correos electr\u00f3nicos.<\/p>\n<p>El presidente Donald Trump dijo la tarde del viernes que planea despedir a \u201cmuchos\u201d empleados federales en represalia por el cierre del Gobierno, prometiendo enfocarse en aquellos considerado<a href=\"https:\/\/www.cnn.com\/politics\/live-news\/government-shutdown-news-10-10-25?post-id=cmglf1iyb00003b6npyjnr3u3\">s alineados con el Partido Dem\u00f3crata.<\/a><\/p>\n<p>\u201cCreemos que ellos comenzaron esto, as\u00ed que deben estar orientados hacia los dem\u00f3cratas\u201d, dijo Trump, culpando a los legisladores dem\u00f3cratas por el cierre del Gobierno. Trump no dio detalles sobre qu\u00e9 calificaba a los empleados afectados como \u201corientados hacia los dem\u00f3cratas\u201d.<\/p>\n<p>Un<a href=\"https:\/\/storage.courtlistener.com\/recap\/gov.uscourts.cand.457131\/gov.uscourts.cand.457131.39.0_1.pdf\"> documento judicial<\/a> en ese caso indica que m\u00e1s de 4.100 empleados federales se vieron afectados por los recortes, entre 1.100 y 1.200 del Departamento de Salud y Servicios Humanos (HHS, por sus siglas en ingl\u00e9s). Hasta la tarde del viernes, tambi\u00e9n se hab\u00edan enviado avisos de RIF (reducciones de personal) a empleados de los departamentos de Comercio, Educaci\u00f3n, Energ\u00eda, Vivienda y Desarrollo Urbano, Seguridad Nacional y Tesoro, seg\u00fan portavoces de los departamentos, representantes sindicales y fuentes directamente afectadas.<\/p>\n<p>La legalidad de despedir empleados federales durante un cierre del Gobierno tambi\u00e9n est\u00e1 en discusi\u00f3n. Poco despu\u00e9s de que el director de la Oficina de Administraci\u00f3n y Presupuesto, Russell Vought, publicara en X el viernes: \u201cLos RIF han comenzado\u201d, la Federaci\u00f3n Estadounidense de Empleados Gubernamentales, el sindicato que representa a los empleados federales,<a href=\"https:\/\/x.com\/AFGENational\/status\/1976691283705114927\"> respondi\u00f3: \u201cLa demanda ha sido presentada\u201d.<\/a><\/p>\n<p>Las cifras exactas de recortes en los CDC a\u00fan se est\u00e1n evaluando. La Dra. Debra Houry, quien recientemente renunci\u00f3 como directora cient\u00edfica y subdirectora de programas y ciencia de la agencia, dijo que en enero los CDC ten\u00edan 13.674 empleados. Antes de los recortes del viernes, hab\u00eda 11.400. Con unos 1.100 recortes proyectados, quedar\u00e1n alrededor de 10.300, se\u00f1al\u00f3.<\/p>\n<p>El Servicio de Inteligencia Epidemiol\u00f3gica (EIS, por sus siglas en ingl\u00e9s) de los CDC, que capacita a los reconocidos \u201cdetectives de enfermedades\u201d de la agencia, perdi\u00f3 al menos a 30 miembros de su personal que coordinan el programa y a 40 oficiales de EIS que estaban en su segundo a\u00f1o de formaci\u00f3n, seg\u00fan un segundo funcionario de la agencia que pidi\u00f3 no ser identificado por temor a represalias. El EIS se hab\u00eda salvado en una ronda anterior de recortes realizada en abril.<\/p>\n<p>Los despidos se producen mientras el pa\u00eds se dirige a la temporada invernal de virus respiratorios, una \u00e9poca en la que infecciones como el virus respiratorio sincitial (VRS), la influenza y el covid-19 provocan un aumento de hospitalizaciones y muertes. Los recortes significan que habr\u00e1 menos expertos monitoreando la gravedad de la temporada y qu\u00e9 ciudades y estados son los m\u00e1s afectados.<\/p>\n<p>\u201cEl da\u00f1o es irreparable\u201d, dijo Daskalakis. \u201cDebilitar a los CDC, incluso como una t\u00e1ctica para crear presi\u00f3n pol\u00edtica para poner fin al cierre del Gobierno, significa que Estados Unidos est\u00e1 a\u00fan menos preparado para brotes y amenazas de enfermedades infecciosas\u201d.<\/p>\n<p>Todo el personal del informe semanal Informe semanal sobre morbilidad y mortalidad de la agencia, una revista conocida como MMWR que ha publicado datos de vigilancia sobre la salud nacional durante m\u00e1s de un siglo, tambi\u00e9n fue despedido, seg\u00fan Houry.<\/p>\n<p>\u201cNo es radicalmente transparente si la agencia no puede comunicarse. Recortar cosas como el MMWR impedir\u00e1 que los cient\u00edficos comuniquen sobre temas cl\u00ednicos y cient\u00edficos urgentes\u201d, dijo Houry.<\/p>\n<p>Tambi\u00e9n hubo recortes de personal de apoyo, incluyendo personas que organizan viajes y seguridad para los cient\u00edficos de los CDC que trabajan en brotes internacionales. La Oficina de Seguridad y Gesti\u00f3n de Activos de la agencia tambi\u00e9n se vio afectada, a pesar de que su personal recibi\u00f3 recientemente elogios por evitar que un hombre armado accediera al campus durante un tiroteo en agosto en el que muri\u00f3 un agente de Polic\u00eda del condado de DeKalb, David Rose, y dej\u00f3 varios edificios del campus con cientos de agujeros de bala.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC, por sus siglas en ingl\u00e9s) sufrieron otra ronda de dr\u00e1sticos recortes de personal la noche del viernes, con epidemi\u00f3logos, especialistas previsores de brotes y oficinas de pol\u00edticas y datos entre los afectados, seg\u00fan cuatro fuentes con conocimiento de los despidos. \u201cLa administraci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467299","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;El da\u00f1o es irreparable&quot;: los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;El da\u00f1o es irreparable&quot;: los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC, por sus siglas en ingl\u00e9s) sufrieron otra ronda de dr\u00e1sticos recortes de personal la noche del viernes, con epidemi\u00f3logos, especialistas previsores de brotes y oficinas de pol\u00edticas y datos entre los afectados, seg\u00fan cuatro fuentes con conocimiento de los despidos. \u201cLa administraci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-12T00:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;El da\u00f1o es irreparable&#187;: los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal\",\"datePublished\":\"2025-10-12T00:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/\"},\"wordCount\":1006,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/\",\"name\":\"\\\"El da\u00f1o es irreparable\\\": los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-12T00:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;El da\u00f1o es irreparable&#187;: los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"El da\u00f1o es irreparable\": los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\"El da\u00f1o es irreparable\": los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal - Noticias","og_description":"Los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC, por sus siglas en ingl\u00e9s) sufrieron otra ronda de dr\u00e1sticos recortes de personal la noche del viernes, con epidemi\u00f3logos, especialistas previsores de brotes y oficinas de pol\u00edticas y datos entre los afectados, seg\u00fan cuatro fuentes con conocimiento de los despidos. \u201cLa administraci\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-12T00:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/"},"author":{"name":"","@id":""},"headline":"&#171;El da\u00f1o es irreparable&#187;: los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal","datePublished":"2025-10-12T00:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/"},"wordCount":1006,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/","name":"\"El da\u00f1o es irreparable\": los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-12T00:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;El da\u00f1o es irreparable&#187;: los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;El da\u00f1o es irreparable&#187;: los CDC enfrentan otra ronda de dr\u00e1sticos recortes de personal","url":"http:\/\/noticiasya.com\/aspen\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/10\/11\/cdc-enfrentan-drasticos-recortes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-12T00:03:48Z","datePublished":"2025-10-12T00:03:48Z","dateModified":"2025-10-12T00:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;El da\\u00f1o es irreparable&#187;: los CDC enfrentan otra ronda de dr\\u00e1sticos recortes de personal\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/11\\\/cdc-enfrentan-drasticos-recortes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/11\\\/cdc-enfrentan-drasticos-recortes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-12T00:03:48Z\",\"datePublished\":\"2025-10-12T00:03:48Z\",\"dateModified\":\"2025-10-12T00:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467314,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/12\/restituyen-personal-despedido-cdc-trax\/","url_meta":{"origin":1467299,"position":0},"title":"M\u00e1s de la mitad del personal de los CDC recientemente despedido por la administraci\u00f3n Trump ha sido reintegrado","author":"","date":"octubre 12, 2025","format":false,"excerpt":"Cientos de empleados de los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC, por sus siglas en ingl\u00e9s) despedidos el viernes por la noche fueron reincorporados, seg\u00fan la Federaci\u00f3n Estadounidense de Empleados Gubernamentales (AFGE, pro sus siglas en ingl\u00e9s).Tras una nueva ronda de notificaciones de despido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460421,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/25\/lideres-cdc-se-marcharan-recortes-profundos-trax\/","url_meta":{"origin":1467299,"position":1},"title":"Cinco altos l\u00edderes de los CDC dejan la agencia de salud p\u00fablica que se prepara para recortes masivos","author":"","date":"marzo 25, 2025","format":false,"excerpt":"Cinco l\u00edderes de una divisi\u00f3n clave de los Centros para el Control y la Prevenci\u00f3n de Enfermedades (CDC, por sus siglas en ingl\u00e9s) de EE.UU. est\u00e1n dejando la agencia de salud p\u00fablica mientras se prepara para recortes que podr\u00edan afectar hasta un tercio de su fuerza laboral.Las salidas, anunciadas internamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467371,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/","url_meta":{"origin":1467299,"position":2},"title":"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.?","author":"","date":"octubre 14, 2025","format":false,"excerpt":"Douglas Jackson, un veterano discapacitado en servicio que fue despedido durante los recortes federales del viernes, no pod\u00eda creerlo cuando escuch\u00f3 al vicepresidente decir que el Gobierno de Trump se ve\u00eda obligado a elegir entre los estadounidenses y los \u201cbur\u00f3cratas federales\u201d.\u201cSoy un veterano de Orlando. No soy un bur\u00f3crata de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458762,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/14\/despidos-personal-nuclear-supervisan-arsenal-armas-trax\/","url_meta":{"origin":1467299,"position":3},"title":"Funcionarios de Trump despidieron al personal nuclear sin saber que supervisan el arsenal de armas de EE.UU., seg\u00fan fuentes","author":"","date":"febrero 14, 2025","format":false,"excerpt":"Funcionarios del Gobierno de Trump despidieron a m\u00e1s de 300 empleados el jueves por la noche en la Administraci\u00f3n Nacional de Seguridad Nuclear (NNSA, por sus siglas en ingl\u00e9s), la agencia encargada de gestionar el arsenal nuclear del pa\u00eds, como parte de despidos m\u00e1s amplios en el Departamento de Energ\u00eda,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459082,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/22\/trump-musk-divierten-recortes-acumulan-trax\/","url_meta":{"origin":1467299,"position":4},"title":"AN\u00c1LISIS | Trump y Musk se divierten en Washington mientras los recortes se acumulan en el pa\u00eds","author":"","date":"febrero 22, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, y Elon Musk parecen estar disfrutando en Washington, eliminando elementos del Gobierno federal y arrebatando poder a los estados y al Congreso.Su regocijo contrasta con la creciente evidencia de repercusiones y enfado en el pa\u00eds por su enfoque de recortar primero y preguntar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470696,"url":"https:\/\/noticiasya.com\/aspen\/2026\/01\/31\/analisis-despidos-amazon-asombrosos-trax\/","url_meta":{"origin":1467299,"position":5},"title":"Los despidos en Amazon son sorprendentes. Ya lo hemos visto antes","author":"","date":"enero 31, 2026","format":false,"excerpt":"Las grandes tecnol\u00f3gicas siguen lidiando con despidos masivos, el m\u00e1s reciente con el anuncio de Amazon de recortar 16.000 empleos. Es una tendencia que comenz\u00f3 mucho antes de la carrera de la IA: el cambio organizacional provocado por la llegada de las nuevas tecnolog\u00edas.Los gigantes tecnol\u00f3gicos prosperan o fracasan seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1467299"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467299\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1467299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1467299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1467299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}