{"id":1467321,"date":"2025-10-12T19:03:38","date_gmt":"2025-10-13T02:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/"},"modified":"2025-10-12T19:03:38","modified_gmt":"2025-10-13T02:03:38","slug":"familias-militares-incertidumbre-pago-cierre-del-gobierno-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/","title":{"rendered":"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno"},"content":{"rendered":"<p>Bashtye Bailey estaba de pie bajo el c\u00e1lido sol de octubre en un banco de alimentos para familias militares cerca de la Estaci\u00f3n Naval de Norfolk, la base naval m\u00e1s grande del mundo. Esperaba su turno para recibir una provisi\u00f3n de verduras frescas, pollo y huevos.<\/p>\n<p>Esposa de un marino y veterana ella misma, Bailey ya se estaba preparando para no recibir su pago el mi\u00e9rcoles, un temor que amenazaba con convertirse en una responsabilidad pol\u00edtica tan grande que el presidente Donald Trump orden\u00f3 el s\u00e1bado al Departamento de Defensa encontrar otros fondos para asegurar que el pago militar contin\u00fae la pr\u00f3xima semana.<\/p>\n<p>\u201cYa hemos recortado en ciertas cosas y ciertos gastos\u201d, dijo Bailey, quien agreg\u00f3 que el pago de su esposo suele ser apenas suficiente para salir adelante.<\/p>\n<p>El cierre del Gobierno es el m\u00e1s reciente desaf\u00edo para los miembros de las fuerzas armadas y empleados federales despu\u00e9s de un a\u00f1o tumultuoso marcado por despidos, licencias y reasignaciones de trabajo. Los pagos de algunos empleados civiles dejaron de llegar el viernes, y 1,3 millones de militares en servicio activo estaban programados para seguir la misma suerte esta semana a menos que la acci\u00f3n de Trump entrara en vigor.<\/p>\n<p>La amenaza inminente de pagos perdidos a\u00fan no hab\u00eda obligado al Congreso y la Casa Blanca a llegar a un compromiso para reabrir el Gobierno cuando Trump dijo el s\u00e1bado que la administraci\u00f3n hab\u00eda \u201cidentificado fondos\u201d para pagar a los militares el 15 de octubre.<\/p>\n<p>Los fondos para los pagos militares se tomar\u00e1n del dinero de investigaci\u00f3n y desarrollo del Pent\u00e1gono que est\u00e1 disponible por dos a\u00f1os, seg\u00fan un portavoz de la Oficina de Administraci\u00f3n y Presupuesto de la Casa Blanca. Un creciente grupo bipartidista de legisladores ha estado instando sin \u00e9xito a los l\u00edderes del Congreso a aprobar una medida independiente para pagar a los militares durante el cierre.<\/p>\n<p>Ecos de ira y ansiedad resuenan en las conversaciones en el sureste de Virginia, donde el Gobierno de EE.UU. es la savia econ\u00f3mica de la regi\u00f3n de Hampton Roads, con 85.000 militares en servicio activo, 58.000 empleados civiles federales y un sinn\u00famero de contratistas gubernamentales.<\/p>\n<p>Aqu\u00ed, a unos 320 kil\u00f3metros al sur de la capital del pa\u00eds, las consecuencias inmediatas son m\u00e1s pr\u00e1cticas que pol\u00edticas. Las discusiones sobre el aumento de las primas de atenci\u00f3n m\u00e9dica y sobre si Trump y los republicanos o los dem\u00f3cratas tienen m\u00e1s culpa a medida que el cierre se prolonga quedan opacadas por las preocupaciones econ\u00f3micas de la comunidad.<\/p>\n<p>\u201cPronto lo ver\u00e1s en la calle principal de aqu\u00ed\u201d, dijo Bob McNab, profesor de econom\u00eda en la Universidad Old Dominion en Norfolk. \u201cTu vecino o el vecino de tu vecino probablemente no est\u00e1 recibiendo su pago. Y eso se manifiesta en dolor bastante r\u00e1pido e intensamente\u201d.<\/p>\n<p>McNab dijo que aproximadamente US$ 4 de cada US$ 10 gastados en la regi\u00f3n est\u00e1n directa o indirectamente relacionados con el Gobierno federal. El dolor econ\u00f3mico de un cierre de un mes podr\u00eda ser al menos de US$ 1.000 millones si los trabajadores reciben pago retroactivo, dijo, pero considerando que muchos contratistas del Gobierno no lo recibir\u00e1n, los costos probablemente ser\u00e1n mucho m\u00e1s altos.<\/p>\n<p>\u201cSi no se les reembolsa, volvemos a p\u00e9rdidas potenciales que ascienden a miles de millones si el cierre dura cinco semanas o m\u00e1s\u201d, dijo McNab. \u201cHay un verdadero efecto domin\u00f3\u201d.<\/p>\n<p>Richard Maigue ya est\u00e1 friendo menos smashburgers en Kitchenfinity, un acogedor restaurante que \u00e9l y su esposa poseen justo afuera de la Estaci\u00f3n Naval. Un flujo constante de comensales uniformados y civiles se detuvo a almorzar en una tarde reciente, pero Maigue teme que el negocio disminuya si el pago no llega el mi\u00e9rcoles.<\/p>\n<p>\u201cNo s\u00e9 si ellos viven de cheque en cheque, pero creo que es parte de la vida que intentan salir adelante\u201d, dijo Maigue. \u201cTodos necesitan comer, pero probablemente intentar\u00e1n recortar gastos en alg\u00fan lado\u201d.<\/p>\n<p>Maricen Corrales, quien abri\u00f3 el restaurante con su esposo hace dos a\u00f1os, dijo que le preocupan sus clientes habituales que est\u00e1n soportando dificultades debido al cierre. Pero tambi\u00e9n teme por el destino de su propio peque\u00f1o negocio, que ya enfrenta altos costos por el precio de los alimentos y otros suministros.<\/p>\n<p>\u201cMa\u00f1ana, no sabemos\u2026 c\u00f3mo podremos sobrevivir si no vienen clientes\u201d, dijo ella. \u201cPero de cualquier manera, seguiremos ofreciendo el excelente servicio y comida mientras podamos\u201d.<\/p>\n<p>A principios de este mes, el presidente visit\u00f3 la regi\u00f3n, donde habl\u00f3 ante miles de marineros a bordo del USS George H.W. Bush para conmemorar el 250 aniversario de la Infanter\u00eda de Marina. Trump ofreci\u00f3 una promesa durante su discurso de una hora, diciendo: \u201cLes conseguiremos a nuestros miembros del servicio hasta el \u00faltimo centavo. No se preocupen por eso. No se preocupen\u201d.<\/p>\n<p>Al d\u00eda siguiente, hab\u00eda mucha preocupaci\u00f3n entre quienes hac\u00edan fila en un banco de alimentos m\u00f3vil para familias militares.<\/p>\n<p>\u201cNos pagan cada dos semanas, as\u00ed que si no nos pagan despu\u00e9s de eso, puede empezar a convertirse en una situaci\u00f3n realmente estresante y un verdadero desaf\u00edo\u201d, dijo Kady Frazier, quien se est\u00e1 preparando para no recibir el pago de su familia esta semana. \u201cRealmente no entiendo por qu\u00e9 sigue sucediendo y por qu\u00e9 no podemos simplemente mantener el Gobierno funcionando\u201d.<\/p>\n<p>Frazier, quien est\u00e1 casada con un t\u00e9cnico de la Marina, sosten\u00eda a uno de sus hijos mientras esperaba para entrar al mercado m\u00f3vil Hunger Heroes, un programa del Banco de Alimentos del Sureste de Virginia y la Costa Este. Los organizadores se est\u00e1n preparando para una mayor demanda a medida que el cierre se prolonga.<\/p>\n<p>\u201cDefinitivamente anticipamos que habr\u00e1 m\u00e1s necesidad si el cierre del Gobierno contin\u00faa por m\u00e1s tiempo\u201d, dijo Mallory Rackling, directora de comunicaciones del banco de alimentos. \u201cCuando el cierre de 2018 dur\u00f3 unos 35 d\u00edas, nuestras filas aumentaron significativamente. Mucha gente acud\u00eda a nosotros por primera vez\u201d.<\/p>\n<p>El \u00faltimo cierre del Gobierno, que dur\u00f3 m\u00e1s de un mes durante la primera administraci\u00f3n de Trump, a\u00fan est\u00e1 grabado en la mente de muchas familias militares. Mientras Bailey esperaba su turno para recibir verduras, pollo y huevos, dijo que de repente est\u00e1 reviviendo ese per\u00edodo mientras cuenta los d\u00edas hasta que el pago de su familia vuelva a faltar.<\/p>\n<p>\u201cFue muy estresante,\u201d dijo Bailey. \u201cRezo para que esta vez no se prolongue tantos d\u00edas\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bashtye Bailey estaba de pie bajo el c\u00e1lido sol de octubre en un banco de alimentos para familias militares cerca de la Estaci\u00f3n Naval de Norfolk, la base naval m\u00e1s grande del mundo. Esperaba su turno para recibir una provisi\u00f3n de verduras frescas, pollo y huevos. Esposa de un marino y veterana ella misma, Bailey [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467321","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno - Noticias\" \/>\n<meta property=\"og:description\" content=\"Bashtye Bailey estaba de pie bajo el c\u00e1lido sol de octubre en un banco de alimentos para familias militares cerca de la Estaci\u00f3n Naval de Norfolk, la base naval m\u00e1s grande del mundo. Esperaba su turno para recibir una provisi\u00f3n de verduras frescas, pollo y huevos. Esposa de un marino y veterana ella misma, Bailey [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-13T02:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno\",\"datePublished\":\"2025-10-13T02:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/\"},\"wordCount\":1151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/\",\"name\":\"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-13T02:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno - Noticias","og_description":"Bashtye Bailey estaba de pie bajo el c\u00e1lido sol de octubre en un banco de alimentos para familias militares cerca de la Estaci\u00f3n Naval de Norfolk, la base naval m\u00e1s grande del mundo. Esperaba su turno para recibir una provisi\u00f3n de verduras frescas, pollo y huevos. Esposa de un marino y veterana ella misma, Bailey [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-13T02:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/"},"author":{"name":"","@id":""},"headline":"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno","datePublished":"2025-10-13T02:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/"},"wordCount":1151,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/","name":"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-13T02:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Familias de militares en EE.UU. enfrenan tensi\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno","url":"http:\/\/noticiasya.com\/aspen\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/10\/12\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-13T02:03:38Z","datePublished":"2025-10-13T02:03:38Z","dateModified":"2025-10-13T02:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Familias de militares en EE.UU. enfrenan tensi\\u00f3n e incertidumbre por su pago mientras se prolonga el cierre del Gobierno\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/12\\\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/12\\\/familias-militares-incertidumbre-pago-cierre-del-gobierno-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-13T02:03:38Z\",\"datePublished\":\"2025-10-13T02:03:38Z\",\"dateModified\":\"2025-10-13T02:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467295,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/11\/republicanos-cierre-gobierno-presion-partido-trax\/","url_meta":{"origin":1467321,"position":0},"title":"L\u00edderes republicanos se mantienen firmes en su postura sobre el cierre del Gobierno pese a la creciente presi\u00f3n en el partido","author":"","date":"octubre 11, 2025","format":false,"excerpt":"Los principales republicanos en el Congreso de Estados Unidos se arriesgar\u00e1n enormemente con la pol\u00edtica de cierre del Gobierno en los pr\u00f3ximos d\u00edas: los l\u00edderes del Partido Republicano no intervendr\u00e1n para evitar que las Fuerzas Armadas dejen de recibir su salario.Es la medida m\u00e1s dram\u00e1tica hasta ahora por parte del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471735,"url":"https:\/\/noticiasya.com\/aspen\/2026\/02\/27\/cierre-parcial-gobierno-pago-tsa-trax\/","url_meta":{"origin":1467321,"position":1},"title":"Inicio del cierre parcial del Gobierno afecta el pago de los trabajadores de la TSA","author":"","date":"febrero 27, 2026","format":false,"excerpt":"Los trabajadores de la Administraci\u00f3n de Seguridad en el Transporte (TSA, por sus siglas en ingl\u00e9s) recibir\u00e1n solo una parte de su pr\u00f3ximo pago, que est\u00e1 previsto que reciban tan pronto como este viernes, seg\u00fan un funcionario sindical. La reducci\u00f3n se produce mientras el cierre parcial del Gobierno entra en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456921,"url":"https:\/\/noticiasya.com\/aspen\/2024\/12\/24\/irs-cheque-estimulo-trax\/","url_meta":{"origin":1467321,"position":2},"title":"El IRS est\u00e1 enviando dinero a un mill\u00f3n de contribuyentes en Estados Unidos que no lo esperan","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"\u00bfA qui\u00e9n no podr\u00eda servirle un poco de dinero extra en enero sin tener que mover un dedo?Un mill\u00f3n de contribuyentes pronto recibir\u00e1n una carta del Servicio de Impuestos Internos de Estados Unidos (IRS, por sus siglas en ingl\u00e9s) indicando que tienen dinero por recibir porque eran elegibles para recibir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469386,"url":"https:\/\/noticiasya.com\/aspen\/2025\/12\/18\/trump-cheques-1-776-militares-trax\/","url_meta":{"origin":1467321,"position":3},"title":"Trump anuncia el env\u00edo de cheques de US$ 1.776 a casi un mill\u00f3n y medio de militares antes de Navidad","author":"","date":"diciembre 18, 2025","format":false,"excerpt":"El presidente Donald Trump anunci\u00f3 el mi\u00e9rcoles que emitir\u00e1 cheques para miembros de las Fuerzas Armadas con un valor de $1.776 \u2014 en honor al a\u00f1o de la independencia de Estados Unidos\u2014, a los que denomin\u00f3 \u201cdividendo del guerrero\u201d.\u201c1.450.000 militares recibir\u00e1n un dividendo especial, al que llamamos \u2018dividendo del guerrero\u2019,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467438,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/16\/quieres-tramitar-o-renovar-tu-parole-tendras-que-pagar-una-tarifa-de-ususd-1-000\/","url_meta":{"origin":1467321,"position":4},"title":"\u00bfQuieres tramitar o renovar tu &#171;parole&#187;? Tendr\u00e1s que pagar una tarifa de US$ 1.000","author":"","date":"octubre 16, 2025","format":false,"excerpt":"Si est\u00e1s pensando en tramitar o renovar tu parole en Estados Unidos, debes comenzar a considerar una nueva tarifa de US$ 1.000.Desde este jueves, todos los extranjeros que soliciten parole tendr\u00e1n que pagar esa cantidad para poder obtenerlo, seg\u00fan un aviso del Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467174,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/07\/cierre-del-gobierno-golpea-contratistas-federales-trax\/","url_meta":{"origin":1467321,"position":5},"title":"&#171;No s\u00e9 c\u00f3mo voy a alimentar a mis hijos&#187;: el cierre del Gobierno golpea duramente a los contratistas federales","author":"","date":"octubre 7, 2025","format":false,"excerpt":"Audrey Murray est\u00e1 perdiendo el sue\u00f1o por el cierre del Gobierno que pronto podr\u00eda descarrilar sus cheques de pago.Murray, de 65 a\u00f1os, ha trabajado como limpiadora en el Museo Smithsonian de Historia Estadounidense durante casi tres d\u00e9cadas. Ahora se encuentra entre los cientos de miles de contratistas del Gobierno federal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1467321"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467321\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1467321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1467321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1467321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}