{"id":1467326,"date":"2025-10-12T20:03:39","date_gmt":"2025-10-13T03:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/"},"modified":"2025-10-12T20:03:39","modified_gmt":"2025-10-13T03:03:39","slug":"entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/","title":{"rendered":"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas"},"content":{"rendered":"<p>La familia de Norlan Guzm\u00e1n Fuentes recibi\u00f3 el f\u00e9retro con sus restos mortales la noche del domingo en una de las terminales del aeropuerto internacional de El Salvador.<\/p>\n<p>Guzm\u00e1n, de 37 a\u00f1os, es uno de los fallecidos durante el tiroteo en una oficina local del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas a finales de septiembre.<\/p>\n<p>La familia de Guzm\u00e1n lleg\u00f3 a la terminal a\u00e9rea para recibir el cuerpo y trasladarlo a la comunidad Ciudad Romero, en Jiquilisco, departamento de Usulut\u00e1n, de donde era originario.<\/p>\n<p>\u201cYo esperaba irlo a traer cuando llegara deportado, no en un ata\u00fad\u201d, dijo a CNN Alba Guzm\u00e1n Fuentes, hermana de Norlan.<\/p>\n<p>El sepelio est\u00e1 programado para este lunes por la tarde, dijeron sus parientes.<\/p>\n<p>Guzm\u00e1n, quien trabajaba como jardinero en Estados Unidos, se encontraba en las oficinas de ICE como parte de los tr\u00e1mites relacionados a su proceso de deportaci\u00f3n a El Salvador tras haber sido detenido varias semanas antes por una ri\u00f1a, explicaron sus parientes.<\/p>\n<p>En el tiroteo murieron otros dos migrantes. Todos estaban en una furgoneta en la entrada controlada de la instalaci\u00f3n, inform\u00f3 el Departamento de Seguridad Nacional.<\/p>\n<p>Las autoridades identificaron al tirador como Joshua Jahn, quien estaba apostado en el techo de otro edificio cuando dispar\u00f3 indiscriminadamente contra la oficina de campo de ICE en Dallas. Agregaron que Jahn, de 29 a\u00f1os, muri\u00f3 poco despu\u00e9s del tiroteo de una herida de bala autoinfligida.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La familia de Norlan Guzm\u00e1n Fuentes recibi\u00f3 el f\u00e9retro con sus restos mortales la noche del domingo en una de las terminales del aeropuerto internacional de El Salvador. Guzm\u00e1n, de 37 a\u00f1os, es uno de los fallecidos durante el tiroteo en una oficina local del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467326","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas - Noticias\" \/>\n<meta property=\"og:description\" content=\"La familia de Norlan Guzm\u00e1n Fuentes recibi\u00f3 el f\u00e9retro con sus restos mortales la noche del domingo en una de las terminales del aeropuerto internacional de El Salvador. Guzm\u00e1n, de 37 a\u00f1os, es uno de los fallecidos durante el tiroteo en una oficina local del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-13T03:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas\",\"datePublished\":\"2025-10-13T03:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/\"},\"wordCount\":291,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/\",\"name\":\"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-13T03:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas - Noticias","og_description":"La familia de Norlan Guzm\u00e1n Fuentes recibi\u00f3 el f\u00e9retro con sus restos mortales la noche del domingo en una de las terminales del aeropuerto internacional de El Salvador. Guzm\u00e1n, de 37 a\u00f1os, es uno de los fallecidos durante el tiroteo en una oficina local del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-13T03:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/"},"author":{"name":"","@id":""},"headline":"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas","datePublished":"2025-10-13T03:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/"},"wordCount":291,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/","name":"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-13T03:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Entregan a familia el cuerpo del salvadore\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas","url":"http:\/\/noticiasya.com\/aspen\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/10\/12\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-13T03:03:39Z","datePublished":"2025-10-13T03:03:39Z","dateModified":"2025-10-13T03:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Entregan a familia el cuerpo del salvadore\\u00f1o fallecido en el tiroteo en las oficinas de ICE en Dallas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/12\\\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/12\\\/entregan-cuerpo-salvadoreno-fallecido-tiroteo-ice-dallas-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-13T03:03:39Z\",\"datePublished\":\"2025-10-13T03:03:39Z\",\"dateModified\":\"2025-10-13T03:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466976,"url":"https:\/\/noticiasya.com\/aspen\/2025\/09\/30\/muere-segundo-detenido-tiroteo-oficina-ice-dallas-trax\/","url_meta":{"origin":1467326,"position":0},"title":"Muere el inmigrante mexicano detenido que fue herido en tiroteo en oficina de ICE en Dallas","author":"","date":"septiembre 30, 2025","format":false,"excerpt":"Un segundo detenido que recibi\u00f3 un disparo en un centro de ICE en Dallas la semana pasada falleci\u00f3 este martes, seg\u00fan un funcionario de Seguridad Nacional y portavoz nacional de LULAC, David Cruz.Miguel \u00c1ngel Garc\u00eda Hern\u00e1ndez, un inmigrante mexicano de 32 a\u00f1os, uno de los tres detenidos de ICE que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466788,"url":"https:\/\/noticiasya.com\/aspen\/2025\/09\/24\/joshua-jahn-presunto-atacante-tiroteo-ice-dallas-trax\/","url_meta":{"origin":1467326,"position":1},"title":"\u00bfQui\u00e9n era Joshua Jahn, el presunto atacante contra una instalaci\u00f3n del ICE en Dallas?","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"El atacante se\u00f1alado como responsable de matar a un detenido y herir a otros dos en una instalaci\u00f3n del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas, Texas, es Joshua Jahn, seg\u00fan tres fuentes con conocimiento del caso.Ten\u00eda 29 a\u00f1os, asegur\u00f3 a CNN\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466869,"url":"https:\/\/noticiasya.com\/aspen\/2025\/09\/26\/mexicano-critico-ataque-ice-dallas-univision-trax\/","url_meta":{"origin":1467326,"position":2},"title":"Mexicano est\u00e1 en estado cr\u00edtico tras recibir varios disparos durante el ataque a oficinas del ICE, seg\u00fan Univisi\u00f3n","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"Un ciudadano mexicano se encuentra en estado cr\u00edtico tras recibir varios disparos, incluyendo al menos uno en el cuello, durante el ataque a una instalaci\u00f3n del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas esta semana, seg\u00fan Univisi\u00f3n, afiliada de CNN.Miguel \u00c1ngel Garc\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467030,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/01\/mexicano-fallecio-tiroteo-ice-dallas-protegio-otro-inmigrante-trax\/","url_meta":{"origin":1467326,"position":3},"title":"El mexicano que falleci\u00f3 tras tiroteo en centro de ICE en Dallas protegi\u00f3 a otro inmigrante de los disparos, dicen abogados","author":"","date":"octubre 1, 2025","format":false,"excerpt":"Una de las v\u00edctimas del tiroteo en una instalaci\u00f3n de ICE en Dallas la semana pasada us\u00f3 su cuerpo para proteger a otro inmigrante detenido despu\u00e9s de ser herido, dijeron el mi\u00e9rcoles los abogados de su viuda.Mientras era transportado a la instalaci\u00f3n de ICE el 24 de septiembre, Miguel \u00c1ngel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451457,"url":"https:\/\/noticiasya.com\/aspen\/2024\/07\/26\/lideres-narcotrafico-detenidos-extraditados-sexenio-amlo-orix\/","url_meta":{"origin":1467326,"position":4},"title":"L\u00edderes del narcotr\u00e1fico detenidos y extraditados durante el sexenio de Andr\u00e9s Manuel L\u00f3pez Obrador","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Desde 2020, autoridades de M\u00e9xico y Estados Unidos han detenido y extraditado a seis l\u00edderes del narcotr\u00e1fico: Jos\u00e9 Antonio Y\u00e9pez, Rafael Caro Quintero, Ovidio Guzm\u00e1n, N\u00e9stor Isidoro P\u00e9rezs, Ismael Zambada y Joaqu\u00edn Guzm\u00e1n L\u00f3pez.Jos\u00e9 Antonio Y\u00e9pez, \u201cEl Marro\u201d (agosto de 2020)Jos\u00e9 Antonio Y\u00e9pez, \u201cEl Marro\u201d. (Cr\u00e9dito: Creative Commons)Jos\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466771,"url":"https:\/\/noticiasya.com\/aspen\/2025\/09\/24\/tiroteo-ice-dallas-trax\/","url_meta":{"origin":1467326,"position":5},"title":"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"Al menos tres personas resultaron heridas en un tiroteo ocurrido en una oficina local del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas en la ma\u00f1ana de este mi\u00e9rcoles, seg\u00fan el director interino del ICE, Todd Lyons.\u201cLa informaci\u00f3n preliminar indica que se trata\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1467326"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467326\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1467326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1467326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1467326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}