{"id":1467352,"date":"2025-10-14T03:03:50","date_gmt":"2025-10-14T10:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/"},"modified":"2025-10-14T03:03:50","modified_gmt":"2025-10-14T10:03:50","slug":"expresidente-frances-sarkozy-carcel-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/","title":{"rendered":"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas"},"content":{"rendered":"<p>Como expresidente de Francia, <a href=\"https:\/\/www.cnn.com\/world\/europe\/nicolas-sarkozy-fast-facts\">Nicolas Sarkozy<\/a> ha estado tras muchas puertas cerradas para el ciudadano franc\u00e9s medio.<\/p>\n<p>El 21 de octubre, cuando el fr\u00edo acero de la puerta de su celda resuene tras \u00e9l, estar\u00e1 en una habitaci\u00f3n a la que pocos desear\u00edan entrar.<\/p>\n<p>El exl\u00edder franc\u00e9s fue <a href=\"https:\/\/www.cnn.com\/2025\/09\/25\/europe\/sarkozy-trial-libya-verdict-intl\">condenado<\/a> en septiembre por conspiraci\u00f3n criminal en lo que, seg\u00fan el tribunal, fue un plan para financiar su\u202f <a href=\"https:\/\/www.cnn.com\/2025\/01\/06\/europe\/nicolas-sarkozy-france-trial-gadhafi-intl\">campa\u00f1a presidencial de 2007 con fondos<\/a> \u202flibios a cambio de favores diplom\u00e1ticos. Fue condenado a cinco a\u00f1os de prisi\u00f3n, pero es probable que sea puesto en libertad condicional a mitad de su cumplimiento.<\/p>\n<p>El expresidente tiene intenci\u00f3n de apelar, pero mientras tanto se espera que ocupe una celda en r\u00e9gimen de aislamiento o en el llamado \u201cala VIP\u201d del complejo penitenciario de La Sant\u00e9 en Par\u00eds, la \u00fanica prisi\u00f3n de la capital francesa.<\/p>\n<p>Ese pabell\u00f3n est\u00e1 reservado para reclusos considerados no aptos para integrarse a la poblaci\u00f3n general de la prisi\u00f3n, generalmente por temor a su propia seguridad. Podr\u00edan ser pol\u00edticos, expolic\u00edas, miembros de organizaciones de extrema derecha o personas vinculadas a grupos terroristas islamistas, seg\u00fan inform\u00f3 BFMTV, afiliada de CNN.<\/p>\n<p>Ubicada frente a un hogar de ancianos en un rinc\u00f3n residencial del distrito 14 de Par\u00eds, la discreta presencia de La Sant\u00e9 solo se delata por el ocasional sonido de la sirena mientras los prisioneros son transportados hacia y desde el lugar.<\/p>\n<p>En los meses de invierno, a veces se pueden ver los rostros de los reclusos asom\u00e1ndose tras las ventanas enrejadas de la prisi\u00f3n, a trav\u00e9s de las ramas desnudas de la avenida arbolada. En ocasiones, sus miradas son devueltas por un paquete lanzado por encima de los muros por un transe\u00fante, como presenci\u00f3 CNN.<\/p>\n<p>Durante el \u00faltimo siglo y medio, los muros de la Sant\u00e9 han privado a muchos franceses famosos de su libertad.<\/p>\n<p>Uno de los terroristas m\u00e1s buscados del mundo durante las d\u00e9cadas de 1970 y 1980, Ilich Ram\u00edrez S\u00e1nchez, alias \u201cCarlos el Chacal\u201d, pas\u00f3 un tiempo en La Sant\u00e9, al igual que Jacques Mesrine, un conocido asesino y ladr\u00f3n de bancos de la d\u00e9cada de 1970, cuya carrera criminal fue retratada en una pel\u00edcula de 2008 protagonizada por Vincent Cassel. Mesrine tambi\u00e9n es famoso por escaparse de los muros de La Sant\u00e9.<\/p>\n<p>Otros reclusos conocidos incluyen a Alfred Dreyfus, el capit\u00e1n del Ej\u00e9rcito jud\u00edo en el centro del caso Dreyfus de finales del siglo XIX, en el que el antisemitismo lo llev\u00f3 a ser condenado injustamente por traici\u00f3n, y m\u00e1s recientemente <a href=\"https:\/\/www.cnn.com\/2021\/11\/05\/europe\/macron-bodyguard-jail-sentence-intl\">Alexandre Benalla<\/a>, un asistente y ex guardaespaldas de Emmanuel Macron sentenciado a prisi\u00f3n despu\u00e9s de ser filmado golpeando a manifestantes de los chalecos amarillos.<\/p>\n<p>Sarkozy ni siquiera ser\u00e1 el primer l\u00edder mundial en la prisi\u00f3n. Manuel Noriega, el exdictador de Panam\u00e1, pas\u00f3 un tiempo all\u00ed tras su extradici\u00f3n desde Estados Unidos tras la invasi\u00f3n estadounidense que lo derroc\u00f3.<\/p>\n<p>No es de sorprender que Sarkozy no est\u00e9 contento con ir a prisi\u00f3n.<\/p>\n<p>\u201cSi quieren que duerma en la c\u00e1rcel, dormir\u00e9 en la c\u00e1rcel. Pero con la frente en alto. Soy inocente\u201d, dijo tras la audiencia de sentencia, con la voz llena de ira.<\/p>\n<p>\u201cEsta injusticia es un esc\u00e1ndalo\u201d, continu\u00f3, acompa\u00f1ado de su esposa, la cantante y modelo Carla Bruni-Sarkozy.<\/p>\n<p>Es probable que sea una de las primeras ex supermodelos en ingresar a la prisi\u00f3n si lo visita.<\/p>\n<p>Pero detr\u00e1s de sus altos muros de ladrillo, La Sant\u00e9 no es una mazmorra.<\/p>\n<p>\u201cEst\u00e1 bien, La Sant\u00e9, es como un hotel Ibis\u201d, dijo Marco Mouly, un expreso del ala VIP de la prisi\u00f3n, a BFMTV en un documental de 2022, refiri\u00e9ndose a una popular cadena europea de hoteles econ\u00f3micos.<\/p>\n<p>Construida en 1867, con un dise\u00f1o radial distintivo dise\u00f1ado para dar a los prisioneros la sensaci\u00f3n de estar bajo vigilancia constante, la prisi\u00f3n se someti\u00f3 recientemente a un programa de renovaci\u00f3n y modernizaci\u00f3n de cuatro a\u00f1os, reabriendo en 2019.<\/p>\n<p>Si Sarkozy es alojado en el ala VIP, se le asignar\u00e1 una de las 18 celdas id\u00e9nticas, cada una de las cuales cuenta con un hornillo para cocinar, un frigor\u00edfico, un televisor, una ducha y un inodoro, adem\u00e1s de una l\u00ednea telef\u00f3nica fija que permite a los presos llamar a determinados n\u00fameros autorizados.<\/p>\n<p>Las celdas miden nueve metros cuadrados (casi 97 pies cuadrados), no m\u00e1s grandes que las celdas normales, aunque los residentes en esta ala especial no est\u00e1n obligados a compartir una celda, generalmente por preocupaci\u00f3n por su seguridad.<\/p>\n<p>A\u00fan as\u00ed, la estancia est\u00e1 lejos de ser c\u00f3moda, dicen quienes lo han experimentado.<\/p>\n<p>\u201cEl problema es el ruido\u201d, declar\u00f3 Didier Schuller, exfuncionario y pol\u00edtico recluido durante varias semanas en La Sant\u00e9, a BFMTV en 2022. \u201cPor la noche, te despiertan los gritos\u201d.<\/p>\n<p>Un expolic\u00eda entrevistado por la emisora \u200b\u200bdescribi\u00f3 los insultos que le gritaban sin parar los presos de otras alas cuando se enteraban de que hab\u00eda llegado como interno.<\/p>\n<p>Es poco probable que Sarkozy no atraiga una atenci\u00f3n similar tras las rejas. Y a pesar de su promesa de apelar la condena, su libertad puede parecer lejana en esa primera noche en prisi\u00f3n.<\/p>\n<p>\u201cSabes cu\u00e1ndo entras\u201d, declar\u00f3 Patrick Balkany, exalcalde de Levallois-P\u00e9ret, al noroeste de Par\u00eds, a BFMTV sobre La Sant\u00e9, donde cumpli\u00f3 varios meses de prisi\u00f3n por evasi\u00f3n fiscal antes de ser liberado por motivos de salud. \u201cNo sabes cu\u00e1ndo saldr\u00e1s\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como expresidente de Francia, Nicolas Sarkozy ha estado tras muchas puertas cerradas para el ciudadano franc\u00e9s medio. El 21 de octubre, cuando el fr\u00edo acero de la puerta de su celda resuene tras \u00e9l, estar\u00e1 en una habitaci\u00f3n a la que pocos desear\u00edan entrar. El exl\u00edder franc\u00e9s fue condenado en septiembre por conspiraci\u00f3n criminal en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467352","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Como expresidente de Francia, Nicolas Sarkozy ha estado tras muchas puertas cerradas para el ciudadano franc\u00e9s medio. El 21 de octubre, cuando el fr\u00edo acero de la puerta de su celda resuene tras \u00e9l, estar\u00e1 en una habitaci\u00f3n a la que pocos desear\u00edan entrar. El exl\u00edder franc\u00e9s fue condenado en septiembre por conspiraci\u00f3n criminal en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-14T10:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas\",\"datePublished\":\"2025-10-14T10:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/\"},\"wordCount\":978,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/\",\"name\":\"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-14T10:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas - Noticias","og_description":"Como expresidente de Francia, Nicolas Sarkozy ha estado tras muchas puertas cerradas para el ciudadano franc\u00e9s medio. El 21 de octubre, cuando el fr\u00edo acero de la puerta de su celda resuene tras \u00e9l, estar\u00e1 en una habitaci\u00f3n a la que pocos desear\u00edan entrar. El exl\u00edder franc\u00e9s fue condenado en septiembre por conspiraci\u00f3n criminal en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-14T10:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/"},"author":{"name":"","@id":""},"headline":"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas","datePublished":"2025-10-14T10:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/"},"wordCount":978,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/","name":"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-14T10:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas","url":"http:\/\/noticiasya.com\/aspen\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-14T10:03:50Z","datePublished":"2025-10-14T10:03:50Z","dateModified":"2025-10-14T10:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/14\\\/expresidente-frances-sarkozy-carcel-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/10\\\/14\\\/expresidente-frances-sarkozy-carcel-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-14T10:03:50Z\",\"datePublished\":\"2025-10-14T10:03:50Z\",\"dateModified\":\"2025-10-14T10:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467572,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/21\/por-que-prision-francia-nicolas-sarkozy-orix\/","url_meta":{"origin":1467352,"position":0},"title":"\u00bfPor qu\u00e9 fue a prisi\u00f3n el expresidente de Francia Nicolas Sarkozy?","author":"","date":"octubre 21, 2025","format":false,"excerpt":"El expresidente de Francia Nicolas Sarkozy (2002-2012) est\u00e1 en prisi\u00f3n en Par\u00eds para cumplir una condena de cinco a\u00f1os, que a\u00fan puede apelar, por un caso de asociaci\u00f3n delictiva en el financiamiento de una campa\u00f1a.Sarkozy fue sentenciado a cinco a\u00f1os de c\u00e1rcel por conspiraci\u00f3n criminal por su papel en un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467556,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/21\/expresidente-francia-nicolas-sarkozy-prision-trax\/","url_meta":{"origin":1467352,"position":1},"title":"El expresidente de Francia Nicolas Sarkozy llega a prisi\u00f3n para cumplir su condena de cinco a\u00f1os","author":"","date":"octubre 21, 2025","format":false,"excerpt":"Nicolas Sarkozy ingres\u00f3 el martes en una prisi\u00f3n de Par\u00eds, el primer d\u00eda de una condena de cinco a\u00f1os, lo que marca la primera vez que un ex l\u00edder de la Francia moderna pasa tiempo tras las rejas.Sarkozy fue trasladado al complejo penitenciario el martes por la ma\u00f1ana y salud\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468193,"url":"https:\/\/noticiasya.com\/aspen\/2025\/11\/10\/nicolas-sarkozy-liberacion-prision-condena-trax\/","url_meta":{"origin":1467352,"position":2},"title":"El expresidente de Francia Nicolas Sarkozy sale de la c\u00e1rcel mientras apela su condena","author":"","date":"noviembre 10, 2025","format":false,"excerpt":"El expresidente de Francia Nicolas Sarkozy sali\u00f3 de la prisi\u00f3n despu\u00e9s de que un tribunal de Par\u00eds dictaminara este lunes que pod\u00eda ser excarcelado mientras apela su condena de septiembre por conspiraci\u00f3n criminal, seg\u00fan inform\u00f3 la afiliada de CNN, BFMTV.El exmandatario fue declarado culpable por su participaci\u00f3n en un esquema\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460631,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/31\/marine-le-pen-excluida-carrera-presidencial-francia-trax\/","url_meta":{"origin":1467352,"position":3},"title":"L\u00edder de extrema derecha Marine Le Pen fue excluida de la carrera presidencial de 2027, llevando caos a la pol\u00edtica francesa","author":"","date":"marzo 31, 2025","format":false,"excerpt":"La l\u00edder de extrema derecha francesa Marine Le Pen ha sido inhabilitada para postularse a un cargo pol\u00edtico durante cinco a\u00f1os tras ser declarada culpable de malversaci\u00f3n de fondos de la Uni\u00f3n Europea, en un fallo pol\u00edticamente explosivo que ha destrozado sus esperanzas de ganar la presidencia en 2027.Un tribunal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472216,"url":"https:\/\/noticiasya.com\/aspen\/2026\/03\/15\/funcion-renal-expresidente-jair-bolsonaro-mejora-cuidados-intensivos-ap\/","url_meta":{"origin":1467352,"position":4},"title":"La funci\u00f3n renal de Jair Bolsonaro mejora, pero el expresidente de Brasil sigue en cuidados intensivos","author":"","date":"marzo 15, 2026","format":false,"excerpt":"La funci\u00f3n renal del expresidente de Brasil Jair Bolsonaro mejor\u00f3, pero permanecer\u00e1 en la unidad de cuidados intensivos debido a una neumon\u00eda, seg\u00fan inform\u00f3 este domingo un hospital de la capital del pa\u00eds, Brasilia.El expresidente, de 70 a\u00f1os, tambi\u00e9n ha recibido m\u00e1s antibi\u00f3ticos desde el s\u00e1bado, seg\u00fan un comunicado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469715,"url":"https:\/\/noticiasya.com\/aspen\/2026\/01\/01\/bolsonaro-alta-medica-prision-hospitalizado-efe\/","url_meta":{"origin":1467352,"position":5},"title":"Bolsonaro recibe alta m\u00e9dica y vuelve a prisi\u00f3n tras ocho d\u00edas hospitalizado","author":"","date":"enero 1, 2026","format":false,"excerpt":"El expresidente brasile\u00f1o Jair Bolsonaro fue recluido este jueves nuevamente en la celda de la Polic\u00eda Federal en la que cumple su condena de 27 a\u00f1os de prisi\u00f3n por golpismo, tras recibir el alta m\u00e9dica luego de haber sido sometido a cuatro operaciones en los ocho d\u00edas en que estuvo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1467352"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1467352\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1467352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1467352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1467352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}