{"id":1468225,"date":"2025-11-11T07:03:57","date_gmt":"2025-11-11T15:03:57","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/"},"modified":"2025-11-11T07:03:57","modified_gmt":"2025-11-11T15:03:57","slug":"noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/","title":{"rendered":"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel"},"content":{"rendered":"<p>A pocos d\u00edas de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/17\/latinoamerica\/noboa-convoca-asamblea-constituyente-orix\">un refer\u00e9ndum<\/a> en Ecuador y en medio de tensiones dentro del sistema penitenciario tras registrarse una nueva masacre en una prisi\u00f3n el fin de semana, el presidente Daniel Noboa confirm\u00f3 este lunes que 300 reclusos fueron trasladados a una nueva c\u00e1rcel ubicada en la comunidad de Juntas del Pac\u00edfico en la provincia de Santa Elena, en la costa del pa\u00eds.<\/p>\n<p>\u201cEl crimen quiso desafiar al Ecuador y empezar su campa\u00f1a. Hoy, el Ecuador le respondi\u00f3 con hechos. Los primeros 300 privados de la libertad m\u00e1s peligrosos ya fueron trasladados a la c\u00e1rcel del Encuentro\u201d, inform\u00f3 Noboa en una publicaci\u00f3n en su cuenta de X.<\/p>\n<p>El anuncio del presidente fue sorpresivo, pues la nueva c\u00e1rcel -que tendr\u00e1 una capacidad para 800 presos- no hab\u00eda sido inaugurada de forma oficial y el Gobierno no detall\u00f3 el estado de la obra.<\/p>\n<p>\u201cEstamos trasladando a los delincuentes m\u00e1s peligrosos del pa\u00eds. Hemos tratado de manejar la informaci\u00f3n por temas de seguridad para precautelar el traslado\u201d, dijo el ministro del Interior, Jhon Reimberg, en declaraciones a una radio local.<\/p>\n<p>Reimberg agreg\u00f3 que el Servicio de Atenci\u00f3n a Personas Privadas de la Libertad (SNAI) ya no ser\u00e1 el encargado de administrar esta prisi\u00f3n, sino directamente el Ministerio del Interior, pues afirma que el SNAI \u201cha fracasado\u201d en su funci\u00f3n.<\/p>\n<p>\u201cHoy est\u00e1n en una c\u00e1rcel de m\u00e1xima seguridad donde se acab\u00f3 la comunicaci\u00f3n. Est\u00e1n en celdas dise\u00f1adas para que no tengan contacto ni comunicaciones con absolutamente nadie\u201d, agreg\u00f3.<\/p>\n<p>El traslado de los reclusos se realiz\u00f3 en buses y tambi\u00e9n por v\u00eda a\u00e9rea bajo fuertes medidas de seguridad y vigilancia policial y militar. Horas antes se hab\u00eda registrado una masacre en la c\u00e1rcel de Machala, en la provincia de El Oro, que dej\u00f3 31 reos muertos tras enfrentamientos y represalias entre dos facciones del grupo criminal Los Lobos, seg\u00fan indic\u00f3 Reimberg.<\/p>\n<p>En un informe preliminar el SNAI report\u00f3 que los reos murieron por asfixia, sin que hasta el momento existan m\u00e1s detalles o respuestas para aclarar el contexto.<\/p>\n<p>Noboa se mantuvo muy activo en sus redes sociales este lunes, en medio del ambiente electoral previo al refer\u00e9ndum del domingo en el que los ciudadanos definir\u00edan si aprueban reformas en materia constitucional y de seguridad.<\/p>\n<p>\u201cYa empezar\u00e1n con la quejadera\u201d, escribi\u00f3 Noboa en X junto a una imagen que muestra restos de cabello en el piso.<\/p>\n<p>En una publicaci\u00f3n anterior, el mandatario mostr\u00f3 fotos de los reos trasladados a la nueva c\u00e1rcel en Santa Elena con sus cabezas rapadas y sus manos amarradas, una imagen similar a las de los presos que cumplen sentencia en el temido Centro de Confinamiento del Terrorismo (CECOT), en El Salvador.<\/p>\n<p>Adem\u00e1s, Noboa public\u00f3 otro video que muestra a un grupo de reclusos cubiertos con telas negras en sus cabezas y las manos amarradas hacia atr\u00e1s, bajo la custodia de las Fuerzas Armadas y la Polic\u00eda Nacional.<\/p>\n<p>Un equipo de la cadena local Ecuavisa, afiliada de CNN, viaj\u00f3 hasta la comuna Juntas del Pac\u00edfico, donde se construy\u00f3 la c\u00e1rcel y constat\u00f3 que el tr\u00e1nsito est\u00e1 restringido hacia el centro y que la zona est\u00e1 totalmente militarizada.<\/p>\n<p>La noche del lunes, Noboa, inform\u00f3 que el exvicepresidente Jorge Glas, quien cumple dos sentencias por corrupci\u00f3n, fue trasladado a la nueva c\u00e1rcel, y acompa\u00f1\u00f3 su mensaje con dos fotograf\u00edas de Glas con traje naranja.<\/p>\n<p>\u201cBienvenido al nuevo hogar. Pronto llegar\u00e1n otros criminales\u201d, escribi\u00f3 Noboa.<\/p>\n<p>Su mensaje desat\u00f3 la reacci\u00f3n de Sonia Vera, abogada de Glas, quien dijo a CNN que no hab\u00eda recibido ninguna notificaci\u00f3n previa sobre el traslado.<\/p>\n<p>\u201cEn el contexto de una nueva masacre penitenciaria y de un proceso electoral en curso, la utilizaci\u00f3n del sistema carcelario como herramienta de propaganda constituye un uso pol\u00edtico del dolor humano y una manifestaci\u00f3n de tortura psicol\u00f3gica institucionalizada, proscrita de forma absoluta por el derecho internacional de los derechos humanos\u201d, enfatiz\u00f3 Vera.<\/p>\n<p>Adem\u00e1s, se\u00f1al\u00f3 que el mensaje de Noboa sobre Glas en su cuenta de X es una \u201cexpresi\u00f3n de burla y escarnio\u201d en su contra.<\/p>\n<p>Tambi\u00e9n se pronunci\u00f3 en redes el expresidente Rafael Correa. \u201c\u00bfJorge Glas entre los presos m\u00e1s \u00abpeligrosos\u00bb? \u00a1Sinverg\u00fcenza! Todo en ti es show, maldad y falsedad\u201d, escribi\u00f3 en <a href=\"https:\/\/x.com\/MashiRafael\/status\/1988169470825709603?s=20\">un mensaje<\/a> que responde a la publicaci\u00f3n de Noboa sobre Glas.<\/p>\n<p>Por su parte, Vera agreg\u00f3 que considera que el Gobierno ejerci\u00f3 un acto de \u201cdesacato\u201d, pues asegura que est\u00e1 incumpliendo con las medidas provisionales de car\u00e1cter internacional otorgadas a favor de Glas el 17 de octubre. La Corte Interamericana de Derechos Humanos otorg\u00f3 medidas cautelares a favor del exvicepresidente Glas y pidi\u00f3 al Estado ecuatoriano que garantice su salud f\u00edsica y mental, con el fin de asegurar sus derechos a la salud, integridad personal y vida.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pocos d\u00edas de un refer\u00e9ndum en Ecuador y en medio de tensiones dentro del sistema penitenciario tras registrarse una nueva masacre en una prisi\u00f3n el fin de semana, el presidente Daniel Noboa confirm\u00f3 este lunes que 300 reclusos fueron trasladados a una nueva c\u00e1rcel ubicada en la comunidad de Juntas del Pac\u00edfico en la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468225","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel - Noticias\" \/>\n<meta property=\"og:description\" content=\"A pocos d\u00edas de un refer\u00e9ndum en Ecuador y en medio de tensiones dentro del sistema penitenciario tras registrarse una nueva masacre en una prisi\u00f3n el fin de semana, el presidente Daniel Noboa confirm\u00f3 este lunes que 300 reclusos fueron trasladados a una nueva c\u00e1rcel ubicada en la comunidad de Juntas del Pac\u00edfico en la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T15:03:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel\",\"datePublished\":\"2025-11-11T15:03:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/\"},\"wordCount\":872,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/\",\"name\":\"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-11T15:03:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/","og_locale":"es_ES","og_type":"article","og_title":"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel - Noticias","og_description":"A pocos d\u00edas de un refer\u00e9ndum en Ecuador y en medio de tensiones dentro del sistema penitenciario tras registrarse una nueva masacre en una prisi\u00f3n el fin de semana, el presidente Daniel Noboa confirm\u00f3 este lunes que 300 reclusos fueron trasladados a una nueva c\u00e1rcel ubicada en la comunidad de Juntas del Pac\u00edfico en la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-11T15:03:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/"},"author":{"name":"","@id":""},"headline":"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel","datePublished":"2025-11-11T15:03:57+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/"},"wordCount":872,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/","name":"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-11T15:03:57+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"En la previa del refer\u00e9ndum, Noboa apuesta a una demostraci\u00f3n de poder y traslada a 300 presos a una nueva c\u00e1rcel","url":"http:\/\/noticiasya.com\/aspen\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/11\/11\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-11T15:03:57Z","datePublished":"2025-11-11T15:03:57Z","dateModified":"2025-11-11T15:03:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"En la previa del refer\\u00e9ndum, Noboa apuesta a una demostraci\\u00f3n de poder y traslada a 300 presos a una nueva c\\u00e1rcel\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/11\\\/11\\\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/11\\\/11\\\/noboa-referendum-demostracion-traslado-300-presos-nueva-carcel-ecuador-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-11T15:03:57Z\",\"datePublished\":\"2025-11-11T15:03:57Z\",\"dateModified\":\"2025-11-11T15:03:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450594,"url":"https:\/\/noticiasya.com\/aspen\/2024\/06\/21\/construccion-carcel-maxima-seguridad-ecuador-violencia-orix\/","url_meta":{"origin":1468225,"position":0},"title":"Comienza la construcci\u00f3n de una c\u00e1rcel de m\u00e1xima seguridad en la costa de Ecuador, en medio de la lucha contra la violencia","author":"","date":"junio 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El presidente de Ecuador, Daniel Noboa, y varios funcionarios de su Gobierno anunciaron en un acto oficial el inicio de la construcci\u00f3n de una c\u00e1rcel de m\u00e1xima seguridad en la provincia costera de Santa Elena, con la que buscan combatir al crimen organizado y ordenar el sistema\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469048,"url":"https:\/\/noticiasya.com\/aspen\/2025\/12\/07\/comunidad-rural-pacifica-vecino-incomodo-ecuador-orix\/","url_meta":{"origin":1468225,"position":1},"title":"Esta era una comunidad rural pac\u00edfica. Hasta que comenz\u00f3 a instalarse un &#171;vecino inc\u00f3modo&#187;","author":"","date":"diciembre 7, 2025","format":false,"excerpt":"Entre calles polvorientas, precarias construcciones y militares desplegados en actitud de vigilancia, la vida en la comunidad rural de Juntas del Pac\u00edfico, ubicada en la provincia costera de Santa Elena, en Ecuador, ha cambiado dr\u00e1sticamente en los \u00faltimos meses debido a la llegada de un nuevo e inc\u00f3modo vecino: una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443969,"url":"https:\/\/noticiasya.com\/aspen\/2024\/01\/16\/presidente-noboa-advierte-que-escalada-de-violencia-en-ecuador-trasciende-fronteras-y-requiere-cooperacion-internacional-2\/","url_meta":{"origin":1468225,"position":2},"title":"Presidente Noboa advierte que escalada de violencia en Ecuador \u201ctrasciende fronteras\u201d y requiere \u201ccooperaci\u00f3n internacional\u201d","author":"","date":"enero 16, 2024","format":false,"excerpt":"(CNN) -- Ecuador inst\u00f3 a Estados Unidos y otras naciones alrededor del mundo a apoyar al pa\u00eds tras el aumento de la violencia, que recientemente incluy\u00f3 el asalto a una cadena de televisi\u00f3n y la toma de instalaciones penitenciarias en el pa\u00eds.En declaraciones a Christiane Amanpour de CNN el martes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463824,"url":"https:\/\/noticiasya.com\/aspen\/2025\/06\/21\/rolando-federico-gomez-quinde-fuga-carcel-ecuador-orix\/","url_meta":{"origin":1468225,"position":3},"title":"Rolando Federico G\u00f3mez Quinde, presunto l\u00edder del grupo criminal Las \u00c1guilas, se fuga de una c\u00e1rcel de Ecuador","author":"","date":"junio 21, 2025","format":false,"excerpt":"Rolando Federico G\u00f3mez Quinde, alias \u201cFede\u201d, presunto l\u00edder del grupo criminal Las \u00c1guilas, se fug\u00f3 este viernes del Centro de Privaci\u00f3n de Libertad N\u00famero 1, ubicado en la ciudad de Guayaquil, informaron este s\u00e1bado el presidente de Ecuador, Daniel Noboa, y la Fiscal\u00eda del pa\u00eds sudamericano.Noboa repudi\u00f3 el hecho con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445963,"url":"https:\/\/noticiasya.com\/aspen\/2024\/02\/23\/reos-fugan-carcel-ecuador-orix\/","url_meta":{"origin":1468225,"position":4},"title":"Tres reos se fugan de la c\u00e1rcel de Cotopaxi en Ecuador","author":"","date":"febrero 23, 2024","format":false,"excerpt":"(CNN) -- Tres reos se fugaron de la c\u00e1rcel de Cotopaxi durante la madrugada de este jueves, informaron el viernes las Fuerzas Armadas de Ecuador, que mantienen el control de las prisiones del pa\u00eds como parte del plan del Gobierno del presidente Daniel Noboa para frenar la violencia que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447941,"url":"https:\/\/noticiasya.com\/aspen\/2024\/04\/10\/ecuador-embajada-mexico-latinoamerica-trax\/","url_meta":{"origin":1468225,"position":5},"title":"El operativo de Ecuador en la embajada de M\u00e9xico conmocion\u00f3 a Latinoam\u00e9rica. \u00bfPor qu\u00e9 Noboa a\u00fan puede beneficiarse de eso?","author":"","date":"abril 10, 2024","format":false,"excerpt":"Bogot\u00e1 (CNN) -- Latinoam\u00e9rica ha sido testigo de muchas luchas diplom\u00e1ticas en las \u00faltimas semanas, desde el presidente de Argentina llamando a su hom\u00f3logo colombiano \"asesino terrorista\" hasta el \u00faltimo intento de Venezuela de recuperar un territorio gobernado por la vecina Guyana. Pero nada de esto ha tenido tanta repercusi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1468225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1468225"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1468225\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1468225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1468225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1468225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}