{"id":1468229,"date":"2025-11-11T08:03:40","date_gmt":"2025-11-11T16:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/"},"modified":"2025-11-11T08:03:40","modified_gmt":"2025-11-11T16:03:40","slug":"bovino-patrulla-fronteriza-dejan-chicago","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/","title":{"rendered":"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana"},"content":{"rendered":"<p>Gregory Bovino, el m\u00e1ximo responsable de la Patrulla Fronteriza a cargo de la ofensiva migratoria del Gobierno de Trump en las ciudades, planea abandonar Chicago junto con sus agentes esta misma semana, mientras busca otras ubicaciones para intensificar las detenciones, seg\u00fan tres funcionarios estadounidenses familiarizados con la planificaci\u00f3n.<\/p>\n<p>Bovino se ha convertido en la cara visible del esfuerzo del presidente Donald Trump por desplegar un gran n\u00famero de fuerzas del orden federales en estados y ciudades dem\u00f3cratas, independientemente de si las autoridades locales las quieren all\u00ed; primero en Los \u00c1ngeles, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/17\/eeuu\/chicago-epicentro-contra-inmigracion-trax\">ahora en Chicago<\/a>, donde los violentos enfrentamientos con manifestantes han sido el centro de un litigio en curso.<\/p>\n<p>Se espera que Bovino y sus agentes se dirijan a Charlotte, Carolina del Norte, y luego contin\u00faen hacia Nueva Orleans, seg\u00fan dos funcionarios, quienes recalcaron que los planes a\u00fan se est\u00e1n ultimando. Se prev\u00e9 que el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) contin\u00fae sus operaciones en Chicago.<\/p>\n<p>En un comunicado, la portavoz del Departamento de Seguridad Nacional, Tricia McLaughlin, declar\u00f3 a CNN: \u201cNo nos vamos de Chicago\u201d, y destac\u00f3 los resultados de la Operaci\u00f3n Midway Blitz en la ciudad.<\/p>\n<p>Trump ya hab\u00eda mencionado Nueva Orleans como posible destino para su ofensiva federal, afirmando en una reuni\u00f3n en el Despacho Oval este a\u00f1o que el Gobierno estaba \u201ctomando una decisi\u00f3n\u201d.<\/p>\n<p>\u201c\u00bfVamos a Chicago? \u00bfO vamos a un lugar como Nueva Orleans, donde tenemos un gran gobernador, Jeff Landry, que quiere que entremos y pongamos orden en una zona muy agradable de este pa\u00eds que se ha vuelto bastante, ya saben, bastante dif\u00edcil, bastante mala?\u201d, dijo.<\/p>\n<p>Cuando CNN le pregunt\u00f3 el mes pasado a d\u00f3nde planeaba ir despu\u00e9s, Bovino respondi\u00f3 que depend\u00eda de la inteligencia.<\/p>\n<p>\u201cContamos con un excelente equipo de liderazgo al que admiramos y para el que trabajamos, y ese equipo est\u00e1 conformado por el presidente Trump, Kristi Noem y todos ellos\u201d, dijo. \u201cPrestamos atenci\u00f3n a lo que dicen y a lo que nos dicen nuestros servicios de inteligencia. Combinamos ambas perspectivas y actuamos con contundencia\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gregory Bovino, el m\u00e1ximo responsable de la Patrulla Fronteriza a cargo de la ofensiva migratoria del Gobierno de Trump en las ciudades, planea abandonar Chicago junto con sus agentes esta misma semana, mientras busca otras ubicaciones para intensificar las detenciones, seg\u00fan tres funcionarios estadounidenses familiarizados con la planificaci\u00f3n. Bovino se ha convertido en la cara [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468229","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana - Noticias\" \/>\n<meta property=\"og:description\" content=\"Gregory Bovino, el m\u00e1ximo responsable de la Patrulla Fronteriza a cargo de la ofensiva migratoria del Gobierno de Trump en las ciudades, planea abandonar Chicago junto con sus agentes esta misma semana, mientras busca otras ubicaciones para intensificar las detenciones, seg\u00fan tres funcionarios estadounidenses familiarizados con la planificaci\u00f3n. Bovino se ha convertido en la cara [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T16:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana\",\"datePublished\":\"2025-11-11T16:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/\"},\"wordCount\":389,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/\",\"name\":\"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-11T16:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/","og_locale":"es_ES","og_type":"article","og_title":"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana - Noticias","og_description":"Gregory Bovino, el m\u00e1ximo responsable de la Patrulla Fronteriza a cargo de la ofensiva migratoria del Gobierno de Trump en las ciudades, planea abandonar Chicago junto con sus agentes esta misma semana, mientras busca otras ubicaciones para intensificar las detenciones, seg\u00fan tres funcionarios estadounidenses familiarizados con la planificaci\u00f3n. Bovino se ha convertido en la cara [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/","og_site_name":"Noticias","article_published_time":"2025-11-11T16:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/"},"author":{"name":"","@id":""},"headline":"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana","datePublished":"2025-11-11T16:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/"},"wordCount":389,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/","url":"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/","name":"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-11T16:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana","url":"http:\/\/noticiasya.com\/aspen\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/11\/11\/bovino-patrulla-fronteriza-dejan-chicago\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-11T16:03:40Z","datePublished":"2025-11-11T16:03:40Z","dateModified":"2025-11-11T16:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gregory Bovino y sus agentes de la Patrulla Fronteriza planean abandonar Chicago esta misma semana\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/11\\\/11\\\/bovino-patrulla-fronteriza-dejan-chicago\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/11\\\/11\\\/bovino-patrulla-fronteriza-dejan-chicago\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-11T16:03:40Z\",\"datePublished\":\"2025-11-11T16:03:40Z\",\"dateModified\":\"2025-11-11T16:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467201,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/08\/jefe-patrulla-fronteriza-gregory-bovino-chicago-trax\/","url_meta":{"origin":1468229,"position":0},"title":"&#171;No hay un santuario aqu\u00ed&#187;: este es el jefe de la Patrulla Fronteriza a cargo de la represi\u00f3n en Chicago","author":"","date":"octubre 8, 2025","format":false,"excerpt":"Los agentes fuertemente armados que llevan a cabo la agresiva campa\u00f1a migratoria del presidente Donald Trump en Chicago suelen llevar una m\u00e1scara. El hombre que los lidera no.Casi tres d\u00e9cadas despu\u00e9s de comenzar su carrera en la Patrulla Fronteriza de Estados Unidos, Gregory Bovino se ha convertido en el rostro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470501,"url":"https:\/\/noticiasya.com\/aspen\/2026\/01\/26\/gregory-bovino-patrulla-fronteriza-salida-minneapolis-trump-trax\/","url_meta":{"origin":1468229,"position":1},"title":"Gregory Bovino, el pol\u00e9mico comandante general de la Patrulla Fronteriza, abandonar\u00eda Minneapolis el martes, seg\u00fan fuentes","author":"","date":"enero 26, 2026","format":false,"excerpt":"Se espera que el comandante gemeral de la Patrulla Fronteriza Gregory Bovino y algunos de sus agentes salgan de Minneapolis el martes y regresen a sus respectivos sectores, seg\u00fan tres fuentes familiarizadas con las discusiones, dejando de lado a un actor clave en la ofensiva migratoria del Gobierno de Trump.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467916,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/31\/tribunal-anula-orden-patrulla-fronteriza-trax\/","url_meta":{"origin":1468229,"position":2},"title":"Tribunal anula orden de jueza que exig\u00eda a jefe de Patrulla Fronteriza informar diario las actividades de agentes en Chicago","author":"","date":"octubre 31, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones anul\u00f3 este viernes la orden de una jueza de Illinois que requer\u00eda que el comandante de la Patrulla Fronteriza, Gregory Bovino, proporcionara informes diarios al tribunal sobre las t\u00e1cticas de cumplimiento de la ley de inmigraci\u00f3n de sus agentes en el \u00e1rea de Chicago.La breve\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467698,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/24\/gregory-bovino-patrulla-fronteriza-orden-judicial-chicago-trax\/","url_meta":{"origin":1468229,"position":3},"title":"Acusan a alto funcionario de la Patrulla Fronteriza de violar la orden judicial sobre el uso de la fuerza en Chicago","author":"","date":"octubre 24, 2025","format":false,"excerpt":"El alto funcionario de la Patrulla Fronteriza, Gregory Bovino, est\u00e1 acusado de lanzar al menos un cartucho de gas lacrim\u00f3geno contra una multitud de manifestantes en un barrio de Chicago el jueves, en una posible violaci\u00f3n de la orden judicial que restringe a los agentes federales el uso de t\u00e1cticas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470461,"url":"https:\/\/noticiasya.com\/aspen\/2026\/01\/25\/gregory-bovino-rostro-antiinmigratoria-trax\/","url_meta":{"origin":1468229,"position":4},"title":"\u00bfC\u00f3mo se convirti\u00f3 Gregory Bovino en el rostro de la campa\u00f1a antiinmigratoria de Trump?","author":"","date":"enero 25, 2026","format":false,"excerpt":"Hace un a\u00f1o, pocos estadounidenses conoc\u00edan el nombre de Gregory Bovino. Ahora es el rostro de la campa\u00f1a antiinmigratoria de la administraci\u00f3n Trump.Y todo, desde las t\u00e1cticas del comandante general de la Patrulla Fronteriza en el campo hasta sus elecciones de vestuario, se ha convertido en un foco de atenci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467851,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/29\/jefe-patrulla-fronteriza-comparecer-jueza-federal-chicago-trax\/","url_meta":{"origin":1468229,"position":5},"title":"Tribunal suspende la orden que obligaba al jefe de la Patrulla Fronteriza en Chicago a comparecer ante una jueza federal","author":"","date":"octubre 29, 2025","format":false,"excerpt":"El jefe de la Patrulla Fronteriza, Gregory Bovino, no tendr\u00e1 que comparecer ante una jueza federal de Chicago la noche de este mi\u00e9rcoles, despu\u00e9s de que un tribunal de apelaciones suspendiera la orden de la jueza que exig\u00eda que Bovino presentara informes diarios en la corte sobre las t\u00e1cticas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1468229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1468229"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1468229\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1468229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1468229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1468229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}