{"id":1468253,"date":"2025-11-12T02:03:48","date_gmt":"2025-11-12T10:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/"},"modified":"2025-11-12T02:03:48","modified_gmt":"2025-11-12T10:03:48","slug":"analisis-corte-suprema-batalla-arancelaria-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/","title":{"rendered":"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump"},"content":{"rendered":"<p>En un caso en el que el presidente de la Corte Suprema de Justicia de EE.UU., John Roberts, se enfrenta al punto clave de la agenda del presidente, las decisiones pueden depender de lo que el magistrado considere un impuesto.<\/p>\n<p>Eso fue lo que sucedi\u00f3 con la Ley de Cuidado de Salud Asequible, u Obamacare, cuando <a href=\"https:\/\/www.cnn.com\/2019\/03\/21\/politics\/john-roberts-obamacare-the-chief\">Roberts sorprendi\u00f3 a los conservadores y republicanos<\/a> al defender la ley y su requisito, ya derogado, de que las personas deb\u00edan pagar una multa o un impuesto si no compraban un seguro m\u00e9dico.<\/p>\n<p>Ahora Roberts se enfrenta a los aranceles de Trump, que obviamente son un impuesto, pero que el presidente dice que son una herramienta.<\/p>\n<p>Revertir los aranceles, advirti\u00f3 Trump en una publicaci\u00f3n en redes sociales a altas horas de la madrugada de este martes, podr\u00eda costarle al Gobierno billones de d\u00f3lares.<\/p>\n<p>Fue tanto una indicaci\u00f3n de la presi\u00f3n que sufren los jueces con este caso como un recordatorio de que Trump aument\u00f3 unilateralmente los impuestos al imponer aranceles.<\/p>\n<p>Tambi\u00e9n ha sugerido un posible <a href=\"https:\/\/www.cnn.com\/2025\/11\/10\/economy\/tariff-rebate-check-proposal-what-to-know\">reembolso de US$ 2.000<\/a> para los contribuyentes estadounidenses.<\/p>\n<p>Cuando la Corte Suprema <a href=\"https:\/\/www.cnn.com\/2025\/11\/06\/politics\/supreme-court-tariffs-d-john-sauer-trump-lawyer\">escuch\u00f3 los argumentos orales la semana pasada<\/a> en una impugnaci\u00f3n al uso generalizado de poderes de emergencia por parte de Trump para imponer impuestos a casi todas las importaciones, surgi\u00f3 la opini\u00f3n de Roberts sobre los impuestos.<\/p>\n<p>Habl\u00e9 con Joan Biskupic, analista principal de la Corte Suprema de CNN, sobre los argumentos y c\u00f3mo los jueces abordar\u00e1n un caso que afecta a casi toda la econom\u00eda estadounidense y pone a prueba el lenguaje claro de la Constituci\u00f3n.<\/p>\n<p>A continuaci\u00f3n reproducimos nuestra conversaci\u00f3n, realizada por tel\u00e9fono y editada por motivos de extensi\u00f3n y claridad.<\/p>\n<p><strong>WOLF: <\/strong>Lo que me llam\u00f3 la atenci\u00f3n de los argumentos orales es que el caso de los aranceles podr\u00eda depender en \u00faltima instancia de si el presidente de la Corte Suprema, John Roberts, cree que los aranceles son impuestos.<\/p>\n<p>Me hizo pensar en Obamacare, la ley que Roberts salv\u00f3, en parte porque dedujo que el mandato individual era un impuesto. \u00bfEs una buena manera de plantearlo?<\/p>\n<p><strong>BISKUPIC:<\/strong> Hay algunos paralelismos con las dos principales iniciativas presidenciales, la de Obama en 2012 y la de Trump ahora. Y hay algunos paralelismos con la palabra \u201cimpuesto\u201d.<\/p>\n<p>Pero perm\u00edtanme darles algo de contexto que les ayudar\u00e1 a decidir si hay algo m\u00e1s en este caso que simplemente decir que un arancel podr\u00eda ser un impuesto.<\/p>\n<p>Hay varias corrientes encontradas aqu\u00ed, y no estamos seguros de qu\u00e9 prevalecer\u00e1 para los jueces. Por ejemplo, escuchamos preocupaciones de que el presidente estaba usurpando el poder del Congreso.<\/p>\n<p>En la direcci\u00f3n opuesta, escuchamos preocupaciones sobre la inhibici\u00f3n del poder ejecutivo sobre las relaciones exteriores.<\/p>\n<p><strong>WOLF: <\/strong>Si Roberts considera los aranceles como un impuesto, \u00bfsugiere eso que se opondr\u00e1 a las acciones de Trump, ya que la Constituci\u00f3n otorga al Congreso el poder de imponer impuestos?<\/p>\n<p><strong>BISKUPIC:<\/strong> Roberts dijo mucho durante la <a href=\"https:\/\/www.supremecourt.gov\/oral_arguments\/argument_transcripts\/2025\/24-1287_097c.pdf\">sesi\u00f3n de preguntas y respuestas,<\/a> lo que sugiere que s\u00ed considera los aranceles como un impuesto.<\/p>\n<p>Pero eso no es todo. Como dijo en un momento dado: \u201cLos aranceles son un impuesto, y ese es un poder fundamental del Congreso. Pero son, y voy a citarlo, \u2018un impuesto orientado al exterior\u2019\u201d. Y continu\u00f3 dici\u00e9ndole al abogado de los demandantes: \u201cLos asuntos exteriores son un poder fundamental del ejecutivo. Y no creo que se puedan ignorar las consecuencias\u201d.<\/p>\n<p>Por lo tanto, poder calificar estos aranceles como un tipo de impuesto no significa que definitivamente ser\u00e1n anulados.<\/p>\n<p>Durante la sesi\u00f3n de preguntas y respuestas, tambi\u00e9n se plante\u00f3 la cuesti\u00f3n de si los aranceles podr\u00edan compararse con las licencias, que podr\u00edan tener un mayor alcance regulatorio que un impuesto puramente generador de ingresos.<\/p>\n<p><strong>WOLF: <\/strong>Me sorprendi\u00f3 un poco que no se discutiera m\u00e1s durante los alegatos orales que la Constituci\u00f3n otorga espec\u00edficamente al Congreso la autoridad para imponer aranceles. \u00bfPor qu\u00e9 no?<\/p>\n<p><strong>BISKUPIC:<\/strong> El Congreso puede ceder parte de ese poder mediante legislaci\u00f3n. Y la pregunta es: \u00bfLe otorg\u00f3 el Congreso cierto poder arancelario al presidente en la IEEPA (Ley de Poderes Econ\u00f3micos de Emergencia Internacional)?<\/p>\n<p>Por lo general, la autoridad arancelaria es espec\u00edfica y est\u00e1 cuidadosamente delimitada por el Congreso. Pero la IEEPA ni siquiera menciona la palabra \u201carancel\u201d.<\/p>\n<p>La administraci\u00f3n Trump argumenta que el lenguaje de la IEEPA relacionado con la \u201cregulaci\u00f3n\u201d de las \u201cimportaciones\u201d es lo suficientemente amplio como para abarcar los aranceles.<\/p>\n<p>Los tribunales inferiores no estuvieron de acuerdo.<\/p>\n<p><strong>WOLF: <\/strong>Estos aranceles son una parte importante de la agenda de Trump que prometi\u00f3 durante la campa\u00f1a. Su magnitud significa que afectan a gran parte de la econom\u00eda estadounidense.<br \/>\u00bfHasta qu\u00e9 punto es probable que los jueces hablen sobre su magnitud y si se debe mostrar deferencia hacia el presidente debido a las elecciones? \u00bfTendr\u00e1n en cuenta el contexto externo?<\/p>\n<p><strong>BISKUPIC:<\/strong> En algunos casos, lo externo se convierte en interno. Los asuntos relacionados con el poder ejecutivo pesan especialmente sobre esta mayor\u00eda conservadora.<\/p>\n<p>Y el tribunal ha dictaminado a lo largo del tiempo, no solo en la era conservadora actual, que un presidente tiene una amplia autoridad en materia de asuntos exteriores.<\/p>\n<p>As\u00ed que eso est\u00e1 en el ambiente, as\u00ed como el hecho de que esta es una iniciativa emblem\u00e1tica del presidente. Al igual que sucedi\u00f3 con Obamacare.<\/p>\n<p>Por lo tanto, lo que haga la Corte se ver\u00e1 como una gran aprobaci\u00f3n o un gran rechazo.<\/p>\n<p>Y no creo que se pueda descartar que a los jueces les preocupe si la gente conf\u00eda en la Corte, que no sea simplemente una herramienta de la administraci\u00f3n. Todos estos factores hacen que este sea un caso muy re\u00f1ido<\/p>\n<p>Creo que muchos de los jueces, especialmente el presidente, son conscientes de que existe esta narrativa p\u00fablica de que la Corte siempre se pone del lado de Donald Trump.<\/p>\n<p>Ahora bien, no les gusta esa narrativa. No creen en esa narrativa. Pero est\u00e1 ah\u00ed. No digo que estos factores ser\u00edan decisivos, pero no creo que podamos descartarlos.<\/p>\n<p><strong>WOLF: <\/strong>Los jueces han hablado de sus preocupaciones sobre la seguridad. \u00bfCree que tienen miedo o se sienten intimidados ante la idea de enfrentarse a Trump de forma importante?<\/p>\n<p><strong>BISKUPIC:<\/strong> No. No lo creo. Analicemos a los nueve: creo que tenemos tres jueces que lo apoyar\u00e1n en esta disputa arancelaria: Clarence Thomas, Samuel Alito y Brett Kavanaugh.<\/p>\n<p>En contra de \u00e9l parecen estar Sonia Sotomayor, Elena Kagan y Ketanji Brown Jackson.<\/p>\n<p>En el medio estar\u00edan el presidente y los jueces Neil Gorsuch y Amy Coney Barrett. No creo que ninguno de los tres tema contradecir a Trump, como usted lo expres\u00f3.<\/p>\n<p>Y mencion\u00f3 la seguridad. Dir\u00eda que es una preocupaci\u00f3n general en todo el poder judicial, pero estos jueces tienen seguridad las 24 horas.<\/p>\n<p>Francamente, son los jueces de tribunales inferiores quienes tienen temores m\u00e1s reales sobre su seguridad. Est\u00e1n en primera l\u00ednea y no est\u00e1n acostumbrados a estar tan expuestos al p\u00fablico.<\/p>\n<p>Y no creo que ninguno de los jueces sienta que no puede votar de cierta manera porque van a provocar la ira del presidente Trump. En muchos casos, est\u00e1n con \u00e9l de todos modos.<\/p>\n<p>Esa es la conclusi\u00f3n para esta Corte de supermayor\u00eda conservadora. Est\u00e1n muy alineados con Donald Trump en materia legal.<\/p>\n<p><strong>WOLF: <\/strong>\u00bfQu\u00e9 espera de la decisi\u00f3n?<\/p>\n<p><strong>BISKUPIC:<\/strong> Creo que el presidente, con un caso de esta magnitud, querr\u00e1 redactar la opini\u00f3n del tribunal. Al comenzar el caso, la ventaja estaba del lado de los demandantes debido a c\u00f3mo fallaron los tribunales inferiores.<\/p>\n<p>Y tal vez los jueces tambi\u00e9n est\u00e9n yendo en esa direcci\u00f3n. Pero recuerden que solo vimos un atisbo de sus puntos de vista en los alegatos orales.<\/p>\n<p>Ya han realizado una votaci\u00f3n privada y est\u00e1n comenzando negociaciones que tomar\u00e1n meses.<\/p>\n<p>Como dije, hay corrientes encontradas aqu\u00ed. No necesariamente creo que los votos cambien. Pero con Obamacare, el presidente hizo m\u00faltiples cambios de voto. As\u00ed que no se acaba hasta que se acaba.<\/p>\n<p><strong>WOLF: <\/strong>\u00bfPor qu\u00e9 cambi\u00f3 en el \u00faltimo minuto?<\/p>\n<p><strong>BISKUPIC:<\/strong> Al principio, estaba con sus compa\u00f1eros conservadores para anular Obamacare bajo la Cl\u00e1usula de Comercio. Pero luego decidi\u00f3 que pod\u00eda defenderlo bajo el poder tributario del Congreso. Por eso hiciste una conexi\u00f3n entre este caso y aquel sobre la palabra \u201cimpuesto\u201d.<\/p>\n<p><strong>WOLF:<\/strong> Es interesante que tengan que negociar entre ellos para llegar a algo en lo que todos est\u00e9n de acuerdo o en lo que la mayor\u00eda est\u00e9 de acuerdo.<\/p>\n<p><strong>BISKUPIC:<\/strong> Exactamente. Se necesitan cinco votos para la mayor\u00eda, pero el jefe podr\u00eda querer intentar conseguir m\u00e1s, con m\u00e1s concesiones, porque es un caso muy importante y hay mucho en juego para el presidente Trump y su agenda.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un caso en el que el presidente de la Corte Suprema de Justicia de EE.UU., John Roberts, se enfrenta al punto clave de la agenda del presidente, las decisiones pueden depender de lo que el magistrado considere un impuesto. Eso fue lo que sucedi\u00f3 con la Ley de Cuidado de Salud Asequible, u Obamacare, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468253","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"En un caso en el que el presidente de la Corte Suprema de Justicia de EE.UU., John Roberts, se enfrenta al punto clave de la agenda del presidente, las decisiones pueden depender de lo que el magistrado considere un impuesto. Eso fue lo que sucedi\u00f3 con la Ley de Cuidado de Salud Asequible, u Obamacare, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-12T10:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump\",\"datePublished\":\"2025-11-12T10:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/\"},\"wordCount\":1543,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/\",\"name\":\"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-12T10:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump - Noticias","og_description":"En un caso en el que el presidente de la Corte Suprema de Justicia de EE.UU., John Roberts, se enfrenta al punto clave de la agenda del presidente, las decisiones pueden depender de lo que el magistrado considere un impuesto. Eso fue lo que sucedi\u00f3 con la Ley de Cuidado de Salud Asequible, u Obamacare, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-12T10:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump","datePublished":"2025-11-12T10:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/"},"wordCount":1543,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/","name":"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-12T10:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfSon los aranceles un impuesto? La opini\u00f3n de la Corte Suprema podr\u00eda decidir el destino de la batalla arancelaria de Trump","url":"http:\/\/noticiasya.com\/aspen\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/11\/12\/analisis-corte-suprema-batalla-arancelaria-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-12T10:03:48Z","datePublished":"2025-11-12T10:03:48Z","dateModified":"2025-11-12T10:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfSon los aranceles un impuesto? La opini\\u00f3n de la Corte Suprema podr\\u00eda decidir el destino de la batalla arancelaria de Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/11\\\/12\\\/analisis-corte-suprema-batalla-arancelaria-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/11\\\/12\\\/analisis-corte-suprema-batalla-arancelaria-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-12T10:03:48Z\",\"datePublished\":\"2025-11-12T10:03:48Z\",\"dateModified\":\"2025-11-12T10:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468065,"url":"https:\/\/noticiasya.com\/aspen\/2025\/11\/05\/conclusiones-argumentos-trump-corte-suprema-aranceles-trax\/","url_meta":{"origin":1468253,"position":0},"title":"Conclusiones de los argumentos de Trump ante la Corte Suprema sobre los aranceles globales","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"La Corte Suprema mostr\u00f3 profunda preocupaci\u00f3n este mi\u00e9rcoles por la dependencia del presidente Donald Trump en una ley federal ambigua para imponer aranceles globales, con varios miembros del ala conservadora cuestionando la postura del Gobierno en un caso que podr\u00eda tener amplias implicaciones para la econom\u00eda y el poder presidencial.Durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471484,"url":"https:\/\/noticiasya.com\/aspen\/2026\/02\/20\/corte-suprema-aranceles-ilegales-trump-trax\/","url_meta":{"origin":1468253,"position":1},"title":"La Corte Suprema dictamina que los aranceles de Trump son ilegales","author":"","date":"febrero 20, 2026","format":false,"excerpt":"Este viernes, la Corte Suprema dictamin\u00f3 que el presidente Donald Trump viol\u00f3 la ley federal al imponer unilateralmente aranceles generalizados en todo el mundo, en una contundente derrota para la pol\u00edtica exterior de la Casa Blanca y la agenda econ\u00f3mica del presidente.Esta decisi\u00f3n es posiblemente la derrota m\u00e1s importante que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471506,"url":"https:\/\/noticiasya.com\/aspen\/2026\/02\/21\/corte-suprema-ee-uu-enfrenta-trump-aranceles-trax\/","url_meta":{"origin":1468253,"position":2},"title":"La Corte Suprema de EE.UU. se enfrenta a Trump en materia de aranceles de emergencia. Conclusiones sobre un fallo clave","author":"","date":"febrero 21, 2026","format":false,"excerpt":"La Corte Suprema de Justicia de EE.UU. anul\u00f3 este viernes los amplios aranceles de emergencia del presidente Donald Trump, una decisi\u00f3n importante que podr\u00eda reorientar el curso de la agenda econ\u00f3mica y de pol\u00edtica exterior de la administraci\u00f3n.La decisi\u00f3n de 6-3, que incluy\u00f3 a jueces tanto conservadores como liberales en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470553,"url":"https:\/\/noticiasya.com\/aspen\/2026\/01\/28\/decision-corte-suprema-aranceles-trump-trax\/","url_meta":{"origin":1468253,"position":3},"title":"\u00bfD\u00f3nde est\u00e1 la decisi\u00f3n de la Corte Suprema sobre los aranceles de Trump?","author":"","date":"enero 28, 2026","format":false,"excerpt":"Cuando la Corte Suprema accedi\u00f3 en septiembre a escuchar una disputa sobre los aranceles multimillonarios impuestos por el presidente Donald Trump a los productos extranjeros, atendi\u00f3 la petici\u00f3n del Gobierno de que el tiempo era crucial.Para Trump, el caso es una cuesti\u00f3n de \u201cVIDA O MUERTE para nuestro pa\u00eds\u201d, como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471517,"url":"https:\/\/noticiasya.com\/aspen\/2026\/02\/21\/john-roberts-trump-corte-suprema-trax\/","url_meta":{"origin":1468253,"position":4},"title":"John Roberts pone fin a la racha de victorias de Trump en la Corte Suprema","author":"","date":"febrero 21, 2026","format":false,"excerpt":"El presidente del Tribunal Supremo, John Roberts, aport\u00f3 dramatismo el viernes al subir al estrado del tribunal para declarar, por fin, que los aranceles del presidente Donald Trump son ilegales.Durante 10 apasionantes minutos, expuso met\u00f3dicamente los argumentos contra la emblem\u00e1tica iniciativa econ\u00f3mica de Trump, que ha generado miles de millones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471631,"url":"https:\/\/noticiasya.com\/aspen\/2026\/02\/25\/trump-corte-suprema-aranceles-trax\/","url_meta":{"origin":1468253,"position":5},"title":"Trump critica el &#171;fallo desafortunado&#187; de la Corte Suprema sobre aranceles mientras los jueces guardan silencio","author":"","date":"febrero 25, 2026","format":false,"excerpt":"El presidente Donald Trump utiliz\u00f3 su discurso sobre el Estado de la Uni\u00f3n el martes para criticar la decisi\u00f3n de la Corte Suprema contra sus amplios aranceles de emergencia, calificando repetidamente el fallo de \u201cdesafortunado\u201d, aunque sugiri\u00f3 que su administraci\u00f3n lo superar\u00eda r\u00e1pidamente.Con cuatro jueces sentados a escasos metros de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1468253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1468253"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1468253\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1468253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1468253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1468253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}