{"id":1468302,"date":"2025-11-13T07:03:42","date_gmt":"2025-11-13T15:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/"},"modified":"2025-11-13T07:03:42","modified_gmt":"2025-11-13T15:03:42","slug":"bloquean-casinos-mexico-presunto-lavado-dinero-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/","title":{"rendered":"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero"},"content":{"rendered":"<p>La Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico de M\u00e9xico bloque\u00f3 la operaci\u00f3n en 13 casinos en donde se detectaron operaciones millonarias en efectivo, flujos internacionales y uso de plataformas digitales no supervisadas, seg\u00fan informaron.<\/p>\n<p>El secretario de Seguridad y Protecci\u00f3n Ciudadana, Omar Garc\u00eda Harfuch, detall\u00f3 que, luego de una investigaci\u00f3n interinstitucional, se detectaron trece casas de juego f\u00edsicas y virtuales con operaciones irregulares en Jalisco, Nuevo Le\u00f3n, Sinaloa, Sonora, Baja California, Estado de M\u00e9xico, Chiapas y Ciudad de M\u00e9xico.<\/p>\n<p>Tras los hallazgos, se presentaron denuncias ante la Fiscal\u00eda General de la Rep\u00fablica, se notific\u00f3 a la Procuradur\u00eda Fiscal y se suspendieron actividades, bloquearon sitios web y cuentas bancarias, detall\u00f3 Garc\u00eda Harfuch.<\/p>\n<p>\u201cLa unidad de inteligencia financiera, encargada de integrar los reportes de operaciones inusuales, as\u00ed como de realizar el an\u00e1lisis estrat\u00e9gico y operativo, permiti\u00f3 identificar redes financieras vinculadas con presuntas actividades il\u00edcitas\u201d, se\u00f1al\u00f3 el funcionario en conferencia de prensa este mi\u00e9rcoles.<\/p>\n<p>Entre otras cosas, se detectaron \u201ccasinos con operaciones en efectivo y simulaci\u00f3n fiscal, donde se registr\u00f3 dispersi\u00f3n de recursos entre filiales y declaraciones en cerros\u201d; \u201ccasinos con flujos internacionales de origen extranjero que transfirieron grandes montos a pa\u00edses como Ruman\u00eda, Suiza y Estados Unidos sin justificar su procedencia\u201d; \u201ccasinos digitales o plataformas tecnol\u00f3gicas no supervisadas que operaron pagos en l\u00ednea y agregadores tecnol\u00f3gicos con destino a Malta y Emiratos \u00c1rabes Unidos, fuera de la regulaci\u00f3n financiera nacional\u201d, detall\u00f3 Garc\u00eda Harfuch.<\/p>\n<p>Tras esta investigaci\u00f3n, el Gobierno de M\u00e9xico anunci\u00f3 que impulsar\u00e1 reformas a la ley para regular los casinos y las plataformas digitales de apuestas.<\/p>\n<p>\u201cHoy se hacen much\u00edsimas apuestas de manera digital. Existen los casinos f\u00edsicos a donde van a hacer apuestas las personas, todos tienen que cumplir una normatividad, pero ahora ya hay much\u00edsimos, lo ven ustedes anunciado en much\u00edsimas redes sociales, televisi\u00f3n, etc\u00e9tera, muchos casinos digitales\u201d, dijo la presidenta Claudia Sheinbaum en su rueda de prensa del mi\u00e9rcoles, al reconocer que la regulaci\u00f3n tiene que actualizarse.<\/p>\n<p>\u201cParte de la estrategia de seguridad ten\u00eda que ver tambi\u00e9n con lo que dicen muchos expertos (\u2026) que es dar seguimiento al recurso que est\u00e1 vinculado presuntamente con la delincuencia organizada o con alg\u00fan esquema de lavado de dinero\u201d, dijo Sheinbaum. La mandataria sostuvo que el delito que se investiga en este caso es el lavado de dinero, aunque no necesariamente vinculado a un grupo criminal espec\u00edfico.<\/p>\n<p>Tambi\u00e9n resalt\u00f3 la cooperaci\u00f3n internacional en el seguimiento financiero, con unidades de inteligencia financiera en Estados Unidos y en otros pa\u00edses del mundo.<\/p>\n<p><em>Con informaci\u00f3n de la agencia EFE<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico de M\u00e9xico bloque\u00f3 la operaci\u00f3n en 13 casinos en donde se detectaron operaciones millonarias en efectivo, flujos internacionales y uso de plataformas digitales no supervisadas, seg\u00fan informaron. El secretario de Seguridad y Protecci\u00f3n Ciudadana, Omar Garc\u00eda Harfuch, detall\u00f3 que, luego de una investigaci\u00f3n interinstitucional, se detectaron trece casas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468302","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico de M\u00e9xico bloque\u00f3 la operaci\u00f3n en 13 casinos en donde se detectaron operaciones millonarias en efectivo, flujos internacionales y uso de plataformas digitales no supervisadas, seg\u00fan informaron. El secretario de Seguridad y Protecci\u00f3n Ciudadana, Omar Garc\u00eda Harfuch, detall\u00f3 que, luego de una investigaci\u00f3n interinstitucional, se detectaron trece casas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-13T15:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero\",\"datePublished\":\"2025-11-13T15:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/\"},\"wordCount\":492,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/\",\"name\":\"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-13T15:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero - Noticias","og_description":"La Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico de M\u00e9xico bloque\u00f3 la operaci\u00f3n en 13 casinos en donde se detectaron operaciones millonarias en efectivo, flujos internacionales y uso de plataformas digitales no supervisadas, seg\u00fan informaron. El secretario de Seguridad y Protecci\u00f3n Ciudadana, Omar Garc\u00eda Harfuch, detall\u00f3 que, luego de una investigaci\u00f3n interinstitucional, se detectaron trece casas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-13T15:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/"},"author":{"name":"","@id":""},"headline":"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero","datePublished":"2025-11-13T15:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/"},"wordCount":492,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/","name":"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-13T15:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Bloquean la operaci\u00f3n de 13 casinos en M\u00e9xico por presunto lavado de dinero","url":"http:\/\/noticiasya.com\/aspen\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/11\/13\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-13T15:03:42Z","datePublished":"2025-11-13T15:03:42Z","dateModified":"2025-11-13T15:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Bloquean la operaci\\u00f3n de 13 casinos en M\\u00e9xico por presunto lavado de dinero\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/11\\\/13\\\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/11\\\/13\\\/bloquean-casinos-mexico-presunto-lavado-dinero-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-13T15:03:42Z\",\"datePublished\":\"2025-11-13T15:03:42Z\",\"dateModified\":\"2025-11-13T15:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464405,"url":"https:\/\/noticiasya.com\/aspen\/2025\/07\/10\/tension-diplomatica-el-salvador-mexico-interceptacion-avioneta-droga-orix\/","url_meta":{"origin":1468302,"position":0},"title":"Tensi\u00f3n diplom\u00e1tica entre El Salvador y M\u00e9xico por interceptaci\u00f3n de avioneta con droga","author":"","date":"julio 10, 2025","format":false,"excerpt":"El presidente de El Salvador, Nayib Bukele, ha vuelto a pedir este mi\u00e9rcoles una aclaraci\u00f3n al Gobierno de M\u00e9xico sobre una avioneta interceptada que transportaba coca\u00edna, despu\u00e9s de que autoridades de ese pa\u00eds aseguraran que proven\u00eda de tierras salvadore\u00f1as.La tensi\u00f3n comenz\u00f3 el martes cuando el secretario de Seguridad y Protecci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464064,"url":"https:\/\/noticiasya.com\/aspen\/2025\/06\/30\/mexico-combustible-robo-detenidos-orix\/","url_meta":{"origin":1468302,"position":1},"title":"Detienen en M\u00e9xico a 43 presuntos integrantes de dos redes dedicadas al robo de combustibles","author":"","date":"junio 30, 2025","format":false,"excerpt":"Autoridades de M\u00e9xico detuvieron a 43 presuntos integrantes de dos redes dedicadas al robo de combustibles en diversas entidades del pa\u00eds, inform\u00f3 este domingo el secretario de Seguridad federal, Omar Garc\u00eda Harfuch.Los arrestos se realizaron en dos operaciones, una en el centro de M\u00e9xico y otra en el norte, dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458593,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/11\/investigacion-piloto-operacion-contra-mayo-zambada-orix\/","url_meta":{"origin":1468302,"position":2},"title":"M\u00e9xico investiga a piloto presuntamente vinculado a operaci\u00f3n contra Ismael &#171;El Mayo&#187; Zambada","author":"","date":"febrero 11, 2025","format":false,"excerpt":"El secretario de Seguridad de M\u00e9xico, Omar Garc\u00eda Harfuch, confirm\u00f3 este martes que se investiga a un hombre detenido el 8 de febrero en Sinaloa, quien ser\u00eda un \u201cpiloto de confianza del l\u00edder de la c\u00e9lula delictiva\u201d presuntamente involucrada en la operaci\u00f3n que termin\u00f3 con la entrega de Ismael \u201cEl\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468557,"url":"https:\/\/noticiasya.com\/aspen\/2025\/11\/20\/presunto-autor-intelectual-homicidio-manzo-quien-es-orix\/","url_meta":{"origin":1468302,"position":3},"title":"\u00bfQu\u00e9 sabemos del presunto autor intelectual del homicidio del alcalde de Uruapan en M\u00e9xico?","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"Autoridades de seguridad de M\u00e9xico anunciaron el mi\u00e9rcoles la detenci\u00f3n de uno de los presuntos autores intelectuales del homicidio de Carlos Manzo, el alcalde del municipio de Uruapan asesinado la noche del 1 de noviembre despu\u00e9s de participar en una festividad p\u00fablica de ese municipio del estado de Michoac\u00e1n.El secretario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465472,"url":"https:\/\/noticiasya.com\/aspen\/2025\/08\/13\/como-operativo-mexico-eeuu-miembros-carteles-orix\/","url_meta":{"origin":1468302,"position":4},"title":"\u00bfC\u00f3mo fue el operativo en el que M\u00e9xico envi\u00f3 a EE.UU. a 26 miembros de c\u00e1rteles que estaban en prisi\u00f3n?","author":"","date":"agosto 13, 2025","format":false,"excerpt":"El Gobierno de M\u00e9xico envi\u00f3 el martes a Estados Unidos a 26 miembros de c\u00e1rteles del narcotr\u00e1fico que se encontraban en prisiones federales y estatales del pa\u00eds.Entre estos integrantes, que fueron enviados en avi\u00f3n, destacan Abigael Gonz\u00e1lez Valencia, l\u00edder de \u201cLos Cuinis\u201d, grupo vinculado al C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG);\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460406,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/25\/incautan-drogas-fentanilo-operacion-frontera-norte-orix\/","url_meta":{"origin":1468302,"position":5},"title":"Incautan 23.000 kilos de drogas y casi un mill\u00f3n de pastillas de fentanilo en Operaci\u00f3n Frontera Norte, dicen autoridades","author":"","date":"marzo 25, 2025","format":false,"excerpt":"El secretario de Seguridad y Protecci\u00f3n Ciudadana de M\u00e9xico, Omar Garc\u00eda Harfuch, inform\u00f3 este marte sobre los resultados de la Operaci\u00f3n Frontera Norte, entre los cuales se encuentran el decomiso de m\u00e1s de 23.000 kilos de drogas, de estos 129 kilos son de fentanilo; tambi\u00e9n incautaron casi un mill\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1468302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1468302"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1468302\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1468302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1468302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1468302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}