{"id":1469217,"date":"2025-12-12T11:03:40","date_gmt":"2025-12-12T19:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/"},"modified":"2025-12-12T11:03:40","modified_gmt":"2025-12-12T19:03:40","slug":"centavo-dolar-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/aspen\/2025\/12\/12\/centavo-dolar-trump-trax\/","title":{"rendered":"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses"},"content":{"rendered":"<p>Las pr\u00f3ximas se\u00f1ales de la divisi\u00f3n pol\u00edtica de Estados Unidos podr\u00edan sonar en tu bolsillo en 2026.<\/p>\n<p>El Gobierno planea emitir una moneda de 1 d\u00f3lar con la imagen del presidente Donald Trump el pr\u00f3ximo a\u00f1o, a pesar de un precedente centenario de no honrar a presidentes en ejercicio ni expresidentes vivos en las monedas.<\/p>\n<p>Adem\u00e1s, en lugar de monedas de 25 centavos que conmemoran la abolici\u00f3n de la esclavitud, el derecho al voto de las mujeres y el movimiento por los Derechos Civiles, el Tesoro emitir\u00e1 monedas hist\u00f3ricas de 25 centavos con hombres blancos de los siglos XVIII y XIX, que ya estaban bien representados en las monedas y en homenajes hist\u00f3ricos.<\/p>\n<p>Las nuevas monedas, que llegar\u00e1n despu\u00e9s de que el Gobierno dejara de emitir nuevos centavos a principios de este a\u00f1o, evidencian el af\u00e1n de Trump por dejar su propia huella en la Presidencia mucho m\u00e1s all\u00e1 de los confines de la Casa Blanca, ya sea poniendo su rostro y nombre en las instituciones estadounidenses o reduciendo las iniciativas de diversidad para replantear la historia de Estados Unidos.<\/p>\n<p>La Casa de la Moneda de Estados Unidos public\u00f3 el jueves los dise\u00f1os finales de las monedas de 25 centavos hist\u00f3ricas que celebran el 250 \u00ba aniversario del pa\u00eds el pr\u00f3ximo a\u00f1o. En lugar de la lucha contra la esclavitud o la concesi\u00f3n del voto a las mujeres, los dise\u00f1os honran principalmente una visi\u00f3n m\u00e1s homog\u00e9nea de la historia estadounidense: George Washington por la Guerra de la Independencia, Thomas Jefferson y la Declaraci\u00f3n de Independencia, James Madison y la Constituci\u00f3n, Abraham Lincoln y el discurso de Gettysburg, as\u00ed como a los peregrinos que celebraron el Pacto del Mayflower.<\/p>\n<p>\u201cLos dise\u00f1os de estas monedas hist\u00f3ricas representan la historia del camino de Estados Unidos hacia una \u2018uni\u00f3n m\u00e1s perfecta\u2019 y celebran los ideales de libertad que definen a Estados Unidos\u201d, declar\u00f3 Kristie McNally, directora interina de la Casa de la Moneda, en un comunicado. \u201cEsperamos ofrecer a cada estadounidense la oportunidad de tener en la palma de su mano los 250 a\u00f1os de historia de nuestra naci\u00f3n, mientras conectamos a Estados Unidos a trav\u00e9s de las monedas\u201d.<\/p>\n<p>La Casa de la Moneda no explic\u00f3 por qu\u00e9 decidi\u00f3 eliminar las monedas de veinticinco centavos que se recomendaban anteriormente para homenajear la abolici\u00f3n de la esclavitud, el sufragio y el movimiento por los Derechos Civiles. Ni el Departamento del Tesoro, encargado de la aprobaci\u00f3n final de los dise\u00f1os de las monedas, ni la Casa de la Moneda de Estados Unidos respondieron a las preguntas de CNN sobre el cambio.<\/p>\n<p>Sin embargo, Trump ha atacado regularmente a museos y otras instituciones por su visi\u00f3n demasiado negativa de Estados Unidos y su historia.<\/p>\n<p>En marzo, emiti\u00f3 un decreto para revocar las exhibiciones en propiedades federales como el Smithsonian que, seg\u00fan \u00e9l, retrataban err\u00f3neamente el \u201clegado incomparable de la naci\u00f3n en la promoci\u00f3n de la libertad, los derechos individuales y la felicidad humana\u201d. La orden fue ampliamente considerada como parte de los intentos del Gobierno de frenar las iniciativas de diversidad.<\/p>\n<p>La abolici\u00f3n de la esclavitud, el sufragio femenino y las monedas conmemorativas de los Derechos Civiles no hab\u00edan sido temas aprobados por el Departamento del Tesoro para conmemorar el 250 \u00ba aniversario de Estados Unidos. Sin embargo, estos temas fueron recomendados el a\u00f1o pasado por el Comit\u00e9 ciudadano asesor de monedas, un organismo gubernamental bipartidista, seg\u00fan las actas de la reuni\u00f3n revisadas por CNN.<\/p>\n<p>El panel recomend\u00f3 una moneda por la abolici\u00f3n de la esclavitud con la imagen de Frederick Douglass, destacado abolicionista y l\u00edder de los Derechos Civiles del siglo XIX, en el anverso. En el reverso, una mano y un brazo liber\u00e1ndose de cadenas.<\/p>\n<p>La moneda por el sufragio femenino habr\u00eda mostrado a una mujer portando una pancarta que ped\u00eda \u201cVoto para las Mujeres\u201d.<\/p>\n<p>Y la moneda por los Derechos Civiles habr\u00eda mostrado a Ruby Bridges, una ni\u00f1a de seis a\u00f1os, con sus libros escolares cerca del pecho mientras integraba una escuela primaria en Nueva Orleans en 1960. Ella y otras tres compa\u00f1eras negras fueron acompa\u00f1adas a clase por alguaciles federales. El reverso de la moneda hubiera mostrado a manifestantes por los Derechos Civiles abrazados.<\/p>\n<p>Los dise\u00f1os, desarrollados a lo largo de a\u00f1os, surgieron de la legislaci\u00f3n que el propio Trump firm\u00f3 en la \u00faltima semana de su primer mandato en 2021.<\/p>\n<p>Dicha ley, que establec\u00eda que Estados Unidos podr\u00eda emitir hasta cinco monedas de 25 centavos en 2026 para celebrar el 250.\u00ba aniversario de Estados Unidos, establec\u00eda que un dise\u00f1o deb\u00eda ser \u201cemblem\u00e1tico de la contribuci\u00f3n de una o varias mujeres al nacimiento de la naci\u00f3n, a la Declaraci\u00f3n de Independencia o a cualquier otro momento monumental de la historia estadounidense\u201d.<\/p>\n<p>La controvertida moneda de d\u00f3lar de Trump tambi\u00e9n forma parte del plan del Tesoro para conmemorar el 250 \u00ba aniversario de Estados Unidos.<\/p>\n<p>La Casa de la Moneda de Estados Unidos emiti\u00f3 el jueves tres propuestas de moneda con distintas im\u00e1genes de Trump, incluyendo una que se asemeja a su famosa foto policial de 2023. Los dise\u00f1os del reverso incluyen diferentes versiones del \u00e1guila americana.<\/p>\n<p>Una versi\u00f3n anterior de la moneda tambi\u00e9n mostraba a Trump en el reverso, levantando el pu\u00f1o tras un intento de asesinato el a\u00f1o pasado. Sin embargo, la ley estadounidense proh\u00edbe las im\u00e1genes de personas vivas en el reverso de las monedas. No existe tal restricci\u00f3n en los anversos, aunque la ley estadounidense desde 1866 establece que no pueden aparecer personas vivas en el papel moneda.<\/p>\n<p>Aun as\u00ed, la moneda de Trump marcar\u00e1 la segunda vez que una moneda estadounidense presente a un presidente vivo. La primera fue una moneda de medio d\u00f3lar con George Washington y el entonces presidente Calvin Coolidge, emitida en 1926 para conmemorar el 150\u00ba aniversario del pa\u00eds.<\/p>\n<p>Fue extremadamente impopular: del mill\u00f3n de monedas acu\u00f1adas, casi 860.000 fueron devueltas a la Casa de la Moneda y fundidas, seg\u00fan la Asociaci\u00f3n Numism\u00e1tica Estadounidense.<\/p>\n<p>Ir\u00f3nicamente, como parte de la conmemoraci\u00f3n del 250 \u00ba aniversario de la naci\u00f3n, la Casa de la Moneda planea emitir una cantidad limitada de centavos una vez m\u00e1s el pr\u00f3ximo a\u00f1o, marcando los a\u00f1os 1776-2026 en ellos.<\/p>\n<p>De lo contrario, los centavos ser\u00e1n id\u00e9nticos a los centavos regulares, que la Casa de la Moneda acaba de descontinuar.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las pr\u00f3ximas se\u00f1ales de la divisi\u00f3n pol\u00edtica de Estados Unidos podr\u00edan sonar en tu bolsillo en 2026. El Gobierno planea emitir una moneda de 1 d\u00f3lar con la imagen del presidente Donald Trump el pr\u00f3ximo a\u00f1o, a pesar de un precedente centenario de no honrar a presidentes en ejercicio ni expresidentes vivos en las monedas. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469217","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las pr\u00f3ximas se\u00f1ales de la divisi\u00f3n pol\u00edtica de Estados Unidos podr\u00edan sonar en tu bolsillo en 2026. El Gobierno planea emitir una moneda de 1 d\u00f3lar con la imagen del presidente Donald Trump el pr\u00f3ximo a\u00f1o, a pesar de un precedente centenario de no honrar a presidentes en ejercicio ni expresidentes vivos en las monedas. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T19:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses\",\"datePublished\":\"2025-12-12T19:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/\"},\"wordCount\":1142,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/\",\"name\":\"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-12T19:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses - Noticias","og_description":"Las pr\u00f3ximas se\u00f1ales de la divisi\u00f3n pol\u00edtica de Estados Unidos podr\u00edan sonar en tu bolsillo en 2026. El Gobierno planea emitir una moneda de 1 d\u00f3lar con la imagen del presidente Donald Trump el pr\u00f3ximo a\u00f1o, a pesar de un precedente centenario de no honrar a presidentes en ejercicio ni expresidentes vivos en las monedas. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-12T19:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses","datePublished":"2025-12-12T19:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/"},"wordCount":1142,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/","name":"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-12T19:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/centavo-dolar-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/aspen\/2025\/12\/12\/centavo-dolar-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses","url":"http:\/\/noticiasya.com\/aspen\/2025\/12\/12\/centavo-dolar-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/aspen\/2025\/12\/12\/centavo-dolar-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-12T19:03:40Z","datePublished":"2025-12-12T19:03:40Z","dateModified":"2025-12-12T19:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Eliminar el centavo fue solo el comienzo: Trump est\\u00e1 reescribiendo las reglas de las monedas estadounidenses\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/12\\\/12\\\/centavo-dolar-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/aspen\\\/2025\\\/12\\\/12\\\/centavo-dolar-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-12T19:03:40Z\",\"datePublished\":\"2025-12-12T19:03:40Z\",\"dateModified\":\"2025-12-12T19:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458506,"url":"https:\/\/noticiasya.com\/aspen\/2025\/02\/10\/trump-detencion-centavos-trax\/","url_meta":{"origin":1469217,"position":0},"title":"Trump ordena al Tesoro que detenga la producci\u00f3n de monedas de un centavo","author":"","date":"febrero 10, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, anunci\u00f3 el domingo que dio instrucciones al secretario del Tesoro, Scott Bessent, para detener la producci\u00f3n de monedas de un centavo, citando el alto costo de producir los centavos.\u201cDurante demasiado tiempo, Estados Unidos ha acu\u00f1ado monedas de un centavo que literalmente nos cuestan m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468270,"url":"https:\/\/noticiasya.com\/aspen\/2025\/11\/12\/ultimo-centavo-acunado-trax\/","url_meta":{"origin":1469217,"position":1},"title":"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia","author":"","date":"noviembre 12, 2025","format":false,"excerpt":"El centavo estadounidense desaparecer\u00e1 este mi\u00e9rcoles tras una larga enfermedad. Ten\u00eda 238 a\u00f1os.El \u00faltimo centavo se acu\u00f1\u00f3 el mi\u00e9rcoles por la tarde en la Casa de la Moneda de Estados Unidos en Filadelfia, bajo la supervisi\u00f3n del tesorero estadounidense, Brandon Beach. El presidente Donald Trump anunci\u00f3 en febrero a trav\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462783,"url":"https:\/\/noticiasya.com\/aspen\/2025\/05\/25\/que-pasara-millones-centavos-produccion-trax\/","url_meta":{"origin":1469217,"position":2},"title":"\u00bfQu\u00e9 pasar\u00e1 con los 114.000 millones de centavos de Estados Unidos una vez que el pa\u00eds deje de producirlos?","author":"","date":"mayo 25, 2025","format":false,"excerpt":"El centavo estadounidense no desaparecer\u00e1 en el corto plazo.El Departamento del Tesoro de Estados Unidos anunci\u00f3 el jueves que planea comenzar a reducir la producci\u00f3n de la moneda de un centavo que ha acu\u00f1ado durante m\u00e1s de 230 a\u00f1os. Sin embargo, el centavo seguir\u00e1 siendo de curso legal y se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460518,"url":"https:\/\/noticiasya.com\/aspen\/2025\/03\/27\/coleccion-monedas-ususd-100-millones-enterrada-subastadas-trax\/","url_meta":{"origin":1469217,"position":3},"title":"Una colecci\u00f3n de monedas de US$ 100 millones, enterrada durante d\u00e9cadas, ser\u00e1 subastada","author":"","date":"marzo 27, 2025","format":false,"excerpt":"Se espera que una vasta colecci\u00f3n de monedas, gran parte de la cual estuvo enterrada bajo tierra durante m\u00e1s de 50 a\u00f1os, alcance m\u00e1s de US$ 100 millones en una subasta, seg\u00fan los expertos.La Colecci\u00f3n Traveller, considerada la colecci\u00f3n de monedas m\u00e1s cara jam\u00e1s subastada, se vender\u00e1 en los pr\u00f3ximos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456141,"url":"https:\/\/noticiasya.com\/aspen\/2024\/11\/28\/encuentran-monedas-oro-us-1-millon-robadas-naufragio-siglo-xviii-trax\/","url_meta":{"origin":1469217,"position":4},"title":"Encuentran monedas de oro valuadas en US$ 1 mill\u00f3n que fueron robadas en naufragios del siglo XVIII","author":"","date":"noviembre 28, 2024","format":false,"excerpt":"(CNN) -- Despu\u00e9s de una extensa investigaci\u00f3n, las autoridades de Florida recuperaron decenas de monedas de oro valoradas en m\u00e1s de US$ 1 mill\u00f3n que fueron robadas de un rescate de naufragio hace nueve a\u00f1os.Ahora puedes seguirnos en\u00a0WhatsApp ChannelLa Comisi\u00f3n de Conservaci\u00f3n de Pesca y Vida Silvestre de Florida anunci\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467100,"url":"https:\/\/noticiasya.com\/aspen\/2025\/10\/04\/diseno-moneda-usd1-trump-trax\/","url_meta":{"origin":1469217,"position":5},"title":"El dise\u00f1o preliminar de la moneda de US$ 1 de Trump es &#171;real&#187;, dice el tesorero de EE.UU.","author":"","date":"octubre 4, 2025","format":false,"excerpt":"Un retrato del presidente Donald Trump podr\u00eda aparecer en una moneda conmemorativa de US$ 1 emitida por la Casa de la Moneda de Estados Unidos en honor al 250\u00ba aniversario de Estados Unidos en 2026, seg\u00fan los primeros bocetos de las im\u00e1genes confirmados por el Departamento del Tesoro.\u201cNo hay noticias\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/aspen\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1469217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/comments?post=1469217"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/posts\/1469217\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/media?parent=1469217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/categories?post=1469217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/aspen\/wp-json\/wp\/v2\/tags?post=1469217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}