{"id":1448389,"date":"2024-04-23T00:03:59","date_gmt":"2024-04-23T07:03:59","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/"},"modified":"2024-04-23T00:03:59","modified_gmt":"2024-04-23T07:03:59","slug":"cervantes-shakespeare-murieron-mismo-dia-libro-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/","title":{"rendered":"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Cada 23 de abril se celebra el D\u00eda Internacional del Libro, pero \u00bfpor qu\u00e9 fue elegido este d\u00eda en especial?<\/p>\n<p>La Unesco lo explica en su p\u00e1gina web: el 23 de abril es &#171;un d\u00eda simb\u00f3lico&#187; para la literatura mundial &#171;ya que ese d\u00eda en 1616 fallecieron Cervantes, Shakespeare e Inca Garcilaso de la Vega&#187;.<\/p>\n<p>Adem\u00e1s, &#171;la fecha tambi\u00e9n coincide con el nacimiento o la muerte de otros autores prominentes como Maurice Druon, Haldor K. Laxness, Vladimir Nabokov, Josep Pla y Manuel Mej\u00eda Vallejo&#187;, explica la entidad de la ONU.<\/p>\n<p>Por eso, en 1995, la Conferencia General de la Unesco, que se celebra en Par\u00eds, decidi\u00f3 &#171;rendir un homenaje universal a los libros y autores en esta fecha, alentando a todos, y en particular a los j\u00f3venes, a descubrir el placer de la lectura&#187;.<\/p>\n<p>El D\u00eda del Libro tiene como objetivo &#171;valorar las irremplazables contribuciones de aquellos quienes han impulsado el progreso social y cultural de la humanidad&#187;, dice la Unesco.<\/p>\n<p>\u00bfMurieron el mismo d\u00eda Cervantes y Shakespeare?<\/p>\n<p>Pero, un momento.<\/p>\n<p>\u00bfDe verdad Cervantes y Shakespeare murieron el mismo d\u00eda del mismo a\u00f1o? Siempre se ha dicho eso, pero podr\u00eda no ser cierto del todo. \u00bfEl motivo? Ciertas costumbres y los calendarios usados por Espa\u00f1a y Gran Breta\u00f1a en aquella \u00e9poca.<\/p>\n<p>Miguel de Cervantes Saavedra no muri\u00f3 el 23 de abril, sino que lo enterraron ese d\u00eda. En realidad, muri\u00f3 el d\u00eda antes, el 22 de abril de 1616.<\/p>\n<p>As\u00ed lo indica el Ministerio de Educaci\u00f3n, Cultura y Deporte de Espa\u00f1a en la web conmemorativa del 400 aniversario de la muerte del escritor.<\/p>\n<p>En aquellos tiempos, la costumbre era enterrar al finado al d\u00eda siguiente de su fallecimiento \u2014algo que contin\u00faa hoy en d\u00eda\u2014 y anotar en la partida de defunci\u00f3n la fecha del enterramiento, no de la muerte, tal y como recuerda la agencia EFE.<\/p>\n<p>Es por eso que su muerte pas\u00f3 a la historia como el d\u00eda 23 de abril, cuando realmente ocurri\u00f3 el 22.<\/p>\n<p>\u00bfWilliam Shakespeare escrib\u00eda obras bajo la influencia de drogas?<\/p>\n<p>\u00bfY William Shakespeare? En este caso, las referencias de que muri\u00f3 el 23 de abril de 1616 son inequ\u00edvocas, as\u00ed lo dice la Enciclopedia Brit\u00e1nica, por ejemplo.<\/p>\n<p>Sin embargo, cuando se menciona la fecha se olvida un dato importante: el calendario que reg\u00eda a Reino Unido en aquella \u00e9poca.<\/p>\n<p>Hasta 1582 todo el mundo occidental se reg\u00eda por el calendario juliano, impuesto por el emperador romano Julio C\u00e9sar. Ese a\u00f1o el papa Gregorio XII cre\u00f3 el suyo propio: el gregoriano, que fue r\u00e1pidamente implantado en pa\u00edses cat\u00f3licos como Espa\u00f1a, Francia y Portugal, seg\u00fan relata Aciprensa.com.<\/p>\n<p>Reino Unido no implant\u00f3 el calendario gregoriano hasta el a\u00f1o 1752, seg\u00fan esta misma p\u00e1gina web. Es decir, en 1616, cuando murieron los dos escritores, ambos pa\u00edses se reg\u00edan por calendarios que difer\u00edan en 10 d\u00edas y, el 23 de abril de Reino Unido era, en Espa\u00f1a (y la gran parte del mundo occidental), el 3 de mayo de 1616.<\/p>\n<p>As\u00ed lo confirm\u00f3 a CNN en Espa\u00f1ol tambi\u00e9n Carlos Mayoral, fil\u00f3logo espa\u00f1ol y autor del libro &#171;Empiezo a creer que es mentira&#187;, quien describe como &#171;mito, postureo y marketing&#187; el hacer coincidir las dos defunciones.<\/p>\n<p>Miguel de Cervantes Saavedra cuatro siglos despu\u00e9s<\/p>\n<p>Las ciudades designadas Capital Mundial del Libro se comprometen a promover el libro y la lectura y a organizar actividades a lo largo del a\u00f1o.<\/p>\n<p>Entre las anteriores est\u00e1n:<\/p>\n<p>Madrid, Espa\u00f1a (2001)<\/p>\n<p>Alejandr\u00eda, Egipto (2002)<\/p>\n<p>Nueva Delhi, India (2003)<\/p>\n<p>Amberes, B\u00e9lgica (2004)<\/p>\n<p>Montreal, Canad\u00e1 (2005)<\/p>\n<p>Tur\u00edn, Italia (2006)<\/p>\n<p>Bogot\u00e1, Colombia (2007)<\/p>\n<p>\u00c1msterdam, Pa\u00edses Bajos (2008)<\/p>\n<p>Beirut, L\u00edbano (2009)<\/p>\n<p>Liubliana, Eslovenia (2010)<\/p>\n<p>Buenos Aires, Argentina (2011)<\/p>\n<p>Erevan, Armenia (2012)<\/p>\n<p>Bangkok, Tailandia (2013)<\/p>\n<p>Port Harcourt, Nigeria (2014)<\/p>\n<p>Incheon, Corea del Sur (2015)<\/p>\n<p>Breslavia, Polonia (2016)<\/p>\n<p>Conakry, Guinea (2017)<\/p>\n<p>Atenas, Grecia (2018)<\/p>\n<p>Sharjah, Emiratos \u00c1rabes Unidos (2019)<\/p>\n<p>Kuala Lumpur, Malasia (2020)<\/p>\n<p>Tiflis, Georgia (2021)<\/p>\n<p>Guadalajara, M\u00e9xico (2022)<\/p>\n<p>Accra, Ghana (2023)<\/p>\n<p>&#8212; Esta noticia ha sido publicada previamente y actualizada el 23 de abril del 2024.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Cada 23 de abril se celebra el D\u00eda Internacional del Libro, pero \u00bfpor qu\u00e9 fue elegido este d\u00eda en especial? La Unesco lo explica en su p\u00e1gina web: el 23 de abril es &#171;un d\u00eda simb\u00f3lico&#187; para la literatura mundial &#171;ya que ese d\u00eda en 1616 fallecieron Cervantes, Shakespeare e Inca Garcilaso [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448389","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Cada 23 de abril se celebra el D\u00eda Internacional del Libro, pero \u00bfpor qu\u00e9 fue elegido este d\u00eda en especial? La Unesco lo explica en su p\u00e1gina web: el 23 de abril es &#171;un d\u00eda simb\u00f3lico&#187; para la literatura mundial &#171;ya que ese d\u00eda en 1616 fallecieron Cervantes, Shakespeare e Inca Garcilaso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T07:03:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia\",\"datePublished\":\"2024-04-23T07:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/\"},\"wordCount\":710,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/\",\"name\":\"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-23T07:03:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Cada 23 de abril se celebra el D\u00eda Internacional del Libro, pero \u00bfpor qu\u00e9 fue elegido este d\u00eda en especial? La Unesco lo explica en su p\u00e1gina web: el 23 de abril es &#171;un d\u00eda simb\u00f3lico&#187; para la literatura mundial &#171;ya que ese d\u00eda en 1616 fallecieron Cervantes, Shakespeare e Inca Garcilaso [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-23T07:03:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/"},"author":{"name":"","@id":""},"headline":"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia","datePublished":"2024-04-23T07:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/"},"wordCount":710,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/","name":"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-23T07:03:59+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"D\u00eda del Libro 2024: \u00bfCervantes y Shakespeare murieron el mismo d\u00eda? Esta es la verdadera historia","url":"http:\/\/noticiasya.com\/boston\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/04\/23\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-23T07:03:59Z","datePublished":"2024-04-23T07:03:59Z","dateModified":"2024-04-23T07:03:59Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"D\\u00eda del Libro 2024: \\u00bfCervantes y Shakespeare murieron el mismo d\\u00eda? Esta es la verdadera historia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/04\\\/23\\\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/04\\\/23\\\/cervantes-shakespeare-murieron-mismo-dia-libro-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-23T07:03:59Z\",\"datePublished\":\"2024-04-23T07:03:59Z\",\"dateModified\":\"2024-04-23T07:03:59Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463559,"url":"https:\/\/noticiasya.com\/boston\/2025\/06\/14\/origen-dia-padre-cuando-se-celebra-por-que-orix\/","url_meta":{"origin":1448389,"position":0},"title":"\u00bfCu\u00e1l es el origen del D\u00eda del Padre en Estados Unidos, cu\u00e1ndo se celebra y por qu\u00e9?","author":"","date":"junio 14, 2025","format":false,"excerpt":"Como dicta la costumbre, el D\u00eda del Padre en Estados Unidos se lleva a cabo todos los meses de junio para celebrar a los pap\u00e1s en el pa\u00eds.La historia de la celebraci\u00f3n tiene una cercana relaci\u00f3n con el D\u00eda de la Madre y, desde sus or\u00edgenes, junio fue el mes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450346,"url":"https:\/\/noticiasya.com\/boston\/2024\/06\/14\/cuando-dia-del-padre-estados-unidos-2024-orix\/","url_meta":{"origin":1448389,"position":1},"title":"\u00bfCu\u00e1l es el origen del D\u00eda del Padre en Estados Unidos, cu\u00e1ndo se celebra y por qu\u00e9?","author":"","date":"junio 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Como dicta la costumbre, el D\u00eda del Padre en Estados Unidos se lleva a cabo todos los meses de junio para celebrar a los pap\u00e1s en el pa\u00eds.La historia de la celebraci\u00f3n tiene una cercana relaci\u00f3n con el D\u00eda de la Madre y, desde sus or\u00edgenes, junio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462205,"url":"https:\/\/noticiasya.com\/boston\/2025\/05\/10\/cuando-se-celebra-dia-de-madres-por-que-orix\/","url_meta":{"origin":1448389,"position":2},"title":"\u00bfCu\u00e1ndo se celebra el D\u00eda de las Madres en EE.UU. en 2025 y por qu\u00e9?","author":"","date":"mayo 10, 2025","format":false,"excerpt":"Estados Unidos celebra el D\u00eda de las Madres este domingo 11 de mayo, uni\u00e9ndose as\u00ed a otros pa\u00edses como M\u00e9xico, Colombia o Espa\u00f1a, que tambi\u00e9n conmemoran la labor de las madres en el mes de mayo.En EE.UU. y Colombia festejan a las mam\u00e1s el segundo domingo de cada mayo, es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449382,"url":"https:\/\/noticiasya.com\/boston\/2024\/05\/10\/cuando-celebra-dia-madre-colombia-por-que-orix\/","url_meta":{"origin":1448389,"position":3},"title":"\u00bfCu\u00e1ndo se celebra el D\u00eda de la Madre en Colombia y EE.UU. en 2024 y por qu\u00e9?","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2014 Colombia celebrar\u00e1 este a\u00f1o el D\u00eda de la Madre el domingo 12 de mayo, uni\u00e9ndose as\u00ed a otros pa\u00edses como M\u00e9xico, Estados Unidos o Espa\u00f1a que tambi\u00e9n conmemoran la labor de las madres en el mes de mayo.En Colombia y EE.UU. festejan a las mam\u00e1s el segundo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455049,"url":"https:\/\/noticiasya.com\/boston\/2024\/10\/12\/que-celebra-espana-dia-de-la-hispanidad-orix\/","url_meta":{"origin":1448389,"position":4},"title":"\u00bfQu\u00e9 celebra Espa\u00f1a en el D\u00eda de la Hispanidad?","author":"","date":"octubre 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El 12 de octubre es una fecha que se conmemora en diferentes lugares del mundo, y desde distintas perspectivas.Ese d\u00eda de 1942 la expedici\u00f3n de Cristobal Col\u00f3n toc\u00f3 tierra en la isla Guanahani, de las Bahamas, junto a una tripulaci\u00f3n de 90 personas que hab\u00edan zarpado unas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461821,"url":"https:\/\/noticiasya.com\/boston\/2025\/04\/30\/por-que-ee-uu-no-celebra-el-1-de-mayo-dia-del-trabajo-orix\/","url_meta":{"origin":1448389,"position":5},"title":"\u00bfPor qu\u00e9 EE.UU no celebra el 1 de mayo como el D\u00eda del Trabajo?","author":"","date":"abril 30, 2025","format":false,"excerpt":"El 1 de mayo se celebra el D\u00eda Internacional de los Trabajadores o, como se conoce en muchas partes del mundo, el D\u00eda del Trabajo. Sin embargo, en otras partes del mundo, no es un d\u00eda de protestas y manifestaciones, sino el momento para iniciar los festejos por la la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1448389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1448389"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1448389\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1448389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1448389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1448389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}