{"id":1448394,"date":"2024-04-23T01:03:42","date_gmt":"2024-04-23T08:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/"},"modified":"2024-04-23T01:03:42","modified_gmt":"2024-04-23T08:03:42","slug":"biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/","title":{"rendered":"&#171;Nadie deber\u00eda tener que vivir con miedo&#187;: Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva"},"content":{"rendered":"<p>(CNN) &#8212; Los pacientes tienen derecho a la intimidad en lo que respecta a su informaci\u00f3n m\u00e9dica, incluso cuando viajan a otro estado para someterse a un aborto, a un procedimiento de fertilizaci\u00f3n in vitro, a un control de natalidad u otros tipos de atenci\u00f3n de la salud reproductiva, declararon funcionarios federales en una nueva regla.<\/p>\n<p>La norma final, denominada Regla de privacidad de la HIPAA para apoyar la privacidad de la atenci\u00f3n sanitaria reproductiva, se anunci\u00f3 este lunes y proh\u00edbe la divulgaci\u00f3n de la informaci\u00f3n sanitaria de un paciente en lo que se refiere a la atenci\u00f3n sanitaria reproductiva, adem\u00e1s de reforzar la protecci\u00f3n de la privacidad de ese paciente, su familia y los m\u00e9dicos que le prestan o facilitan la atenci\u00f3n.<\/p>\n<p>Esto significa que la norma impide que los historiales m\u00e9dicos se utilicen en contra de las personas por proporcionar o recibir ciertos tipos de atenci\u00f3n sanitaria reproductiva, incluso si un paciente viaj\u00f3 a otro estado para recibir esa atenci\u00f3n, dijo Melanie Fontes Rainer, directora de la Oficina de Derechos Civiles, en una conferencia de prensa este lunes.<\/p>\n<p>&#171;Esta norma proh\u00edbe a los regulados por la HIPAA \u2014proveedores de atenci\u00f3n sanitaria, planes de salud, c\u00e1maras de compensaci\u00f3n y sus asociados comerciales\u2014 utilizar o divulgar la informaci\u00f3n sanitaria protegida de una persona para llevar a cabo una investigaci\u00f3n o imponer responsabilidad a cualquier persona por el mero hecho de buscar, obtener, proporcionar o facilitar atenci\u00f3n sanitaria reproductiva legal, incluido el aborto&#187;, dijo Rainer, refiri\u00e9ndose a la Ley de Portabilidad y Responsabilidad del Seguro M\u00e9dico de 1996.<\/p>\n<p>&#171;Si una persona recibe atenci\u00f3n m\u00e9dica reproductiva, como una prueba de embarazo o tratamiento para un embarazo ect\u00f3pico, y esa atenci\u00f3n m\u00e9dica reproductiva es legal en el estado donde se recibe la atenci\u00f3n, la informaci\u00f3n sobre la atenci\u00f3n no puede ser revelada o utilizada por el proveedor de atenci\u00f3n m\u00e9dica o plan de salud para una investigaci\u00f3n, o para imponer la responsabilidad por la aplicaci\u00f3n de la ley en el paciente o el proveedor&#187;, dijo. &#171;Y si la atenci\u00f3n sanitaria reproductiva, como la anticoncepci\u00f3n, est\u00e1 protegida, exigida o autorizada por la legislaci\u00f3n federal, incluida la Constituci\u00f3n, tampoco podr\u00e1 utilizarse ni divulgarse en virtud de esta norma&#187;.<\/p>\n<p>Aborto en Estados Unidos: en d\u00f3nde est\u00e1 prohibido, restringido o permitido<\/p>\n<p>En general, &#171;nadie deber\u00eda tener que vivir con el temor de que sus conversaciones con su m\u00e9dico o los datos de sus reclamaciones m\u00e9dicas puedan utilizarse para perseguirle o seguirle la pista por buscar atenci\u00f3n m\u00e9dica reproductiva legal&#187;, dijo Rainer.<\/p>\n<p>El a\u00f1o pasado, la Oficina de Derechos Civiles public\u00f3 los cambios propuestos a la Norma de Privacidad de la HIPAA y recibi\u00f3 casi 30.000 comentarios del p\u00fablico en respuesta a lo que deber\u00eda implicar la norma final, seg\u00fan el Departamento de Salud y Servicios Humanos de EE.UU..<\/p>\n<p>Ahora, la norma definitiva forma parte de un esfuerzo continuado de la administraci\u00f3n Biden-Harris por proteger el acceso a la atenci\u00f3n sanitaria reproductiva tras la anulaci\u00f3n del caso Roe vs. Wade, declar\u00f3 el Secretario del HHS, Xavier Becerra.<\/p>\n<p>&#171;Todos y cada uno de los estadounidenses siguen teniendo derecho a su intimidad, especialmente cuando se trata de informaci\u00f3n sanitaria muy privada y personal&#187;, declar\u00f3 Becerra este lunes. &#171;Seg\u00fan la legislaci\u00f3n federal, tienen derecho a su intimidad. De eso se trata hoy: de asegurarse de que los estadounidenses que transmiten informaci\u00f3n sanitaria muy personal y privada a un proveedor sepan que tienen derechos&#187;.<\/p>\n<p>La nueva norma llega en un momento en que 14 estados tienen prohibiciones totales del aborto.<\/p>\n<p>Tras la sentencia del Tribunal Supremo de junio de 2022 en el caso Dobbs contra Jackson Women&#8217;s Health Organization, que elimin\u00f3 el derecho constitucional al aborto en todo el pa\u00eds, casi dos decenas de estados de EE.UU. han prohibido o limitado el acceso a este procedimiento. Los estados donde el aborto est\u00e1 m\u00e1s limitado registran tasas m\u00e1s elevadas de mortalidad materna e infantil, as\u00ed como una mayor inseguridad econ\u00f3mica.<\/p>\n<p>Muchas pacientes que viven en estados con restricciones al aborto han tenido que viajar a estados sin restricciones para poder recibir atenci\u00f3n, dijo Rainer este lunes.<\/p>\n<p>AN\u00c1LISIS | Arizona demuestra que dejar el aborto en manos de los estados en EE.UU. no aliviar\u00e1 el problema que significa para Trump<\/p>\n<p>Seg\u00fan la nueva norma, &#171;cuando una mujer viaja de un estado donde la atenci\u00f3n podr\u00eda estar prohibida a otro para recibir atenci\u00f3n sanitaria reproductiva legal, independientemente de cu\u00e1l sea esa atenci\u00f3n sanitaria \u2014ya sea una p\u00edldora, un procedimiento o simplemente un examen m\u00e9dico\u2014, cuando esa mujer vuelva a casa, su historial m\u00e9dico estar\u00e1 protegido&#187;, dijo Rainer.<\/p>\n<p>&#171;Ella misma, sus proveedores, sus proveedores a domicilio que literalmente no tuvieron nada que ver con la atenci\u00f3n que recibi\u00f3 en primera instancia, estar\u00e1n protegidos, y podr\u00e1n decir &#8216;No, no pueden tener esta informaci\u00f3n'&#187;, dijo Rainer. &#171;El proveedor del estado al que viaj\u00f3 tambi\u00e9n estar\u00e1 protegido frente a la posibilidad de que la gente intente obtener ese tipo de atenci\u00f3n m\u00e9dica, que es uno de los principales objetivos de esta norma: que las mujeres puedan buscar atenci\u00f3n, incluso frente al mosaico de leyes que tenemos ahora en todo el pa\u00eds&#187;.<\/p>\n<p>La lucha en torno al aborto contin\u00faa en muchas legislaturas y tribunales estatales. Recientemente, el 9 de abril, el Tribunal Supremo de Arizona restableci\u00f3 una ley de 1864, de la \u00e9poca de la Guerra Civil, que prohib\u00eda el aborto en casi todas las circunstancias. La sentencia, sin embargo, se ha suspendido durante dos semanas, y mientras tanto sigue vigente la prohibici\u00f3n de las 15 semanas.<\/p>\n<p>Adem\u00e1s, el Tribunal Supremo de EE.UU. escuch\u00f3 en marzo los argumentos de un caso contra la p\u00edldora abortiva y esta semana ver\u00e1 un recurso contra la prohibici\u00f3n casi total de Idaho. En Florida, una prohibici\u00f3n de seis semanas sustituir\u00e1 a la actual prohibici\u00f3n de 15 semanas el 1 de mayo.<\/p>\n<p>Aunque la nueva norma final es un paso en el esfuerzo por proteger los derechos reproductivos de las mujeres en Estados Unidos, Becerra dijo que no deshar\u00e1 por completo los efectos que la anulaci\u00f3n de Roe contra Wade ha tenido en las pacientes de todo el pa\u00eds.<\/p>\n<p>&#171;No nos hacemos ilusiones de que todo lo que el presidente nos ha instado a hacer con nuestras autoridades vaya a deshacer Dobbs&#187;, dijo Becerra. &#171;Dobbs quit\u00f3 derechos. Hasta que no tengamos una ley nacional que reinstaure Roe v. Wade, vamos a tener problemas&#187;.<\/p>\n<p>&#8212; Annette Choi y Devan Cole de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los pacientes tienen derecho a la intimidad en lo que respecta a su informaci\u00f3n m\u00e9dica, incluso cuando viajan a otro estado para someterse a un aborto, a un procedimiento de fertilizaci\u00f3n in vitro, a un control de natalidad u otros tipos de atenci\u00f3n de la salud reproductiva, declararon funcionarios federales en una nueva [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448394","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Nadie deber\u00eda tener que vivir con miedo&quot;: Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Nadie deber\u00eda tener que vivir con miedo&quot;: Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los pacientes tienen derecho a la intimidad en lo que respecta a su informaci\u00f3n m\u00e9dica, incluso cuando viajan a otro estado para someterse a un aborto, a un procedimiento de fertilizaci\u00f3n in vitro, a un control de natalidad u otros tipos de atenci\u00f3n de la salud reproductiva, declararon funcionarios federales en una nueva [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T08:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Nadie deber\u00eda tener que vivir con miedo&#187;: Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva\",\"datePublished\":\"2024-04-23T08:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/\"},\"wordCount\":1189,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/\",\"name\":\"\\\"Nadie deber\u00eda tener que vivir con miedo\\\": Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-23T08:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Nadie deber\u00eda tener que vivir con miedo&#187;: Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Nadie deber\u00eda tener que vivir con miedo\": Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\"Nadie deber\u00eda tener que vivir con miedo\": Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva - Noticias","og_description":"(CNN) &#8212; Los pacientes tienen derecho a la intimidad en lo que respecta a su informaci\u00f3n m\u00e9dica, incluso cuando viajan a otro estado para someterse a un aborto, a un procedimiento de fertilizaci\u00f3n in vitro, a un control de natalidad u otros tipos de atenci\u00f3n de la salud reproductiva, declararon funcionarios federales en una nueva [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-23T08:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/"},"author":{"name":"","@id":""},"headline":"&#171;Nadie deber\u00eda tener que vivir con miedo&#187;: Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva","datePublished":"2024-04-23T08:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/"},"wordCount":1189,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/","name":"\"Nadie deber\u00eda tener que vivir con miedo\": Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-23T08:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Nadie deber\u00eda tener que vivir con miedo&#187;: Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Nadie deber\u00eda tener que vivir con miedo&#187;: Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\u00f3n sanitaria reproductiva","url":"http:\/\/noticiasya.com\/boston\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/04\/23\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-23T08:03:42Z","datePublished":"2024-04-23T08:03:42Z","dateModified":"2024-04-23T08:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Nadie deber\\u00eda tener que vivir con miedo&#187;: Gobierno de Biden promulga una nueva norma para proteger la intimidad de quienes buscan atenci\\u00f3n sanitaria reproductiva\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/04\\\/23\\\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/04\\\/23\\\/biden-regla-salud-reproductiva-privacidad-aborto-invitro-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-23T08:03:42Z\",\"datePublished\":\"2024-04-23T08:03:42Z\",\"dateModified\":\"2024-04-23T08:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450021,"url":"https:\/\/noticiasya.com\/boston\/2024\/06\/04\/estados-unidos-tasa-mortalidad-materna-altos-ingresos-trax\/","url_meta":{"origin":1448394,"position":0},"title":"Estados Unidos tiene la tasa m\u00e1s alta de mortalidad materna entre los pa\u00edses de altos ingresos","author":"","date":"junio 4, 2024","format":false,"excerpt":"(CNN) -- Estados Unidos sigue teniendo una tasa m\u00e1s alta de mujeres que mueren durante el embarazo, el parto o el posparto en comparaci\u00f3n con todas las dem\u00e1s naciones de altos ingresos, incluso a pesar de los recientes descensos en la tasa de mortalidad materna estadounidense, seg\u00fan muestra un nuevo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446978,"url":"https:\/\/noticiasya.com\/boston\/2024\/03\/14\/olivia-rodrigo-reparte-anticonceptivos-de-emergencia-gratuitos-trax\/","url_meta":{"origin":1448394,"position":1},"title":"Olivia Rodrigo reparte anticonceptivos de emergencia gratuitos en un concierto en EE.UU.","author":"","date":"marzo 14, 2024","format":false,"excerpt":"(CNN) -- Olivia Rodrigo puso anticonceptivos de emergencia a disposici\u00f3n de quienes asistieron al concierto de su gira \"Guts\" en Missouri el martes, como parte de su iniciativa Fund 4 Good.Como se pudo ver en las redes sociales, en el interior del local de St. Louis donde actu\u00f3 Rodrigo se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455588,"url":"https:\/\/noticiasya.com\/boston\/2024\/11\/05\/10-estados-decidiran-aborto-boleta-electoral-2024-trax\/","url_meta":{"origin":1448394,"position":2},"title":"Estos 10 estados tambi\u00e9n decidir\u00e1n sobre el aborto en la boleta electoral de 2024","author":"","date":"noviembre 5, 2024","format":false,"excerpt":"(CNN) -- M\u00e1s de dos a\u00f1os despu\u00e9s de que la Corte Suprema de EE.UU. anulara Roe v. Wade y pusiera fin al derecho constitucional federal al aborto, los votantes en 10 estados deciden si consolidar los derechos reproductivos en sus constituciones estatales.Esto va un paso m\u00e1s all\u00e1 para los residentes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452837,"url":"https:\/\/noticiasya.com\/boston\/2024\/09\/19\/estados-unidos-ocupa-ultimo-lugar-medidas-clave-de-asistencia-sanitaria-trax\/","url_meta":{"origin":1448394,"position":3},"title":"Estados Unidos ocupa el \u00faltimo lugar en medidas clave de asistencia sanitaria respecto a otros pa\u00edses de renta alta, a pesar de ser el que m\u00e1s gasta, seg\u00fan un informe","author":"","date":"septiembre 19, 2024","format":false,"excerpt":"(CNN) -- Estados Unidos gasta m\u00e1s en asistencia sanitaria que cualquier otro pa\u00eds de renta alta, pero un nuevo informe sugiere que \"los estadounidenses est\u00e1n m\u00e1s enfermos, mueren m\u00e1s j\u00f3venes y tienen dificultades para costearse la asistencia sanitaria esencial\".En comparaci\u00f3n con otros nueve pa\u00edses de renta alta, Estados Unidos ocupa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462837,"url":"https:\/\/noticiasya.com\/boston\/2025\/05\/27\/dolor-genital-cronico-gaslighting-medico-trax\/","url_meta":{"origin":1448394,"position":4},"title":"Las personas que sufren dolor genital cr\u00f3nico a menudo son manipuladas por los m\u00e9dicos: aqu\u00ed est\u00e1 el porqu\u00e9","author":"","date":"mayo 27, 2025","format":false,"excerpt":"Nota del editor: Las opiniones expresadas en este art\u00edculo son exclusivas de los autores. CNN presenta el trabajo de \u201cThe Conversation\u201d, una colaboraci\u00f3n entre periodistas y acad\u00e9micos para ofrecer an\u00e1lisis y comentarios de noticias. El contenido es producido exclusivamente por T\u201dhe Conversation\u201d.Para las personas con dolor ginecol\u00f3gico cr\u00f3nico, el dolor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444404,"url":"https:\/\/noticiasya.com\/boston\/2024\/01\/25\/casi-65-000-embarazos-por-violacion-ocurrieron-en-estados-con-prohibiciones-del-aborto-estima-un-estudio\/","url_meta":{"origin":1448394,"position":5},"title":"Casi 65.000 embarazos por violaci\u00f3n ocurrieron en estados con prohibiciones del aborto, estima un estudio","author":"","date":"enero 25, 2024","format":false,"excerpt":"(CNN) --\u00a0Decenas de miles de embarazos han sido el resultado de violaciones en estados donde el aborto no es una opci\u00f3n legal, estiman los investigadores en un nuevo estudio .En el estudio, publicado este mi\u00e9rcoles en la revista JAMA Internal Medicine, investigadores de Planned Parenthood, Resound Research for Reproductive Health\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1448394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1448394"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1448394\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1448394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1448394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1448394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}