{"id":1451706,"date":"2024-08-09T19:03:42","date_gmt":"2024-08-10T02:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/"},"modified":"2024-08-09T19:03:42","modified_gmt":"2024-08-10T02:03:42","slug":"descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/","title":{"rendered":"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d"},"content":{"rendered":"<p>(CNN) &#8212; La atleta refugiada Manizha Talash fue descalificada de la competencia de breaking B-Girl en los Juegos Ol\u00edmpicos por usar una capa con las palabras \u201cliberen a las mujeres\u201d durante su competencia del viernes.<\/p>\n<p>La joven de 21 a\u00f1os, que huy\u00f3 de Afganist\u00e1n despu\u00e9s de que los talibanes comenzaran a tomar el control en 2021, ahora vive en Espa\u00f1a y representa al Equipo de Refugiados en los juegos como B-girl Talash.<\/p>\n<p>Cuando hizo su debut durante la batalla previa a la clasificaci\u00f3n, Talash revel\u00f3 una capa azul celeste debajo de su jersey adornada con las palabras que ped\u00edan la emancipaci\u00f3n de las mujeres afganas.<\/p>\n<p>La Federaci\u00f3n Mundial de DanceSport, que rige el deporte, emiti\u00f3 un comunicado m\u00e1s tarde el viernes diciendo: \u201cB-Girl TALASH (EOR) fue descalificada por mostrar un eslogan pol\u00edtico en su vestimenta durante la batalla previa a la clasificaci\u00f3n. Los resultados se han actualizado en consecuencia\u201d.<\/p>\n<p>\u201cNo sal\u00ed de Afganist\u00e1n porque tenga miedo de los talibanes o porque no pueda vivir en Afganist\u00e1n\u201d, dijo Talash antes de que comenzaran las acciones. \u201cMe fui porque quiero hacer lo que pueda por las ni\u00f1as de Afganist\u00e1n, por mi vida, mi futuro, por todos\u201d.<\/p>\n<p>Bajo el Gobierno talib\u00e1n, Afganist\u00e1n se convirti\u00f3 en el pa\u00eds m\u00e1s represivo del mundo en materia de derechos de las mujeres, de acuerdo con la Organizaci\u00f3n de las Naciones Unidas. El grupo islamista de l\u00ednea dura cerr\u00f3 escuelas secundarias para ni\u00f1as, prohibi\u00f3 a las mujeres asistir a la universidad, restringi\u00f3 sus viajes sin un acompa\u00f1ante masculino y les prohibi\u00f3 la entrada a espacios p\u00fablicos como parques y gimnasios.<\/p>\n<p>La llamada polic\u00eda de la moralidad de los talibanes tambi\u00e9n ha atacado desproporcionadamente a mujeres y ni\u00f1as, creando un \u201cclima de miedo e intimidaci\u00f3n\u201d, seg\u00fan un informe de la ONU publicado el mes pasado.<\/p>\n<p>Talash descubir\u00f3 el breaking viendo videos en las redes sociales. Sin embargo, su capacidad para entrenar se vio interrumpida mientras buscaba un lugar donde establecerse.<\/p>\n<p>La profesional del breaking se convirti\u00f3 en uno de los 37 atletas que representan al Equipo Ol\u00edmpico de Refugiados en Par\u00eds, y est\u00e1 orgullosa de ello.<\/p>\n<p>Equipo Ol\u00edmpico de Refugiados en Par\u00eds 2024: qui\u00e9nes son y en qu\u00e9 categor\u00edas compiten<\/p>\n<p>&#171;Todos los refugiados tienen una vida muy dif\u00edcil, pero ir\u00e1n a los Juegos&#187;, afirm\u00f3. &#171;Entonces, para m\u00ed, ser parte del equipo significa fuerza\u201d. Y a\u00f1adi\u00f3: \u201cLa gente de mi pa\u00eds, incluso las ni\u00f1as, me dec\u00edan: \u2018Tienes que aprender a cocinar y limpiar la casa\u2019&#187;.<\/p>\n<p>El breaking ha florecido en las calles de Nueva York y otras ciudades estadounidenses desde la d\u00e9cada de 1970, pero en Par\u00eds es la primera vez que sus atletas, conocidos como B-boys y B-girls, realizan sus movimientos con estilo libre en el escenario m\u00e1s grande del mundo.<\/p>\n<p>La capa de Talash puede haber infringido las reglas contra los lemas pol\u00edticos en los Juegos Ol\u00edmpicos, pero tambi\u00e9n ha encontrado sus seguidores.<\/p>\n<p>\u201cMe gustar\u00eda decir que solo han pasado 11 minutos de breaking y una competidora ya sac\u00f3 una chaqueta sorpresa que dice \u201cLiberen a las mujeres afganas\u201d\u2014ESO s\u00ed es romper. ESO es la cultura hiphop\u201d, escribi\u00f3 en X Nadira Goffe, escritora asociada de la revista Slate.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La atleta refugiada Manizha Talash fue descalificada de la competencia de breaking B-Girl en los Juegos Ol\u00edmpicos por usar una capa con las palabras \u201cliberen a las mujeres\u201d durante su competencia del viernes. La joven de 21 a\u00f1os, que huy\u00f3 de Afganist\u00e1n despu\u00e9s de que los talibanes comenzaran a tomar el control en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451706","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La atleta refugiada Manizha Talash fue descalificada de la competencia de breaking B-Girl en los Juegos Ol\u00edmpicos por usar una capa con las palabras \u201cliberen a las mujeres\u201d durante su competencia del viernes. La joven de 21 a\u00f1os, que huy\u00f3 de Afganist\u00e1n despu\u00e9s de que los talibanes comenzaran a tomar el control en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-10T02:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d\",\"datePublished\":\"2024-08-10T02:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/\"},\"wordCount\":598,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/\",\"name\":\"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-10T02:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d - Noticias","og_description":"(CNN) &#8212; La atleta refugiada Manizha Talash fue descalificada de la competencia de breaking B-Girl en los Juegos Ol\u00edmpicos por usar una capa con las palabras \u201cliberen a las mujeres\u201d durante su competencia del viernes. La joven de 21 a\u00f1os, que huy\u00f3 de Afganist\u00e1n despu\u00e9s de que los talibanes comenzaran a tomar el control en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-10T02:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/"},"author":{"name":"","@id":""},"headline":"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d","datePublished":"2024-08-10T02:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/"},"wordCount":598,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/","name":"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-10T02:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Descalifican a atleta ol\u00edmpica de breaking por usar capa que dec\u00eda \u201cliberen a las mujeres afganas\u201d","url":"http:\/\/noticiasya.com\/boston\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/08\/09\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-10T02:03:42Z","datePublished":"2024-08-10T02:03:42Z","dateModified":"2024-08-10T02:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Descalifican a atleta ol\\u00edmpica de breaking por usar capa que dec\\u00eda \\u201cliberen a las mujeres afganas\\u201d\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/09\\\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/09\\\/descalifican-atleta-breaking-capa-liberen-mujeres-afganas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-10T02:03:42Z\",\"datePublished\":\"2024-08-10T02:03:42Z\",\"dateModified\":\"2024-08-10T02:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451751,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/12\/breaker-australiana-raygun-elogiada-juegos-olimpicos-paris-trax\/","url_meta":{"origin":1451706,"position":0},"title":"La breaker australiana Raygun es elogiada por su &#171;valent\u00eda&#187; y &#171;car\u00e1cter&#187; tras su actuaci\u00f3n viral en los Juegos Ol\u00edmpicos de Par\u00eds","author":"","date":"agosto 12, 2024","format":false,"excerpt":"(CNN) --\u00a0Rachael Gunn lleg\u00f3 a Par\u00eds como una competitiva breaker emocionada por hacer su debut ol\u00edmpico. Se ha convertido en una sensaci\u00f3n de Internet y sus actuaciones han sido vistas por millones de personas en las redes sociales.Gunn, tambi\u00e9n conocida como B-girl Raygun, o simplemente Raygun, es una profesora universitaria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452581,"url":"https:\/\/noticiasya.com\/boston\/2024\/09\/10\/raygun-numero-uno-del-mundo-ranking-breakdance-trax\/","url_meta":{"origin":1451706,"position":1},"title":"La atleta ol\u00edmpica viral Raygun es la n\u00famero uno del mundo en el ranking de breakdance, seg\u00fan el organismo rector del deporte","author":"","date":"septiembre 10, 2024","format":false,"excerpt":"(CNN) -- La australiana Rachael Gunn, conocida como B-Girl Raygun, quien se volvi\u00f3 viral tras su actuaci\u00f3n en los Juegos de Par\u00eds, es ahora la n\u00famero uno del mundo en breakdance.La atleta de 37 a\u00f1os se qued\u00f3 con el primer puesto en el \u00faltimo ranking femenino publicado por la World\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470986,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/07\/mujeres-olimpicas-maternidad-sueno-oro-trax\/","url_meta":{"origin":1451706,"position":2},"title":"C\u00f3mo esta generaci\u00f3n de mujeres ol\u00edmpicas borr\u00f3 la idea de que la maternidad es el final del sue\u00f1o de una medalla de oro","author":"","date":"febrero 7, 2026","format":false,"excerpt":"El mensaje que Kendall Coyne Schofield public\u00f3 en sus redes sociales no fue dif\u00edcil de descifrar.Una pizarra enmarcada, colocada frente a los dos perros de Schofield, Penny y Blue, mostraba el mensaje: \u201cBeb\u00e9 Schofield llega en verano de 2023\u201d. Los perros llevaban pa\u00f1uelos iguales que dec\u00edan \u201chermana mayor\u201d, por si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451622,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/06\/breaking-debut-juegos-olimpicos-paris-trax\/","url_meta":{"origin":1451706,"position":3},"title":"Este deporte debuta en los Juegos Ol\u00edmpicos de Par\u00eds. Pero no lo llames breakdance","author":"","date":"agosto 6, 2024","format":false,"excerpt":"(CNN) -- Mientras un DJ pone a sonar la m\u00fasica, los atletas se contorsionan, giran y saltan. Cada movimiento es una mezcla vertiginosa de movimientos de pies y contorsiones de extremidades.Puede parecer m\u00e1s un arte que un deporte, pero el breakdance \u2014conocido profesionalmente como breaking\u2014 debuta este mes en los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471088,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/10\/atleta-olimpico-ucraniano-casco-prohibido-trax\/","url_meta":{"origin":1451706,"position":4},"title":"Atleta ol\u00edmpico ucraniano desafiar\u00e1 la prohibici\u00f3n del COI: &#171;Algunas cosas son m\u00e1s importantes que el deporte&#187;","author":"","date":"febrero 10, 2026","format":false,"excerpt":"El corredor ucraniano de skeleton Vladyslav Heraskevych le dijo a CNN que desafiar\u00e1 al Comit\u00e9 Ol\u00edmpico Internacional (COI) y usar\u00e1 su casco con im\u00e1genes de atletas ca\u00eddos durante la guerra en Ucrania.El COI se mostr\u00f3 comprensivo con la situaci\u00f3n de Heraskevych, pero afirm\u00f3 que el casco \u201ccontraviene\u201d las directrices del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446882,"url":"https:\/\/noticiasya.com\/boston\/2024\/03\/12\/lima-sede-panamericanos-orix\/","url_meta":{"origin":1451706,"position":5},"title":"Lima triunfa frente a Asunci\u00f3n y se queda con la sede de los Juegos Panamericanos 2027","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Lima\u00a0ser\u00e1 la sede de los Juegos Panamericanos 2027, seg\u00fan anunci\u00f3 este martes la organizaci\u00f3n, cerca de dos meses despu\u00e9s de que se le retirara ese t\u00edtulo a la ciudad colombiana de Barranquilla.Lima compet\u00eda contra Asunci\u00f3n para ser la sede de los juegos en 2027.Este martes, ambas ciudades\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1451706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1451706"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1451706\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1451706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1451706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1451706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}