{"id":1451716,"date":"2024-08-10T22:03:38","date_gmt":"2024-08-11T05:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/"},"modified":"2024-08-10T22:03:38","modified_gmt":"2024-08-11T05:03:38","slug":"vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/","title":{"rendered":"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos"},"content":{"rendered":"<p>(CNN) &#8212; El vuelo de Voepass Linhas A\u00e9reas que se estrell\u00f3 cerca de Vinhedo, Brasil, no se report\u00f3 en caso de emergencia seg\u00fan las investigaciones preliminares, dijo el jefe del Centro de Investigaci\u00f3n y Prevenci\u00f3n de Accidentes Aeron\u00e1uticos (CENIPA) de Brasil.<\/p>\n<p>&#171;Es un poco prematuro decirlo, pero lo que tenemos hasta ahora es que no hubo comunicaci\u00f3n entre la aeronave y la torre de control avisando que habr\u00eda una emergencia&#187;, dijo el jefe del CENIPA, brigadier Marcelo Moreno, en una rueda de prensa en la capital brasile\u00f1a, Brasilia.<\/p>\n<p>Seg\u00fan un comunicado de prensa emitido por el CENIPA, las dos cajas negras recuperadas, la Cockpit Voice Recorder y la Flight Data Recorder, estaban en posesi\u00f3n del centro y se comenzar\u00e1 a analizarlas lo antes posible.<br \/>\nDe Marcia Reverdosa en Vinhedo, Brasil<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El vuelo de Voepass Linhas A\u00e9reas que se estrell\u00f3 cerca de Vinhedo, Brasil, no se report\u00f3 en caso de emergencia seg\u00fan las investigaciones preliminares, dijo el jefe del Centro de Investigaci\u00f3n y Prevenci\u00f3n de Accidentes Aeron\u00e1uticos (CENIPA) de Brasil. &#171;Es un poco prematuro decirlo, pero lo que tenemos hasta ahora es que no [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451716","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El vuelo de Voepass Linhas A\u00e9reas que se estrell\u00f3 cerca de Vinhedo, Brasil, no se report\u00f3 en caso de emergencia seg\u00fan las investigaciones preliminares, dijo el jefe del Centro de Investigaci\u00f3n y Prevenci\u00f3n de Accidentes Aeron\u00e1uticos (CENIPA) de Brasil. &#171;Es un poco prematuro decirlo, pero lo que tenemos hasta ahora es que no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T05:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos\",\"datePublished\":\"2024-08-11T05:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/\"},\"wordCount\":181,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/\",\"name\":\"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-11T05:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos - Noticias","og_description":"(CNN) &#8212; El vuelo de Voepass Linhas A\u00e9reas que se estrell\u00f3 cerca de Vinhedo, Brasil, no se report\u00f3 en caso de emergencia seg\u00fan las investigaciones preliminares, dijo el jefe del Centro de Investigaci\u00f3n y Prevenci\u00f3n de Accidentes Aeron\u00e1uticos (CENIPA) de Brasil. &#171;Es un poco prematuro decirlo, pero lo que tenemos hasta ahora es que no [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-11T05:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/"},"author":{"name":"","@id":""},"headline":"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos","datePublished":"2024-08-11T05:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/"},"wordCount":181,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/","name":"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-11T05:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El vuelo de Voepass Linhas A\u00e9reas no inform\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\u00f1o de accidentes a\u00e9reos","url":"http:\/\/noticiasya.com\/boston\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/08\/10\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-11T05:03:38Z","datePublished":"2024-08-11T05:03:38Z","dateModified":"2024-08-11T05:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El vuelo de Voepass Linhas A\\u00e9reas no inform\\u00f3 de emergencia antes de estrellarse dice el jefe del centro brasile\\u00f1o de accidentes a\\u00e9reos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/10\\\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/10\\\/vuelo-voepass-linhas-aereas-no-informo-emergencia-antes-estrellarse-jefe-centro-brasileno-accidentes-aereos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-11T05:03:38Z\",\"datePublished\":\"2024-08-11T05:03:38Z\",\"dateModified\":\"2024-08-11T05:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451708,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/10\/brasil-avion-accidente-sao-paulo-trax\/","url_meta":{"origin":1451716,"position":0},"title":"Un avi\u00f3n brasile\u00f1o se estrella en las afueras de S\u00e3o Paulo y mueren 62 personas, seg\u00fan la compa\u00f1\u00eda a\u00e9rea","author":"","date":"agosto 10, 2024","format":false,"excerpt":"(CNN) -- Un avi\u00f3n de pasajeros que transportaba a 62 personas se estrell\u00f3 en las afueras de S\u00e3o Paulo este viernes por la tarde, y murieron todos los que iban a bordo, seg\u00fan un comunicado emitido por la aerol\u00ednea Voepass.Las dram\u00e1ticas im\u00e1genes que circularon por las redes sociales mostraban la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469530,"url":"https:\/\/noticiasya.com\/boston\/2025\/12\/23\/jefe-ejercito-libia-muere-accidente-aereo-turquia-trax\/","url_meta":{"origin":1451716,"position":1},"title":"El jefe del Ej\u00e9rcito de Libia muere en accidente a\u00e9reo en Turqu\u00eda","author":"","date":"diciembre 23, 2025","format":false,"excerpt":"El jefe del Ej\u00e9rcito de Libia muri\u00f3 en un accidente a\u00e9reo mientras regresaba a Tr\u00edpoli tras una visita oficial a Turqu\u00eda, inform\u00f3 el primer ministro Abdulhamid al-Dbeibah.El teniente general Mohamed al-Haddad falleci\u00f3 junto a cuatro acompa\u00f1antes en un \u201ctr\u00e1gico accidente\u201d durante el vuelo de regreso desde Ankara, seg\u00fan el comunicado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443334,"url":"https:\/\/noticiasya.com\/boston\/2024\/01\/08\/se-encontro-la-pieza-de-avion-de-alaska-airlines-que-exploto-y-se-desprendio-en-pleno-vuelo\/","url_meta":{"origin":1451716,"position":2},"title":"Se encontr\u00f3 la pieza de avi\u00f3n de Alaska Airlines que explot\u00f3 y se desprendi\u00f3 en pleno vuelo","author":"","date":"enero 8, 2024","format":false,"excerpt":"(CNN) -- La presidenta de la NTSB, Jennifer Homendy, anunci\u00f3 en una conferencia de prensa que se ha encontrado el tap\u00f3n de la puerta del vuelo 1282 de Alaska Airlines.Seg\u00fan Homendy, un residente encontr\u00f3 el tap\u00f3n de la puerta en su patio trasero.Homendy solo dijo que el nombre del residente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443337,"url":"https:\/\/noticiasya.com\/boston\/2024\/01\/08\/se-encontro-la-pieza-de-avion-de-alaska-airlines-que-exploto-y-se-desprendio-en-pleno-vuelo-2\/","url_meta":{"origin":1451716,"position":3},"title":"Se encontr\u00f3 la pieza de avi\u00f3n de Alaska Airlines que explot\u00f3 y se desprendi\u00f3 en pleno vuelo","author":"","date":"enero 8, 2024","format":false,"excerpt":"(CNN) -- La presidenta de la NTSB, Jennifer Homendy, anunci\u00f3 en una conferencia de prensa que se ha encontrado el tap\u00f3n de la puerta del vuelo 1282 de Alaska Airlines.Seg\u00fan Homendy, un residente encontr\u00f3 el tap\u00f3n de la puerta en su patio trasero.Homendy solo dijo que el nombre del residente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457232,"url":"https:\/\/noticiasya.com\/boston\/2025\/01\/05\/sobrevivientes-ultimos-accidentes-parte-traser-avion-que-nos-dice-eso-seguridad-trax\/","url_meta":{"origin":1451716,"position":4},"title":"Los sobrevivientes de \u00faltimos accidentes se sentaban en la parte trasera del avi\u00f3n. \u00bfQu\u00e9 significa eso?","author":"","date":"enero 5, 2025","format":false,"excerpt":"Mira las fotograf\u00edas de los dos accidentes a\u00e9reos fatales de las \u00faltimas dos semanas y, en medio del horror y la angustia, un pensamiento podr\u00eda venir a la mente de los viajeros frecuentes.El viejo adagio de los viajeros frecuentes es que sentarse en la parte trasera del avi\u00f3n es m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456982,"url":"https:\/\/noticiasya.com\/boston\/2024\/12\/26\/que-paso-avion-kazajistan-estrellado-trax\/","url_meta":{"origin":1451716,"position":5},"title":"\u00bfPor qu\u00e9 se estrell\u00f3 el avi\u00f3n de Azerbaijan Airlines en Kazajst\u00e1n y a d\u00f3nde se dirig\u00eda? Esto sabemos","author":"","date":"diciembre 26, 2024","format":false,"excerpt":"Varias preguntas circulaban sobre la causa de un accidente de avi\u00f3n en Kazajst\u00e1n ocurrida el 25 de diciembre, mientras Azerbaiy\u00e1n celebraba un d\u00eda de duelo por las decenas de v\u00edctimas del desastre.Las razones por las cuales el vuelo J2-8243 de Azerbaijan Airlines cay\u00f3 a\u00fan son desconocidas. Reuters inform\u00f3 este jueves\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1451716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1451716"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1451716\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1451716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1451716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1451716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}