{"id":1451718,"date":"2024-08-11T00:03:44","date_gmt":"2024-08-11T07:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/"},"modified":"2024-08-11T00:03:44","modified_gmt":"2024-08-11T07:03:44","slug":"kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/","title":{"rendered":"Kamala Harris afirma que murieron &#171;demasiados civiles&#187; en Gaza y pide que el acuerdo de rehenes se haga &#171;ya&#187;"},"content":{"rendered":"<p>(CNN) &#8212; La vicepresidenta Kamala Harris afirm\u00f3 este s\u00e1bado que &#171;hay demasiados&#187; civiles muertos, tras el ataque israel\u00ed contra una escuela y una mezquita en Gaza en el que murieron al menos 93 palestinos, seg\u00fan las autoridades locales.<\/p>\n<p>&#171;Hay demasiados civiles muertos. Israel tiene derecho a perseguir a los terroristas de Hamas. Pero como he dicho muchas, muchas veces, tambi\u00e9n tienen, creo, la importante responsabilidad de evitar v\u00edctimas civiles&#187;, declar\u00f3 Harris antes de su mitin de este s\u00e1bado por la noche en Las Vegas (Nevada). La Defensa Civil de Gaza dijo que la gente estaba celebrando las oraciones del alba en el complejo de Al-Tabi&#8217;in, en el barrio de Al-Daraj, en la parte oriental de la ciudad de Gaza, cuando fue atacado durante la noche del s\u00e1bado. Israel confirm\u00f3 que hab\u00eda llevado a cabo el ataque, afirmando que Hamas operaba all\u00ed.<\/p>\n<p>Al menos 93 muertos tras un ataque israel\u00ed contra una escuela en Gaza<\/p>\n<p>Harris a\u00f1adi\u00f3: &#171;Tenemos que sacar a los rehenes. Necesitamos un acuerdo sobre los rehenes y necesitamos un alto el fuego. No puedo dejar de insistir en la necesidad de llegar a un acuerdo. El acuerdo tiene que hacerse. Tiene que hacerse ya&#187;.<\/p>\n<p>Los comentarios de Harris sobre Israel de este s\u00e1bado fueron algunos de los m\u00e1s sustanciales en materia pol\u00edtica desde que se convirti\u00f3 en la abanderada dem\u00f3crata.<\/p>\n<p>Al igual que Biden, se enfrenta a una cuerda floja pol\u00edtica y diplom\u00e1tica en lo que respecta a Gaza.<\/p>\n<p>Aunque ella y la Casa Blanca han mantenido la esperanza de alcanzar un acuerdo de alto el fuego y toma de rehenes que ponga fin a los combates en Gaza y rebaje la temperatura en la regi\u00f3n, la potestad para alcanzar un acuerdo de este tipo corresponde a Hamas y al primer ministro de Israel, Benjam\u00edn Netanyahu, ninguno de los cuales ha dado su visto bueno definitivo.<\/p>\n<p>Los funcionarios estadounidenses se han sentido frustrados por el estancamiento de los avances hacia un acuerdo, a pesar de que, seg\u00fan ellos, sobre el papel las diferencias entre ambas partes son m\u00ednimas. El reciente asesinato de un alto dirigente de Hamas en Teher\u00e1n, supuestamente cometido por los israel\u00edes, dificult\u00f3 a\u00fan m\u00e1s el avance hacia un acuerdo.<\/p>\n<p>Esto ha dejado a Estados Unidos con cada vez menos opciones para poner fin a la crisis humanitaria, a pesar de las posibles consecuencias pol\u00edticas para Harris en noviembre.<\/p>\n<p>La semana pasada, el presidente Biden hizo un nuevo llamamiento a las conversaciones sobre los rehenes, publicando una declaraci\u00f3n con los l\u00edderes de Qatar y Egipto en la que ped\u00eda volver a la mesa de negociaciones esta semana.<\/p>\n<p>Biden ha incluido a Harris desde el principio en sus tratos con Netanyahu, y ella estuvo presente esta semana en la Sala de Situaci\u00f3n de la Casa Blanca en una reuni\u00f3n de altos funcionarios de seguridad nacional para discutir la escalada de tensiones en Oriente Medio.<\/p>\n<p>En esencia, sus posiciones no han estado re\u00f1idas con las de Biden. Entre bastidores, sin embargo, ha abogado por un enfoque m\u00e1s emp\u00e1tico con los palestinos y en p\u00fablico ha adoptado a veces un tono m\u00e1s en\u00e9rgico que Biden al hablar de la situaci\u00f3n en Gaza.<\/p>\n<p>&#171;No podemos permitirnos insensibilizarnos ante el sufrimiento, y no me quedar\u00e9 callada&#187;, declar\u00f3 el mes pasado tras reunirse con Netanyahu en Washington.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La vicepresidenta Kamala Harris afirm\u00f3 este s\u00e1bado que &#171;hay demasiados&#187; civiles muertos, tras el ataque israel\u00ed contra una escuela y una mezquita en Gaza en el que murieron al menos 93 palestinos, seg\u00fan las autoridades locales. &#171;Hay demasiados civiles muertos. Israel tiene derecho a perseguir a los terroristas de Hamas. Pero como he [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451718","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kamala Harris afirma que murieron &quot;demasiados civiles&quot; en Gaza y pide que el acuerdo de rehenes se haga &quot;ya&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kamala Harris afirma que murieron &quot;demasiados civiles&quot; en Gaza y pide que el acuerdo de rehenes se haga &quot;ya&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La vicepresidenta Kamala Harris afirm\u00f3 este s\u00e1bado que &#171;hay demasiados&#187; civiles muertos, tras el ataque israel\u00ed contra una escuela y una mezquita en Gaza en el que murieron al menos 93 palestinos, seg\u00fan las autoridades locales. &#171;Hay demasiados civiles muertos. Israel tiene derecho a perseguir a los terroristas de Hamas. Pero como he [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T07:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Kamala Harris afirma que murieron &#171;demasiados civiles&#187; en Gaza y pide que el acuerdo de rehenes se haga &#171;ya&#187;\",\"datePublished\":\"2024-08-11T07:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/\"},\"wordCount\":614,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/\",\"name\":\"Kamala Harris afirma que murieron \\\"demasiados civiles\\\" en Gaza y pide que el acuerdo de rehenes se haga \\\"ya\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-11T07:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kamala Harris afirma que murieron &#171;demasiados civiles&#187; en Gaza y pide que el acuerdo de rehenes se haga &#171;ya&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kamala Harris afirma que murieron \"demasiados civiles\" en Gaza y pide que el acuerdo de rehenes se haga \"ya\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Kamala Harris afirma que murieron \"demasiados civiles\" en Gaza y pide que el acuerdo de rehenes se haga \"ya\" - Noticias","og_description":"(CNN) &#8212; La vicepresidenta Kamala Harris afirm\u00f3 este s\u00e1bado que &#171;hay demasiados&#187; civiles muertos, tras el ataque israel\u00ed contra una escuela y una mezquita en Gaza en el que murieron al menos 93 palestinos, seg\u00fan las autoridades locales. &#171;Hay demasiados civiles muertos. Israel tiene derecho a perseguir a los terroristas de Hamas. Pero como he [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-11T07:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/"},"author":{"name":"","@id":""},"headline":"Kamala Harris afirma que murieron &#171;demasiados civiles&#187; en Gaza y pide que el acuerdo de rehenes se haga &#171;ya&#187;","datePublished":"2024-08-11T07:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/"},"wordCount":614,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/","name":"Kamala Harris afirma que murieron \"demasiados civiles\" en Gaza y pide que el acuerdo de rehenes se haga \"ya\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-11T07:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Kamala Harris afirma que murieron &#171;demasiados civiles&#187; en Gaza y pide que el acuerdo de rehenes se haga &#171;ya&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Kamala Harris afirma que murieron &#171;demasiados civiles&#187; en Gaza y pide que el acuerdo de rehenes se haga &#171;ya&#187;","url":"http:\/\/noticiasya.com\/boston\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/08\/11\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-11T07:03:44Z","datePublished":"2024-08-11T07:03:44Z","dateModified":"2024-08-11T07:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Kamala Harris afirma que murieron &#171;demasiados civiles&#187; en Gaza y pide que el acuerdo de rehenes se haga &#171;ya&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/11\\\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/11\\\/kamala-harris-demasiados-civiles-muertos-en-gaza-acuerdo-rehenes-ya-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-11T07:03:44Z\",\"datePublished\":\"2024-08-11T07:03:44Z\",\"dateModified\":\"2024-08-11T07:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451884,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/15\/40-000-palestinos-murieron-10-meses-gaza-trax\/","url_meta":{"origin":1451718,"position":0},"title":"M\u00e1s de 40.000 palestinos murieron en los 10 meses de la guerra en Gaza, seg\u00fan el Ministerio de Salud","author":"","date":"agosto 15, 2024","format":false,"excerpt":"(CNN) -- M\u00e1s de 40.000 palestinos han muerto en Gaza desde que Israel lanz\u00f3 su guerra contra Hamas, seg\u00fan inform\u00f3 este jueves el Ministerio de Salud del enclave, otro hito oscuro en el conflicto que ya lleva 10 meses.El ministerio dijo que 40 personas murieron en Gaza durante las \u00faltimas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451285,"url":"https:\/\/noticiasya.com\/boston\/2024\/07\/20\/muertos-ataques-aereos-israel-campo-de-nuseirat-gaza-trax\/","url_meta":{"origin":1451718,"position":1},"title":"Al menos 13 muertos en ataques a\u00e9reos israel\u00edes contra el campo de Nuseirat en el centro de Gaza","author":"","date":"julio 20, 2024","format":false,"excerpt":"(CNN) -- Al menos 13 personas murieron este s\u00e1bado en ataques a\u00e9reos israel\u00edes contra viviendas en el campo de Nuseirat, en el centro de Gaza, seg\u00fan funcionarios del hospital y la Defensa Civil de Gaza.El n\u00famero de v\u00edctimas se debi\u00f3 a dos ataques distintos sobre el campo, dijeron los funcionarios.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450609,"url":"https:\/\/noticiasya.com\/boston\/2024\/06\/22\/muertos-desaparecidos-dos-ataques-centro-gaza-trax\/","url_meta":{"origin":1451718,"position":2},"title":"M\u00e1s de 40 personas murieron o est\u00e1n desaparecidas tras ataques en el centro de Gaza","author":"","date":"junio 22, 2024","format":false,"excerpt":"(CNN) -- 42 personas han muerto o est\u00e1n desaparecidas tras dos ataques en el centro de Gaza este s\u00e1bado, seg\u00fan report\u00f3 la Oficina de Medios de Comunicaci\u00f3n del Gobierno, controlada por Hamas.El director de la Oficina de Medios de Comunicaci\u00f3n, Ismail Al-Thawabtah, dijo a CNN que los ataques se hab\u00edan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464696,"url":"https:\/\/noticiasya.com\/boston\/2025\/07\/20\/muertos-ayuda-humanitaria-gaza-disparos-israelies-trax\/","url_meta":{"origin":1451718,"position":3},"title":"Soldados israel\u00edes disparan a personas que buscaban ayuda humanitaria en Gaza: hay al menos 73 muertos, seg\u00fan autoridades","author":"","date":"julio 20, 2025","format":false,"excerpt":"Al menos 73 personas murieron y alrededor de 150 resultaron heridas por disparos realizados por soldados israel\u00edes en Gaza mientras intentaban recibir ayuda humanitaria el domingo, seg\u00fan el Ministerio de Salud palestino.El ministerio inform\u00f3 que unas 67 personas murieron en el norte de Gaza, mientras que otras seis fallecieron en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451713,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/10\/israeli-school-strike-gaza-trax\/","url_meta":{"origin":1451718,"position":4},"title":"Al menos 90 palestinos muertos en un ataque israel\u00ed contra una escuela de Gaza, seg\u00fan portavoz de la Defensa Civil","author":"","date":"agosto 10, 2024","format":false,"excerpt":"(CNN) -- Al menos 90 palestinos murieron en un ataque israel\u00ed contra la escuela de Al-Tabi'in, en la ciudad de Gaza, seg\u00fan declar\u00f3 o a CNN el portavoz de la Defensa Civil de Gaza, Mahmoud Basal.\"Hemos recuperado al menos 90\" personas muertas, ha dicho Basal, a\u00f1adiendo que \"muchas de ellas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466438,"url":"https:\/\/noticiasya.com\/boston\/2025\/09\/14\/ataques-israelies-gaza-70-muertos-trax\/","url_meta":{"origin":1451718,"position":5},"title":"Ataques israel\u00edes en Gaza dejan m\u00e1s de 70 muertos en un d\u00eda","author":"","date":"septiembre 14, 2025","format":false,"excerpt":"Al menos 74 palestinos murieron el s\u00e1bado en ataques israel\u00edes sobre Gaza, informaron funcionarios hospitalarios, con m\u00e1s de 50 de las v\u00edctimas en Ciudad de Gaza.Varias personas \u2013entre ellas mujeres, ni\u00f1os y ancianos\u2013 llegaron sin vida o heridas al Hospital Al Quds, seg\u00fan fuentes m\u00e9dicas. Decenas m\u00e1s fueron trasladadas a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1451718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1451718"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1451718\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1451718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1451718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1451718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}