{"id":1451811,"date":"2024-08-13T00:03:44","date_gmt":"2024-08-13T07:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/"},"modified":"2024-08-13T00:03:44","modified_gmt":"2024-08-13T07:03:44","slug":"propuesta-derechos-aborto-arizona-boleta-noviembre-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/","title":{"rendered":"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre"},"content":{"rendered":"<p>(CNN) &#8212; La propuesta de enmienda constitucional de Arizona que establecer\u00eda un &#171;derecho fundamental al aborto&#187; obtuvo suficientes firmas para figurar en la boleta electoral del estado.<\/p>\n<p>La Ley de Acceso al Aborto de Arizona recibi\u00f3 577.971 firmas certificadas, seg\u00fan confirm\u00f3 este lunes la oficina del secretario de Estado de Arizona, casi 200.000 m\u00e1s de las necesarias para aparecer en la boleta electoral de noviembre. Se calcula que se presentaron unas 800.000 firmas, seg\u00fan la oficina.<\/p>\n<p>La medida consagrar\u00eda el derecho al aborto en la Constituci\u00f3n del estado hasta la viabilidad del feto, que los m\u00e9dicos consideran en torno a las 22 o 24 semanas de embarazo.<\/p>\n<p>\u00bfEs posible ser cat\u00f3lico y estar a favor del derecho al aborto? La respuesta de Catholics For Choice<\/p>\n<p>&#171;Hoy hemos recibido la noticia de que los 15 condados de Arizona finalizaron la revisi\u00f3n de una muestra aleatoria de nuestras firmas y el Secretario de Estado confirm\u00f3 que hemos reunido muchas m\u00e1s firmas v\u00e1lidas de las necesarias, un 50 por ciento por encima del m\u00ednimo exigido. Es la mayor cantidad de firmas validadas por una iniciativa ciudadana en la historia del estado&#187;, celebr\u00f3 en un comunicado Arizona por el Acceso al Aborto, el grupo que respalda la medida.<\/p>\n<p>&#171;Se trata de una gran victoria para los votantes de Arizona, que ahora podr\u00e1n votar \u2018s\u00ed\u2019 a la restauraci\u00f3n y protecci\u00f3n del derecho a acceder a la atenci\u00f3n del aborto, libre de interferencias pol\u00edticas, de una vez por todas&#187;, declar\u00f3 la directora de la campa\u00f1a, Cheryl Bruce.<\/p>\n<p>En mayo, el Senado de Arizona vot\u00f3 a favor de derogar la prohibici\u00f3n casi total del aborto que pesaba sobre el estado desde hac\u00eda 160 a\u00f1os, despu\u00e9s de que el Tribunal Supremo del estado reviviera la ley y pusiera los derechos reproductivos en el punto de mira pol\u00edtico.<\/p>\n<p>La gobernadora dem\u00f3crata Katie Hobbs firm\u00f3 la legislaci\u00f3n al d\u00eda siguiente y declar\u00f3: &#171;Debemos volver a comprometernos a proteger la autonom\u00eda corporal de las mujeres, su capacidad para tomar sus propias decisiones sanitarias y la capacidad de controlar sus vidas&#187;.<\/p>\n<p>La ley de Arizona impone actualmente un l\u00edmite de 15 semanas para los abortos. Esa restricci\u00f3n, promulgada en 2022, no incluye excepciones por violaci\u00f3n e incesto.<\/p>\n<p>Esta es la\u00a0reacci\u00f3n\u00a0de Trump ante la prohibici\u00f3n del aborto en Arizona<\/p>\n<p>Tras la decisi\u00f3n del Tribunal Supremo de EE.UU. en junio de 2022, en el caso Dobbs contra la Organizaci\u00f3n de Salud de la Mujer Jackson, que elimin\u00f3 el derecho constitucional al aborto en todo el pa\u00eds, decenas de estados de EE.UU. prohibieron o limitaron el acceso al procedimiento.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La propuesta de enmienda constitucional de Arizona que establecer\u00eda un &#171;derecho fundamental al aborto&#187; obtuvo suficientes firmas para figurar en la boleta electoral del estado. La Ley de Acceso al Aborto de Arizona recibi\u00f3 577.971 firmas certificadas, seg\u00fan confirm\u00f3 este lunes la oficina del secretario de Estado de Arizona, casi 200.000 m\u00e1s de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451811","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La propuesta de enmienda constitucional de Arizona que establecer\u00eda un &#171;derecho fundamental al aborto&#187; obtuvo suficientes firmas para figurar en la boleta electoral del estado. La Ley de Acceso al Aborto de Arizona recibi\u00f3 577.971 firmas certificadas, seg\u00fan confirm\u00f3 este lunes la oficina del secretario de Estado de Arizona, casi 200.000 m\u00e1s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-13T07:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre\",\"datePublished\":\"2024-08-13T07:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/\"},\"wordCount\":484,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/\",\"name\":\"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-13T07:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre - Noticias","og_description":"(CNN) &#8212; La propuesta de enmienda constitucional de Arizona que establecer\u00eda un &#171;derecho fundamental al aborto&#187; obtuvo suficientes firmas para figurar en la boleta electoral del estado. La Ley de Acceso al Aborto de Arizona recibi\u00f3 577.971 firmas certificadas, seg\u00fan confirm\u00f3 este lunes la oficina del secretario de Estado de Arizona, casi 200.000 m\u00e1s de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-13T07:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/"},"author":{"name":"","@id":""},"headline":"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre","datePublished":"2024-08-13T07:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/"},"wordCount":484,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/","name":"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-13T07:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La propuesta sobre el derecho al aborto en Arizona estar\u00e1 en la boleta electoral de noviembre","url":"http:\/\/noticiasya.com\/boston\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/08\/13\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-13T07:03:44Z","datePublished":"2024-08-13T07:03:44Z","dateModified":"2024-08-13T07:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La propuesta sobre el derecho al aborto en Arizona estar\\u00e1 en la boleta electoral de noviembre\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/13\\\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/13\\\/propuesta-derechos-aborto-arizona-boleta-noviembre-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-13T07:03:44Z\",\"datePublished\":\"2024-08-13T07:03:44Z\",\"dateModified\":\"2024-08-13T07:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447621,"url":"https:\/\/noticiasya.com\/boston\/2024\/04\/01\/prohibicion-aborto-seis-semanas-florida-ley-trax\/","url_meta":{"origin":1451811,"position":0},"title":"La prohibici\u00f3n en Florida del aborto a las seis semanas de gestaci\u00f3n pronto se convertir\u00e1 en ley, pero se votar\u00e1 una enmienda constitucional en noviembre","author":"","date":"abril 1, 2024","format":false,"excerpt":"(CNN) --La Corte Suprema de Florida allan\u00f3 el camino este lunes para que la prohibici\u00f3n del aborto a las seis semanas de gestaci\u00f3n entre en vigor en el estado, al tiempo que permiti\u00f3 a los floridanos votar en noviembre si consagran o no las protecciones del aborto en la constituci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455588,"url":"https:\/\/noticiasya.com\/boston\/2024\/11\/05\/10-estados-decidiran-aborto-boleta-electoral-2024-trax\/","url_meta":{"origin":1451811,"position":1},"title":"Estos 10 estados tambi\u00e9n decidir\u00e1n sobre el aborto en la boleta electoral de 2024","author":"","date":"noviembre 5, 2024","format":false,"excerpt":"(CNN) -- M\u00e1s de dos a\u00f1os despu\u00e9s de que la Corte Suprema de EE.UU. anulara Roe v. Wade y pusiera fin al derecho constitucional federal al aborto, los votantes en 10 estados deciden si consolidar los derechos reproductivos en sus constituciones estatales.Esto va un paso m\u00e1s all\u00e1 para los residentes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447905,"url":"https:\/\/noticiasya.com\/boston\/2024\/04\/09\/corte-suprema-arizona-dictamina-estado-adherirse-ley-hace-mas-100-anios-prohibe-casi-todos-abortos-trax\/","url_meta":{"origin":1451811,"position":2},"title":"Corte Suprema de Arizona determina que el estado debe seguir una ley de 123 a\u00f1os que proh\u00edbe el aborto en casi todos los casos","author":"","date":"abril 9, 2024","format":false,"excerpt":"(CNN) -- En una decisi\u00f3n hist\u00f3rica, la Corte Suprema de Arizona determin\u00f3 este martes que el estado debe adherirse a una ley de 123 a\u00f1os de antig\u00fcedad que proh\u00edbe los abortos en su totalidad excepto en los casos en que \"sea necesario para salvar\" la vida de una persona embarazada.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448797,"url":"https:\/\/noticiasya.com\/boston\/2024\/05\/02\/arizona-firma-ley-deroga-prohibicion-aborto-trax\/","url_meta":{"origin":1451811,"position":3},"title":"Gobernadora de Arizona firma proyecto de ley que deroga la prohibici\u00f3n del aborto establecida en 1864","author":"","date":"mayo 2, 2024","format":false,"excerpt":"(CNN) -- La gobernadora de Arizona, Katie Hobbs, firm\u00f3 este jueves una legislaci\u00f3n que deroga la prohibici\u00f3n casi total del aborto en el estado desde hace 160 a\u00f1os, que sienta las bases para que una restricci\u00f3n de 15 semanas siga siendo ley.La gobernadora dem\u00f3crata firm\u00f3 el proyecto de ley un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447926,"url":"https:\/\/noticiasya.com\/boston\/2024\/04\/10\/analisis-trump-aborto-arizona-elecciones-2024-trax\/","url_meta":{"origin":1451811,"position":4},"title":"AN\u00c1LISIS | Arizona demuestra que dejar el aborto en manos de los estados en EE.UU. no aliviar\u00e1 el problema que significa para Trump","author":"","date":"abril 10, 2024","format":false,"excerpt":"(CNN) -- Solo hizo falta un d\u00eda \u2014y una sorprendente sentencia judicial que revive una prohibici\u00f3n del aborto de la \u00e9poca de la Guerra Civil en un vital estado indeciso\u2014 para desmentir la afirmaci\u00f3n que hizo Donald Trump de que la cuesti\u00f3n del aborto hab\u00eda quedado \"pr\u00e1cticamente fuera de juego\"\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448744,"url":"https:\/\/noticiasya.com\/boston\/2024\/05\/01\/encuesta-cnn-mayoria-estadounidenses-revocacion-roe-unanimidad-aborto-trax\/","url_meta":{"origin":1451811,"position":5},"title":"Encuesta CNN | La mayor\u00eda de los estadounidenses a\u00fan se opone a la revocaci\u00f3n de Roe, pero no hay unanimidad sobre legislaci\u00f3n del aborto","author":"","date":"mayo 1, 2024","format":false,"excerpt":"(CNN) -- Casi dos a\u00f1os despu\u00e9s de la decisi\u00f3n de la Corte Suprema que revoc\u00f3 el caso Roe vs. Wade, los estadounidenses siguen oponi\u00e9ndose ampliamente a la sentencia, seg\u00fan una nueva encuesta de CNN realizada por SSRS. Pero en medio de una campa\u00f1a presidencial en la que los principales candidatos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1451811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1451811"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1451811\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1451811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1451811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1451811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}