{"id":1452261,"date":"2024-08-29T01:03:55","date_gmt":"2024-08-29T08:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/"},"modified":"2024-08-29T01:03:55","modified_gmt":"2024-08-29T08:03:55","slug":"kamala-harris-entrevista-cnn-analisis-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/","title":{"rendered":"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial"},"content":{"rendered":"<p>(CNN) &#8212; La vicepresidenta Kamala Harris se enfrenta este jueves a la siguiente prueba en su carrera presidencial con su primera entrevista sin guion con un importante medio de comunicaci\u00f3n desde que se convirti\u00f3 en la candidata dem\u00f3crata.<\/p>\n<p>Harris aspira a extender el impulso que ha conjurado en el inicio de su campa\u00f1a; y evitar los tipos de errores no forzados que plagaron su primera candidatura presidencial en 2019, as\u00ed como sus primeros d\u00edas como vicepresidenta. Tambi\u00e9n es una oportunidad para que la reci\u00e9n nombrada candidata acent\u00fae el contraste con el republicano Donald Trump, conecte con los votantes indecisos y destaque sus credenciales para liderar el Despacho Oval en un momento tenso para Estados Unidos dentro y fuera del pa\u00eds.<\/p>\n<p>Harris aparecer\u00e1 junto a su candidato a la vicepresidencia, Tim Walz, en un programa especial en horario de m\u00e1xima audiencia de CNN que se emitir\u00e1 a las 9 pm hora del este de Estados Unidos, desde Georgia, donde se encuentra en una gira en autob\u00fas dise\u00f1ada para volver a poner en el tablero un estado indeciso que el Partido Republicano pensaba que estaba cerca de asegurar en noviembre. La entrevista es el cap\u00edtulo m\u00e1s importante de la campa\u00f1a entre la convenci\u00f3n dem\u00f3crata de la semana pasada en Chicago y el debate presidencial previsto en Filadelfia el 10 de septiembre.<\/p>\n<p>Harris y Walz dar\u00e1n a CNN su primera entrevista conjunta exclusiva desde que comenz\u00f3 la campa\u00f1a<\/p>\n<p>La entrevista, con Dana Bash, adquiri\u00f3 una gran importancia debido a la comprimida carrera que Harris est\u00e1 llevando a cabo tras convertirse en la candidata de su partido y por la forma en que se ha convertido en un problema entre las enemistadas campa\u00f1as. Es el \u00faltimo momento de gran expectativa en una carrera desenfrenada en la que Trump se convirti\u00f3 en el primer candidato de un partido importante que fue condenado por un delito y, el expresidente sobrevivi\u00f3 a un intento de asesinato. Por su parte, la desastrosa actuaci\u00f3n del presidente Joe Biden en el debate de CNN en Atlanta desencaden\u00f3 una crisis que acab\u00f3 con su candidatura a la reelecci\u00f3n.<\/p>\n<p>Las grandes entrevistas televisivas, como la de este jueves, tambi\u00e9n desempe\u00f1aron un papel desproporcionado: el presidente acept\u00f3 varias en un intento de frenar su ca\u00edda, pero solo exacerbaron las preocupaciones sobre su edad y su capacidad para cumplir un segundo mandato completo.<\/p>\n<p>Al no programar una entrevista importante antes de ahora, Harris se expuso a las quejas de Trump y de algunos observadores no partidistas de que est\u00e1 tratando de eludir el escrutinio. Esto aumenta las posibilidades de que cualquier metedura de pata sea aprovechada por la campa\u00f1a de Trump. Sin embargo, una buena actuaci\u00f3n de la vicepresidenta supondr\u00eda otro reto para Trump, que ha pasado apuros desde que Harris transform\u00f3 la carrera al reducir su ventaja en los campos de batalla electorales y recaudar US$ 500 millones.<\/p>\n<p>A\u00f1adir sustancia a un alegre despliegue<\/p>\n<p>Aunque Harris despert\u00f3 un intenso entusiasmo en la Convenci\u00f3n Nacional Dem\u00f3crata de Chicago la semana pasada, repleta de estrellas, as\u00ed como en alegres reuniones entre dem\u00f3cratas que antes estaban desmoralizados por las posibilidades de reelecci\u00f3n de Biden, a\u00fan tiene que entrar en un foro en el que sus respuestas y pol\u00edticas puedan ser rebatidas. Sus discursos han estado repletos de lo que quiere hacer como presidenta: desde aliviar la carga econ\u00f3mica de los estadounidenses hasta desencadenar un auge de la construcci\u00f3n de viviendas o ganar la contienda geopol\u00edtica del siglo XXI contra China. Pero la vicepresidenta no ha concretado exactamente c\u00f3mo llevar\u00eda a la pr\u00e1ctica algunas de esas aspiraciones ni c\u00f3mo las financiar\u00eda en un Washington profundamente dividido.<\/p>\n<p>En la entrevista se ver\u00e1 si Harris se distancia en temas clave con Biden, ya que se presenta como una candidata del cambio a pesar de haber sido vicepresidenta en una administraci\u00f3n impopular. Harris ya ha ido m\u00e1s lejos que su jefe al comprometerse a combatir los elevados precios de los alimentos que afectan a millones de estadounidenses. Este giro populista puede ser pol\u00edticamente inteligente, pero fue criticado por muchos economistas.<\/p>\n<p>La entrevista se ha convertido en un obst\u00e1culo para la vicepresidenta porque los asesores de Trump llevan semanas incit\u00e1ndola, aparentemente convencidos de que no responder\u00e1 a las preguntas dif\u00edciles, de que se quedar\u00e1 en blanco en los detalles pol\u00edticos y de que carece de instintos pol\u00edticos \u00e1giles. En un comunicado este mi\u00e9rcoles, la campa\u00f1a de Trump se burl\u00f3 de Harris, diciendo que ella hab\u00eda &#171;reunido el coraje para sentarse para una &#8216;entrevista conjunta&#8217; despu\u00e9s de 39 d\u00edas de esconderse de los periodistas&#187;. Aunque no se ha sentado para una entrevista importante, Harris ha respondido a algunas preguntas de periodistas que viajaban con ella.<\/p>\n<p>AN\u00c1LISIS | El debate entre Harris y Trump se perfila ya como otro punto de inflexi\u00f3n hist\u00f3rico en una campa\u00f1a extraordinaria<\/p>\n<p>La candidata presidencial dem\u00f3crata, la vicepresidenta Kamala Harris, y su compa\u00f1ero de f\u00f3rmula, el gobernador de Minnesota, Tim Walz, descienden de su autob\u00fas de campa\u00f1a en Savannah, Georgia, el 28 de agosto de 2024. (Cr\u00e9dito: Saul Loeb\/AFP\/Getty Images)<\/p>\n<p>Tras a\u00f1os como fiscal general de California y senadora que destac\u00f3 en audiencias de alto nivel, Harris ha parecido a menudo m\u00e1s c\u00f3moda haciendo preguntas penetrantes que respondiendo a ellas. Carece de las d\u00e9cadas de experiencia pol\u00edtica que ayudaron a la excandidata dem\u00f3crata Hillary Clinton, por ejemplo, a convertir las entrevistas en seminarios pol\u00edticos. Y a diferencia de Trump, no inunda a los entrevistadores con torrentes de falsedades, declaraciones escandalosas y grandilocuencia, lo que significa que \u00e9l a menudo es capaz de distraer la atenci\u00f3n de lo que realmente dice.<\/p>\n<p>Los republicanos est\u00e1n convencidos de que Harris quedar\u00e1 en evidencia en situaciones de alta presi\u00f3n<\/p>\n<p>La confianza de los republicanos en que Harris pueda quedar en evidencia en una entrevista televisada tiene su origen en un cara a cara que mantuvo con Lester Holt, de NBC, al principio de su vicepresidencia, y que se centr\u00f3 en su papel como como emisaria ante las naciones latinoamericanas que representan la fuente de gran parte de la migraci\u00f3n indocumentada a Estados Unidos.<\/p>\n<p>Cuando se le pregunt\u00f3 por qu\u00e9 no hab\u00eda visitado la frontera sur como vicepresidenta, Harris se\u00f1al\u00f3 que tampoco hab\u00eda visitado Europa desde que asumi\u00f3 el cargo. Su incomodidad dio lugar a a\u00f1os de ataques republicanos y la entrevista sigue pesando sobre su mandato como vicepresidenta. En aquella entrevista, Harris parec\u00eda mal preparada, una situaci\u00f3n que parece poco probable que se repita teniendo en cuenta que est\u00e1 inmersa en los preparativos del debate. En entrevistas m\u00e1s recientes, por ejemplo, en el programa &#171;60 Minutes&#187; de CBS el pasado octubre y con Anderson Cooper de CNN a finales de junio, cuando defendi\u00f3 a Biden, parec\u00eda mucho m\u00e1s tranquila.<\/p>\n<p>De cara a la entrevista de este jueves, los republicanos tambi\u00e9n exigen respuestas sobre por qu\u00e9 Harris ha abandonado algunas posiciones que mantuvo en su ef\u00edmera candidatura presidencial de 2020, incluyendo &#171;Medicare para todos&#187;. Su campa\u00f1a tambi\u00e9n ha indicado que ya no se opone al fracking, un tema importante en Pensilvania, donde Trump est\u00e1 destacando la industria energ\u00e9tica de carbono de la mancomunidad.<\/p>\n<p>Campa\u00f1a de Trump se prepara para un repunte de Harris en las encuestas y una prolongada &#171;luna de miel&#187; para la candidata dem\u00f3crata<\/p>\n<p>La campa\u00f1a de Trump y los medios conservadores retrataron este mi\u00e9rcoles la presencia en la entrevista de Walz, el gobernador de Minnesota, como una muleta para la vicepresidenta. Sin embargo, no es inusual que los candidatos presidenciales aparezcan con sus vicepresidentes. Trump se sent\u00f3 con su candidato a vicepresidente, el senador de Ohio, J.D. Vance, en una entrevista amistosa en Fox News el mes pasado que termin\u00f3 con un segmento de &#171;preguntas de los fans&#187;. El expresidente tambi\u00e9n hizo una entrevista conjunta con el nombrado candidato a la vicepresidencia, Mike Pence, en su \u00e1tico de la Torre Trump en el programa &#171;60 Minutes&#187; en 2016. El futuro vicepresidente trat\u00f3 de matizar las posturas extremas del hombre que lo eligi\u00f3, mientras Trump no paraba de interrumpirle.<\/p>\n<p>Kamala Harris y Tim Walz visitan la escuela secundaria Liberty County High School en Hinesville, Georgia, el 28 de agosto de 2024. (Cr\u00e9dito: Elizabeth Frantz\/Reuters)<\/p>\n<p>Harris mantuvo una entrevista conjunta con Biden en 2020, cuando era candidata a la vicepresidencia, y la candidata dem\u00f3crata Clinton y su compa\u00f1ero de f\u00f3rmula, Tim Kaine, hicieron lo propio en 2016.<\/p>\n<p>Dejando a un lado las disputas partidistas sobre la entrevista, hay muchas razones por las que tiene sentido que los candidatos presidenciales se sometan a duras entrevistas. Alguien que aspira a dirigir el pa\u00eds deber\u00eda sentirse en la obligaci\u00f3n de explicar lo que planea hacer, aunque sus directores de campa\u00f1a prefieran restringir sus apariciones a medios partidistas de bajo riesgo y a personas influyentes y emp\u00e1ticas en las redes sociales. Cuantas m\u00e1s entrevistas concede un pol\u00edtico, m\u00e1s pr\u00e1ctica adquiere. Un plan de medios m\u00e1s s\u00f3lido podr\u00eda haber ayudado a Harris a perfeccionar sus habilidades antes de debatir con Trump.<\/p>\n<p>AN\u00c1LISIS | Por qu\u00e9 Harris quiere darle voz a Trump en el debate<\/p>\n<p>Las presidencias de \u00e9xito tambi\u00e9n se basan en el capital pol\u00edtico acumulado durante la campa\u00f1a. Puede que ya hayan pasado los d\u00edas en que las campa\u00f1as presidenciales se basaban en discursos pol\u00edticos de peso, y en esta carrera tan comprimida hay poco tiempo para tales actos.<\/p>\n<p>Sin embargo, los candidatos presidenciales del pasado demostraron su credibilidad haciendo part\u00edcipes a los votantes de sus planes pol\u00edticos. En 1960, por ejemplo, el candidato dem\u00f3crata John F. Kennedy expuso durante la campa\u00f1a un programa sobre cuestiones como los derechos civiles, la vivienda y la pol\u00edtica exterior que se convirti\u00f3 en la base de los logros pol\u00edticos de su presidencia y de la posterior de Lyndon Johnson.<\/p>\n<p>La entrevista de este jueves se produce en un momento en que los dem\u00f3cratas debaten si Harris debe concentrarse m\u00e1s en cuestiones pol\u00edticas o en establecer contrastes de car\u00e1cter con Trump, mientras dice a los votantes que tienen una oportunidad &#171;fugaz&#187; de pasar p\u00e1gina a su cacofon\u00eda.<\/p>\n<p>Estas son las ideas de Harris: son m\u00e1s progresistas que las de Biden<\/p>\n<p>Kate Bedingfield, exdirectora de comunicaciones de Biden en la Casa Blanca, dijo que Harris necesitaba aprovechar la ocasi\u00f3n para dejar claro por qui\u00e9n est\u00e1 luchando, y su promesa de proteger a los votantes de lo que ella considera ataques del Partido Republicano a sus libertades.<\/p>\n<p>&#171;Creo que no tiene que dejarse llevar demasiado por la idea de que esto tiene que ser un examen de doctorado de cada uno de los posibles puntos de un Gobierno Harris y utilizarlo realmente como una oportunidad para transmitir mensajes&#187;, dijo Bedingfield, ahora comentarista de CNN.<\/p>\n<p>Pero Leon Panetta, exdirector de la CIA, exsecretario de Defensa y ex secretario general de la Casa Blanca, dijo a Brianna Keilar, de CNN, que los candidatos deber\u00edan hablar de los temas en los que creen para demostrar que pueden llevar al pa\u00eds por un camino mejor.<\/p>\n<p>Y a\u00f1adi\u00f3: \u201cM\u00e1s vale que sepan muy bien las respuestas a preguntas concretas, porque eso pondr\u00e1 a prueba si solo est\u00e1n hablando en t\u00e9rminos generales o si realmente tienen una pol\u00edtica concreta que quieren poner en marcha&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La vicepresidenta Kamala Harris se enfrenta este jueves a la siguiente prueba en su carrera presidencial con su primera entrevista sin guion con un importante medio de comunicaci\u00f3n desde que se convirti\u00f3 en la candidata dem\u00f3crata. Harris aspira a extender el impulso que ha conjurado en el inicio de su campa\u00f1a; y evitar [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452261","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La vicepresidenta Kamala Harris se enfrenta este jueves a la siguiente prueba en su carrera presidencial con su primera entrevista sin guion con un importante medio de comunicaci\u00f3n desde que se convirti\u00f3 en la candidata dem\u00f3crata. Harris aspira a extender el impulso que ha conjurado en el inicio de su campa\u00f1a; y evitar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-29T08:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial\",\"datePublished\":\"2024-08-29T08:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/\"},\"wordCount\":1998,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/\",\"name\":\"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-29T08:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial - Noticias","og_description":"(CNN) &#8212; La vicepresidenta Kamala Harris se enfrenta este jueves a la siguiente prueba en su carrera presidencial con su primera entrevista sin guion con un importante medio de comunicaci\u00f3n desde que se convirti\u00f3 en la candidata dem\u00f3crata. Harris aspira a extender el impulso que ha conjurado en el inicio de su campa\u00f1a; y evitar [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-29T08:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial","datePublished":"2024-08-29T08:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/"},"wordCount":1998,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/","name":"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-29T08:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial","url":"http:\/\/noticiasya.com\/boston\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/08\/29\/kamala-harris-entrevista-cnn-analisis-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-29T08:03:55Z","datePublished":"2024-08-29T08:03:55Z","dateModified":"2024-08-29T08:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | La entrevista de Harris con CNN es el \\u00faltimo y muy esperado giro en la desenfrenada carrera presidencial\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/29\\\/kamala-harris-entrevista-cnn-analisis-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/29\\\/kamala-harris-entrevista-cnn-analisis-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-29T08:03:55Z\",\"datePublished\":\"2024-08-29T08:03:55Z\",\"dateModified\":\"2024-08-29T08:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452286,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/30\/conclusiones-entrevista-cnn-harris-walz-trax\/","url_meta":{"origin":1452261,"position":0},"title":"Conclusiones de la entrevista de CNN a Kamala Harris y Tim Walz","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) -- La vicepresidenta Kamala Harris dijo sentirse \"profundamente conmovida\" por una foto de su sobrina nieta, con coletas, vi\u00e9ndola hablar en la Convenci\u00f3n Nacional Dem\u00f3crata en Chicago la semana pasada.Aunque Harris no ha hecho hincapi\u00e9 en ello \u2013ha dicho que se presenta para ser presidenta de \"todos los estadounidenses\"\u2013,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451569,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/02\/kamala-harris-votos-candidatura-presidencial-democrata-trax\/","url_meta":{"origin":1452261,"position":1},"title":"Kamala Harris obtuvo suficientes votos para ganar la candidatura presidencial dem\u00f3crata, anuncia el presidente del partido","author":"","date":"agosto 2, 2024","format":false,"excerpt":"(CNN) -- La vicepresidenta Kamala Harris obtuvo suficientes votos de los delegados dem\u00f3cratas para ganar la candidatura del partido a la presidencia, anunci\u00f3 el viernes el presidente de la Comisi\u00f3n Nacional Dem\u00f3crata, Jaime Harrison.Harris se convertir\u00e1 en la primera mujer negra y la primera estadounidense de origen asi\u00e1tico en encabezar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451312,"url":"https:\/\/noticiasya.com\/boston\/2024\/07\/22\/kamala-harris-candidata-democrata-respuestas-preguntas-decision-biden-abandonar-carrera-electoral-trax\/","url_meta":{"origin":1452261,"position":2},"title":"\u00bfEs Kamala Harris ahora la candidata dem\u00f3crata? Respuestas a las preguntas clave sobre la decisi\u00f3n de Biden de abandonar la carrera electoral","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN) -- El presidente Joe Biden anunci\u00f3 este domingo que no buscar\u00e1 ser reelegido como presidente en 2024, y respald\u00f3 a la vicepresidenta Kamala Harris para convertirse en la candidata dem\u00f3crata.Pero la decisi\u00f3n del presidente de 81 a\u00f1os \u2014a poco m\u00e1s de 100 d\u00edas de las elecciones\u2014 dio lugar a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451316,"url":"https:\/\/noticiasya.com\/boston\/2024\/07\/22\/5-cosas-22-julio-retiro-biden-candidatura-orix\/","url_meta":{"origin":1452261,"position":3},"title":"Las 5 cosas que debes saber este 22 de julio: \u00bfPor qu\u00e9 se retir\u00f3 Biden?","author":"","date":"julio 22, 2024","format":false,"excerpt":"\u00bfQu\u00e9 pasar\u00e1 con las elecciones de EE.UU. y la candidatura dem\u00f3crata tras el retiro de Biden de la contienda? Trump reacciona al retiro de Biden de la reelecci\u00f3n presidencial. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451350,"url":"https:\/\/noticiasya.com\/boston\/2024\/07\/22\/harris-apoyos-delegados-nominacion-presidencial-democrata-trax\/","url_meta":{"origin":1452261,"position":4},"title":"Harris consigue suficientes apoyos de delegados para ganar la nominaci\u00f3n presidencial dem\u00f3crata","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN) -- Kamala Harris cuenta con el apoyo de suficientes delegados dem\u00f3cratas para ganar la nominaci\u00f3n del partido a la presidencia, seg\u00fan la estimaci\u00f3n de delegados de la CNN.Mientras siguen llegando los apoyos de los delegados, la vicepresidenta cuenta ya con el respaldo de m\u00e1s de los 1.976 delegados comprometidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455547,"url":"https:\/\/noticiasya.com\/boston\/2024\/11\/04\/quien-favorito-ganar-elecciones-presidenciales-ee-uu-2024-encuestas-orix\/","url_meta":{"origin":1452261,"position":5},"title":"\u00bfQui\u00e9n es favorito para ganar las elecciones presidenciales en EE.UU. 2024? Esto dicen las encuestas","author":"","date":"noviembre 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Estados Unidos completar\u00e1 pronto sus elecciones generales de 2024, en las que est\u00e1n en juego los puestos m\u00e1s importantes del pa\u00eds: presidencia y vicepresidencia. Las encuestas muestran un panorama re\u00f1ido para el puesto de la Casa Blanca.Ahora puedes seguirnos en\u00a0WhatsApp ChannelPor un lado, el expresidente Donald Trump es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1452261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1452261"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1452261\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1452261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1452261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1452261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}