{"id":1452292,"date":"2024-08-30T09:03:50","date_gmt":"2024-08-30T16:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/"},"modified":"2024-08-30T09:03:50","modified_gmt":"2024-08-30T16:03:50","slug":"muere-jugador-de-la-nhl-johnny-gaudreau-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/","title":{"rendered":"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Johnny Gaudreau, jugador de la NHL, y su hermano murieron atropellados por una camioneta cuando circulaban en bicicleta por una carretera de Nueva Jersey, seg\u00fan informaron las autoridades. La tragedia se produjo la v\u00edspera de la boda de su hermana.<\/p>\n<p>El equipo de Gaudreau, los Columbus Blue Jackets, calific\u00f3 las muertes de &#171;tragedia inimaginable&#187; en una publicaci\u00f3n en las redes sociales el viernes.<\/p>\n<p>Johnny Gaudreau, de 31 a\u00f1os, y Matthew Gaudreau, de 29, montaban en bicicleta sobre las 08:19 p.m. del jueves en una carretera comarcal de Oldmans Township -una comunidad del sur de Nueva Jersey cercana al r\u00edo Delaware- cuando un Jeep Grand Cherokee que intentaba adelantar a dos veh\u00edculos que circulaban m\u00e1s despacio les golpe\u00f3, seg\u00fan la Polic\u00eda Estatal de Nueva Jersey.<\/p>\n<p>El conductor del Jeep, que la polic\u00eda identific\u00f3 como Sean Higgins, de 43 a\u00f1os, est\u00e1 acusado de dos cargos por las muertes. &#171;A partir de una investigaci\u00f3n adicional, Higgins era sospechoso de estar bajo la influencia de alcohol&#187;, dijo el sargento de la Polic\u00eda Estatal Jeffrey Lebron en un comunicado de prensa.<\/p>\n<p>Higgins estaba detenido sin fianza en el Centro Correccional del condado de Salem el viernes por la ma\u00f1ana, seg\u00fan muestran los registros de la c\u00e1rcel. No hab\u00eda disponible informaci\u00f3n sobre un abogado.<\/p>\n<p>Se preve\u00eda que los hermanos Gaudreau fueran los padrinos de la boda de su hermana el viernes en Filadelfia, seg\u00fan su p\u00e1gina de registro en l\u00ednea en TheKnot.com.<\/p>\n<p>Apodado &#171;Johnny Hockey&#187;, Johnny Gaudreau fue reclutado por los Calgary Flames en la cuarta ronda del Draft de la NHL de 2011 procedente del Boston College.<\/p>\n<p>Firm\u00f3 con los Columbus Blue Jackets antes de la temporada 2022-2023 y anot\u00f3 12 goles y dio 48 asistencias la temporada pasada.<\/p>\n<p>&#171;Los Columbus Blue Jackets est\u00e1n conmocionados y devastados por esta tragedia inimaginable. Johnny no s\u00f3lo era un gran jugador de hockey, sino tambi\u00e9n un esposo, padre, hijo, hermano y amigo. Extendemos nuestro m\u00e1s sentido p\u00e9same a su esposa, Meredith, a sus hijos, Noa y Johnny, a sus padres, a su familia y amigos por la repentina p\u00e9rdida de Johnny y Matthew&#187;, dijeron los Blue Jackets en el comunicado.<\/p>\n<p>&#171;Johnny jug\u00f3 con gran alegr\u00eda que fue sentida por todos los que lo vieron en el hielo. Llevaba consigo un amor genuino por el hockey a todas partes donde jug\u00f3, desde Boston College a los Calgary Flames, al Team USA y a los Blue Jackets. Emocionaba a los aficionados como s\u00f3lo Johnny Hockey pod\u00eda hacerlo&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Johnny Gaudreau, jugador de la NHL, y su hermano murieron atropellados por una camioneta cuando circulaban en bicicleta por una carretera de Nueva Jersey, seg\u00fan informaron las autoridades. La tragedia se produjo la v\u00edspera de la boda de su hermana. El equipo de Gaudreau, los Columbus Blue Jackets, calific\u00f3 las muertes de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452292","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Johnny Gaudreau, jugador de la NHL, y su hermano murieron atropellados por una camioneta cuando circulaban en bicicleta por una carretera de Nueva Jersey, seg\u00fan informaron las autoridades. La tragedia se produjo la v\u00edspera de la boda de su hermana. El equipo de Gaudreau, los Columbus Blue Jackets, calific\u00f3 las muertes de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T16:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana\",\"datePublished\":\"2024-08-30T16:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/\"},\"wordCount\":476,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/\",\"name\":\"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-30T16:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Johnny Gaudreau, jugador de la NHL, y su hermano murieron atropellados por una camioneta cuando circulaban en bicicleta por una carretera de Nueva Jersey, seg\u00fan informaron las autoridades. La tragedia se produjo la v\u00edspera de la boda de su hermana. El equipo de Gaudreau, los Columbus Blue Jackets, calific\u00f3 las muertes de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-30T16:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/"},"author":{"name":"","@id":""},"headline":"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana","datePublished":"2024-08-30T16:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/"},"wordCount":476,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/","name":"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-30T16:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\u00edspera de la boda de su hermana","url":"http:\/\/noticiasya.com\/boston\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/08\/30\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-30T16:03:50Z","datePublished":"2024-08-30T16:03:50Z","dateModified":"2024-08-30T16:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El jugador de la NHL Johnny Gaudreau y su hermano mueren en un choque la v\\u00edspera de la boda de su hermana\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/30\\\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/30\\\/muere-jugador-de-la-nhl-johnny-gaudreau-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-30T16:03:50Z\",\"datePublished\":\"2024-08-30T16:03:50Z\",\"dateModified\":\"2024-08-30T16:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471540,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/22\/estados-unidos-canada-final-hockey-hielo-trax\/","url_meta":{"origin":1452292,"position":0},"title":"EE.UU. gan\u00f3 la medalla de oro en hockey sobre hielo en una \u00e9pica final y la Casa Blanca se burl\u00f3 de Canad\u00e1","author":"","date":"febrero 22, 2026","format":false,"excerpt":"Fue el final que todos esperaban, pero result\u00f3 ser mejor de lo que nadie podr\u00eda haber imaginado.El equipo de EE.UU. realiz\u00f3 una de las mejores actuaciones ol\u00edmpicas de la historia al vencer a Canad\u00e1 en tiempo extra y ganar su primera medalla de oro en hockey sobre hielo masculino desde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467111,"url":"https:\/\/noticiasya.com\/boston\/2025\/10\/04\/adolescentes-paseo-bicicleta-atropelladas-trax\/","url_meta":{"origin":1452292,"position":1},"title":"Dos adolescentes murieron atropelladas mientras paseaban en bicicleta. Ahora, otro joven enfrenta cargos de homicidio","author":"","date":"octubre 4, 2025","format":false,"excerpt":"Dos mejores amigas adolescentes salieron a dar un paseo en bicicleta el\u00e9ctrica por la tarde a principios de esta semana en Cranford, Nueva Jersey, una peque\u00f1a ciudad a solo 29 kil\u00f3metros al sur de la ciudad de Nueva York.Nunca regresaron a casa. Ambas chicas fueron atropelladas por un auto y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466659,"url":"https:\/\/noticiasya.com\/boston\/2025\/09\/21\/personas-baleadas-nueva-hampshire-trax\/","url_meta":{"origin":1452292,"position":2},"title":"Un muerto y varios heridos en un tiroteo en Nueva Hampshire, seg\u00fan la Polic\u00eda; una persona de inter\u00e9s est\u00e1 bajo custodia","author":"","date":"septiembre 21, 2025","format":false,"excerpt":"Una persona muri\u00f3 y otras resultaron heridas en un tiroteo en el Sky Meadow Country Club en Nashua, Nueva Hampshire, la noche del s\u00e1bado, seg\u00fan informaron las autoridades.Algunas de las lesiones fueron heridas de bala y otras se produjeron durante el caos, dijo el fiscal general adjunto de Nueva Hampshire,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464222,"url":"https:\/\/noticiasya.com\/boston\/2025\/07\/04\/muerte-diogo-jota-hermano-liverpool-trax\/","url_meta":{"origin":1452292,"position":3},"title":"As\u00ed fue el accidente de la estrella del Liverpool Diogo Jota y de su hermano Andr\u00e9 Silva","author":"","date":"julio 4, 2025","format":false,"excerpt":"El mundo del f\u00fatbol est\u00e1 de luto tras la muerte de Diogo Jota, estrella del Liverpool y de la selecci\u00f3n de Portugal, en un accidente automovil\u00edstico ocurrido en Espa\u00f1a en la madrugada del jueves. Jota ten\u00eda 28 a\u00f1os.Su hermano Andr\u00e9 Silva, tambi\u00e9n futbolista profesional, tambi\u00e9n falleci\u00f3 junto a Jota en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471675,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/26\/hijo-recrea-fotografias-viaje-bicicleta-padre-trax\/","url_meta":{"origin":1452292,"position":4},"title":"Sigui\u00f3 el recorrido en bicicleta que hizo su padre hasta Australia en los 80 y recre\u00f3 las fotos al detalle","author":"","date":"febrero 26, 2026","format":false,"excerpt":"A primera vista, las dos fotos parecen id\u00e9nticas: un joven ciclista bajo los glaciares, cerca del campo Base del Everest, con la bicicleta al hombro y la determinaci\u00f3n en el rostro.Las im\u00e1genes podr\u00edan haber sido tomadas con apenas unos segundos de diferencia: el mismo lugar, la misma luz, las mismas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464326,"url":"https:\/\/noticiasya.com\/boston\/2025\/07\/08\/diogo-jota-manejaba-exceso-velocidad-trax\/","url_meta":{"origin":1452292,"position":5},"title":"Diogo Jota manejaba al momento del accidente y probablemente lo hac\u00eda con exceso de velocidad, seg\u00fan la investigaci\u00f3n","author":"","date":"julio 8, 2025","format":false,"excerpt":"El delantero del Liverpool Diogo Jota conduc\u00eda el autom\u00f3vil y probablemente iba por encima de la velocidad permitida cuando su auto se estrell\u00f3 en Espa\u00f1a el jueves, causando la muerte de \u00e9l y de su hermano menor, seg\u00fan una primera investigaci\u00f3n policial.Jota y su hermano, Andr\u00e9 Silva, murieron cuando su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1452292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1452292"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1452292\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1452292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1452292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1452292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}