{"id":1452295,"date":"2024-08-30T10:03:48","date_gmt":"2024-08-30T17:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/"},"modified":"2024-08-30T10:03:48","modified_gmt":"2024-08-30T17:03:48","slug":"fallece-julian-ortega-actor-elite-netflix-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/","title":{"rendered":"Fallece Juli\u00e1n Ortega, actor de la serie &#171;\u00c9lite&#187; de Netflix, a los 41 a\u00f1os"},"content":{"rendered":"<p>(CNN) &#8212; El actor espa\u00f1ol Juli\u00e1n Ortega, conocido por aparecer en la popular serie dram\u00e1tica en espa\u00f1ol de Netflix &#171;\u00c9lite&#187;, falleci\u00f3, seg\u00fan anunci\u00f3 el sindicato de actores y actrices del pa\u00eds. Ten\u00eda 41 a\u00f1os.<\/p>\n<p>&#171;Nuestro m\u00e1s sentido p\u00e9same a su familia y amigos&#187;, escribi\u00f3 el sindicato en un comunicado el lunes.<\/p>\n<p>Ortega, hijo de la actriz espa\u00f1ola Gloria Mu\u00f1oz, naci\u00f3 en Madrid en 1983. Estudi\u00f3 arte dram\u00e1tico en la capital espa\u00f1ola, seg\u00fan el sindicato.<\/p>\n<p>Despu\u00e9s lanz\u00f3 su carrera de m\u00e1s de dos d\u00e9cadas en la pantalla, apareciendo en pel\u00edculas en espa\u00f1ol, como el drama de 2000 &#171;El otro barrio&#187; y la fantas\u00eda de terror de 2008 &#171;La ra\u00edz del mal&#187;.<\/p>\n<p>Apareci\u00f3 en varias series de televisi\u00f3n en Espa\u00f1a, antes de saltar a la fama internacional tras aparecer en seis episodios de &#171;\u00c9lite&#187; de Netflix.<\/p>\n<p>Ortega interpret\u00f3 al gerente de un restaurante en el drama de instituto con tintes de asesinato y misterio, que se centra en estudiantes adinerados de un colegio privado.<\/p>\n<p>Sus apariciones m\u00e1s recientes fueron en series dram\u00e1ticas como &#171;El Pueblo&#187; y &#171;4 estrellas&#187;.<\/p>\n<p>&#171;Eras un gran hombre, humilde, siempre con una sonrisa, generoso, atento&#8230; tan buen compa\u00f1ero&#8230; Gracias, por todo&#187;, escribi\u00f3 el lunes su compa\u00f1era de reparto en &#171;El Pueblo&#187;, Ruth D\u00edaz, en una publicaci\u00f3n de Instagram.<\/p>\n<p>&#171;Qu\u00e9 bueno compartir esos meses en El Pueblo y haberte podido conocer un poquito. Te has ido demasiado pronto&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Ortega tambi\u00e9n trabaj\u00f3 en proyectos teatrales, entre ellos la obra &#171;Ira&#187;, de 2021, que escribi\u00f3 y luego protagoniz\u00f3 junto a su madre, seg\u00fan el Teatro Espa\u00f1ol de Madrid.<\/p>\n<p>No se ha anunciado oficialmente la causa de su muerte.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El actor espa\u00f1ol Juli\u00e1n Ortega, conocido por aparecer en la popular serie dram\u00e1tica en espa\u00f1ol de Netflix &#171;\u00c9lite&#187;, falleci\u00f3, seg\u00fan anunci\u00f3 el sindicato de actores y actrices del pa\u00eds. Ten\u00eda 41 a\u00f1os. &#171;Nuestro m\u00e1s sentido p\u00e9same a su familia y amigos&#187;, escribi\u00f3 el sindicato en un comunicado el lunes. Ortega, hijo de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452295","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fallece Juli\u00e1n Ortega, actor de la serie &quot;\u00c9lite&quot; de Netflix, a los 41 a\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fallece Juli\u00e1n Ortega, actor de la serie &quot;\u00c9lite&quot; de Netflix, a los 41 a\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El actor espa\u00f1ol Juli\u00e1n Ortega, conocido por aparecer en la popular serie dram\u00e1tica en espa\u00f1ol de Netflix &#171;\u00c9lite&#187;, falleci\u00f3, seg\u00fan anunci\u00f3 el sindicato de actores y actrices del pa\u00eds. Ten\u00eda 41 a\u00f1os. &#171;Nuestro m\u00e1s sentido p\u00e9same a su familia y amigos&#187;, escribi\u00f3 el sindicato en un comunicado el lunes. Ortega, hijo de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T17:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fallece Juli\u00e1n Ortega, actor de la serie &#171;\u00c9lite&#187; de Netflix, a los 41 a\u00f1os\",\"datePublished\":\"2024-08-30T17:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/\"},\"wordCount\":327,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/\",\"name\":\"Fallece Juli\u00e1n Ortega, actor de la serie \\\"\u00c9lite\\\" de Netflix, a los 41 a\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-30T17:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fallece Juli\u00e1n Ortega, actor de la serie &#171;\u00c9lite&#187; de Netflix, a los 41 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fallece Juli\u00e1n Ortega, actor de la serie \"\u00c9lite\" de Netflix, a los 41 a\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Fallece Juli\u00e1n Ortega, actor de la serie \"\u00c9lite\" de Netflix, a los 41 a\u00f1os - Noticias","og_description":"(CNN) &#8212; El actor espa\u00f1ol Juli\u00e1n Ortega, conocido por aparecer en la popular serie dram\u00e1tica en espa\u00f1ol de Netflix &#171;\u00c9lite&#187;, falleci\u00f3, seg\u00fan anunci\u00f3 el sindicato de actores y actrices del pa\u00eds. Ten\u00eda 41 a\u00f1os. &#171;Nuestro m\u00e1s sentido p\u00e9same a su familia y amigos&#187;, escribi\u00f3 el sindicato en un comunicado el lunes. Ortega, hijo de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-30T17:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/"},"author":{"name":"","@id":""},"headline":"Fallece Juli\u00e1n Ortega, actor de la serie &#171;\u00c9lite&#187; de Netflix, a los 41 a\u00f1os","datePublished":"2024-08-30T17:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/"},"wordCount":327,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/","name":"Fallece Juli\u00e1n Ortega, actor de la serie \"\u00c9lite\" de Netflix, a los 41 a\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-30T17:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fallece Juli\u00e1n Ortega, actor de la serie &#171;\u00c9lite&#187; de Netflix, a los 41 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fallece Juli\u00e1n Ortega, actor de la serie &#171;\u00c9lite&#187; de Netflix, a los 41 a\u00f1os","url":"http:\/\/noticiasya.com\/boston\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/08\/30\/fallece-julian-ortega-actor-elite-netflix-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-30T17:03:48Z","datePublished":"2024-08-30T17:03:48Z","dateModified":"2024-08-30T17:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fallece Juli\\u00e1n Ortega, actor de la serie &#171;\\u00c9lite&#187; de Netflix, a los 41 a\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/30\\\/fallece-julian-ortega-actor-elite-netflix-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/30\\\/fallece-julian-ortega-actor-elite-netflix-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-30T17:03:48Z\",\"datePublished\":\"2024-08-30T17:03:48Z\",\"dateModified\":\"2024-08-30T17:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442753,"url":"https:\/\/noticiasya.com\/boston\/2023\/12\/27\/berlin-resucita-al-personaje-de-pedro-alonso-en-la-casa-de-papel-de-netflix\/","url_meta":{"origin":1452295,"position":0},"title":"&#8216;Berl\u00edn&#8217; resucita al personaje de Pedro Alonso en &#8216;La casa de papel&#8217; de Netflix","author":"","date":"diciembre 27, 2023","format":false,"excerpt":"(CNN) -- Si le preguntas a Pedro Alonso qu\u00e9 le gusta de Berl\u00edn, su famoso personaje en \"La casa de papel\", lo pondr\u00e1s en un aprieto.\"Cuando le\u00eda el guion, me preguntaba: '\u00bfQu\u00e9 va a pensar la gente de este tipo? Es un terrorista emocional'\", dijo Alonso en una videollamada, sin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464238,"url":"https:\/\/noticiasya.com\/boston\/2025\/07\/04\/julian-mcmahon-muere-56-anios-trax\/","url_meta":{"origin":1452295,"position":1},"title":"Julian McMahon, estrella de &#171;Fantastic Four&#187; y &#171;Nip\/Tuck&#187;, muere a los 56 a\u00f1os","author":"","date":"julio 4, 2025","format":false,"excerpt":"El actor Julian McMahon, uno de los dos protagonistas de la influyente serie de FX \u201cNip\/Tuck\u201d y quien tambi\u00e9n interpret\u00f3 al Dr. Doom en las pel\u00edculas de \u201cFantastic Four\u201d de los a\u00f1os 2000, falleci\u00f3. Seg\u00fan los reportes, ten\u00eda 56 a\u00f1os.La noticia fue confirmada mediante un comunicado en la p\u00e1gina oficial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451813,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/13\/julian-alvarez-salida-atletico-madrid-machester-city-104-millones-dolares-trax\/","url_meta":{"origin":1452295,"position":2},"title":"Juli\u00e1n \u00c1lvarez sella su fichaje en el Atl\u00e9tico de Madrid procedente del Manchester City en un acuerdo de US$ 104 millones","author":"","date":"agosto 13, 2024","format":false,"excerpt":"(CNN) -- Juli\u00e1n \u00c1lvarez fue fichado por el Atl\u00e9tico de Madrid procedente del Manchester City en un acuerdo por un valor aproximado de US$ 104 millones, anunci\u00f3 el club espa\u00f1ol este lunes.El delantero argentino firm\u00f3 un contrato de seis a\u00f1os con el conjunto espa\u00f1ol. Seg\u00fan los medios brit\u00e1nicos, el Atleti\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467631,"url":"https:\/\/noticiasya.com\/boston\/2025\/10\/22\/como-anime-conquisto-latinoamerica-orix\/","url_meta":{"origin":1452295,"position":3},"title":"C\u00f3mo el anime conquist\u00f3 Latinoam\u00e9rica: el fen\u00f3meno cultural de &#8216;Candy Candy&#8217; a &#8216;Demon Slayer&#8217;","author":"","date":"octubre 22, 2025","format":false,"excerpt":"En Latinoam\u00e9rica se ha llorado con \u201cCandy Candy\u201d y \u201cMarco\u201d, se ha re\u00eddo con Chispita y Chito en \u201cMeteoro\u201d y se han pasado noches en vela con las aventuras de Goku en \u201cDragon Ball Z\u201d. El anime, que es como se llama a la animaci\u00f3n hecha en Jap\u00f3n, ha sido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453209,"url":"https:\/\/noticiasya.com\/boston\/2024\/09\/30\/humberto-ortega-hermano-presidente-nicaragua-sufre-brusco-deterioro-salud-segun-hospital-militar\/","url_meta":{"origin":1452295,"position":4},"title":"Humberto Ortega, hermano del presidente de Nicaragua, sufre &#171;brusco deterioro de salud&#187;, seg\u00fan hospital militar","author":"","date":"septiembre 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El excomandate Humberto Ortega, hermano del presidente Daniel Ortega y exministro de Defensa de Nicaragua, \u201csufri\u00f3 un choque cardiog\u00e9nico\u201d este domingo, que se presenta cuando el coraz\u00f3n no puede suministrar suficiente sangre y ox\u00edgeno a los \u00f3rganos del cuerpo, \u201ccon alteraci\u00f3n del estado de conciencia\u201d lo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449712,"url":"https:\/\/noticiasya.com\/boston\/2024\/05\/23\/salud-humberto-ortega-hermano-presidente-nicaragua-daniel-ortega-orix\/","url_meta":{"origin":1452295,"position":5},"title":"\u00bfQu\u00e9 est\u00e1 pasando con Humberto Ortega, el hermano del presidente de Nicaragua?","author":"","date":"mayo 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Medios centroamericanos dicen que no han logrado comunicarse en los \u00faltimos d\u00edas con Humberto Ortega, excomandante y fundador del Ej\u00e9rcito Popular Sandinista, exministro de la Defensa y hermano del presidente nicarag\u00fcense Daniel Ortega, seg\u00fan dijo a CNN una persona cercana al caso este mi\u00e9rcoles.La Polic\u00eda Nacional de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1452295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1452295"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1452295\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1452295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1452295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1452295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}