{"id":1452300,"date":"2024-08-30T15:03:42","date_gmt":"2024-08-30T22:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/"},"modified":"2024-08-30T15:03:42","modified_gmt":"2024-08-30T22:03:42","slug":"california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/","title":{"rendered":"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os"},"content":{"rendered":"<p>(CNN) &#8212; La Legislatura de California aprob\u00f3 un proyecto de ley con apoyo bipartidista que proh\u00edbe el uso del colorante rojo n\u00ba 40 y otras cinco sustancias qu\u00edmicas presentes en los alimentos que se sirven en las escuelas p\u00fablicas.<\/p>\n<p>El jueves, el llamado Estado Dorado se convirti\u00f3 en el primero del pa\u00eds en aprobar un proyecto de ley que, de convertirse en ley, prohibir\u00eda el uso de los ingredientes que se encuentran en algunos cereales, helados, bebidas, caramelos, paletas, patatas fritas con sabor a queso, gelatinas y m\u00e1s productos populares, seg\u00fan el Environmental Working Group (EWG), una organizaci\u00f3n de salud ambiental sin fines de lucro que copatrocin\u00f3 la ley junto con Consumer Reports.<\/p>\n<p>Conocida como la Ley de Seguridad Alimentaria Escolar de California y presentada por el asamble\u00edsta dem\u00f3crata Jesse Gabriel en febrero, la Ley de la Asamblea 2.316 proh\u00edbe a un distrito escolar, superintendencia de escuelas del condado o escuela aut\u00f3noma con grados desde jard\u00edn de infantes hasta 12\u00ba ofrecer alimentos o bebidas que contengan colorante rojo n\u00ba 40, colorantes amarillos n\u00ba 5 y 6, colorantes azules n\u00ba 1 y 2 y colorante verde n\u00ba 3.<\/p>\n<p>El gobernador de California, Gavin Newsom, dem\u00f3crata, tiene hasta el 30 de septiembre para firmar la ley que, de aprobarse, se promulgar\u00eda el 31 de diciembre de 2027.<\/p>\n<p>Australia lanza el primer programa de inmunoterapia contra la alergia al man\u00ed para beb\u00e9s<\/p>\n<p>California alberga el sistema escolar p\u00fablico m\u00e1s grande de la naci\u00f3n, con m\u00e1s de 6,3 millones de estudiantes y 10.000 escuelas, dijo Tony Thurmond, superintendente estatal de instrucci\u00f3n p\u00fablica y copatrocinador del proyecto de ley, en una conferencia de prensa organizada por el EWG el 6 de agosto.<\/p>\n<p>El proyecto de ley surge de las preocupaciones de que estos colorantes puedan da\u00f1ar la capacidad de los ni\u00f1os para para aprender, ya que se han relacionado con dificultades de comportamiento y disminuci\u00f3n de la atenci\u00f3n entre los ni\u00f1os, seg\u00fan un estudio de 2021 de la Oficina de Evaluaci\u00f3n de Riesgos para la Salud Ambiental de California.<\/p>\n<p>La ley es &#171;importante para m\u00ed como padre, es importante para m\u00ed como alguien que luch\u00f3 con el TDAH (trastorno cr\u00f3nico caracterizado por la dificultad para prestar atenci\u00f3n, la hiperactividad y la impulsividad) cuando era ni\u00f1o, y es importante para m\u00ed como padre de un ni\u00f1o que lucha con el TDAH&#187;, dijo Gabriel en la sesi\u00f3n informativa. &#171;Sabemos que los colorantes alimentarios sint\u00e9ticos que se ven afectados por este proyecto de ley pueden causar da\u00f1o a todos los ni\u00f1os, pero sabemos que hay un impacto especialmente pronunciado en muchos de nuestros j\u00f3venes con TDAH y otros problemas&#187;.<\/p>\n<p>Gabriel y el EWG dijeron que, aunque &#171;hay nueva informaci\u00f3n cient\u00edfica disponible&#187;, las regulaciones actuales de la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) sobre los colorantes en los alimentos se basan en investigaciones que tienen entre 35 y 70 a\u00f1os.<\/p>\n<p>&#171;Reevaluar la seguridad de los productos qu\u00edmicos en los alimentos a medida que se dispone de nuevos datos relevantes es una prioridad para la FDA&#187;, dijo la agencia en un comunicado. &#171;La FDA ha revisado la investigaci\u00f3n sobre los efectos de los colorantes en el comportamiento de los ni\u00f1os, incluida la revisi\u00f3n bibliogr\u00e1fica citada por el proyecto de ley. La totalidad de la evidencia cient\u00edfica muestra que la mayor\u00eda de los ni\u00f1os no sufren efectos adversos al consumir alimentos que contienen colorantes, pero algunas evidencias sugieren que ciertos ni\u00f1os pueden ser sensibles a ellos&#187;.<\/p>\n<p>Adem\u00e1s de las evaluaciones propias de la FDA, la agencia tambi\u00e9n apoya y participa en evaluaciones de riesgo internacionales realizadas bajo el Comit\u00e9 Mixto de Expertos en Aditivos Alimentarios de la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura de la Organizaci\u00f3n Mundial de la Salud.<\/p>\n<p>&#171;Todos los colorantes enumerados han sido sometidos recientemente a evaluaciones de seguridad en alimentos por parte de la JEFCA y se determin\u00f3 que son seguros para su uso en alimentos en las condiciones de uso actuales&#187;, dijo la FDA.<\/p>\n<p>Sin embargo, la agencia continuar\u00e1 evaluando la evidencia cient\u00edfica emergente y garantizando la seguridad de los colorantes aprobados, incluso mediante la celebraci\u00f3n de una reuni\u00f3n p\u00fablica en septiembre para revisar el proceso de evaluaci\u00f3n posterior a la comercializaci\u00f3n de las sustancias qu\u00edmicas en los alimentos, seg\u00fan la declaraci\u00f3n.<\/p>\n<p>Impactos de la AB 2316<\/p>\n<p>John Hewitt, de la Asociaci\u00f3n de Marcas de Consumo, que representa a m\u00e1s de 1.700 marcas, dijo en una declaraci\u00f3n que &#171;es lamentable que los ingredientes cient\u00edficamente probados y seguros hayan sido demonizados con el prop\u00f3sito de promover una agenda pol\u00edtica&#187;.<\/p>\n<p>&#171;Ninguna industria est\u00e1 m\u00e1s comprometida con la seguridad alimentaria que la industria de bienes de consumo envasados. Es por eso que hemos instado a la FDA a que reconozca agresivamente su responsabilidad como regulador de la seguridad alimentaria de la naci\u00f3n&#187;, dijo Hewitt, vicepresidente s\u00e9nior de envasado y sostenibilidad y asuntos estatales de la asociaci\u00f3n, por correo electr\u00f3nico. &#171;La aprobaci\u00f3n de este proyecto de ley podr\u00eda costar dinero a las escuelas y las familias, limitar la elecci\u00f3n y el acceso, y crear confusi\u00f3n en los consumidores&#187;.<\/p>\n<p>Pero Thurmond destac\u00f3 la mayor importancia del &#171;costo de nuestra inacci\u00f3n\u2026 en una naci\u00f3n donde nuestros ni\u00f1os ya tienen algunas de las tasas m\u00e1s altas de enfermedad, asma, diabetes (y) enfermedades card\u00edacas&#187;, en comparaci\u00f3n con otros pa\u00edses.<\/p>\n<p>Las etiquetas de los alimentos pueden ayudarte a prevenir problemas con tu peso<\/p>\n<p>Gabriel respondi\u00f3 a esos comentarios, al a\u00f1adir que el proyecto de ley puede, en \u00faltima instancia, ahorrar dinero a California al reducir el uso de los recursos necesarios para ayudar a los ni\u00f1os que tienen dificultades en el aula.<\/p>\n<p>&#171;Veo esto tanto a trav\u00e9s de mi experiencia personal como tambi\u00e9n del trabajo que hago como legislador&#187;, a\u00f1adi\u00f3. &#171;Es realmente caro&#187;.<\/p>\n<p>Si Newsom firma el proyecto de ley, la decisi\u00f3n har\u00eda que el entorno alimentario de Estados Unidos se alineara m\u00e1s con el de la Uni\u00f3n Europea, donde los productos que incluyen estos colorantes deben tener una etiqueta de advertencia que diga que pueden da\u00f1ar a los j\u00f3venes, a\u00f1adi\u00f3 Gabriel.<\/p>\n<p>&#171;El objetivo de este proyecto de ley es alentar a los fabricantes a realizar modificaciones menores en sus recetas, para que puedan servir los mismos alimentos que todos amamos, que aman nuestros ni\u00f1os, pero sin estos qu\u00edmicos peligrosos que da\u00f1an a las personas&#187;, a\u00f1adi\u00f3. &#171;Tenemos una confianza incre\u00edble en que pueden hacerlo\u2026 porque elaboran los mismos productos en muchos pa\u00edses alrededor del mundo, solo que sin los qu\u00edmicos da\u00f1inos&#187;.<\/p>\n<p>El EWG ha se\u00f1alado en el pasado que pocos alimentos disponibles en las escuelas de California utilizan los ingredientes que el proyecto de ley prohibir\u00eda si se aprobara.<\/p>\n<p>Sin embargo, Gabriel y otros asamble\u00edstas creen que, dado el tama\u00f1o de la econom\u00eda de California, la ley es una &#171;gran victoria para el movimiento de seguridad alimentaria no solo aqu\u00ed en el estado de California, sino tambi\u00e9n a nivel nacional&#187;, dijo, y tambi\u00e9n se\u00f1al\u00f3 que m\u00e1s de 70 organizaciones apoyan el proyecto de ley.<\/p>\n<p>Despu\u00e9s de que el estado prohibiera el aceite vegetal bromado, utilizado principalmente en algunos refrescos, como parte de su Ley de Seguridad Alimentaria de California en octubre de 2023, la FDA revoc\u00f3 la regulaci\u00f3n para su uso nueve meses despu\u00e9s.<\/p>\n<p>Y al menos otros 10 estados han seguido el ejemplo de California, introduciendo una legislaci\u00f3n basada en esa ley, dijo Gabriel.<\/p>\n<p>C\u00f3mo evitar estos qu\u00edmicos en los alimentos<\/p>\n<p>Si le preocupan los posibles impactos de estos colorantes en la salud de su hijo, puede evitarlos revisando las listas de ingredientes de cualquier producto que compre, explicaron los expertos, en particular los alimentos envasados, que suelen ser ultraprocesados \u200b\u200by, por lo tanto, es m\u00e1s probable que incluyan colorantes artificiales, seg\u00fan el EWG.<\/p>\n<p>Tambi\u00e9n puede probar alternativas sin esos ingredientes: los alimentos que est\u00e1n certificados como org\u00e1nicos por el USDA, por ejemplo, no pueden contener colorantes alimentarios artificiales. Reduzca tambi\u00e9n los refrescos, jugos o bebidas deportivas que puedan contenerlos. Ofrecerles a los ni\u00f1os sustitutos puede ser m\u00e1s efectivo que negarles rotundamente algo que anhelan.<\/p>\n<p>&#171;Haga hincapi\u00e9 en los productos de colores brillantes&#187;, sugiere el EWG. &#171;La mejor competencia para los llamativos paquetes de alimentos ultraprocesados \u200b\u200bes el arco iris de colores de las frutas y verduras frescas&#187;.<\/p>\n<p>La actriz Lesley-Ann Brandt mantiene conversaciones constantes con su hijo de siete a\u00f1os sobre qu\u00e9 alimentos son m\u00e1s o menos saludables para comer y por qu\u00e9, dijo en la sesi\u00f3n informativa.<\/p>\n<p>&#171;Hablamos con \u00e9l como si fuera un adulto y \u00e9l sabe que no comemos esto por eso, pero aqu\u00ed hay una alternativa&#187;, dijo Brandt. &#171;Tambi\u00e9n preparamos algunos de nuestros alimentos y es una forma de hablar sobre nutrici\u00f3n&#187;.<\/p>\n<p>Brandt tambi\u00e9n ha sido testigo de los beneficios de la nutrici\u00f3n en su familia de origen, agreg\u00f3. Despu\u00e9s de crecer en dos sistemas alimentarios &#171;muy diferentes&#187; de Sud\u00e1frica y Nueva Zelanda, &#171;realmente not\u00e9 la diferencia al venir a Estados Unidos hace 14 a\u00f1os&#187;, dijo.<\/p>\n<p>&#171;Tambi\u00e9n soy la hermana mayor de una persona que tuvo un trastorno por d\u00e9ficit de atenci\u00f3n con hiperactividad grave cuando era ni\u00f1o, as\u00ed que pude ver de primera mano el impacto de la nutrici\u00f3n y c\u00f3mo lo ayud\u00f3&#187;, dijo Brandt. &#171;Una de las primeras cosas que hizo mi madre para evitar medicarlo en exceso fue analizar su nutrici\u00f3n y los az\u00facares procesados, los ingredientes, los colorantes alimentarios y los productos qu\u00edmicos sint\u00e9ticos que simplemente no iban a servirle en la escuela&#187;, a\u00f1adi\u00f3.<\/p>\n<p>&#171;Y realmente fue la diferencia entre un estudiante con una nota B y uno con una nota C para \u00e9l&#187;, dijo. &#171;Eso tambi\u00e9n afect\u00f3 su confianza&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La Legislatura de California aprob\u00f3 un proyecto de ley con apoyo bipartidista que proh\u00edbe el uso del colorante rojo n\u00ba 40 y otras cinco sustancias qu\u00edmicas presentes en los alimentos que se sirven en las escuelas p\u00fablicas. El jueves, el llamado Estado Dorado se convirti\u00f3 en el primero del pa\u00eds en aprobar un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452300","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La Legislatura de California aprob\u00f3 un proyecto de ley con apoyo bipartidista que proh\u00edbe el uso del colorante rojo n\u00ba 40 y otras cinco sustancias qu\u00edmicas presentes en los alimentos que se sirven en las escuelas p\u00fablicas. El jueves, el llamado Estado Dorado se convirti\u00f3 en el primero del pa\u00eds en aprobar un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T22:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os\",\"datePublished\":\"2024-08-30T22:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/\"},\"wordCount\":1739,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/\",\"name\":\"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-30T22:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os - Noticias","og_description":"(CNN) &#8212; La Legislatura de California aprob\u00f3 un proyecto de ley con apoyo bipartidista que proh\u00edbe el uso del colorante rojo n\u00ba 40 y otras cinco sustancias qu\u00edmicas presentes en los alimentos que se sirven en las escuelas p\u00fablicas. El jueves, el llamado Estado Dorado se convirti\u00f3 en el primero del pa\u00eds en aprobar un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-30T22:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/"},"author":{"name":"","@id":""},"headline":"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os","datePublished":"2024-08-30T22:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/"},"wordCount":1739,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/","name":"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-30T22:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os","url":"http:\/\/noticiasya.com\/boston\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-30T22:03:42Z","datePublished":"2024-08-30T22:03:42Z","dateModified":"2024-08-30T22:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"California aprueba un proyecto de ley que proh\\u00edbe seis sustancias qu\\u00edmicas relacionadas con problemas de conducta en los ni\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/30\\\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/08\\\/30\\\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-30T22:03:42Z\",\"datePublished\":\"2024-08-30T22:03:42Z\",\"dateModified\":\"2024-08-30T22:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452352,"url":"https:\/\/noticiasya.com\/boston\/2024\/09\/02\/promulgan-ley-puerto-rico-prohibe-publicar-informacion-personal-menores-redes-sociales-orix\/","url_meta":{"origin":1452300,"position":0},"title":"Promulgan ley en Puerto Rico que proh\u00edbe publicar informaci\u00f3n personal de menores en redes sociales","author":"","date":"septiembre 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El gobernador de Puerto Rico, Pedro Pierluisi, firm\u00f3 este domingo un proyecto de ley que proh\u00edbe que cualquier red social publique o divulgue informaci\u00f3n personal de los usuarios menores de 18 a\u00f1os que residan en la isla, sin el consentimiento del padre, madre o tutor legal.La Fortaleza,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472160,"url":"https:\/\/noticiasya.com\/boston\/2026\/03\/13\/vivienda-asequible-senado-trax\/","url_meta":{"origin":1452300,"position":1},"title":"Senado de EE.UU. aprueba el mayor paquete de asequibilidad de vivienda en una generaci\u00f3n","author":"","date":"marzo 13, 2026","format":false,"excerpt":"Un grupo bipartidista de senadores en EE.UU. aprob\u00f3 el jueves un proyecto de ley destinado a mejorar la asequibilidad de la vivienda.La medida contiene aproximadamente 40 disposiciones para aumentar la oferta de vivienda y reducir los costos. A\u00fan est\u00e1 por verse si la C\u00e1mara de Representantes la aprobar\u00e1 tal como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447352,"url":"https:\/\/noticiasya.com\/boston\/2024\/03\/25\/gobernador-florida-ley-acceso-ninos-redes-sociales-trax\/","url_meta":{"origin":1452300,"position":2},"title":"El gobernador Ron DeSantis firma ley en Florida que restringe el acceso de los ni\u00f1os a las redes sociales","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El gobernador de Florida, el republicano Ron DeSantis, firm\u00f3 este lunes un proyecto de ley que proh\u00edbe a los ni\u00f1os menores de 14 a\u00f1os tener sus propias cuentas de redes sociales, seg\u00fan un comunicado de prensa de su oficina.Los j\u00f3venes de 14 y 15 a\u00f1os podr\u00e1n tener cuentas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447136,"url":"https:\/\/noticiasya.com\/boston\/2024\/03\/20\/alabama-aprueba-un-proyecto-de-ley-integral-que-prohibiria-la-diversidad-equidad-e-inclusion-en-escuelas-y-universidades-publicas\/","url_meta":{"origin":1452300,"position":3},"title":"Alabama aprueba un proyecto de ley integral que prohibir\u00eda la diversidad, equidad e inclusi\u00f3n en escuelas y universidades p\u00fablicas","author":"","date":"marzo 20, 2024","format":false,"excerpt":"(CNN) -- Los legisladores de Alabama aprobaron un proyecto de ley este martes que, de ser promulgado, prohibir\u00eda a las escuelas y universidades p\u00fablicas mantener o financiar programas de diversidad, equidad e inclusi\u00f3n (DEI por sus siglas en ingl\u00e9s).El proyecto de ley, SB129, tambi\u00e9n requerir\u00eda que las universidades p\u00fablicas \"designen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446874,"url":"https:\/\/noticiasya.com\/boston\/2024\/03\/12\/maestros-florida-discutir-sexualidad-identidad-genero-entornos-escolares-acuerdo-legal-trax\/","url_meta":{"origin":1452300,"position":4},"title":"Maestros de Florida pueden discutir temas de sexualidad e identidad de g\u00e9nero en algunos entornos escolares, aclara un acuerdo legal","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN) -- Funcionarios de educaci\u00f3n de Florida y un grupo de defensores de derechos LGBTQ y familias llegaron a un acuerdo legal este lunes que aclara el alcance de una ley referida por cr\u00edticos como la ley \"Don't Say Gay\", especificando que a los estudiantes y maestros se les permite\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463995,"url":"https:\/\/noticiasya.com\/boston\/2025\/06\/26\/congreso-politica-gran-hermoso-proyecto-ley-trump-trax\/","url_meta":{"origin":1452300,"position":5},"title":"El &#171;gran y hermoso proyecto de ley&#187; de Trump puede ser un desastre y no ser bien recibido, pero es probable que se apruebe","author":"","date":"junio 26, 2025","format":false,"excerpt":"El \u201cgran y hermoso proyecto de ley\u201d del presidente Donald Trump, al que el jueves denomin\u00f3 la \u201ccodificaci\u00f3n definitiva\u201d de la agenda MAGA, es una paradoja que muestra c\u00f3mo funciona el poder en un sistema pol\u00edtico quebrado, donde el republicano es la mayor fuerza.Mientras avanza a trompicones en el Senado,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1452300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1452300"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1452300\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1452300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1452300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1452300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}