{"id":1456635,"date":"2024-12-15T17:03:42","date_gmt":"2024-12-16T01:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/"},"modified":"2024-12-15T17:03:42","modified_gmt":"2024-12-16T01:03:42","slug":"harris-futuro-candidata-gobernadora-california-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/","title":{"rendered":"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028"},"content":{"rendered":"<p>Los principales asesores y personas cercanas a <a href=\"https:\/\/www.cnn.com\/2024\/11\/06\/politics\/harris-concedes-election\/index.html\">Kamala Harris<\/a> est\u00e1n divididos sobre si deber\u00eda regresar a casa para postularse a la gobernaci\u00f3n de California en 2026, y todo se reduce a si creen que podr\u00eda ganar la designaci\u00f3n dem\u00f3crata para presidente en una primaria competitiva esperada en 2028.<\/p>\n<p>Algunos creen que una nueva candidatura, despu\u00e9s de mejorar r\u00e1pidamente su reputaci\u00f3n y recaudar m\u00e1s de US$ 1.000 millones en su sorprendente campa\u00f1a de 100 d\u00edas, deber\u00eda ser suya. A otros les preocupa que en una campa\u00f1a m\u00e1s larga, contra algunos de los otros principales contendientes dem\u00f3cratas que ya se abstuvieron de participar en 2024 en deferencia primero a <a href=\"https:\/\/www.cnn.com\/politics\/joe-biden\">Joe Biden<\/a> y luego a ella, Harris pueda fracasar y, tras su derrota ante Donald Trump, sufrir la humillaci\u00f3n de ser rechazada por su propio partido.<\/p>\n<p>Mientras tanto, la carrera para gobernadora parece servida en bandeja de plata: Harris fue elegida a nivel estatal tres veces y sirvi\u00f3 10 a\u00f1os combinados como fiscal general estatal y senadora de EE.UU., y cuando CNN les pregunt\u00f3, varios candidatos importantes dejaron en claro, ya sea directamente o a trav\u00e9s de asistentes, que probablemente se har\u00edan a un lado si ella fuera por el cargo.<\/p>\n<p>En la conversaci\u00f3n de CNN con m\u00e1s de una docena de asesores actuales y anteriores de Harris y otros actores dem\u00f3cratas importantes de California, el \u00fanico consenso en torno a la vicepresidenta es que probablemente no pueda hacer ambas cosas, ya que eso requerir\u00eda esencialmente lanzar una campa\u00f1a presidencial poco despu\u00e9s de ser juramentada como gobernadora.<\/p>\n<p>Los principales asesores de Harris creen que para entrar en la carrera por la gobernaci\u00f3n ser\u00eda necesario dejar claras sus intenciones a m\u00e1s tardar en el verano de 2025. Eso significa que Harris tendr\u00e1 que decidir muy pronto despu\u00e9s de la investidura de Trump si renunciar\u00e1 r\u00e1pidamente a su sue\u00f1o de ser presidenta (que, en su opini\u00f3n, se vio defraudada por las circunstancias de este a\u00f1o) y, en cambio, optar\u00e1 por un puesto que, aunque es uno de los m\u00e1s poderosos en la pol\u00edtica estadounidense, claramente ser\u00eda un remanente.<\/p>\n<p>\u201cSi est\u00e1s pensando en postularte a la presidencia en 2028, lo peor que puedes hacer es postularte a gobernadora en 2026\u201d, dijo una persona que la ha asesorado en el pasado.<\/p>\n<p>Otra persona cercana a Harris le dijo a CNN que la apuesta de saltarse la carrera para gobernador vale la pena por los posibles beneficios.<\/p>\n<p>\u201cPostularse a gobernadora ser\u00eda un paso atr\u00e1s e interferir\u00eda con su capacidad de postularse nuevamente a la presidencia\u201d, dijo la fuente. \u201cNo s\u00e9 si volver\u00e1 a postularse a la presidencia, pero la posibilidad de postularse nuevamente a la presidencia hace que valga la pena renunciar a postularse a gobernadora\u201d.<\/p>\n<p>Varias personas que han hablado directamente con la vicepresidenta dijeron a CNN que ella misma sigue indecisa, sin saber c\u00f3mo canalizar los sentimientos que, por ahora, ha plasmado en frases como \u201cno han visto lo \u00faltimo de m\u00ed\u201d y \u201cno me voy a ir en silencio a la noche\u201d, repetidas a sus simpatizantes que le preguntan qu\u00e9 sigue.<\/p>\n<p>M\u00e1s de una persona ha notado que ella no ha interrumpido la conversaci\u00f3n cuando ha surgido el tema de postularse para gobernador.<\/p>\n<p>Mientras tanto, Harris ha mantenido un perfil notablemente bajo, apareciendo en solo un pu\u00f1ado de eventos p\u00fablicos desde su discurso de concesi\u00f3n, mientras que sus llamadas telef\u00f3nicas de agradecimiento con donantes y otros partidarios a menudo han sido largas, con l\u00e1grimas en ambos extremos, seg\u00fan personas familiarizadas con las llamadas. Recibi\u00f3 a muchos miembros de su oficina y de su campa\u00f1a para una fiesta navide\u00f1a en el Observatorio Naval el mi\u00e9rcoles pasado, y a un grupo m\u00e1s peque\u00f1o de amigos cercanos y partidarios para una cena de gala all\u00ed el viernes por la noche.<\/p>\n<p>El martes, Harris pronunciar\u00e1 un discurso en los suburbios de Washington, ante estudiantes de secundaria y universitarios, as\u00ed como ante reci\u00e9n graduados y aprendices. Un funcionario de la Casa Blanca dijo en el anuncio que ser\u00e1 \u201cuna continuaci\u00f3n\u201d de su \u201cliderazgo m\u00e1s amplio y enofcado en el futuro\u201d, pero esas declaraciones ser\u00e1n un mensaje m\u00e1s generalizado sobre su compromiso que cualquier pista sobre sus propios planes, seg\u00fan varias personas que han visto los borradores.<\/p>\n<p>Harris y aquellos que est\u00e1n m\u00e1s comprometidos con ella no quieren que Trump haya escrito su final pol\u00edtico y que su \u00faltimo acto oficial importante sea presidir la certificaci\u00f3n de la victoria en el Colegio Electoral en el cuarto aniversario del disturbio en el Capitolio de Estados Unidos para intentar detener la certificaci\u00f3n de Biden y la de ella misma.<\/p>\n<p>Algunas personas se\u00f1alan que tambi\u00e9n existe la opci\u00f3n C: terminar con la pol\u00edtica, firmar un contrato para publicar un libro y dirigir alg\u00fan tipo de organizaci\u00f3n que le permita seguir involucrada sin tener que volver a estar en campa\u00f1a.<\/p>\n<p>Pero cuando en las semanas posteriores a las elecciones surgieron dudas sobre la posibilidad de que la campa\u00f1a presidencial de Harris quedara endeudada, una opci\u00f3n que descartaron definitivamente sus allegados fue vender la lista de correos electr\u00f3nicos y contactos recopilada por la campa\u00f1a (actualmente, la lista m\u00e1s valiosa en la pol\u00edtica dem\u00f3crata). La necesitar\u00eda si decide qu\u00e9 campa\u00f1a sigue, dijeron. Y es parte de la raz\u00f3n por la que esas mismas personas est\u00e1n frustradas porque la campa\u00f1a sigue enviando correos electr\u00f3nicos para recaudar fondos, y les preocupa que esto est\u00e9 llevando a donantes y partidarios a quienes eventualmente tendr\u00e1 que cancelar su suscripci\u00f3n o a quienes se enfadar\u00e1n con ella.<\/p>\n<p>La \u00fanica persona que gan\u00f3 la Casa Blanca en un segundo intento como candidato del partido fue Richard Nixon, otro senador de California que se convirti\u00f3 en vicepresidente y que primero intent\u00f3 reducir su poder con una candidatura a gobernador (y perdi\u00f3), un paralelo hist\u00f3rico que ha estado en la mente de las personas en los niveles m\u00e1s altos de la pol\u00edtica de California.<\/p>\n<p>Por otra parte, Trump es el \u00fanico otro presidente que ha regresado al cargo despu\u00e9s de una derrota desde Grover Cleveland hace m\u00e1s de 100 a\u00f1os.<\/p>\n<p>Para una nueva candidatura presidencial, Harris tendr\u00eda que esperar que se produzca el tipo de remordimiento por haber votado a Trump que ahora solo existe en las fantas\u00edas dem\u00f3cratas y, si se produce, que no se transforme en resentimiento hacia ella por haber perdido la campa\u00f1a que hizo posible su regreso. Y tendr\u00eda que convencer a una amplia gama de l\u00edderes del partido que dejaron de lado temporalmente su escepticismo sobre ella despu\u00e9s de que Biden se retir\u00f3, pero que ahora se muestran fr\u00edos en privado ante la idea de otra candidatura.<\/p>\n<p>Por supuesto, ser gobernadora de California es un trabajo que conlleva mucho poder y prominencia, debido a que se encarga de dirigir la quinta econom\u00eda m\u00e1s grande del mundo y el laboratorio de larga data de Estados Unidos para la pol\u00edtica capitalista progresista. Fue suficiente para sacar a Arnold Schwarzenegger de las pel\u00edculas y convertir a Ronald Reagan y Jerry Brown en candidatos presidenciales.<\/p>\n<p>Varios asesores se\u00f1alaron que ser gobernadora podr\u00eda darle a Harris tiempo para construir un historial m\u00e1s s\u00f3lido con la esperanza de presentarse no en 2028, sino en 2032 o 2036, y qui\u00e9n sabe qu\u00e9 podr\u00eda pasar en el pa\u00eds o en la pol\u00edtica en el medio. Tambi\u00e9n reconocen que podr\u00eda ser un retroceso de una d\u00e9cada.<\/p>\n<p>Adem\u00e1s, est\u00e1 el factor Gavin Newsom. Los dos llevan mucho tiempo compitiendo en la pol\u00edtica de California y, en 2016, ella se adelant\u00f3 a Newsom, entonces vicegobernador del estado, al lanzarse a una carrera abierta por el Senado, tomando la decisi\u00f3n de cu\u00e1l de las estrellas en ascenso optar\u00eda por la primera gran vacante estatal que ambos hab\u00edan esperado. Newsom, a su vez, se postul\u00f3 para gobernador en 2018 y, desde entonces, ha derrotado un intento de destituci\u00f3n y ha ganado la reelecci\u00f3n.<\/p>\n<p>Presentarse como candidato a gobernadora ahora significar\u00eda optar a un trabajo que Newsom ya no quiere hacer y probablemente mientras lo ve hacer su propia campa\u00f1a esperada para presidente.<\/p>\n<p>Esa tarde y noche de julio, despu\u00e9s de que Biden se retirara, mientras Harris hac\u00eda llamadas desde el Observatorio Naval para conseguir apoyos, varios otros candidatos potenciales se consultaban entre s\u00ed: \u00bfrealmente iban a alinearse todos? \u00bfHab\u00eda margen para lanzar una campa\u00f1a, aunque solo fuera por el bien de una pelea por la designaci\u00f3n, si no por la remota esperanza de superarla? Esperaron sus apoyos durante unas horas, algunos hasta la ma\u00f1ana siguiente, debido a que decidieron que no pod\u00edan desafiar a Harris de manera cre\u00edble, seg\u00fan personas familiarizadas con algunas de las conversaciones.<\/p>\n<p>No tendr\u00edan la misma deferencia si Harris se postulara nuevamente en 2028, se\u00f1alan personas que trabajan con varios de los posibles candidatos.<\/p>\n<p>A varios asesores de Harris les preocupa que la intensa competencia podr\u00eda no ser su \u00fanico problema.<\/p>\n<p>Incluso cuando atribuyen gran parte de la culpa de su derrota a Biden y a factores econ\u00f3micos que est\u00e1n fuera de su control, observan su peor desempe\u00f1o de lo esperado entre los votantes m\u00e1s j\u00f3venes y negros y ven un motivo de gran preocupaci\u00f3n. Otros dicen que el hecho de que haya empoderado al peque\u00f1o grupo de asesores de alto rango que han sido criticados interna y externamente por la forma en que la guiaron durante el oto\u00f1o demuestra una mala toma de decisiones que crear\u00eda a\u00fan m\u00e1s problemas en una campa\u00f1a presidencial que dura un par de a\u00f1os en lugar de un par de meses.<\/p>\n<p>Pero varios asesores argumentaron que todas las quejas y luchas internas s\u00f3lo importan un poco en comparaci\u00f3n con el apoyo y las conexiones que Harris construy\u00f3 r\u00e1pidamente en todo el pa\u00eds.<\/p>\n<p>\u201cNormalmente los dem\u00f3cratas destierran a sus candidatos derrotados, pero ella en realidad tendr\u00eda una gran oportunidad de volver a la carga debido a lo bien que se desempe\u00f1\u00f3 en comparaci\u00f3n con la calificaci\u00f3n que le dieron sus esc\u00e9pticos antes de julio\u201d, dijo un ex asesor principal. \u201cTermin\u00f3 la carrera con mucha m\u00e1s popularidad de la que ten\u00eda al principio\u201d.<\/p>\n<p>Harris sin duda recibir\u00eda m\u00e1s deferencia en una campa\u00f1a para gobernador, aunque algunos involucrados en la contienda ya se\u00f1alan en privado que, en 2010, apenas gan\u00f3 su primera contienda para fiscal general y que las encuestas estatales m\u00e1s recientes no le han dado buenos resultados, como se\u00f1ales de que podr\u00eda ser m\u00e1s d\u00e9bil de lo que se supon\u00eda. Algunos relacionados con otros candidatos a gobernador ya usan las palabras \u201cpremio de consolaci\u00f3n\u201d para tratar de desestimar su posible candidatura, argumentando que as\u00ed es como lo ver\u00edan los votantes de California.<\/p>\n<p>Las personas cercanas a Harris que quieren que se postule para gobernadora dicen que, si llega all\u00ed, esa es exactamente la raz\u00f3n por la que necesitar\u00eda articular una justificaci\u00f3n clara para participar en la carrera que est\u00e9 conectada con las propuestas de su campa\u00f1a presidencial y que no sea simplemente anti-Trump.<\/p>\n<p>La representante saliente Katie Porter, que perdi\u00f3 una candidatura al Senado este a\u00f1o y ha estado enviando una encuesta que la muestra al frente del campo de candidatos a gobernador, predijo en un panel en la Universidad de California, Irvine a principios de diciembre que la entrada de Harris tendr\u00eda un \u201cefecto casi de limpieza del campo\u201d, y la vicegobernadora de California Eleni Kounalakis, que ya ha lanzado su campa\u00f1a para gobernadora, lo insinu\u00f3 en una entrevista con CNN.<\/p>\n<p>\u201cSoy amiga y partidaria de la vicepresidenta desde hace mucho tiempo. Si ella decidiera postularse para gobernadora, estoy segura de que primero tendr\u00edamos una conversaci\u00f3n\u201d, dijo Kounalakis.<\/p>\n<p>Los expertos pol\u00edticos de California comenzaron a especular sobre un efecto domin\u00f3 a partir de la entrada de Harris, pregunt\u00e1ndose qu\u00e9 candidato podr\u00eda cambiar de carrera a nivel estatal para dejarle paso a ella.<\/p>\n<p>Una persona cercana a Antonio Villaraigosa destac\u00f3 la fortaleza del exalcalde de Los \u00c1ngeles en las primeras encuestas y la recaudaci\u00f3n de fondos, y dijo que si bien tiene un tremendo respeto por Harris y su trayectoria, su enfoque est\u00e1 en la carrera y no en posibles candidatos futuros.<\/p>\n<p>La campa\u00f1a de la expresidenta de la Asamblea de California Toni Atkins no respondi\u00f3 a una solicitud de comentarios.<\/p>\n<p>Luego est\u00e1 Rick Caruso, el desarrollador multimillonario que se convirti\u00f3 en dem\u00f3crata para postularse, pero perdi\u00f3, a la alcald\u00eda de Los \u00c1ngeles en 2022 y que podr\u00eda aprovechar el sistema de \u201clos dos primeros\u201d de California, en lugar de las primarias partidarias, para autofinanciar una campa\u00f1a de un a\u00f1o contra Harris desde el centro.<\/p>\n<p>Pero tambi\u00e9n existe una disposici\u00f3n entre algunos dem\u00f3cratas de California a regresar a casa.<\/p>\n<p>\u201cKamala Harris tiene un profundo respeto y afecto en California y una importante experiencia a nivel estatal para solucionar los problemas de California con los altos alquileres y los costos de la vivienda, la falta de vivienda y la delincuencia\u201d, dijo el representante de California Ro Khanna, un esc\u00e9ptico a veces de Harris que est\u00e1 considerando postularse a la presidencia en 2028. \u201cElla ser\u00eda formidable, si decide presentarse\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los principales asesores y personas cercanas a Kamala Harris est\u00e1n divididos sobre si deber\u00eda regresar a casa para postularse a la gobernaci\u00f3n de California en 2026, y todo se reduce a si creen que podr\u00eda ganar la designaci\u00f3n dem\u00f3crata para presidente en una primaria competitiva esperada en 2028. Algunos creen que una nueva candidatura, despu\u00e9s [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456635","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028 - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los principales asesores y personas cercanas a Kamala Harris est\u00e1n divididos sobre si deber\u00eda regresar a casa para postularse a la gobernaci\u00f3n de California en 2026, y todo se reduce a si creen que podr\u00eda ganar la designaci\u00f3n dem\u00f3crata para presidente en una primaria competitiva esperada en 2028. Algunos creen que una nueva candidatura, despu\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T01:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028\",\"datePublished\":\"2024-12-16T01:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/\"},\"wordCount\":2346,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/\",\"name\":\"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-16T01:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028 - Noticias","og_description":"Los principales asesores y personas cercanas a Kamala Harris est\u00e1n divididos sobre si deber\u00eda regresar a casa para postularse a la gobernaci\u00f3n de California en 2026, y todo se reduce a si creen que podr\u00eda ganar la designaci\u00f3n dem\u00f3crata para presidente en una primaria competitiva esperada en 2028. Algunos creen que una nueva candidatura, despu\u00e9s [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-16T01:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/"},"author":{"name":"","@id":""},"headline":"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028","datePublished":"2024-12-16T01:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/"},"wordCount":2346,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/","name":"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-16T01:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Harris eval\u00faa postularse a gobernadora de California, lo que excluir\u00eda su candidatura presidencial en 2028","url":"http:\/\/noticiasya.com\/boston\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/12\/15\/harris-futuro-candidata-gobernadora-california-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-16T01:03:42Z","datePublished":"2024-12-16T01:03:42Z","dateModified":"2024-12-16T01:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Harris eval\\u00faa postularse a gobernadora de California, lo que excluir\\u00eda su candidatura presidencial en 2028\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/15\\\/harris-futuro-candidata-gobernadora-california-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/15\\\/harris-futuro-candidata-gobernadora-california-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-16T01:03:42Z\",\"datePublished\":\"2024-12-16T01:03:42Z\",\"dateModified\":\"2024-12-16T01:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465020,"url":"https:\/\/noticiasya.com\/boston\/2025\/07\/31\/kamala-harris-gobernadora-california-2026-trax\/","url_meta":{"origin":1456635,"position":0},"title":"Kamala Harris no se postular\u00e1 para gobernadora de California en 2026","author":"","date":"julio 31, 2025","format":false,"excerpt":"La exvicepresidenta Kamala Harris anunci\u00f3 el mi\u00e9rcoles que no se postular\u00e1 para gobernadora de California en 2026, lo que pone fin a las preguntas sobre su inter\u00e9s en el cargo, pero genera nuevas dudas sobre los planes futuros de la designada dem\u00f3crata a la presidencia en 2024.\u201cPor ahora, mi liderazgo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471547,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/22\/gavin-newsom-kamala-harris-candidatura-2028-trax\/","url_meta":{"origin":1456635,"position":1},"title":"\u00bfNewsom vs. Harris en 2028? El gobernador de California habla al respecto y revela por qu\u00e9 su hijo se opone","author":"","date":"febrero 22, 2026","format":false,"excerpt":"El gobernador de California, Gavin Newsom, quien inicia una gira de libros que muchos ven como preludio a una candidatura presidencial, habl\u00f3 con CNN sobre la posibilidad de competir contra la exvicepresidenta Kamala Harris, otra figura de larga trayectoria en la pol\u00edtica californiana.\u201c\u00bfQu\u00e9 pasa si y cuando esas carreras paralelas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450928,"url":"https:\/\/noticiasya.com\/boston\/2024\/07\/06\/harris-se-centra-en-vencer-a-trump-no-en-preocupaciones-sobre-biden-trax\/","url_meta":{"origin":1456635,"position":2},"title":"Harris se centra en vencer a Trump, no en las preocupaciones sobre Biden, en su intento de atraer a los votantes negros","author":"","date":"julio 6, 2024","format":false,"excerpt":"(CNN) -- La vicepresidenta Kamala Harris puso el foco este s\u00e1bado en los peligros de un segundo gobierno de Trump, en lugar de las crecientes preocupaciones sobre la candidatura del presidente Joe Biden, mientras intentaba convencer a los votantes negros para dar una vez m\u00e1s una victoria al boleto Biden-Harris.\"Esta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450902,"url":"https:\/\/noticiasya.com\/boston\/2024\/07\/05\/opinion-kamala-harris-gretchen-whitmer-candidatura-ganadora-trax\/","url_meta":{"origin":1456635,"position":3},"title":"OPINI\u00d3N | Kamala Harris y Gretchen Whitmer podr\u00edan formar una candidatura ganadora para los dem\u00f3cratas","author":"","date":"julio 5, 2024","format":false,"excerpt":"Nota del editor: Julian Zelizer, analista pol\u00edtico de CNN, es profesor de Historia y Asuntos P\u00fablicos en la Universidad de Princeton. Es autor y editor de 25 libros, entre ellos el de pr\u00f3xima aparici\u00f3n, \"Our Nation at Risk: Election Integrity as a National Security Issue\". S\u00edguelo en Twitter @julianzelizer. Las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451508,"url":"https:\/\/noticiasya.com\/boston\/2024\/07\/30\/harris-anuncio-eleccion-vicepresidencia-aspirantes-principales-trax\/","url_meta":{"origin":1456635,"position":4},"title":"Harris se acerca al anuncio de su elecci\u00f3n para la vicepresidencia mientras su equipo eval\u00faa a los aspirantes principales","author":"","date":"julio 30, 2024","format":false,"excerpt":"(CNN) --\u00a0Kamala Harris se encuentra en pleno proceso de elecci\u00f3n de su compa\u00f1ero de f\u00f3rmula para la vicepresidencia, y su campa\u00f1a prev\u00e9 un anuncio en los pr\u00f3ximos d\u00edas al que seguir\u00eda inmediatamente una gira conjunta por una serie de estados disputados.Harris, lanzada abruptamente al papel de candidata presidencial hace menos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473039,"url":"https:\/\/noticiasya.com\/boston\/2026\/04\/10\/kamala-harris-presidencia-2028-trax\/","url_meta":{"origin":1456635,"position":5},"title":"Kamala Harris explica por qu\u00e9 eval\u00faa postularse a la presidencia en 2028: &#171;S\u00e9 lo que hace falta&#187;","author":"","date":"abril 10, 2026","format":false,"excerpt":"La exvicepresidenta de Estados Unidos Kamala Harris dijo este viernes que \u201cpodr\u00eda\u201d postularse a la presidencia en 2028 y a\u00f1adi\u00f3, durante la Convenci\u00f3n 2026 de la National Action Network, que lo est\u00e1 \u201cconsiderando\u201d.\u201cEscuchen, podr\u00eda, podr\u00eda. Lo estoy pensando. Lo estoy pensando\u201d, dijo Harris al reverendo Al Sharpton cuando le pregunt\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1456635"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456635\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1456635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1456635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1456635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}