{"id":1456636,"date":"2024-12-15T18:03:44","date_gmt":"2024-12-16T02:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/"},"modified":"2024-12-15T18:03:44","modified_gmt":"2024-12-16T02:03:44","slug":"medicos-dan-alta-lula-da-silva-cirugia-brasil-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/","title":{"rendered":"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda"},"content":{"rendered":"<p>El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, fue dado de alta m\u00e9dica este domingo del hospital de Sao Paulo donde se recuperaba tras haber sido <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/12\/latinoamerica\/lula-da-silva-recupera-cirugia-orix\">operado por un derrame cerebral<\/a>.<\/p>\n<p>En su cuenta de la red social X, el presidente public\u00f3 un fragmento en video de la conferencia de prensa que sus m\u00e9dicos ofrecieron la ma\u00f1ana de este domingo a la que \u00e9l sorprendi\u00f3 a los doctores y a la prensa para integrarse y dar un breve discurso de agradecimiento.<\/p>\n<p>Lula da Silva confes\u00f3 que se sinti\u00f3 asustado por el creciente volumen de l\u00edquido en su cabeza, del cual fue operado el pasado lunes 9 de diciembre.<\/p>\n<p>El l\u00edder de izquierda tambi\u00e9n relat\u00f3 c\u00f3mo fue el accidente que deriv\u00f3 en esta cirug\u00eda: dijo que tras cortarse las u\u00f1as de las manos se cay\u00f3 de un banco y se golpe\u00f3 la cabeza con la tina de hidromasaje del ba\u00f1o del Palacio de la Alvorada en Brasilia el 19 de octubre.<\/p>\n<p>Seg\u00fan el equipo m\u00e9dico del presidente, Lula da Silva ser\u00e1 monitoreado hasta el pr\u00f3ximo jueves y, si los ex\u00e1menes m\u00e9dicos lo avalan, podr\u00e1 continuar con sus actividades en Brasilia tales como reuniones y diligencias internas pero sin realizar viajes internacionales o hacer ejercicios f\u00edsicos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, fue dado de alta m\u00e9dica este domingo del hospital de Sao Paulo donde se recuperaba tras haber sido operado por un derrame cerebral. En su cuenta de la red social X, el presidente public\u00f3 un fragmento en video de la conferencia de prensa que sus m\u00e9dicos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456636","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, fue dado de alta m\u00e9dica este domingo del hospital de Sao Paulo donde se recuperaba tras haber sido operado por un derrame cerebral. En su cuenta de la red social X, el presidente public\u00f3 un fragmento en video de la conferencia de prensa que sus m\u00e9dicos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T02:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda\",\"datePublished\":\"2024-12-16T02:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/\"},\"wordCount\":252,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/\",\"name\":\"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-16T02:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda - Noticias","og_description":"El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, fue dado de alta m\u00e9dica este domingo del hospital de Sao Paulo donde se recuperaba tras haber sido operado por un derrame cerebral. En su cuenta de la red social X, el presidente public\u00f3 un fragmento en video de la conferencia de prensa que sus m\u00e9dicos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-16T02:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/"},"author":{"name":"","@id":""},"headline":"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda","datePublished":"2024-12-16T02:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/"},"wordCount":252,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/","name":"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-16T02:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\u00eda","url":"http:\/\/noticiasya.com\/boston\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/12\/15\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-16T02:03:44Z","datePublished":"2024-12-16T02:03:44Z","dateModified":"2024-12-16T02:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e9dicos dan de alta al presidente de Brasil Lula da Silva tras su cirug\\u00eda\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/15\\\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/15\\\/medicos-dan-alta-lula-da-silva-cirugia-brasil-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-16T02:03:44Z\",\"datePublished\":\"2024-12-16T02:03:44Z\",\"dateModified\":\"2024-12-16T02:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456502,"url":"https:\/\/noticiasya.com\/boston\/2024\/12\/11\/lula-procedimiento-medico-cirugia-hemorragia-trax\/","url_meta":{"origin":1456636,"position":0},"title":"Lula se someter\u00e1 a un procedimiento m\u00e9dico adicional tras cirug\u00eda de emergencia por hemorragia cerebral","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Se espera que el presidente de Brasil, Luiz In\u00e1cio Lula da Silva, se someta a un procedimiento m\u00e9dico adicional el jueves como parte de su tratamiento luego de la cirug\u00eda de emergencia que tuvo el martes para drenar una hemorragia en su cerebro.Los m\u00e9dicos del Hospital S\u00edrio-Liban\u00e9s de Sao Paulo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456518,"url":"https:\/\/noticiasya.com\/boston\/2024\/12\/12\/lula-da-silva-recupera-cirugia-orix\/","url_meta":{"origin":1456636,"position":1},"title":"Lula se recupera de una segunda cirug\u00eda &#171;exitosa&#187;, informa m\u00e9dico","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, se recupera con \u00e9xito de un procedimiento m\u00e9dico adicional que le realizaron este jueves como parte de su tratamiento tras la cirug\u00eda de emergencia a la que se someti\u00f3 el martes para drenar una hemorragia cerebral, inform\u00f3 el doctor Roberto Kalil\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469715,"url":"https:\/\/noticiasya.com\/boston\/2026\/01\/01\/bolsonaro-alta-medica-prision-hospitalizado-efe\/","url_meta":{"origin":1456636,"position":2},"title":"Bolsonaro recibe alta m\u00e9dica y vuelve a prisi\u00f3n tras ocho d\u00edas hospitalizado","author":"","date":"enero 1, 2026","format":false,"excerpt":"El expresidente brasile\u00f1o Jair Bolsonaro fue recluido este jueves nuevamente en la celda de la Polic\u00eda Federal en la que cumple su condena de 27 a\u00f1os de prisi\u00f3n por golpismo, tras recibir el alta m\u00e9dica luego de haber sido sometido a cuatro operaciones en los ocho d\u00edas en que estuvo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456647,"url":"https:\/\/noticiasya.com\/boston\/2024\/12\/16\/5-cosas-16-diciembre-altos-golan-orix\/","url_meta":{"origin":1456636,"position":3},"title":"Las 5 cosas que debes saber este 16 de diciembre: Altos del Gol\u00e1n, drones, Kamala Harris, TikTok","author":"","date":"diciembre 16, 2024","format":false,"excerpt":"Muere otro fotoperiodista en Gaza tras un ataque de Israel. El mapa pol\u00edtico de Am\u00e9rica Latina. Drones misteriosos en EE.UU. TikTok se enfrenta a la prohibici\u00f3n en EE.UU. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469696,"url":"https:\/\/noticiasya.com\/boston\/2025\/12\/31\/alta-medica-bolsonaro-cuatro-operaciones-efe\/","url_meta":{"origin":1456636,"position":4},"title":"Bolsonaro recibir\u00e1 el alta m\u00e9dica el jueves tras cuatro operaciones, dicen sus m\u00e9dicos","author":"","date":"diciembre 31, 2025","format":false,"excerpt":"El expresidente de Brasil Jair Bolsonaro, que cumple una condena de 27 a\u00f1os de prisi\u00f3n por golpismo, recibir\u00e1 el alta m\u00e9dica el jueves, tras ocho d\u00edas hospitalizado y en los que fue sometido a cuatro diferentes operaciones, anunci\u00f3 este mi\u00e9rcoles el equipo de doctores que lo atiende.\u201cHicimos nuevos ex\u00e1menes para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464623,"url":"https:\/\/noticiasya.com\/boston\/2025\/07\/17\/lula-da-silva-brasil-trump-no-es-emperador-del-mundo-trax\/","url_meta":{"origin":1456636,"position":5},"title":"Lula da Silva afirma que Trump &#171;no fue elegido para ser el emperador del mundo&#187; y aumenta la disputa entre EE.UU. y Brasil","author":"","date":"julio 17, 2025","format":false,"excerpt":"El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, respondi\u00f3 a las amenazas arancelarias de Donald Trump y dijo que su hom\u00f3logo estadounidense fue elegido como l\u00edder de Estados Unidos y \u201cno para ser el emperador del mundo\u201d.La semana pasada, Trump amenaz\u00f3 a Brasil con aranceles catastr\u00f3ficos del 50 %\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1456636"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456636\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1456636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1456636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1456636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}