{"id":1456659,"date":"2024-12-16T11:03:43","date_gmt":"2024-12-16T19:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/"},"modified":"2024-12-16T11:03:43","modified_gmt":"2024-12-16T19:03:43","slug":"venezuela-excarcelo-protestas-poselectorales-foro-penal-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/","title":{"rendered":"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155"},"content":{"rendered":"<p>El Ministerio P\u00fablico de <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/16\/latinoamerica\/gobiernos-condenan-asedio-embajada-argentina-caracas-orix\">Venezuela<\/a> inform\u00f3 este lunes la excarcelaci\u00f3n de otras 179 personas detenidas tras las protestas desatadas por el resultado las controvertidas elecciones presidenciales que se suman, seg\u00fan sus registros, a otras 354 anunciadas con anterioridad, lo que da un total de 533 personas relacionadas con estos episodios que han salido de prisi\u00f3n, de acuerdo con un comunicado.<\/p>\n<p>La cifra anunciada este lunes es mayor a la que por ahora tiene documentada la organizaci\u00f3n no gubernamental Foro Penal, que a\u00fan no ha reaccionado al anuncio hecho por la Fiscal\u00eda General de la Rep\u00fablica del pa\u00eds sudamericano.<\/p>\n<p>Hasta el 14 de diciembre, su presidente, Alfredo Romero, inform\u00f3 que hab\u00edan ocurrido solo 48 excarcelaciones desde el 10 de diciembre, de las cuales 42 correspond\u00edan a menores de edad, un c\u00e1lculo que se suma a las 107 que hab\u00edan confirmado hasta el 16 de noviembre, para un total de 155.<\/p>\n<p>CNN consult\u00f3 a la Fiscal\u00eda sobre la diferencia en las cifras y est\u00e1 a la espera de una respuesta.<\/p>\n<p>Hasta el 2 de diciembre, Foro Penal contabilizaba 1.905 arrestos relacionados con los disturbios que se presentaron tras el pol\u00e9mico anuncio del Consejo Nacional Electoral, controlado por el oficialismo, que dio la victoria al presidente Nicol\u00e1s Maduro sin presentar resultados detallados por centro y mesa de votaci\u00f3n. Los resultados fueron refrendados por el Tribunal Supremo de Justicia, que tambi\u00e9n controla el chavismo.<\/p>\n<p>Las excarcelaciones se producen luego de que a mediados de noviembre el presidente Nicol\u00e1s Maduro pidiera en su programa semanal de televisi\u00f3n que se revisara la situaci\u00f3n de las personas detenidas para \u201crectificar y revisar tambi\u00e9n que haya justicia\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio P\u00fablico de Venezuela inform\u00f3 este lunes la excarcelaci\u00f3n de otras 179 personas detenidas tras las protestas desatadas por el resultado las controvertidas elecciones presidenciales que se suman, seg\u00fan sus registros, a otras 354 anunciadas con anterioridad, lo que da un total de 533 personas relacionadas con estos episodios que han salido de prisi\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456659","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155 - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Ministerio P\u00fablico de Venezuela inform\u00f3 este lunes la excarcelaci\u00f3n de otras 179 personas detenidas tras las protestas desatadas por el resultado las controvertidas elecciones presidenciales que se suman, seg\u00fan sus registros, a otras 354 anunciadas con anterioridad, lo que da un total de 533 personas relacionadas con estos episodios que han salido de prisi\u00f3n, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T19:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155\",\"datePublished\":\"2024-12-16T19:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/\",\"name\":\"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-16T19:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155 - Noticias","og_description":"El Ministerio P\u00fablico de Venezuela inform\u00f3 este lunes la excarcelaci\u00f3n de otras 179 personas detenidas tras las protestas desatadas por el resultado las controvertidas elecciones presidenciales que se suman, seg\u00fan sus registros, a otras 354 anunciadas con anterioridad, lo que da un total de 533 personas relacionadas con estos episodios que han salido de prisi\u00f3n, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-16T19:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/"},"author":{"name":"","@id":""},"headline":"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155","datePublished":"2024-12-16T19:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/","name":"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-16T19:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fiscal\u00eda de Venezuela dice que excarcel\u00f3 a m\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\u00f3 155","url":"http:\/\/noticiasya.com\/boston\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/12\/16\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-16T19:03:43Z","datePublished":"2024-12-16T19:03:43Z","dateModified":"2024-12-16T19:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fiscal\\u00eda de Venezuela dice que excarcel\\u00f3 a m\\u00e1s de 500 personas tras protestas poselectorales; Foro Penal solo registr\\u00f3 155\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/16\\\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/16\\\/venezuela-excarcelo-protestas-poselectorales-foro-penal-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-16T19:03:43Z\",\"datePublished\":\"2024-12-16T19:03:43Z\",\"dateModified\":\"2024-12-16T19:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456810,"url":"https:\/\/noticiasya.com\/boston\/2024\/12\/20\/fiscalia-venezuela-dice-733-excarcelaciones-protestas-orix\/","url_meta":{"origin":1456659,"position":0},"title":"Fiscal\u00eda de Venezuela dice que suman 733 excarcelaciones tras protestas poselectorales; Foro Penal registra solo 155","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"La Fiscal\u00eda General de Venezuela dijo este viernes que excarcel\u00f3 a otras 200 personas que fueron detenidas durante las protestas ocurridas despu\u00e9s de las controvertidas elecciones presidenciales del 28 de julio, con lo cual, seg\u00fan la instituci\u00f3n, suman 733 excarcelaciones.En un comunicado, la Fiscal\u00eda dijo que continuar\u00e1 con la revisi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456896,"url":"https:\/\/noticiasya.com\/boston\/2024\/12\/23\/fiscalia-venezuela-excarcelado-910-protestas-poselectorales-foro-penal-orix\/","url_meta":{"origin":1456659,"position":1},"title":"Fiscal\u00eda de Venezuela asegura que ha excarcelado a 910 personas tras protestas poselectorales; Foro Penal registra solo 155","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"El Ministerio P\u00fablico de Venezuela orden\u00f3 la excarcelaci\u00f3n de 177 personas detenidas en las protestas posteriores a las pol\u00e9micas elecciones presidenciales de ese pa\u00eds luego de un proceso de revisi\u00f3n de sus casos judiciales, de acuerdo con un comunicado firmado por el fiscal general, Tarek William Saab.Con esas adiciones van\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459430,"url":"https:\/\/noticiasya.com\/boston\/2025\/03\/03\/venezuela-liberacion-110-manifestantes-detenidos-durante-protestas-electorales-orix\/","url_meta":{"origin":1456659,"position":2},"title":"Fiscal de Venezuela informa la liberaci\u00f3n de 110 manifestantes detenidos durante las protestas electorales","author":"","date":"marzo 3, 2025","format":false,"excerpt":"El Ministerio P\u00fablico de Venezuela, en coordinaci\u00f3n con el Poder Judicial, determin\u00f3 que se liberen a 110 manifestantes que fueron detenidos durante las protestas electorales tras los comicios del 28 de julio, inform\u00f3 este lunes el fiscal general, Tarek William Saab, en un comunicado.En la nota de prensa difundida en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455863,"url":"https:\/\/noticiasya.com\/boston\/2024\/11\/15\/fiscalia-venezuela-225-casos-detenidos-protestas-orix\/","url_meta":{"origin":1456659,"position":3},"title":"La Fiscal\u00eda de Venezuela revisar\u00e1 225 casos de los detenidos en protestas poselectorales","author":"","date":"noviembre 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Ministerio P\u00fablico de Venezuela revisar\u00e1 las medidas impuestas a 225 personas detenidas durante las protestas posteriores a las controvertidas elecciones del 28 de julio, inform\u00f3 el fiscal general, Tarek William Saab, sin precisar qu\u00e9 medidas podr\u00edan cambiar.\"Esta acci\u00f3n, que tiene como centro la reunificaci\u00f3n familiar, consolida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456965,"url":"https:\/\/noticiasya.com\/boston\/2024\/12\/25\/excarcelan-adolescentes-protestas-poselectorales-orix\/","url_meta":{"origin":1456659,"position":4},"title":"Excarcelan a todos los adolescentes detenidos en las protestas poselectorales en Venezuela, dice ONG Foro Penal","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Todos los adolescentes que fueron detenidos durante las protestas registradas despu\u00e9s de las controvertidas elecciones presidenciales de Venezuela quedaron excarcelados en los \u00faltimos d\u00edas, dijo Alfredo Romero, director presidente de Foro Penal, organizaci\u00f3n no gubernamental de derechos humanos que ha dado seguimiento a estos casos.\u201cEso es una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456496,"url":"https:\/\/noticiasya.com\/boston\/2024\/12\/11\/liberan-14-detenidos-protestas-postelectorales-orix\/","url_meta":{"origin":1456659,"position":5},"title":"Liberan a 14 personas detenidas en las protestas poselectorales en Venezuela, seg\u00fan Foro Penal","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Al menos 14 detenidos durante la crisis poselectoral en Venezuela han salido de la c\u00e1rcel entre este martes y mi\u00e9rcoles, inform\u00f3 en redes sociales el director de la organizaci\u00f3n no gubernamental Foro Penal, Alfredo Romero.La ONG, que promueve la defensa de los derechos humanos y la asistencia a v\u00edctimas y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1456659"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456659\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1456659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1456659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1456659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}