{"id":1456669,"date":"2024-12-16T18:03:40","date_gmt":"2024-12-17T02:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/"},"modified":"2024-12-16T18:03:40","modified_gmt":"2024-12-17T02:03:40","slug":"deporta-mexico-osiel-cardenas-cartel-del-golfo-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/","title":{"rendered":"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo"},"content":{"rendered":"<p>Estados Unidos deport\u00f3 este lunes a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo, donde fue recluido en un penal de m\u00e1xima seguridad, le dijo a CNN una fuente del Gobierno de M\u00e9xico.<\/p>\n<p>Agreg\u00f3 que C\u00e1rdenas Guill\u00e9n lleg\u00f3 al pa\u00eds por el paso fronterizo Tijuana-San Diego.<\/p>\n<p>El hombre enfrenta en M\u00e9xico los cargos de delitos contra la salud, delincuencia organizada y operaciones con recursos de procedencia il\u00edcita.<\/p>\n<p>C\u00e1rdenas Guill\u00e9n fue detenido en 2003 luego de un enfrentamiento con militares en Matamoros, Tamaulipas, en su frontera con Texas. Autoridades de Estados Unidos lo acusaron desde el a\u00f1o 2000 de introducir ilegalmente a ese pa\u00eds drogas y de amenazar a agentes de la Administraci\u00f3n de Control de Drogas (DEA, por sus siglas en ingl\u00e9s) y de Aduanas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos deport\u00f3 este lunes a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo, donde fue recluido en un penal de m\u00e1xima seguridad, le dijo a CNN una fuente del Gobierno de M\u00e9xico. Agreg\u00f3 que C\u00e1rdenas Guill\u00e9n lleg\u00f3 al pa\u00eds por el paso fronterizo Tijuana-San Diego. El hombre enfrenta en M\u00e9xico los cargos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456669","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Estados Unidos deport\u00f3 este lunes a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo, donde fue recluido en un penal de m\u00e1xima seguridad, le dijo a CNN una fuente del Gobierno de M\u00e9xico. Agreg\u00f3 que C\u00e1rdenas Guill\u00e9n lleg\u00f3 al pa\u00eds por el paso fronterizo Tijuana-San Diego. El hombre enfrenta en M\u00e9xico los cargos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-17T02:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo\",\"datePublished\":\"2024-12-17T02:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/\"},\"wordCount\":178,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/\",\"name\":\"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-17T02:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo - Noticias","og_description":"Estados Unidos deport\u00f3 este lunes a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo, donde fue recluido en un penal de m\u00e1xima seguridad, le dijo a CNN una fuente del Gobierno de M\u00e9xico. Agreg\u00f3 que C\u00e1rdenas Guill\u00e9n lleg\u00f3 al pa\u00eds por el paso fronterizo Tijuana-San Diego. El hombre enfrenta en M\u00e9xico los cargos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-17T02:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/"},"author":{"name":"","@id":""},"headline":"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo","datePublished":"2024-12-17T02:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/"},"wordCount":178,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/","name":"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-17T02:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. deporta a M\u00e9xico a Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del C\u00e1rtel del Golfo","url":"http:\/\/noticiasya.com\/boston\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/12\/16\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-17T02:03:40Z","datePublished":"2024-12-17T02:03:40Z","dateModified":"2024-12-17T02:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. deporta a M\\u00e9xico a Osiel C\\u00e1rdenas Guill\\u00e9n, exl\\u00edder del C\\u00e1rtel del Golfo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/16\\\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/16\\\/deporta-mexico-osiel-cardenas-cartel-del-golfo-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-17T02:03:40Z\",\"datePublished\":\"2024-12-17T02:03:40Z\",\"dateModified\":\"2024-12-17T02:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452347,"url":"https:\/\/noticiasya.com\/boston\/2024\/09\/02\/osiel-cardenas-guillen-exlider-cartel-del-golfo-quien-es-orix\/","url_meta":{"origin":1456669,"position":0},"title":"\u00bfQui\u00e9n es Osiel C\u00e1rdenas Guill\u00e9n, exl\u00edder del c\u00e1rtel del Golfo en M\u00e9xico y de Los Zetas, liberado de prisi\u00f3n en EE.UU.?","author":"","date":"septiembre 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Osiel C\u00e1rdenas Guill\u00e9n, el exl\u00edder del c\u00e1rtel del Golfo en M\u00e9xico y de Los Zetas que lleg\u00f3 a estar en la lista de los m\u00e1s buscados del Servicio de Migraci\u00f3n y Control de Aduanas estadounidense (ICE, por sus siglas en ingl\u00e9s), fue liberado de prisi\u00f3n este viernes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452302,"url":"https:\/\/noticiasya.com\/boston\/2024\/08\/30\/liberan-narcotraficante-mexicano-osiel-cardenas-prision-orix\/","url_meta":{"origin":1456669,"position":1},"title":"Liberan al narcotraficante mexicano Osiel C\u00e1rdenas de prisi\u00f3n en Estados Unidos","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Osiel C\u00e1rdenas, exl\u00edder del c\u00e1rtel del Golfo en M\u00e9xico, fue liberado de prisi\u00f3n este viernes, confirm\u00f3 la Oficina Federal de Prisiones de Estados Unidos a CNN.C\u00e1rdenas ahora est\u00e1 bajo la custodia del Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s), inform\u00f3 el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458929,"url":"https:\/\/noticiasya.com\/boston\/2025\/02\/19\/carteles-criminales-terroristas-sinaloa-aragua-golfo-eeuu-orix\/","url_meta":{"origin":1456669,"position":2},"title":"Las organizaciones criminales latinoamericanas que Trump designar\u00e1 como terroristas","author":"","date":"febrero 19, 2025","format":false,"excerpt":"El gobierno del presidente de Estados Unidos, Donald Trump, design\u00f3 a varios grupos criminales latinoamericanos como organizaciones terroristas extranjeras, seg\u00fan se puede constatar en el registro federal. La designaci\u00f3n entra en vigor este 20 de febrero. Esto es consecuencia del decreto del 20 de enero de Trump que ordena elaborar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468661,"url":"https:\/\/noticiasya.com\/boston\/2025\/11\/24\/organizaciones-terroristas-trump-designacion-orix\/","url_meta":{"origin":1456669,"position":3},"title":"Cu\u00e1les son los grupos latinoamericanos que Trump design\u00f3 como terroristas desde que asumi\u00f3 en enero","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"El denominado Cartel de los Soles se convirti\u00f3 este lunes en la decimotercera organizaci\u00f3n latinoamericana designada como terrorista por el Departamento de Estado de EE.UU. en lo que va del segundo mandato del presidente Donald Trump, que comenz\u00f3 en enero.Un mes despu\u00e9s del retorno a la Casa Blanca, el Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471597,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/24\/mexico-carteles-principales-donde-operan-orix\/","url_meta":{"origin":1456669,"position":4},"title":"Mapa: cu\u00e1les son los principales grupos criminales de M\u00e9xico y d\u00f3nde operan","author":"","date":"febrero 24, 2026","format":false,"excerpt":"M\u00e9xico lleva d\u00e9cadas en lucha contra los carteles, que a\u00f1o a a\u00f1o le presentaron desaf\u00edos cambiantes y crecientes.El regreso de Donald Trump a la presidencia de EE.UU., en 2025, le sum\u00f3 un reto m\u00e1s esa lucha del Gobierno mexicano: ir tras los capos que manejan los carteles.La misi\u00f3n nunca fue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450038,"url":"https:\/\/noticiasya.com\/boston\/2024\/06\/04\/como-afectarian-mexico-drasticas-medidas-migratorias-biden-orix\/","url_meta":{"origin":1456669,"position":5},"title":"\u00bfC\u00f3mo afectar\u00edan a M\u00e9xico las dr\u00e1sticas medidas migratorias de Biden?","author":"","date":"junio 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Gobierno del presidente Joe Biden impondr\u00e1 una nueva acci\u00f3n ejecutiva que prohibir\u00e1 a los migrantes que cruzan la frontera ilegalmente solicitar asilo, una medida dr\u00e1stica que en la pr\u00e1ctica implicar\u00eda \u201cel cierre de la frontera\u201d a los miles de refugiados que se encuentran en M\u00e9xico a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1456669"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456669\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1456669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1456669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1456669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}