{"id":1456705,"date":"2024-12-18T04:03:45","date_gmt":"2024-12-18T12:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/"},"modified":"2024-12-18T04:03:45","modified_gmt":"2024-12-18T12:03:45","slug":"5-cosas-18-diciembre-tiroteos-mangione-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/","title":{"rendered":"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot"},"content":{"rendered":"<p>R\u00e9cord de tiroteos en escuelas de EE.UU. en 2024. El dif\u00edcil 2024 de Cuba y lo que podr\u00eda enfrentar en 2025. Vin\u00edcius Jr. y Aitana Bonmat\u00ed fueron elegidos como los mejores jugadores del a\u00f1o en los premios The Best de la FIFA. <em>Esto es lo que debes saber para comenzar el d\u00eda.<\/em><strong> Primero la verdad.<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.cnn.com\/newsletters\/5-cosas\"><strong>Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/www.cnn.com\/audio\/podcasts\/5-cosas\"><strong>\ud83c\udf99 Escucha las 5 cosas de CNN<\/strong><\/a><\/li>\n<\/ul>\n<p>Tras un descenso significativo durante la pandemia, <a href=\"https:\/\/cnnespanol.cnn.com\/video\/2024-record-tiroteos-escolares-ush-trax\/\">los tiroteos en escuelas han aumentado a niveles r\u00e9cord cada a\u00f1o desde entonces<\/a>. El tiroteo m\u00e1s reciente en Wisconsin es el n\u00famero 83 de este a\u00f1o.<\/p>\n<ul>\n<li><a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/estados-unidos\/quien-es-natalie-rupnow-tiroteo-wisconsin-orix\"><strong>\u00bfQui\u00e9n era Natalie \u2018Samantha\u2019 Rupnow, la sospechosa del tiroteo en escuela de Wisconsin?<\/strong><\/a><\/li>\n<\/ul>\n<p>Kevin Gallo, hermano del gendarme argentino Nahuel Agust\u00edn Gallo, quien fue detenido en Venezuela cuando iba a visitar a su familia, habl\u00f3 con CNN sobre los esfuerzos que han hecho para ubicarlo. <a href=\"https:\/\/cnnespanol.cnn.com\/video\/nahuel-gallo-gendarme-detenido-milei-venezuela-redaccion-buenos-aires-dusa-tv\/\">La detenci\u00f3n ha generado tensiones diplom\u00e1ticas entre ambos pa\u00edses. <\/a><\/p>\n<p>Cuba vivi\u00f3 en 2024 un a\u00f1o marcado por tragedias naturales, prolongados apagones y pareciera que, de cara al nuevo a\u00f1o, a\u00fan no se ve una luz al final del t\u00fanel. Con una econom\u00eda que se mantiene en recesi\u00f3n y sin perspectivas de recuperaci\u00f3n, ahora se suma el inminente retorno de Donald Trump como presidente de Estados Unidos, <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/latinoamerica\/cuba-economia-de-guerra2024-de-2025-analisis-orix\">lo que podr\u00eda implicar un endurecimiento para las situaciones financiera y migratoria<\/a>.<\/p>\n<p>Luigi Mangione ha sido acusado por el asesinato del CEO de UnitedHealthCare, Brian Thompson. Un jurado investigador de Nueva York vot\u00f3 a favor de acusar a Mangione de 11 cargos penales, <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/estados-unidos\/mangione-acusado-nueva-york-asesinato-brian-thompson-trax\">incluidos uno de asesinato, dos cargos de homicidio y m\u00faltiples cargos de posesi\u00f3n criminal de un arma<\/a>.<\/p>\n<p>CNN obtuvo acceso exclusivo a informes policiales de las autoridades francesas que contienen miles de mensajes que Dominique Pelicot intercambi\u00f3 con <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/mundo\/dominique-pelicot-violaciones-grupales-esposa-mensajes-trax\">estos hombres en salas de chat, por Skype y por mensaje de texto.<\/a><\/p>\n<p><strong>El papa Francisco revela dos intentos de atentados<\/strong><\/p>\n<p>Dos intentos de atentado contra el papa Francisco, uno de ellos perpetrado por una terrorista suicida, fueron frustrados<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/mundo\/papa-francisco-atentados-iraq-trax\"> durante su hist\u00f3rico viaje a Iraq en 2021, revel\u00f3 el pont\u00edfice en una autobiograf\u00eda.<\/a><\/p>\n<p><strong>\u00bfC\u00f3mo es la reforma al Infonavit en M\u00e9xico, qu\u00e9 cambios presenta y por qu\u00e9 es pol\u00e9mica?<\/strong><\/p>\n<p>El Gobierno de Claudia Sheinbaum busca construir un mill\u00f3n de viviendas a bajo costo para garantizar el derecho a un techo de familias mexicanas. Para lograr ese objetivo, el Senado de M\u00e9xico aprob\u00f3 en lo general una reforma constitucional en materia de vivienda. <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/reforma-vivienda-mexico-cambios-a-quien-beneficiara-orix\">Aqu\u00ed te contamos qu\u00e9 cambios tendr\u00eda, a qui\u00e9nes beneficiar\u00e1n y por qu\u00e9 es pol\u00e9mica.<\/a><\/p>\n<p><strong>Hospitalizan al cantante Raphael por un episodio cerebrovascular en Madrid<\/strong><\/p>\n<p>El cantante espa\u00f1ol Raphael, de 81 a\u00f1os, fue trasladado al Hospital Cl\u00ednico San Carlos de Madrid luego de sufrir un episodio cerebrovascular mientras participaba <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/entretenimiento\/raphael-accidente-cerebrovascular-efe\">en la grabaci\u00f3n de un programa de Navidad de Televisi\u00f3n Espa\u00f1ola<\/a>.<\/p>\n<p><strong>Los mejores jugadores del a\u00f1o en los premios The Best de la FIFA<\/strong><\/p>\n<p>La espa\u00f1ola Aitana Bonmat\u00ed gan\u00f3 por segundo a\u00f1o consecutivo el premio The Best a la mejor jugadora. En tanto, el brasile\u00f1o Vin\u00edcius Jr. se <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/ganador-premio-the-best-2024-orix\/\">llev\u00f3 por primera vez el reconocimiento a mejor jugador del a\u00f1o en el mismo galard\u00f3n.<\/a><\/p>\n<p><strong>Honda y Nissan est\u00e1n en conversaciones para fusionarse<\/strong><\/p>\n<p>Honda y Nissan est\u00e1n discutiendo una posible fusi\u00f3n, que potencialmente <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/economia\/honda-nissan-conversaciones-fusionarse-trax\">unir\u00eda a dos titanes de la industria automotriz japonesa<\/a> que recientemente han pasado por tiempos dif\u00edciles.<\/p>\n<p><strong>1.000 pasos<\/strong><\/p>\n<p>Caminar tan solo 1.000 pasos m\u00e1s al d\u00eda podr\u00eda <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/salud\/caminar-1000-pasos-depresion-estudio-trax\">reducir el riesgo de depresi\u00f3n, seg\u00fan un estudio<\/a>.<\/p>\n<p><strong>\u201cDesconoc\u00eda todo lo que estaba sucediendo en los medios mientras estaba fuera y todav\u00eda estoy procesando todo\u201d<\/strong><\/p>\n<p>Hannah Kobayashi, la mujer de Hawai cuya desaparici\u00f3n el mes pasado desat\u00f3 una b\u00fasqueda que dur\u00f3 semanas aunada a im\u00e1genes de vigilancia borrosas y familiares en llanto, dice que desconoc\u00eda <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/estados-unidos\/hannah-kobayashi-desconocia-revuelo-desaparicion-trax\">\u201ctodo lo que estaba sucediendo\u201d mientras estuvo fuera de contacto.<\/a><\/p>\n<p><strong>As\u00ed se vivi\u00f3 el potente terremoto de magnitud 7,3 que sacudi\u00f3 Vanuatu<\/strong><\/p>\n<p>Un fuerte sismo de magnitud 7,3 azot\u00f3 Vanuatu este martes dejando destrucci\u00f3n en varias zonas, incluidos edificios clave en la capital, Port Vila. El terremoto, que se origin\u00f3 a<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/mundo\/video\/imagenes-potente-terremoto-vanuatu-orix\"> 57,1 kil\u00f3metros de profundidad, caus\u00f3 da\u00f1os graves y dej\u00f3 una persona muerta.<\/a><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9cord de tiroteos en escuelas de EE.UU. en 2024. El dif\u00edcil 2024 de Cuba y lo que podr\u00eda enfrentar en 2025. Vin\u00edcius Jr. y Aitana Bonmat\u00ed fueron elegidos como los mejores jugadores del a\u00f1o en los premios The Best de la FIFA. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456705","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot - Noticias\" \/>\n<meta property=\"og:description\" content=\"R\u00e9cord de tiroteos en escuelas de EE.UU. en 2024. El dif\u00edcil 2024 de Cuba y lo que podr\u00eda enfrentar en 2025. Vin\u00edcius Jr. y Aitana Bonmat\u00ed fueron elegidos como los mejores jugadores del a\u00f1o en los premios The Best de la FIFA. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-18T12:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot\",\"datePublished\":\"2024-12-18T12:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/\"},\"wordCount\":776,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/\",\"name\":\"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-18T12:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot - Noticias","og_description":"R\u00e9cord de tiroteos en escuelas de EE.UU. en 2024. El dif\u00edcil 2024 de Cuba y lo que podr\u00eda enfrentar en 2025. Vin\u00edcius Jr. y Aitana Bonmat\u00ed fueron elegidos como los mejores jugadores del a\u00f1o en los premios The Best de la FIFA. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-18T12:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/"},"author":{"name":"","@id":""},"headline":"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot","datePublished":"2024-12-18T12:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/"},"wordCount":776,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/","name":"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-18T12:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot","url":"http:\/\/noticiasya.com\/boston\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/12\/18\/5-cosas-18-diciembre-tiroteos-mangione-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-18T12:03:45Z","datePublished":"2024-12-18T12:03:45Z","dateModified":"2024-12-18T12:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las 5 cosas que debes saber este 18 de diciembre: Tiroteos, gendarme argentino detenido, Cuba, Mangione y textos de Pelicot\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/18\\\/5-cosas-18-diciembre-tiroteos-mangione-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/18\\\/5-cosas-18-diciembre-tiroteos-mangione-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-18T12:03:45Z\",\"datePublished\":\"2024-12-18T12:03:45Z\",\"dateModified\":\"2024-12-18T12:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471100,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/11\/5-cosas-11-de-febrero-orix\/","url_meta":{"origin":1456705,"position":0},"title":"Las 5 cosas que debes saber este 11 de febrero","author":"","date":"febrero 11, 2026","format":false,"excerpt":"Cuba despliega plan para sobrevivir a una de sus peores crisis. Miles de hondure\u00f1os y nicarag\u00fcenses est\u00e1n en riesgo de deportaci\u00f3n tras fallo sobre el TPS. El FBI publica im\u00e1genes de la casa de Nancy Guthrie mientras sigue su b\u00fasqueda. Esto es lo que debes saber para comenzar el d\u00eda.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472521,"url":"https:\/\/noticiasya.com\/boston\/2026\/03\/25\/5-cosas-25-de-marzo-orix\/","url_meta":{"origin":1456705,"position":1},"title":"Las 5 cosas que debes saber este 25 de marzo","author":"","date":"marzo 25, 2026","format":false,"excerpt":"El precio de la gasolina no bajar\u00e1 en el corto plazo. El plan republicano para acabar con el cierre del Departamento de Seguridad Nacional enfrenta obst\u00e1culos. \u00bfC\u00f3mo es el USS Nimitz, el longevo portaviones de EE.UU. enviado a Am\u00e9rica Latina? Esto es lo que debes saber para comenzar el d\u00eda.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471019,"url":"https:\/\/noticiasya.com\/boston\/2026\/02\/09\/5-cosas-9-de-febrero-orix\/","url_meta":{"origin":1456705,"position":2},"title":"Las 5 cosas que debes saber este 9 de febrero","author":"","date":"febrero 9, 2026","format":false,"excerpt":"Hombres fuertemente armados detienen al opositor venezolano Juan Pablo Guanipa horas despu\u00e9s de su liberaci\u00f3n. El desabastecimiento de combustible impacta el turismo de Cuba. \u00bfC\u00f3mo vive Minneapolis tras la \u201creducci\u00f3n\u201d de ICE en la ciudad? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469266,"url":"https:\/\/noticiasya.com\/boston\/2025\/12\/15\/5-cosas-15-diciembre-orix\/","url_meta":{"origin":1456705,"position":3},"title":"Las 5 cosas que debes saber este 15 de diciembre: Triunfo de Kast, tiroteo en Sydney, avi\u00f3n de JetBlue y m\u00e1s","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"Al menos 15 muertos tras el ataque en una playa de Sydney durante una celebraci\u00f3n de Januc\u00e1. Incidente entre un avi\u00f3n de JetBlue y una aeronave militar de EE.UU. Muere el director de Hollywood Rob Reiner. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461340,"url":"https:\/\/noticiasya.com\/boston\/2025\/04\/18\/estudiantes-universidad-florida-tiroteos-violencia-trax\/","url_meta":{"origin":1456705,"position":4},"title":"Alertas, escritorios bloqueando puertas, zapatos abandonados: c\u00f3mo el tiroteo en la Universidad de Florida trastoc\u00f3 el campus","author":"","date":"abril 18, 2025","format":false,"excerpt":"Era una tarde normal para Jayden D\u2019Onofrio, que estaba pasando tiempo con un amigo en su complejo de apartamentos cuando recibi\u00f3 un mensaje de texto que le hel\u00f3 la sangre.Un tirador activo estaba en el campus y su amigo se escond\u00eda en la biblioteca.Sin pensarlo dos veces, corrieron hacia all\u00ed.Un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446266,"url":"https:\/\/noticiasya.com\/boston\/2024\/03\/03\/tiroteos-masivos-james-crumbley-responsabilidades-culpables-juicio-trax\/","url_meta":{"origin":1456705,"position":5},"title":"\u00bfQui\u00e9n es responsable de un tiroteo masivo? Ya no es solo la persona que apret\u00f3 el gatillo","author":"","date":"marzo 3, 2024","format":false,"excerpt":"(CNN) -- El mes pasado, un jurado declar\u00f3 a Jennifer Crumbley culpable de cuatro cargos de homicidio involuntario en relaci\u00f3n con el tiroteo de 2021 en el instituto de Oxford: un cargo por cada alumno al que su hijo mat\u00f3.El hist\u00f3rico juicio, y el sorprendente veredicto, pusieron a prueba los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1456705"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456705\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1456705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1456705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1456705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}