{"id":1456749,"date":"2024-12-19T01:03:38","date_gmt":"2024-12-19T09:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/"},"modified":"2024-12-19T01:03:38","modified_gmt":"2024-12-19T09:03:38","slug":"human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/","title":{"rendered":"Human Rights Watch acusa a Israel de genocidio al restringir &#171;deliberadamente&#187; el agua en Gaza"},"content":{"rendered":"<p>Human Rights Watch (HRW) acus\u00f3 este jueves a Israel de \u201cactos de genocidio\u201d contra los palestinos en Gaza al privarlos de <a href=\"https:\/\/www.cnn.com\/2024\/08\/23\/middleeast\/israel-gaza-water-shortages-heatwave-crisis-intl\/index.html\">suministros de agua adecuados<\/a>.<\/p>\n<p>El grupo, <a href=\"https:\/\/www.hrw.org\/preview-link\/node\/390031\/49ffc8a9-541a-479f-973b-b90043286fd2\">en un extenso informe<\/a>, descubri\u00f3 que entre octubre de 2023 y septiembre de 2024, las autoridades israel\u00edes privaron a los palestinos de lo que la Organizaci\u00f3n Mundial de la Salud (OMS) considera la cantidad m\u00ednima de agua necesaria para sobrevivir en situaciones de emergencia prolongadas. Esto contribuy\u00f3 a miles de muertes y a la propagaci\u00f3n de numerosas enfermedades, seg\u00fan el informe.<\/p>\n<p>CNN se comunic\u00f3 con las Fuerzas de Defensa de Israel (FDI) y COGAT, la agencia israel\u00ed responsable de aprobar la ayuda a Gaza, para solicitar comentarios sobre el informe.<\/p>\n<p>El Gobierno israel\u00ed <a href=\"https:\/\/www.cnn.com\/2024\/12\/04\/world\/amnesty-international-israel-genocide-gaza-intl\/index.html\">neg\u00f3 acusaciones anteriores<\/a> de genocidio calific\u00e1ndolas de \u201ctotalmente infundadas\u201d y neg\u00f3<a href=\"https:\/\/www.cnn.com\/2024\/11\/15\/middleeast\/israel-gaza-genocide-un-special-committee-intl-latam\/index.html\"> categ\u00f3ricamente<\/a> utilizar el hambre como arma de guerra.<\/p>\n<p>Seg\u00fan la OMS, una persona necesita entre 50 y 100 litros de agua al d\u00eda para satisfacer sus \u201cnecesidades b\u00e1sicas\u201d. En situaciones de emergencia prolongadas, la cantidad m\u00ednima de agua puede reducirse a entre 15 y 20 litros al d\u00eda para beber y lavarse.<\/p>\n<p>Para los m\u00e1s de dos millones de palestinos que viven en  Gaza, incluso esto est\u00e1 fuera de su alcance, seg\u00fan constat\u00f3 HRW. La mayor parte o la totalidad del agua a la que tienen acceso los palestinos en Gaza no es potable.<\/p>\n<p>HRW afirma que las acciones de Israel constituyen actos de genocidio seg\u00fan la Convenci\u00f3n sobre el Genocidio y el Estatuto de Roma de la Corte Penal Internacional (CPI). Destaca que la privaci\u00f3n de agua est\u00e1 causando la muerte lenta de palestinos en Gaza, incluidos los beb\u00e9s reci\u00e9n nacidos cuyas madres no pueden alimentarlos debido a la desnutrici\u00f3n y la deshidrataci\u00f3n, y que beben leche en polvo mezclada con agua sucia.<\/p>\n<p>La guerra de Israel en Gaza, lanzada despu\u00e9s del ataque de Hamas en octubre de 2023, ha matado a casi 45.000 palestinos y herido a 106.000 m\u00e1s, seg\u00fan el Ministerio de Salud palestino.<\/p>\n<p>HRW afirma que la obstrucci\u00f3n del agua en Gaza es un acto deliberado de las autoridades israel\u00edes, citando la obstrucci\u00f3n por parte de Israel de la ayuda humanitaria, incluidos los suministros relacionados con el tratamiento y la producci\u00f3n de agua, las restricciones al flujo de agua limpia a trav\u00e9s de tuber\u00edas desde Israel a Gaza, as\u00ed como los da\u00f1os \u201cmasivos\u201d a la infraestructura h\u00eddrica de Gaza causados \u200b\u200bpor los ataques israel\u00edes.<\/p>\n<p>En enero, el Banco Mundial y la firma de investigaci\u00f3n de mercado Ipsos calcularon que casi el 60% de la infraestructura de agua y saneamiento de Gaza hab\u00eda sido da\u00f1ada o destruida por las hostilidades. En agosto, esa cifra hab\u00eda aumentado al 84%.<\/p>\n<p>En julio, soldados israel\u00edes destruyeron un importante dep\u00f3sito de agua que abastece a Rafah, en el sur de Gaza. La explosi\u00f3n fue captada en un video ahora eliminado, que al parecer fue compartido por un soldado israel\u00ed en Instagram y <a href=\"https:\/\/www.cnn.com\/2024\/08\/23\/middleeast\/israel-gaza-water-shortages-heatwave-crisis-intl\/index.html\">geolocalizado por CNN<\/a>.<\/p>\n<p>En una declaraci\u00f3n en X, Oren Marmorstein, portavoz del Ministerio de Asuntos Exteriores de Israel, neg\u00f3 las acusaciones y dijo que Israel hab\u00eda \u201cfacilitado el flujo continuo de agua y ayuda humanitaria\u201d a Gaza.<\/p>\n<p>Dijo que Israel tambi\u00e9n hab\u00eda garantizado que la infraestructura h\u00eddrica, incluidas cuatro tuber\u00edas de agua e instalaciones de bombeo y desalinizaci\u00f3n de agua, siguieran funcionando.<\/p>\n<p>Israel enfrent\u00f3 anteriormente acusaciones de utilizar el agua como arma de guerra en Gaza.<\/p>\n<p>Pedro Arrojo-Agudo, relator especial de la ONU sobre los derechos humanos al agua potable y al saneamiento, dijo en noviembre de 2023 que \u201ccada hora que pasa sin que Israel impida el suministro de agua potable en Gaza, en flagrante violaci\u00f3n del derecho internacional, pone a los habitantes de Gaza en riesgo de morir de sed y de enfermedades relacionadas con la falta de agua potable\u201d.<\/p>\n<p>La crisis aliment\u00f3 <a href=\"https:\/\/www.cnn.com\/2024\/06\/16\/middleeast\/gaza-health-crisis-mosquitoes-sewage-intl\/index.html\">las enfermedades en Gaza<\/a> y caus\u00f3 miles de muertes, seg\u00fan HRW. La organizaci\u00f3n advirti\u00f3 que es posible que nunca se comprenda por completo la magnitud de la devastaci\u00f3n causada por la falta de agua, debido a la destrucci\u00f3n del sistema de atenci\u00f3n sanitaria de Gaza, incluido el seguimiento de las enfermedades.<\/p>\n<p>Un ejemplo de ello es la polio, una enfermedad viral sumamente contagiosa que suele deberse a un acceso insuficiente al agua potable y al saneamiento. Las pruebas de la OMS detectaron por primera vez el virus de la polio en muestras de aguas residuales tomadas en julio de tiendas de campa\u00f1a abarrotadas de personas desplazadas por los ataques a\u00e9reos israel\u00edes en Gaza. El 16 de agosto, el Ministerio de Salud palestino confirm\u00f3 un caso de polio en un ni\u00f1o de 10 meses, el primer caso en Gaza en 25 a\u00f1os.<\/p>\n<p>Las infecciones bacterianas, como la diarrea, se volvieron algo habitual en el enclave debido al consumo de agua contaminada. Al describir el impacto de verse obligado a beber de un pozo sucio, un hombre le dijo a HRW: \u201cMe estaba poniendo enfermo, mis hijos vomitaban y ten\u00edan diarrea, y yo ten\u00eda diarrea\u2026 Esto fue desde el momento en que comenzamos a beber el agua (sucia)\u201d.<\/p>\n<p>El informe de HRW llega en un momento en que sigue siendo dif\u00edcil alcanzar un acuerdo de alto el fuego entre Israel y Hamas, aunque las negociaciones parecen haber tomado un giro m\u00e1s positivo en los \u00faltimos d\u00edas.<\/p>\n<p>En un comunicado oficial publicado el martes, Hamas dijo que era \u201cposible\u201d llegar a un acuerdo. Una fuente de Hamas a\u00f1adi\u00f3 que las conversaciones eran \u201cpositivas y optimistas\u201d. Sin embargo, el grupo militante advirti\u00f3 de que a\u00fan quedan obst\u00e1culos.<\/p>\n<p>Tanto los equipos de Israel como los de Hamas est\u00e1n en la capital qatar\u00ed para mantener negociaciones indirectas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Human Rights Watch (HRW) acus\u00f3 este jueves a Israel de \u201cactos de genocidio\u201d contra los palestinos en Gaza al privarlos de suministros de agua adecuados. El grupo, en un extenso informe, descubri\u00f3 que entre octubre de 2023 y septiembre de 2024, las autoridades israel\u00edes privaron a los palestinos de lo que la Organizaci\u00f3n Mundial de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456749","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Human Rights Watch acusa a Israel de genocidio al restringir &quot;deliberadamente&quot; el agua en Gaza - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Human Rights Watch acusa a Israel de genocidio al restringir &quot;deliberadamente&quot; el agua en Gaza - Noticias\" \/>\n<meta property=\"og:description\" content=\"Human Rights Watch (HRW) acus\u00f3 este jueves a Israel de \u201cactos de genocidio\u201d contra los palestinos en Gaza al privarlos de suministros de agua adecuados. El grupo, en un extenso informe, descubri\u00f3 que entre octubre de 2023 y septiembre de 2024, las autoridades israel\u00edes privaron a los palestinos de lo que la Organizaci\u00f3n Mundial de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-19T09:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Human Rights Watch acusa a Israel de genocidio al restringir &#171;deliberadamente&#187; el agua en Gaza\",\"datePublished\":\"2024-12-19T09:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/\"},\"wordCount\":1011,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/\",\"name\":\"Human Rights Watch acusa a Israel de genocidio al restringir \\\"deliberadamente\\\" el agua en Gaza - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-19T09:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Human Rights Watch acusa a Israel de genocidio al restringir &#171;deliberadamente&#187; el agua en Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Human Rights Watch acusa a Israel de genocidio al restringir \"deliberadamente\" el agua en Gaza - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Human Rights Watch acusa a Israel de genocidio al restringir \"deliberadamente\" el agua en Gaza - Noticias","og_description":"Human Rights Watch (HRW) acus\u00f3 este jueves a Israel de \u201cactos de genocidio\u201d contra los palestinos en Gaza al privarlos de suministros de agua adecuados. El grupo, en un extenso informe, descubri\u00f3 que entre octubre de 2023 y septiembre de 2024, las autoridades israel\u00edes privaron a los palestinos de lo que la Organizaci\u00f3n Mundial de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-19T09:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/"},"author":{"name":"","@id":""},"headline":"Human Rights Watch acusa a Israel de genocidio al restringir &#171;deliberadamente&#187; el agua en Gaza","datePublished":"2024-12-19T09:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/"},"wordCount":1011,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/","name":"Human Rights Watch acusa a Israel de genocidio al restringir \"deliberadamente\" el agua en Gaza - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-19T09:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Human Rights Watch acusa a Israel de genocidio al restringir &#171;deliberadamente&#187; el agua en Gaza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Human Rights Watch acusa a Israel de genocidio al restringir &#171;deliberadamente&#187; el agua en Gaza","url":"http:\/\/noticiasya.com\/boston\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/12\/19\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-19T09:03:38Z","datePublished":"2024-12-19T09:03:38Z","dateModified":"2024-12-19T09:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Human Rights Watch acusa a Israel de genocidio al restringir &#171;deliberadamente&#187; el agua en Gaza\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/19\\\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/19\\\/human-rights-watch-acusa-israel-genocidio-gaza-restringir-agua-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-19T09:03:38Z\",\"datePublished\":\"2024-12-19T09:03:38Z\",\"dateModified\":\"2024-12-19T09:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464934,"url":"https:\/\/noticiasya.com\/boston\/2025\/07\/28\/grupos-acusan-israel-genocidio-gaza-trax\/","url_meta":{"origin":1456749,"position":0},"title":"Dos importantes grupos israel\u00edes de derechos humanos acusan a Israel de genocidio en Gaza por primera vez","author":"","date":"julio 28, 2025","format":false,"excerpt":"Dos importantes grupos israel\u00edes de derechos humanos han acusado a Israel de \u201ccometer genocidio contra los palestinos en Gaza\u201d, convirti\u00e9ndose en las primeras organizaciones de este tipo en hacer esta afirmaci\u00f3n.B\u2019Tselem afirm\u00f3 en un gran informe publicado el lunes que lleg\u00f3 a esta \u201cconclusi\u00f3n inequ\u00edvoca\u201d tras un \u201can\u00e1lisis de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466499,"url":"https:\/\/noticiasya.com\/boston\/2025\/09\/16\/onu-israel-genocidio-gaza-trax\/","url_meta":{"origin":1456749,"position":1},"title":"Comisi\u00f3n de la ONU afirma que Israel est\u00e1 cometiendo genocidio en Gaza","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"Una investigaci\u00f3n independiente de las Naciones Unidas concluy\u00f3 por primera vez que Israel ha cometido genocidio contra los palestinos en Gaza y que los principales l\u00edderes del pa\u00eds han incitado al genocidio, en lo que describi\u00f3 como la \u201cconclusi\u00f3n m\u00e1s autorizada de la ONU hasta la fecha\u201d.En un informe de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467333,"url":"https:\/\/noticiasya.com\/boston\/2025\/10\/13\/cronologia-guerra-israel-hamas-gaza-orix\/","url_meta":{"origin":1456749,"position":2},"title":"Cronolog\u00eda de la guerra de Israel y Hamas desde el 7 de octubre de 2023","author":"","date":"octubre 13, 2025","format":false,"excerpt":"El ataque de Hamas del 7 de octubre de 2023 desencaden\u00f3 una guerra cruda de Israel en Gaza. En ese ataque terrorista murieron m\u00e1s de 1.200 personas y 251 personas fueron secuestradas. Por su parte, la guerra israel\u00ed ha dejado al menos 67.173 muertos y otros 169.780 heridos en Gaza,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465571,"url":"https:\/\/noticiasya.com\/boston\/2025\/08\/17\/grabaciones-general-israeli-muertes-gaza-trax\/","url_meta":{"origin":1456749,"position":3},"title":"&#171;50.000 muertos en Gaza son necesarios&#187; para futuras generaciones, dice exjefe de inteligencia israel\u00ed en grabaci\u00f3n filtrada","author":"","date":"agosto 17, 2025","format":false,"excerpt":"En grabaciones de audio filtradas, se puede escuchar al exjefe de inteligencia militar israel\u00ed diciendo que la muerte de decenas de miles de palestinos en Gaza es \u201cnecesaria y requerida para las futuras generaciones\u201d.\u201cPor todo lo que pas\u00f3 el 7 de octubre, por cada una de las personas del 7\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456275,"url":"https:\/\/noticiasya.com\/boston\/2024\/12\/05\/amnistia-internacional-pruebas-acusar-israel-genocidio-gaza-trax\/","url_meta":{"origin":1456749,"position":4},"title":"Amnist\u00eda Internacional dice que hay &#171;pruebas suficientes&#187; para acusar a Israel de genocidio en Gaza","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"Amnist\u00eda Internacional dijo este mi\u00e9rcoles que hab\u00eda reunido \u201cpruebas suficientes para creer\u201d que la conducta de Israel durante la guerra de Gaza equivale a genocidio contra el pueblo palestino, acusaci\u00f3n que el Gobierno israel\u00ed ha negado con vehemencia.El informe, de 296 p\u00e1ginas, detalla las pruebas reunidas a lo largo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445405,"url":"https:\/\/noticiasya.com\/boston\/2024\/02\/14\/ataques-de-israel-profundizan-el-panico-en-rafah-jefe-de-ayuda-de-la-onu-advierte-que-una-ofensiva-terrestre-podria-resultar-en-una-masacre\/","url_meta":{"origin":1456749,"position":5},"title":"Ataques de Israel profundizan el p\u00e1nico en Rafah; jefe de ayuda de la ONU advierte que una ofensiva terrestre podr\u00eda resultar en una &#171;masacre&#187;","author":"","date":"febrero 14, 2024","format":false,"excerpt":"(CNN) -- El p\u00e1nico se est\u00e1 disparando en Rafah, mientras palestinos desesperados deciden si huir del \u00faltimo refugio en Gaza e Israel elabora planes para una ofensiva terrestre que, seg\u00fan advirti\u00f3 el jefe de ayuda de las Naciones Unidas, podr\u00eda conducir a \"una masacre\".Un n\u00famero cada vez mayor de pa\u00edses\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1456749"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456749\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1456749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1456749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1456749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}