{"id":1456809,"date":"2024-12-20T15:03:43","date_gmt":"2024-12-20T23:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/"},"modified":"2024-12-20T15:03:43","modified_gmt":"2024-12-20T23:03:43","slug":"elon-musk-respalda-extrema-derecha-alemania-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/","title":{"rendered":"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global"},"content":{"rendered":"<p>Elon Musk no solo se est\u00e1 involucrando en la pol\u00edtica estadounidense. Acaba de dar su apoyo p\u00fablico a un partido pol\u00edtico de extrema derecha en Alemania, Alternativa para Alemania o AfD.<\/p>\n<p>Musk, el multimillonario aliado de Trump que desempe\u00f1a un papel p\u00fablico en la administraci\u00f3n entrante, public\u00f3 este viernes su apoyo para el AfD tras el colapso del Gobierno alem\u00e1n esta semana.<\/p>\n<p>\u201cSolo el AfD puede salvar a Alemania\u201d, escribi\u00f3 Musk este viernes mientras volv\u00eda a publicar un video de la activista pol\u00edtica de extrema derecha Naomi Seibt.<\/p>\n<p>El AfD, que ha experimentado un crecimiento de su popularidad en las \u00faltimas elecciones, ha promovido posiciones populistas y antiinmigrantes similares al mensaje de \u201cAlemania primero\u201d. Pero el partido tambi\u00e9n ha sido acusado de resucitar la ideolog\u00eda y los esl\u00f3ganes de la era nazi. En mayo, un juez dictamin\u00f3 que la agencia de inteligencia dom\u00e9stica de Alemania ten\u00eda permitido seguir vigilando al AfD por la amenaza que supuestamente representa para la democracia alemana, rechazando una demanda impuesta por el partido.<\/p>\n<p>El brazo juvenil de la organizaci\u00f3n, la Alternativa Joven (JA), ha sido designado por las autoridades alemanas como una organizaci\u00f3n \u201cconfirmada como extremista\u201d. El candidato principal del partido en el estado oriental alem\u00e1n de Turingia, Bj\u00f6rn H\u00f6cke, fue condenado a principios de este a\u00f1o despu\u00e9s de violar las leyes alemanas contra la pronunciaci\u00f3n de esl\u00f3ganes nazis en p\u00fablico.<\/p>\n<p>Pero el partido tiene un apoyo creciente. El AfD recientemente se convirti\u00f3 en el primer partido de extrema derecha en ganar una elecci\u00f3n estatal en Alemania desde la era nazi, aunque todos los partidos pol\u00edticos principales del pa\u00eds dijeron que no formar\u00edan con ellos una coalici\u00f3n, lo cual es necesario para alcanzar los esca\u00f1os suficientes como para formar gobierno.<\/p>\n<p>No es la primera vez que Musk se involucra en la pol\u00edtica alemana. En junio, respondi\u00f3 a un video de Seibt y pregunt\u00f3: \u201c\u00bfPor qu\u00e9 hay una reacci\u00f3n tan negativa de algunos sobre el AfD? Siguen diciendo \u2018extrema derecha\u2019, pero las pol\u00edticas del AfD que he le\u00eddo no suenan extremistas. Tal vez me estoy perdiendo de algo\u201d, escribi\u00f3. Y el mes pasado etiquet\u00f3 al canciller alem\u00e1n Olaf Scholz como un \u201ctonto\u201d despu\u00e9s de que su coalici\u00f3n de Gobierno colapsara.<\/p>\n<p>Este viernes, Musk continu\u00f3 haciendo publicaciones sobre el AfD, al escribir en respuesta a la publicaci\u00f3n de un usuario sobre la pol\u00edtica de inmigraci\u00f3n del partido que \u201csuena razonable\u201d.<\/p>\n<p>Musk comenz\u00f3 a seguir a la l\u00edder del AfD, Alice Weidel, en X, quien respondi\u00f3 a su respaldo y public\u00f3 un video en el que le expresaba gratitud.<\/p>\n<p>\u201cAlternativa para Alemania es de hecho la \u00fanica y \u00faltima alternativa para nuestro pa\u00eds; nuestra \u00faltima opci\u00f3n. \u00a1Le deseo a usted y al presidente Donald Trump todo lo mejor para el pr\u00f3ximo mandato!\u201d, escribi\u00f3 Weidel.<\/p>\n<p>Christian Lindner, el l\u00edder del Partido Democr\u00e1tico Libre pro-empresarial de Alemania, tambi\u00e9n respondi\u00f3 a la publicaci\u00f3n de Musk este viernes inst\u00e1ndolo a no \u201csacar conclusiones apresuradas desde lejos\u201d.<\/p>\n<p>\u201cSi bien el control de la migraci\u00f3n es crucial para Alemania, el AfD est\u00e1 en contra de la libertad, de los negocios, y es un partido de extrema derecha\u201d, escribi\u00f3 Lindner.<\/p>\n<p>Musk ha apoyado cada vez m\u00e1s causas de extrema derecha en Europa. A principios de este a\u00f1o, Musk se refiri\u00f3 a disturbios antiinmigraci\u00f3n en Reino Unido, al escribir en su plataforma de redes sociales que \u201cla guerra civil es inevitable\u201d en respuesta a una publicaci\u00f3n que culpaba a las violentas manifestaciones por los efectos de la \u201cmigraci\u00f3n masiva y las fronteras abiertas\u201d.<\/p>\n<p>A principios de esta semana, Nigel Farage, el pol\u00edtico populista brit\u00e1nico de extrema derecha y aliado de Trump, dijo que Musk estaba considerando financiar su partido Reform UK.<\/p>\n<p>En el peri\u00f3dico Telegraph, Farage escribi\u00f3 que despu\u00e9s de reunirse con Musk no le qued\u00f3 dudas de su respaldo, y que hab\u00eda \u201cnegociaciones en curso\u201d sobre una contribuci\u00f3n financiera.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elon Musk no solo se est\u00e1 involucrando en la pol\u00edtica estadounidense. Acaba de dar su apoyo p\u00fablico a un partido pol\u00edtico de extrema derecha en Alemania, Alternativa para Alemania o AfD. Musk, el multimillonario aliado de Trump que desempe\u00f1a un papel p\u00fablico en la administraci\u00f3n entrante, public\u00f3 este viernes su apoyo para el AfD tras [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456809","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global - Noticias\" \/>\n<meta property=\"og:description\" content=\"Elon Musk no solo se est\u00e1 involucrando en la pol\u00edtica estadounidense. Acaba de dar su apoyo p\u00fablico a un partido pol\u00edtico de extrema derecha en Alemania, Alternativa para Alemania o AfD. Musk, el multimillonario aliado de Trump que desempe\u00f1a un papel p\u00fablico en la administraci\u00f3n entrante, public\u00f3 este viernes su apoyo para el AfD tras [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-20T23:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global\",\"datePublished\":\"2024-12-20T23:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/\"},\"wordCount\":732,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/\",\"name\":\"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-20T23:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global - Noticias","og_description":"Elon Musk no solo se est\u00e1 involucrando en la pol\u00edtica estadounidense. Acaba de dar su apoyo p\u00fablico a un partido pol\u00edtico de extrema derecha en Alemania, Alternativa para Alemania o AfD. Musk, el multimillonario aliado de Trump que desempe\u00f1a un papel p\u00fablico en la administraci\u00f3n entrante, public\u00f3 este viernes su apoyo para el AfD tras [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-20T23:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/"},"author":{"name":"","@id":""},"headline":"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global","datePublished":"2024-12-20T23:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/"},"wordCount":732,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/","name":"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-20T23:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\u00e1ndose a\u00fan m\u00e1s en la pol\u00edtica global","url":"http:\/\/noticiasya.com\/boston\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2024\/12\/20\/elon-musk-respalda-extrema-derecha-alemania-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-20T23:03:43Z","datePublished":"2024-12-20T23:03:43Z","dateModified":"2024-12-20T23:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Elon Musk respalda al partido de extrema derecha de Alemania, involucr\\u00e1ndose a\\u00fan m\\u00e1s en la pol\\u00edtica global\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/20\\\/elon-musk-respalda-extrema-derecha-alemania-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2024\\\/12\\\/20\\\/elon-musk-respalda-extrema-derecha-alemania-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-20T23:03:43Z\",\"datePublished\":\"2024-12-20T23:03:43Z\",\"dateModified\":\"2024-12-20T23:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457076,"url":"https:\/\/noticiasya.com\/boston\/2024\/12\/30\/alemania-acusa-elon-musk-influir-elecciones-trax\/","url_meta":{"origin":1456809,"position":0},"title":"Alemania acusa a Elon Musk de intentar influir en sus elecciones","author":"","date":"diciembre 30, 2024","format":false,"excerpt":"El Gobierno de Alemania acus\u00f3 este lunes al multimillonario estadounidense Elon Musk de intentar influir en sus elecciones previstas para febrero con art\u00edculos de apoyo al partido de extrema derecha Alternativa para Alemania (AfD), aunque sugiri\u00f3 que equival\u00edan a \u201ctonter\u00edas\u201d.Musk, que est\u00e1 listo para servir al nuevo Gobierno de Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458102,"url":"https:\/\/noticiasya.com\/boston\/2025\/02\/01\/ultraderecha-alemania-obsesionada-trump-musk-trax\/","url_meta":{"origin":1456809,"position":1},"title":"La ultraderecha de Alemania est\u00e1 obsesionada con Trump y Musk","author":"","date":"febrero 1, 2025","format":false,"excerpt":"\u201cTienen que tomar una decisi\u00f3n. \u00bfQuieren al partido de (el canciller) Olaf Scholz y todos esos eunucos? \u00bfO est\u00e1n de nuestro lado, con Elon Musk y Donald Trump? \u00bfCu\u00e1l de los dos lados es m\u00e1s sexy?\u201dEstas fueron las palabras de Maximilian Krah, un pol\u00edtico ultraderechista de Alternativa para Alemania (AfD)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457977,"url":"https:\/\/noticiasya.com\/boston\/2025\/01\/28\/elon-musk-partidos-derecha-canciller-alemania-trax\/","url_meta":{"origin":1456809,"position":2},"title":"El apoyo de Elon Musk a los partidos de derecha &#171;es realmente repugnante&#187;, dice el canciller de Alemania a CNN","author":"","date":"enero 28, 2025","format":false,"excerpt":"El canciller de Alemania, Olaf Scholz, aprovech\u00f3 una oportunidad en la campa\u00f1a electoral de este martes para criticar a Elon Musk, diciendo a CNN que el multimillonario estadounidense \u201cest\u00e1 interviniendo a favor de pol\u00edticos de derecha en toda Europa. Y esto es realmente repugnante\u201d.Antes de las elecciones de febrero en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459124,"url":"https:\/\/noticiasya.com\/boston\/2025\/02\/24\/afd-extrema-derecha-alemania-fuerza-poderosa-trax\/","url_meta":{"origin":1456809,"position":3},"title":"AN\u00c1LISIS | La ultraderecha alemana puede haber quedado fuera del poder, pero la AfD es una fuerza poderosa","author":"","date":"febrero 24, 2025","format":false,"excerpt":"El sistema pol\u00edtico alem\u00e1n est\u00e1 dise\u00f1ado para excluir a los extremistas. Sin embargo, el pa\u00eds est\u00e1 despertando a una nueva realidad pol\u00edtica que se ha inclinado hacia la derecha con el otrora marginado partido Alternativa para Alemania (AfD), ahora firmemente establecido en la pol\u00edtica alemana.Los principales conservadores del pa\u00eds, como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459104,"url":"https:\/\/noticiasya.com\/boston\/2025\/02\/23\/lider-partido-extrema-derecha-afd-elecciones-trax\/","url_meta":{"origin":1456809,"position":4},"title":"Elecciones en Alemania: la l\u00edder del ultraderechista AfD dice que el partido &#171;nunca ha sido m\u00e1s fuerte&#187;","author":"","date":"febrero 23, 2025","format":false,"excerpt":"Alice Weidel, la col\u00edder del partido de extrema derecha Alternativa para Alemania (AfD), dijo que el partido \u201cnunca ha sido m\u00e1s fuerte\u201d mientras sub\u00eda al escenario en una fiesta electoral despu\u00e9s de que se anunciaran las encuestas a pie de urna, que ubicaban a su partido en el segundo lugar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459066,"url":"https:\/\/noticiasya.com\/boston\/2025\/02\/22\/alemania-elecciones-nacionales-europa-trax\/","url_meta":{"origin":1456809,"position":5},"title":"Alemania celebra elecciones nacionales. Esto es lo que est\u00e1 en juego","author":"","date":"febrero 22, 2025","format":false,"excerpt":"Los alemanes acuden a las urnas este domingo en las elecciones nacionales. Los sondeos de opini\u00f3n sugieren que el resultado ser\u00e1 probablemente un nuevo canciller y una nueva coalici\u00f3n de gobierno.Esta campa\u00f1a electoral, que suele ser \u00e1rida y predecible, ha sido, en comparaci\u00f3n, muy agitada.El pasado noviembre, el canciller Olaf\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1456809"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1456809\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1456809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1456809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1456809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}