{"id":1460665,"date":"2025-03-31T19:03:37","date_gmt":"2025-04-01T02:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/"},"modified":"2025-03-31T19:03:37","modified_gmt":"2025-04-01T02:03:37","slug":"abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/boston\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/","title":{"rendered":"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos"},"content":{"rendered":"<p>El equipo de abogados contratado por el Gobierno de Venezuela pidi\u00f3 en rueda de prensa este lunes al Gobierno de El Salvador que respete los derechos humanos de los 238 venezolanos deportados de Estados Unidos a mediados de marzo.<\/p>\n<p>Los abogados solicitaron por escrito la intermediaci\u00f3n de los titulares de la Procuradur\u00eda para la Defensa de los Derechos Humanos, la Comisi\u00f3n Presidencial de Derechos Humanos y el Director General de Centros Penales para que \u201cverifiquen y constaten\u201d las condiciones en las que se encuentran en el Centro de Confinamiento del Terrorismo, Cecot, que tengan acceso a medicamentos y comunicaci\u00f3n con sus familiares.<\/p>\n<p>El equipo de defensores tambi\u00e9n pidi\u00f3 a los titulares de esas instituciones que verifiquen que las personas que representan est\u00e1n en la megaprisi\u00f3n; y que les permitan reunirse con ellos.<\/p>\n<p>A mediados de marzo, 238 migrantes venezolanos fueron enviados a El Salvador por \u00f3rdenes del presidente de Estados Unidos, Donald Trump. Ni Washington ni San Salvador han divulgado las identidades de esos deportados.<\/p>\n<p>Trump y varios de sus altos funcionarios aseguran que estas personas pertenecen a la organizaci\u00f3n delictiva Tren de Aragua, pero hasta ahora no han mostrado pruebas.<\/p>\n<p>Varias organizaciones internacionales han criticado la decisi\u00f3n de expulsarlos de EE.UU. y mantenerlos en prisi\u00f3n sin que hayan enfrentado proceso penal alguno.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo de abogados contratado por el Gobierno de Venezuela pidi\u00f3 en rueda de prensa este lunes al Gobierno de El Salvador que respete los derechos humanos de los 238 venezolanos deportados de Estados Unidos a mediados de marzo. Los abogados solicitaron por escrito la intermediaci\u00f3n de los titulares de la Procuradur\u00eda para la Defensa [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1460665","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos - Noticias\" \/>\n<meta property=\"og:description\" content=\"El equipo de abogados contratado por el Gobierno de Venezuela pidi\u00f3 en rueda de prensa este lunes al Gobierno de El Salvador que respete los derechos humanos de los 238 venezolanos deportados de Estados Unidos a mediados de marzo. Los abogados solicitaron por escrito la intermediaci\u00f3n de los titulares de la Procuradur\u00eda para la Defensa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-01T02:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos\",\"datePublished\":\"2025-04-01T02:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/\"},\"wordCount\":256,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/\",\"name\":\"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-01T02:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos - Noticias","og_description":"El equipo de abogados contratado por el Gobierno de Venezuela pidi\u00f3 en rueda de prensa este lunes al Gobierno de El Salvador que respete los derechos humanos de los 238 venezolanos deportados de Estados Unidos a mediados de marzo. Los abogados solicitaron por escrito la intermediaci\u00f3n de los titulares de la Procuradur\u00eda para la Defensa [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/","og_site_name":"Noticias","article_published_time":"2025-04-01T02:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/"},"author":{"name":"","@id":""},"headline":"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos","datePublished":"2025-04-01T02:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/"},"wordCount":256,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/","name":"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-01T02:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/boston\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos","url":"http:\/\/noticiasya.com\/boston\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/boston\/2025\/03\/31\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-01T02:03:37Z","datePublished":"2025-04-01T02:03:37Z","dateModified":"2025-04-01T02:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Abogados de venezolanos deportados de EE.UU. a El Salvador piden al Gobierno de Bukele garantizar derechos humanos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2025\\\/03\\\/31\\\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/boston\\\/2025\\\/03\\\/31\\\/abogados-venezolanos-deportados-el-salvador-garantizar-derechos-humanos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-01T02:03:37Z\",\"datePublished\":\"2025-04-01T02:03:37Z\",\"dateModified\":\"2025-04-01T02:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461726,"url":"https:\/\/noticiasya.com\/boston\/2025\/04\/28\/organizacion-estadounidense-dd-hh-aboga-venezolanos-el-salvador-trax\/","url_meta":{"origin":1460665,"position":0},"title":"Organizaci\u00f3n estadounidense de DD.HH. aboga por venezolanos detenidos en El Salvador","author":"","date":"abril 28, 2025","format":false,"excerpt":"La organizaci\u00f3n Robert F. Kennedy Human Rights pidi\u00f3 este lunes al Gobierno de El Salvador respetar los derechos humanos de los venezolanos detenidos en el pa\u00eds centroamericano, al denunciar que no les permitieron reunirse con 10 de ellos a quienes representan.\u201cA pesar del derecho que tienen nuestros clientes y miles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461077,"url":"https:\/\/noticiasya.com\/boston\/2025\/04\/11\/hrw-el-salvador-deportados-lista-eeuu-orix\/","url_meta":{"origin":1460665,"position":1},"title":"HRW pide a EE.UU. y El Salvador revelar listado de venezolanos deportados y poner fin a su &#171;detenci\u00f3n arbitraria&#187;","author":"","date":"abril 11, 2025","format":false,"excerpt":"La organizaci\u00f3n Human Rights Watch pidi\u00f3 este viernes a los gobiernos de Estados Unidos y El Salvador hacer p\u00fablico el listado de los venezolanos deportados por \u00f3rdenes de la administraci\u00f3n del presidente estadounidense Donald Trump hacia el pa\u00eds centroamericano a mediados de marzo, donde fueron encerrados su prisi\u00f3n de m\u00e1xima\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460656,"url":"https:\/\/noticiasya.com\/boston\/2025\/03\/31\/fiscal-general-venezuela-acusa-el-salvador-crimenes-lesa-humanidad-orix\/","url_meta":{"origin":1460665,"position":2},"title":"Fiscal general de Venezuela acusa al Gobierno de El Salvador de &#171;cr\u00edmenes de lesa humanidad&#187; por detenci\u00f3n de venezolanos","author":"","date":"marzo 31, 2025","format":false,"excerpt":"El fiscal general de Venezuela, Tarek William Saab, asegur\u00f3 este lunes que la detenci\u00f3n de venezolanos en El Salvador, tras ser deportados por Estados Unidos es \u201cun crimen de lesa humanidad\u201d.A\u00f1adi\u00f3 que estas detenciones son \u201cun acto de discriminaci\u00f3n por ser venezolanos\u201d.\u201cEl Salvador firm\u00f3 el Estatuto de Roma, por lo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460377,"url":"https:\/\/noticiasya.com\/boston\/2025\/03\/25\/deportados-venezolanos-el-salvador-legal-analisis-orix\/","url_meta":{"origin":1460665,"position":3},"title":"En el limbo y sin jurisdicci\u00f3n: el panorama de los deportados por EE.UU. a El Salvador","author":"","date":"marzo 25, 2025","format":false,"excerpt":"Tras una semana de la deportaci\u00f3n de 261 inmigrantes de EE.UU. a El Salvador, las preguntas sobre el proceso judicial que seguir\u00e1n permanecen sin respuestas. Varios expertos consultados por CNN advierten que los detenidos est\u00e1n en una especie de limbo jur\u00eddico y sin una verdadera protecci\u00f3n legal.\u201cLa Constituci\u00f3n salvadore\u00f1a no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460467,"url":"https:\/\/noticiasya.com\/boston\/2025\/03\/26\/ee-uu-aumentar-deportaciones-salvador-kristi-noem-orix\/","url_meta":{"origin":1460665,"position":4},"title":"EE.UU. busca aumentar deportaciones a El Salvador, dice secretaria de Seguridad Nacional Kristi Noem","author":"","date":"marzo 26, 2025","format":false,"excerpt":"La secretaria de Seguridad Nacional de EE.UU., Kristi Noem, arrib\u00f3 este mi\u00e9rcoles a El Salvador para sostener una reuni\u00f3n con el presidente Nayib Bukele. La funcionaria adelant\u00f3 en una publicaci\u00f3n en la red social X que busca un aumento de vuelos con deportados y de expulsiones de personas de otras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460352,"url":"https:\/\/noticiasya.com\/boston\/2025\/03\/24\/corte-suprema-justicia-el-salvador-legalidad-detencion-venezolanos-deportados-eeuu-orix\/","url_meta":{"origin":1460665,"position":5},"title":"Piden a la Corte Suprema de Justicia de El Salvador evaluar la legalidad de la detenci\u00f3n de venezolanos deportados por EE.UU.","author":"","date":"marzo 24, 2025","format":false,"excerpt":"Un equipo de abogados salvadore\u00f1os que representa a los familiares de 30 venezolanos enviados por Estados Unidos a una c\u00e1rcel de El Salvador pidi\u00f3 este lunes a la Corte Suprema de Justicia de este pa\u00eds que eval\u00fae la legalidad de la detenci\u00f3n.Uno de ellos, Jaime Ortega, dijo que fueron contratados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/boston\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1460665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/comments?post=1460665"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/posts\/1460665\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/media?parent=1460665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/categories?post=1460665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/boston\/wp-json\/wp\/v2\/tags?post=1460665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}